{"id":1449575,"date":"2024-05-18T10:03:37","date_gmt":"2024-05-18T17:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/"},"modified":"2024-05-18T10:03:37","modified_gmt":"2024-05-18T17:03:37","slug":"estudiante-aceptado-122-universidades-becas-eligio-musica-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/","title":{"rendered":"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica"},"content":{"rendered":"<p>(CNN) &#8212; Helms Ategeka quiere ser una estrella pop. Pero cuando le dijo a su padre que planeaba estudiar m\u00fasica cuando se graduase el mes que viene en el instituto, a su padre no le hizo mucha gracia.<\/p>\n<p>As\u00ed que el oto\u00f1o pasado, el adolescente de Oakland (California) adopt\u00f3 un enfoque diferente: empez\u00f3 a postularse para las universidades. M\u00e1s de 150.<\/p>\n<p>Al poco tiempo, recibi\u00f3 una carta de aceptaci\u00f3n. Luego otra. Y otra m\u00e1s. El goteo se convirti\u00f3 en avalancha hasta llegar a 122, junto con unos US$ 5,3 millones en propuestas de ayudas econ\u00f3micas y ofertas de becas. (CNN ha visto las cartas de aceptaci\u00f3n).<\/p>\n<p>\u00bfQuieres estudiar en Europa? Estas son las 5 mejores universidades, seg\u00fan Top Universities<\/p>\n<p>Su padre dice que est\u00e1 orgulloso de la nota promedio de 3,94 de Helms y que esperaba que su hijo eligiera una carrera con estabilidad financiera, como medicina o inform\u00e1tica. O quiz\u00e1 Helms siguiera sus propios pasos como ingeniero mec\u00e1nico por la Universidad de California en Berkeley.<\/p>\n<p>Pero a medida que ve\u00eda crecer la monta\u00f1a de cartas de aceptaci\u00f3n en la habitaci\u00f3n de su hijo, la esperanza de Chris Ategeka se desvanec\u00eda. Los mensajes de los sobres multicolores llamaban a la puerta con un entusiasmo innegable. &#171;\u00a1Est\u00e1s dentro!&#187;, dec\u00eda uno. &#171;\u00a1Nuestra familia da la bienvenida a la tuya!&#187;, rezaba otro.<\/p>\n<p>&#171;Est\u00e1 tan seguro de que la m\u00fasica es lo que quiere hacer, que ser\u00eda un flaco favor para m\u00ed intentar guiarle por otro camino&#8230; por eso se present\u00f3 a un trill\u00f3n de universidades para demostrar que ten\u00eda raz\u00f3n&#187;, dice Ategeka. &#171;Le dije: &#8216;\u00bfQuieres ser m\u00fasico? Hay que trabajar mucho&#8217;. Y su reacci\u00f3n fue: usar\u00e9 mi determinaci\u00f3n para hacer esto para demostrarte lo duro que puedo trabajar&#187;.<\/p>\n<p>Pero, \u00bfc\u00f3mo empieza un joven de 18 a\u00f1os a reducir una lista tan enorme de opciones? As\u00ed comenz\u00f3 un viaje que conllev\u00f3 duras lecciones sobre el cambio y el compromiso, tanto para el padre como para el hijo.<\/p>\n<p>Ten\u00eda un requisito clave para las universidades a las que aplicaba<\/p>\n<p>La vida de Helms gira en torno a la m\u00fasica. En el instituto Head-Royce de Oakland forma parte de un grupo a capella que se re\u00fane todas las semanas para cantar versiones de m\u00fasica pop popular. Su habitaci\u00f3n est\u00e1 repleta de CD de Beyonc\u00e9, Prince y Bruno Mars. Antes de empezar la universidad en oto\u00f1o, har\u00e1 un viaje de verano a Per\u00fa con un coro para actuar en iglesias y comunidades.<\/p>\n<p>&#171;Vivo para la m\u00fasica. Paso la mayor parte del tiempo escuchando m\u00fasica, haciendo m\u00fasica o actuando&#187;, dice Helms. &#171;Me siento m\u00e1s vivo y realizado cuando estoy haciendo algo relacionado con la m\u00fasica&#187;.<\/p>\n<p>Por eso, cuando comenz\u00f3 su periplo de solicitudes universitarias, ten\u00eda un requisito clave: La universidad ten\u00eda que tener un buen programa de m\u00fasica.<\/p>\n<p>Helms Ategeka: &#171;Me siento m\u00e1s vivo y realizado cuando hago algo relacionado con la m\u00fasica&#187;. (Cortes\u00eda de Christopher Ategeka)<\/p>\n<p>Utilizaba sobre todo los portales de las universidades para sus solicitudes, dice, lo que le facilitaba copiar y pegar su informaci\u00f3n en varios sitios. Su padre pag\u00f3 la tasa de solicitud que exig\u00edan algunas universidades. Helms pas\u00f3 muchas horas escribiendo ensayos para distintas universidades, aunque la mayor\u00eda eran variaciones de la misma historia personal. En sus ensayos, destacaba su pasi\u00f3n por la m\u00fasica y su origen como inmigrante.<\/p>\n<p>Un peque\u00f1o grupo de escuelas, entre ellas Brown, Wesleyan y Colgate, lo rechazaron o lo incluyeron en su lista de espera.<\/p>\n<p>Pero la lista de escuelas que aceptaron es mucho m\u00e1s larga y abarca todo el pa\u00eds, desde grandes universidades estatales a peque\u00f1as universidades privadas: Bard College, Drexel, Howard, Loyola Marymount, Sarah Lawrence College y, por supuesto, UC Berkeley.<\/p>\n<p>Se traslad\u00f3 a Estados Unidos justo antes de que la pandemia lo cerrara todo<\/p>\n<p>Ategeka emigr\u00f3 a Estados Unidos desde su Uganda natal a finales de la d\u00e9cada de 2000 para estudiar en la Universidad de California en Berkeley. Dej\u00f3 a Helms con su madre en la ciudad de Fort Portal, al oeste de Uganda, donde vivi\u00f3 hasta que se reuni\u00f3 con su padre en California hace cinco a\u00f1os.<\/p>\n<p>Poco despu\u00e9s de que Helms llegara a Estados Unidos en 2019, el mundo se paraliz\u00f3 en gran medida debido a la pandemia de coronavirus. Asisti\u00f3 a su nueva escuela a trav\u00e9s de Zoom y se perdi\u00f3 gran parte de la interacci\u00f3n con los dem\u00e1s y el aprendizaje de los matices de la cultura estadounidense. Como resultado, no estaba seguro de que sus solicitudes para la universidad tuvieran eco o cumplieran muchos de los requisitos, dice.<\/p>\n<p>Los signos de Alzheimer estaban por todas partes, pero su cerebro mejor\u00f3<\/p>\n<p>&#171;Lo di todo en el proceso de solicitud. Me puse en contacto con las universidades para asegurarme de que hab\u00edan recibido mi solicitud y me asegur\u00e9 de dar lo mejor de m\u00ed en mis redacciones. Pero no esperaba que tantas escuelas dijeran que s\u00ed, as\u00ed que no estaba preparado&#187;, dice Helms.<\/p>\n<p>A su profesor de teatro moderno, Ricky Lapidus, no le sorprende que Helms haya recibido tantas ofertas.<\/p>\n<p>&#171;A Helms le encanta aprender: le interesan los dem\u00e1s tanto como las notas&#187;, dice Lapidus, director de la Upper School del instituto Head-Royce. &#171;Es una persona profundamente emp\u00e1tica y as\u00ed es como afronta la escuela: \u00bfc\u00f3mo aprendo m\u00e1s para poder entender mejor a los dem\u00e1s? Lo que le hace destacar para una universidad es una combinaci\u00f3n de su cerebro, seguro, pero tambi\u00e9n su alegr\u00eda y su voluntad de explorar cosas nuevas&#187;.<\/p>\n<p>Utiliz\u00f3 las palabras de su padre en su contra<\/p>\n<p>Helms ha pasado los \u00faltimos meses estudiando las p\u00e1ginas web y las cuentas en redes sociales de las escuelas que le han aceptado.<\/p>\n<p>Ha visto videos de sus programas de m\u00fasica en YouTube y TikTok para hacerse una idea de d\u00f3nde encaja. Y, lo que es m\u00e1s importante, ha mantenido conversaciones francas con su padre sobre las realidades de una carrera musical.<\/p>\n<p>Helms y su padre Christopher Ategeka nacieron en Uganda y se trasladaron a California. (Cortes\u00eda de Christopher Ategeka)<\/p>\n<p>&#171;Como padre inmigrante, pensaba: &#8216;\u00bfC\u00f3mo vas a pagar las facturas?&#8217; Pero \u00e9l es un chico motivado&#8230; y utiliz\u00f3 mis palabras en mi contra&#187;, dice Ategeka.<\/p>\n<p>A trav\u00e9s de este proceso, Ategeka dice que se dio cuenta de que estaba viendo la b\u00fasqueda acad\u00e9mica de su hijo a trav\u00e9s de lo que \u00e9l describe como una &#171;mentalidad de inmigrante africano&#187; que prioriza ciertas carreras lucrativas como marcadores de \u00e9xito.<\/p>\n<p>&#171;Siempre le digo que puede ser lo que quiera y hacer lo que se proponga. Y \u00e9l dijo: &#8216;S\u00ed, esto es lo que realmente quiero hacer'&#187;.<\/p>\n<p>Ategeka dice que poco a poco ha ido aceptando el sue\u00f1o de su hijo de estudiar m\u00fasica y convertirse en cantante pop. Dice que a\u00fan le preocupa su futuro, porque sabe lo dif\u00edcil que es hacerse lo bastante famoso como para ganarse la vida con su talento.<\/p>\n<p>Pero admira la determinaci\u00f3n y concentraci\u00f3n de Helms, al igual que su madre en Uganda. Chris Ategeka dice que su hijo ha demostrado que se toma en serio su carrera musical al ser aceptado en tantas universidades.<\/p>\n<p>&#171;Realmente est\u00e1 remarcando la idea de que no es un chico que est\u00e9 fracasando en la escuela o huyendo de casa para vivir en el metro para hacer que funcione lo de la m\u00fasica&#187;, dice Ategeka.<\/p>\n<p>&#171;Ha enviado el mensaje de que &#8216;s\u00e9 que soy inteligente. Tengo las notas. Puedo ir a la universidad. Puedo hacer lo que quiera. Pero esta es mi pasi\u00f3n, este es mi impulso, esto es lo que he elegido'&#187;.<\/p>\n<p>Su elecci\u00f3n universitaria tiene una conexi\u00f3n con su padre<\/p>\n<p>Tras meses de investigaci\u00f3n, Helms tom\u00f3 su decisi\u00f3n: se quedar\u00e1 cerca y estudiar\u00e1 m\u00fasica en el alma mater de su padre, la UC Berkeley. Un portavoz de Berkeley confirm\u00f3 que hab\u00eda sido aceptado.<\/p>\n<p>&#171;Cre\u00e9 una hoja de c\u00e1lculo y escrib\u00ed los pros y los contras de cada una de las universidades e intent\u00e9 sopesar mis prioridades&#187;, dice. &#171;Si me gustar\u00eda estar cerca de casa, qu\u00e9 tipo de programa tiene o no tiene cada escuela, ese tipo de cosas&#187;.<\/p>\n<p>Ver videos en las redes sociales de los conciertos y otros eventos musicales de las escuelas revel\u00f3 la calidad y diversidad de los programas ofrecidos, lo que ayud\u00f3 a tomar su decisi\u00f3n, dice. Los videos de eventos musicales en Berkeley ten\u00edan una cierta alegr\u00eda por la vida, dice, lo que le ayud\u00f3 a verse a s\u00ed mismo all\u00ed. La escuela tambi\u00e9n tiene una amplia variedad de programas musicales, incluidos conjuntos de m\u00fasica africana y un quinteto de metales.<\/p>\n<p>Como inmigrante, Helms forma parte de un grupo demogr\u00e1fico cada vez m\u00e1s numeroso. Los ni\u00f1os nacidos en el extranjero o en Estados Unidos de padres inmigrantes representaron el 58% del aumento en la matr\u00edcula universitaria del pa\u00eds entre 2000 y 2018, seg\u00fan muestra un estudio del Migration Policy Institute. &#171;La cara de la educaci\u00f3n superior estadounidense est\u00e1 cambiando&#187;, dice el estudio. &#171;Es m\u00e1s probable que los estudiantes provengan de familias inmigrantes que en el pasado&#187;.<\/p>\n<p>El nuevo cap\u00edtulo de Helms llega en un momento precario para las universidades estadounidenses, ya que Berkeley y otras escuelas lidian con las secuelas de las protestas estudiantiles propalestinas que han provocado interrupciones, arrestos y debates sobre los l\u00edmites de la libertad de expresi\u00f3n.<\/p>\n<p>Pero Ategeka afirma que el viaje de su hijo le ha recordado que debe estar abierto a nuevas posibilidades y formas de pensar. Cree que Helms encontrar\u00e1 la forma adecuada de participar en las dif\u00edciles conversaciones del campus.<\/p>\n<p>&#171;La universidad no consiste en conformarse con el statu quo&#8230; es la zona cero para formar a los l\u00edderes que forjar\u00e1n el futuro. Es en la universidad donde las mentes j\u00f3venes se replantean lo viejo y construyen lo nuevo para la humanidad y nuestro planeta&#187;, afirma.<\/p>\n<p>A Helms le entusiasma seguir los pasos de su padre en Berkeley, que tiene una tasa de admisi\u00f3n de alrededor del 12%. De los casi 126.000 estudiantes que solicitaron plaza en oto\u00f1o de 2023, s\u00f3lo unos 15.000 fueron aceptados.<\/p>\n<p>Pero lo m\u00e1s importante, dice, es que est\u00e1 deseando dar el siguiente paso para convertirse en m\u00fasico profesional.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Helms Ategeka quiere ser una estrella pop. Pero cuando le dijo a su padre que planeaba estudiar m\u00fasica cuando se graduase el mes que viene en el instituto, a su padre no le hizo mucha gracia. As\u00ed que el oto\u00f1o pasado, el adolescente de Oakland (California) adopt\u00f3 un enfoque diferente: empez\u00f3 a postularse [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449575","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Helms Ategeka quiere ser una estrella pop. Pero cuando le dijo a su padre que planeaba estudiar m\u00fasica cuando se graduase el mes que viene en el instituto, a su padre no le hizo mucha gracia. As\u00ed que el oto\u00f1o pasado, el adolescente de Oakland (California) adopt\u00f3 un enfoque diferente: empez\u00f3 a postularse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-18T17:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica\",\"datePublished\":\"2024-05-18T17:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/\"},\"wordCount\":1805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/\",\"name\":\"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-18T17:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica - Noticias","og_description":"(CNN) &#8212; Helms Ategeka quiere ser una estrella pop. Pero cuando le dijo a su padre que planeaba estudiar m\u00fasica cuando se graduase el mes que viene en el instituto, a su padre no le hizo mucha gracia. As\u00ed que el oto\u00f1o pasado, el adolescente de Oakland (California) adopt\u00f3 un enfoque diferente: empez\u00f3 a postularse [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-18T17:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/"},"author":{"name":"","@id":""},"headline":"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica","datePublished":"2024-05-18T17:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/"},"wordCount":1805,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/","name":"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-18T17:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\u00f3 seg\u00fan su amor por la m\u00fasica","url":"http:\/\/noticiasya.com\/nacional\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/05\/18\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-18T17:03:37Z","datePublished":"2024-05-18T17:03:37Z","dateModified":"2024-05-18T17:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fue admitido en 122 universidades con US$ 5,3 millones en becas. Eligi\\u00f3 seg\\u00fan su amor por la m\\u00fasica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/18\\\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/18\\\/estudiante-aceptado-122-universidades-becas-eligio-musica-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-18T17:03:37Z\",\"datePublished\":\"2024-05-18T17:03:37Z\",\"dateModified\":\"2024-05-18T17:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464806,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/23\/investigan-universidades-becas-indocumentados-trax\/","url_meta":{"origin":1449575,"position":0},"title":"La Oficina de Derechos Civiles del Departamento de Educaci\u00f3n investiga a 5 universidades por becas para indocumentados","author":"","date":"julio 23, 2025","format":false,"excerpt":"Cinco universidades est\u00e1n siendo investigadas por la Oficina de Derechos Civiles del Departamento de Educaci\u00f3n de Estados Unidos por otorgar becas a inmigrantes indocumentados inscritos en el programa DACA, implementado durante la administraci\u00f3n Obama, seg\u00fan un comunicado del Departamento de Educaci\u00f3n emitido este mi\u00e9rcoles.Acci\u00f3n diferida para los llegados en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460223,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/21\/trump-objetivo-generacional-conservador-riesgo-republicanos-estudiantes-trax\/","url_meta":{"origin":1449575,"position":1},"title":"Trump logra un objetivo generacional conservador, pero es un riesgo tanto para republicanos como para estudiantes","author":"","date":"marzo 21, 2025","format":false,"excerpt":"El presidente Donald Trump se atribuye una serie de victorias generacionales para el Partido Republicano en el campo de batalla cultural e ideol\u00f3gico de la educaci\u00f3n, un terreno que los partidarios de MAGA (Hacer grande a Estados Unidos otra vez) consideran un basti\u00f3n hostil del poder liberal, propenso a ser\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461572,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/24\/trump-revoco-visas-estatutos-estudiantes-internacionales-trax\/","url_meta":{"origin":1449575,"position":2},"title":"El Gobierno de Trump revoc\u00f3 m\u00e1s de 1.500 visas y estatutos de estudiantes internacionales, seg\u00fan un informe de CNN","author":"","date":"abril 24, 2025","format":false,"excerpt":"Este a\u00f1o, m\u00e1s de 1.500 estudiantes internacionales, reci\u00e9n graduados y universidades han visto revocadas sus visas o estatus en el Sistema de Informaci\u00f3n de Estudiantes y Visitantes de Intercambio (SIIS) en m\u00e1s de 200 universidades estadounidenses, seg\u00fan datos de CNN.En Texas, 176 estudiantes se han visto afectados en varias universidades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461201,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/15\/universidades-respuestas-investigaciones-congelacion-financiacion-trax\/","url_meta":{"origin":1449575,"position":3},"title":"El presidente de Harvard rechaz\u00f3 las exigencias de Trump. As\u00ed han respondido otros l\u00edderes universitarios a la Casa Blanca","author":"","date":"abril 15, 2025","format":false,"excerpt":"La tensi\u00f3n entre la Universidad de Harvard y la administraci\u00f3n del presidente Donald Trump aument\u00f3 el lunes, cuando el Gobierno federal congel\u00f3 m\u00e1s de US$ 2.000 millones en subvenciones multianuales y US$ 60 millones en contratos multianuales despu\u00e9s de que la universidad de la Ivy League se negara a cumplir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471219,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/13\/pentagono-prohibir-ayuda-matricula-universidades-hegseth-trax\/","url_meta":{"origin":1449575,"position":4},"title":"El Pent\u00e1gono planea cortar ayuda educativa a militares en universidades de \u00e9lite que Hegseth considere &#171;sesgadas&#187;","author":"","date":"febrero 13, 2026","format":false,"excerpt":"Los oficiales de las Fuerzas Armadas podr\u00edan pronto encontrar decenas de las principales universidades de Estados Unidos abruptamente fuera de alcance para recibir ayuda para la matr\u00edcula, como parte de la campa\u00f1a del secretario de Defensa, Pete Hegseth, contra las escuelas que, seg\u00fan \u00e9l, tienen prejuicios contra el ej\u00e9rcito estadounidense\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461248,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/16\/profesor-harvard-ela-financiacion-congelacion-federal-trax\/","url_meta":{"origin":1449575,"position":5},"title":"Un profesor de Harvard estudiaba ELA. Perdi\u00f3 su financiaci\u00f3n tras la congelaci\u00f3n federal","author":"","date":"abril 16, 2025","format":false,"excerpt":"Un profesor laureado que trabaja en el diagn\u00f3stico temprano de ELA, o esclerosis lateral amiotr\u00f3fica, es uno de varios investigadores de la Universidad de Harvard que recibieron \u00f3rdenes de suspender sus trabajos despu\u00e9s de que la administraci\u00f3n Trump congelara m\u00e1s de US$ 2.200 millones en fondos debido a la negativa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449575"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449575\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}