{"id":1449583,"date":"2024-05-19T04:03:43","date_gmt":"2024-05-19T11:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/"},"modified":"2024-05-19T04:03:43","modified_gmt":"2024-05-19T11:03:43","slug":"simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/","title":{"rendered":"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024"},"content":{"rendered":"<p>(CNN) &#8212; La gimnasta estadounidense Simon Biles comenz\u00f3 su a\u00f1o ol\u00edmpico en plena forma, ganando el oro en el concurso completo femenino en el Core Hydration Classic en su primera competici\u00f3n de 2024. La actual campeona mundial en concurso completo tambi\u00e9n gan\u00f3 el oro en ejercicios de suelo en el encuentro, que fue celebrado en el Centro XL en Hartford, Connecticut.<\/p>\n<p>La puntuaci\u00f3n general de Biles de 59.500 fue casi dos puntos mejor que la medallista de plata general Shilese Jones y m\u00e1s de cuatro puntos m\u00e1s que el medallista de bronce Jordan Chiles.<\/p>\n<p>El siguiente camino hacia los Juegos Ol\u00edmpicos de Par\u00eds para Biles, de 27 a\u00f1os, ser\u00e1 el Campeonato de Estados Unidos en Fort Worth, Texas, que comenzar\u00e1 el 30 de mayo, seguido de las Pruebas Ol\u00edmpicas de Estados Unidos que comenzar\u00e1n el 27 de junio en Minneapolis, Minnesota.<\/p>\n<p>El esperanzador regreso de Biles a los Juegos Ol\u00edmpicos se produce despu\u00e9s de que la siete veces medallista ol\u00edmpica se retirara de la competencia en los Juegos Ol\u00edmpicos de Tokio en 2021 despu\u00e9s de experimentar los &#171;giros&#187;, un bloqueo mental que hace que una gimnasta pierda la noci\u00f3n de su posici\u00f3n en el aire. Biles a\u00fan se llev\u00f3 una medalla de plata por equipos femeninos y un bronce en barra de equilibrio individual en los Juegos de Tokio.<\/p>\n<p>Despu\u00e9s de una ausencia de casi dos a\u00f1os del deporte, Biles regres\u00f3 a la competencia con el oro en el Core Hydration Classic de 2023, seguido del oro en el Campeonato Mundial y de EE. UU. m\u00e1s tarde ese a\u00f1o.<\/p>\n<p>La ceremonia de apertura de los Juegos Ol\u00edmpicos de Par\u00eds 2024 tendr\u00e1 lugar el 26 de julio y la competici\u00f3n de gimnasia art\u00edstica femenina comenzar\u00e1 el 28 de julio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La gimnasta estadounidense Simon Biles comenz\u00f3 su a\u00f1o ol\u00edmpico en plena forma, ganando el oro en el concurso completo femenino en el Core Hydration Classic en su primera competici\u00f3n de 2024. La actual campeona mundial en concurso completo tambi\u00e9n gan\u00f3 el oro en ejercicios de suelo en el encuentro, que fue celebrado en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449583","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La gimnasta estadounidense Simon Biles comenz\u00f3 su a\u00f1o ol\u00edmpico en plena forma, ganando el oro en el concurso completo femenino en el Core Hydration Classic en su primera competici\u00f3n de 2024. La actual campeona mundial en concurso completo tambi\u00e9n gan\u00f3 el oro en ejercicios de suelo en el encuentro, que fue celebrado en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-19T11:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024\",\"datePublished\":\"2024-05-19T11:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/\"},\"wordCount\":335,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/\",\"name\":\"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-19T11:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024 - Noticias","og_description":"(CNN) &#8212; La gimnasta estadounidense Simon Biles comenz\u00f3 su a\u00f1o ol\u00edmpico en plena forma, ganando el oro en el concurso completo femenino en el Core Hydration Classic en su primera competici\u00f3n de 2024. La actual campeona mundial en concurso completo tambi\u00e9n gan\u00f3 el oro en ejercicios de suelo en el encuentro, que fue celebrado en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-19T11:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/"},"author":{"name":"","@id":""},"headline":"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024","datePublished":"2024-05-19T11:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/"},"wordCount":335,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/","name":"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-19T11:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Simone Biles gana el t\u00edtulo completo en su primera competici\u00f3n de 2024","url":"http:\/\/noticiasya.com\/nacional\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/05\/19\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-19T11:03:43Z","datePublished":"2024-05-19T11:03:43Z","dateModified":"2024-05-19T11:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Simone Biles gana el t\\u00edtulo completo en su primera competici\\u00f3n de 2024\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/19\\\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/19\\\/simone-biles-gana-el-titulo-completo-en-su-primera-competicion-de-2024-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-19T11:03:43Z\",\"datePublished\":\"2024-05-19T11:03:43Z\",\"dateModified\":\"2024-05-19T11:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451559,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/01\/brillante-regreso-simone-biles-final-individual-completa-gimnasia-trax\/","url_meta":{"origin":1449583,"position":0},"title":"El brillante regreso de Simone Biles y otras conclusiones de la final individual completa de gimnasia","author":"","date":"agosto 1, 2024","format":false,"excerpt":"Par\u00eds (CNN) -- Simone Biles vuelve a ser la medallista de oro ol\u00edmpica en gimnasia completa individual tras ganar una de las finales m\u00e1s espectaculares de los Juegos Ol\u00edmpicos de Par\u00eds.Biles resisti\u00f3 el en\u00e9rgico desaf\u00edo de la brillante brasile\u00f1a Rebeca Andrade, que volvi\u00f3 a ganar la plata, y la compa\u00f1era\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451583,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/03\/simone-biles-gana-final-de-salto-tercera-medalla-oro-juegos-olimpicos-trax\/","url_meta":{"origin":1449583,"position":1},"title":"Simone Biles logra su tercera medalla de oro en salto en los Juegos de Par\u00eds; la brasile\u00f1a Rebeca Andrade qued\u00f3 segunda","author":"","date":"agosto 3, 2024","format":false,"excerpt":"(CNN) -- Simone Biles gan\u00f3 este s\u00e1bado su tercera medalla de oro de los Juegos Ol\u00edmpicos de Par\u00eds con una actuaci\u00f3n dominante en la final femenina de salto.Biles termin\u00f3 con una puntuaci\u00f3n media de 15.300 y se adjudic\u00f3 su d\u00e9cima medalla ol\u00edmpica (7 de oro, 1 de plata y 2\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451608,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/05\/rebeca-andrade-gimnasta-brasilena-derroto-simone-biles-trax\/","url_meta":{"origin":1449583,"position":2},"title":"Qui\u00e9n es Rebeca Andrade, la gimnasta brasile\u00f1a que derrot\u00f3 a Simone Biles","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) -- Simone Biles, once veces medallista ol\u00edmpica, es dif\u00edcil de batir, pero no imposible.La gimnasta brasile\u00f1a Rebeca Andrade lo demostr\u00f3 al superar a su rival estadounidense en la final de suelo de los Juegos Ol\u00edmpicos de Par\u00eds. Biles se llev\u00f3 la medalla de plata.Fue un momento de catarsis para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451545,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/01\/simone-biles-medalla-oro-gimnasia-individual-completo-paris-2024-orix\/","url_meta":{"origin":1449583,"position":3},"title":"\u00a1La leyenda sigue! Simone Biles gana la medalla de oro en la final individual completa de gimnasia en Par\u00eds 2024","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La gimnasta estadounidense Simone Biles lo volvi\u00f3 a conseguir: obtuvo una nueva medalla de oro, su segunda en los Juegos Ol\u00edmpicos de Par\u00eds 2024, esta vez en la final individual femenina completa de la gimnasia art\u00edstica.En cuatro rotaciones que nos entregaron una final \u00e9pica, Biles termin\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451510,"url":"https:\/\/noticiasya.com\/nacional\/2024\/07\/30\/simone-biles-juegos-olimpicos-remontada-increible-trax\/","url_meta":{"origin":1449583,"position":4},"title":"Simone Biles gana el oro, su octava medalla ol\u00edmpica, y se convierte en la gimnasta estadounidense m\u00e1s condecorada","author":"","date":"julio 30, 2024","format":false,"excerpt":"Par\u00eds (CNN) --\u00a0Era todo lo que ella podr\u00eda haber esperado que fuera.Tres a\u00f1os despu\u00e9s de retirarse de la final de gimnasia por equipos, Simone Biles estaba sola una vez m\u00e1s en los Juegos Ol\u00edmpicos. Pero la energ\u00eda no pod\u00eda ser m\u00e1s diferente.Biles, la \u00faltima gimnasta de la noche, se subi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451757,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/12\/polemica-medalla-bronce-gimnasta-jordan-chiles-trax\/","url_meta":{"origin":1449583,"position":5},"title":"\u00bfPor qu\u00e9 le retiraron la medalla de bronce a la gimnasta Jordan Chiles en los Juegos Ol\u00edmpicos de Par\u00eds 2024?","author":"","date":"agosto 12, 2024","format":false,"excerpt":"(CNN) -- La gimnasia est\u00e1 llena de giros y sorpresas, pero el desarrollo de la saga sobre qu\u00e9 gimnasta se llevar\u00e1 oficialmente a casa el bronce en la final del ejercicio art\u00edstico de suelo femenino de los Juegos Ol\u00edmpicos de 2024 ha sido m\u00e1s complicado de lo que nadie esperaba.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449583"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449583\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}