{"id":1449619,"date":"2024-05-21T01:03:39","date_gmt":"2024-05-21T08:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/"},"modified":"2024-05-21T01:03:39","modified_gmt":"2024-05-21T08:03:39","slug":"the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","title":{"rendered":"&#171;El Apprentice&#187;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes"},"content":{"rendered":"<p>(CNN) &#8212; &#171;The Apprentice&#187;, una nueva pel\u00edcula sobre los negocios inmobiliarios del expresidente Donald Trump en Nueva York en los a\u00f1os 80, se estren\u00f3 con una gran ovaci\u00f3n en el Festival de Cannes y cr\u00edticas por parte de su campa\u00f1a.<\/p>\n<p>La pel\u00edcula sobre el posible candidato republicano para la presidencia de 2024 llega cinco meses antes de las elecciones presidenciales.<\/p>\n<p>Protagonizada por Sebastian Stan como un joven Trump, la pel\u00edcula es una &#171;exploraci\u00f3n del poder y la ambici\u00f3n en un mundo de corrupci\u00f3n y enga\u00f1o&#187;, seg\u00fan la sinopsis oficial.<\/p>\n<p>Jeremy Strong, protagonista de &#171;Succession&#187;, interpreta a Roy Cohn, el abogado que Trump consider\u00f3 su mentor al principio de su carrera.<\/p>\n<p>&#171;Es una historia de mentor-protegido que traza los or\u00edgenes de una dinast\u00eda americana. Llena de personajes m\u00e1s grandes que la vida, revela el coste moral y humano de una cultura definida por ganadores y perdedores&#187;, reza la sinopsis.<\/p>\n<p>&#171;The Apprentice&#187;, que, a pesar del t\u00edtulo, no hace referencia a la serie de telerrealidad protagonizada por Trump, incluye una advertencia de que algunas partes de la historia son ligeramente ficticias. Est\u00e1 escrita por el bi\u00f3grafo y periodista pol\u00edtico Gabriel Sherman y dirigida por el cineasta iran\u00ed-dan\u00e9s Ali Abbasi.<\/p>\n<p>AN\u00c1LISIS | La telerrealidad ayud\u00f3 a formar la imagen de Donald Trump al difuminar las l\u00edneas de la realidad<\/p>\n<p>&#171;En tiempos de agitaci\u00f3n, existe la tendencia a mirar hacia dentro, a enterrar la cabeza en la arena y mirar hacia adentro esperando lo mejor, esperando que la tormenta se aleje&#187;, dijo Abassi al p\u00fablico en el estreno de la pel\u00edcula este lunes, seg\u00fan im\u00e1genes publicadas en Internet.<\/p>\n<p>&#171;Pero la tormenta no se va. De hecho, la tormenta est\u00e1 llegando. Los peores tiempos est\u00e1n por llegar&#187;, agreg\u00f3 Abassi.<\/p>\n<p>El director continu\u00f3 diciendo que eligi\u00f3 hacer una pel\u00edcula &#171;sobre el mundo&#187; a trav\u00e9s de una historia sobre Trump, porque &#171;no hay una manera metaf\u00f3rica agradable de hacer frente a la creciente ola de fascismo&#187;.<\/p>\n<p>&#171;Solo existe la manera desordenada, solo existe la manera banal. Solo existe la manera de enfrentarse a esta ola en su propio terreno, a su propio nivel&#187;, ha dicho. &#171;No va a ser bonito, pero creo que el problema del mundo es que la gente buena ha estado callada durante demasiado tiempo&#187;.<\/p>\n<p>Gabriel Sherman, de izquierda a derecha, Maria Bakalova, el director Ali Abbasi, Sebastian Stan y Martin Donovan posan para los fot\u00f3grafos en el estreno el lunes. (Cr\u00e9dito: AP)<\/p>\n<p>La pel\u00edcula incluye una representaci\u00f3n de la relaci\u00f3n de Trump con su primera esposa, Ivana, y su divorcio, seg\u00fan The Hollywood Reporter. Una escena del expresidente someti\u00e9ndose a una liposucci\u00f3n provoc\u00f3 jadeos audibles entre el p\u00fablico, inform\u00f3 la publicaci\u00f3n.<\/p>\n<p>&#171;Vamos a presentar una demanda para hacer frente a las afirmaciones descaradamente falsas de estos pretendidos cineastas. Esta basura es pura ficci\u00f3n que sensacionaliza mentiras que han sido desmentidas hace mucho tiempo&#187;, dijo Steven Cheung, un portavoz de la campa\u00f1a de Trump, en un comunicado a CNN. &#171;Esta &#8216;pel\u00edcula&#8217; es pura difamaci\u00f3n maliciosa, no deber\u00eda ver la luz del d\u00eda, y ni siquiera merece un lugar en la secci\u00f3n directa a DVD de un contenedor de ofertas en una tienda de pel\u00edculas de descuento que pronto cerrar\u00e1, pertenece a un contenedor de basura&#187;.<\/p>\n<p>Maria Bakalova interpreta a la difunta Ivana Trump, fallecida en 2022. Martin Donovan, Catherine McNally y Charlie Carrick, entre otros, completan el reparto.<\/p>\n<p>Todav\u00eda no se ha anunciado la fecha de estreno de la pel\u00edcula. &#171;The Apprentice&#187; a\u00fan no tiene distribuidor en Estados Unidos, seg\u00fan IMDb.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; &#171;The Apprentice&#187;, una nueva pel\u00edcula sobre los negocios inmobiliarios del expresidente Donald Trump en Nueva York en los a\u00f1os 80, se estren\u00f3 con una gran ovaci\u00f3n en el Festival de Cannes y cr\u00edticas por parte de su campa\u00f1a. La pel\u00edcula sobre el posible candidato republicano para la presidencia de 2024 llega cinco meses [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449619","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;El Apprentice&quot;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;El Apprentice&quot;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; &#171;The Apprentice&#187;, una nueva pel\u00edcula sobre los negocios inmobiliarios del expresidente Donald Trump en Nueva York en los a\u00f1os 80, se estren\u00f3 con una gran ovaci\u00f3n en el Festival de Cannes y cr\u00edticas por parte de su campa\u00f1a. La pel\u00edcula sobre el posible candidato republicano para la presidencia de 2024 llega cinco meses [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T08:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;El Apprentice&#187;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes\",\"datePublished\":\"2024-05-21T08:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/\",\"name\":\"\\\"El Apprentice\\\", una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-21T08:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;El Apprentice&#187;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"El Apprentice\", una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"El Apprentice\", una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes - Noticias","og_description":"(CNN) &#8212; &#171;The Apprentice&#187;, una nueva pel\u00edcula sobre los negocios inmobiliarios del expresidente Donald Trump en Nueva York en los a\u00f1os 80, se estren\u00f3 con una gran ovaci\u00f3n en el Festival de Cannes y cr\u00edticas por parte de su campa\u00f1a. La pel\u00edcula sobre el posible candidato republicano para la presidencia de 2024 llega cinco meses [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-21T08:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;El Apprentice&#187;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes","datePublished":"2024-05-21T08:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","name":"\"El Apprentice\", una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-21T08:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;El Apprentice&#187;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;El Apprentice&#187;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes","url":"http:\/\/noticiasya.com\/nacional\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-21T08:03:39Z","datePublished":"2024-05-21T08:03:39Z","dateModified":"2024-05-21T08:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;El Apprentice&#187;, una pel\\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\\u00e9mica en el Festival de Cine de Cannes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/21\\\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/21\\\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-21T08:03:39Z\",\"datePublished\":\"2024-05-21T08:03:39Z\",\"dateModified\":\"2024-05-21T08:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462339,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/14\/robert-de-niro-contra-trump-discurso-cannes-trax\/","url_meta":{"origin":1449619,"position":0},"title":"Robert De Niro arremete contra Trump en su discurso en Cannes","author":"","date":"mayo 14, 2025","format":false,"excerpt":"El actor de Hollywood Robert De Niro aprovech\u00f3 su discurso de aceptaci\u00f3n de premios en el Festival de Cine de Cannes para criticar al presidente estadounidense Donald Trump.De Niro, de 81 a\u00f1os, recib\u00eda la Palma de Oro a la trayectoria en el evento celebrado el martes en el sur de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462445,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/16\/tiempo-ovaciones-de-pie-aplausos-cannes-orix\/","url_meta":{"origin":1449619,"position":1},"title":"Las ovaciones de pie en Cannes no significan lo que crees: la verdad de los elogios en el festival de cine","author":"","date":"mayo 16, 2025","format":false,"excerpt":"\u00a1Saquen sus cron\u00f3metros! Ahora que arranc\u00f3 una nueva edici\u00f3n del festival de cine de Cannes, la prensa y otros asistentes miden cuidadosamente los minutos y segundos que dura cada una de las ovaciones de pie para las pel\u00edculas en competencia. \u00a1Pero ojo que eso no se traduce en un eventual\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472113,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/11\/barbra-streisand-palma-de-oro-festival-cine-cannes-orix\/","url_meta":{"origin":1449619,"position":2},"title":"Barbra Streisand recibir\u00e1 la Palma de Oro honor\u00edfica en la edici\u00f3n 79 del Festival de Cine de Cannes","author":"","date":"marzo 11, 2026","format":false,"excerpt":"La actriz, cantante y directora Barbra Streisand recibir\u00e1 la Palma de Oro honor\u00edfica en la edici\u00f3n n\u00famero 79 del Festival de Cine de Cannes. El sitio oficial del prestigioso certamen inform\u00f3 que la artista ser\u00e1 homenajeada el pr\u00f3ximo 23 de mayo, cuando recibir\u00e1 este galard\u00f3n que reconoce toda su trayectoriaStreisand\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456406,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/09\/eugenio-derbez-critica-selena-gomez-emilia-perez-orix\/","url_meta":{"origin":1449619,"position":3},"title":"Eugenio Derbez critica desempe\u00f1o de Selena Gomez en la pel\u00edcula &#171;Emilia P\u00e9rez&#187;; ella se defiende","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"El actor mexicano Eugenio Derbez critic\u00f3 el desempe\u00f1o de la superestrella Selena Gomez en la pel\u00edcula \u201cEmilia P\u00e9rez\u201d, en la cual interpreta a un personaje latino y habla en espa\u00f1ol.\u201c(La actuaci\u00f3n de) Selena es indefendible\u201d, dijo Derbez en el podcast Hablemos de cine con.\u201cEmilia P\u00e9rez\u201d es la m\u00e1s reciente pel\u00edcula\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459406,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/02\/anora-ganadora-mejor-pelicula-premios-oscar-2025-trax\/","url_meta":{"origin":1449619,"position":4},"title":"&#171;Anora&#187;, ganadora a mejor pel\u00edcula en los premios Oscar 2025","author":"","date":"marzo 2, 2025","format":false,"excerpt":"\u201cAnora\u201d, de Sean Baker, gan\u00f3 el Oscar a la mejor pel\u00edcula en la 97\u00aa edici\u00f3n de los premios de la Academia.Protagonizada por la estrella revelaci\u00f3n Mikey Madison, \u201cAnora\u201d es una comedia dram\u00e1tica que sigue a una bailarina de striptease de Brooklyn a quien convocan a bailar para el hijo descarriado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471892,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/05\/wagner-moura-carrera-premio-oscar-orix\/","url_meta":{"origin":1449619,"position":5},"title":"Wagner Moura, el atleta suramericano en la carrera por el \u00d3scar","author":"","date":"marzo 5, 2026","format":false,"excerpt":"Durante los \u00faltimos diez meses, el actor brasile\u00f1o Wagner Moura no ha parado de viajar. No se debe a un extenso rodaje, sino a la popularidad de su m\u00e1s reciente pel\u00edcula, \u201cEl agente secreto\u201d (\u201cO Agente Secreto\u201d), cuya promoci\u00f3n lo tiene bastante ocupado desde su estreno en el festival de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449619"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449619\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}