{"id":1449623,"date":"2024-05-21T07:03:47","date_gmt":"2024-05-21T14:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/"},"modified":"2024-05-21T07:03:47","modified_gmt":"2024-05-21T14:03:47","slug":"analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","title":{"rendered":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada"},"content":{"rendered":"<p>(CNN) &#8212; Incluso antes de que el jefe del ej\u00e9rcito de Ir\u00e1n, Mohammad Bagheri, ordenara una investigaci\u00f3n sobre el accidente de helic\u00f3ptero que cost\u00f3 a la Rep\u00fablica Isl\u00e1mica la vida de dos de sus principales pol\u00edticos,\u00a0ya se estaba culpando a Estados Unidos.<\/p>\n<p>El cuerpo del presidente\u00a0Ebrahim Raisi\u00a0era sacado cuidadosamente del lugar del accidente mientras el ex ministro de Asuntos Exteriores Javad Zarif declaraba \u00e1cidamente a la televisi\u00f3n estatal iran\u00ed que &#171;una de las causas de este desgarrador incidente es Estados Unidos, que al sancionar la venta de la industria aeron\u00e1utica a Ir\u00e1n provoc\u00f3 el martirio del presidente y sus acompa\u00f1antes. El crimen de Estados Unidos quedar\u00e1 grabado en la mente del pueblo iran\u00ed y en la historia&#187;. Funcionarios estadounidenses rechazaron r\u00e1pidamente las acusaciones calific\u00e1ndolas de &#171;infundadas&#187;.<\/p>\n<p>Hay muchas razones por las que el envejecido helic\u00f3ptero Bell 212, de fabricaci\u00f3n estadounidense y de la \u00e9poca de la guerra de Vietnam, pudo estrellarse. Un mantenimiento deficiente o un error humano en la densa niebla son algunas de ellas. El ministro de Transporte de Turqu\u00eda, Abdulkadir Uraloglu, declar\u00f3 que es demasiado pronto para pronunciarse sobre la causa del accidente, pero los primeros indicios apuntan a que fue un accidente debido a la niebla.<\/p>\n<p>Ir\u00e1n inicia d\u00edas de ceremonias f\u00fanebres por el presidente Ebrahim Raisi mientras los investigadores establecen las causas del accidente en el que muri\u00f3<\/p>\n<p>Pero, \u00bfpor qu\u00e9 Ir\u00e1n arriesg\u00f3 tanto al presidente como al ministro de Asuntos Exteriores en el mismo helic\u00f3ptero, cuando ese d\u00eda se utilizaron tres para llevar a la delegaci\u00f3n a la inauguraci\u00f3n de la presa en la frontera con Azerbaiy\u00e1n?<\/p>\n<p>Cuando Raisi -acompa\u00f1ado por su ministro de Asuntos Exteriores, Hossein Amir-Abdollahian, el gobernador provincial, Malek Rahmati, y el influyente im\u00e1n de las oraciones del viernes en Tabriz, Mohammed Ali Alehashem- baj\u00f3 del helic\u00f3ptero en la presa de Qiz Ghal&#8217;e el domingo por la ma\u00f1ana, la visibilidad era buena.<\/p>\n<p>El sol brillaba mientras Raisi estrechaba la mano de su hom\u00f3logo azer\u00ed Ilham Aliyav en la frontera, en el puente sobre las tranquilas aguas del r\u00edo Aras, en medio de la presa. El d\u00eda hab\u00eda empezado aparentemente bien. Las relaciones entre las dos naciones, hasta entonces fr\u00edas, parec\u00edan calentarse.<\/p>\n<p>En la ruta elegida por la tripulaci\u00f3n para su viaje al centro regional de Tabriz, donde esperaba el avi\u00f3n del presidente, el tiempo empeoraba.<\/p>\n<p>Aunque las lluvias estacionales hab\u00edan ido disminuyendo, se acercaba otro frente meteorol\u00f3gico. Fr\u00edo y h\u00famedo. La niebla se espesaba alrededor de los escarpados, remotos e implacables picos de 1.800 metros en la ruta de vuelo directa.<\/p>\n<p>Personas lamentan la muerte del presidente de Ir\u00e1n, Ebrahim Raisi, y del ministro de Asuntos Exteriores, Hossein Amir-Abdollahian, en un accidente de helic\u00f3ptero el d\u00eda anterior, en la plaza Valiasr, el 20 de mayo de 2024 en Teher\u00e1n, Ir\u00e1n. (Cr\u00e9dito: Majid Saeedi\/Getty Images)<\/p>\n<p>As\u00ed pues, primera pregunta: \u00bfpor qu\u00e9 volar a trav\u00e9s de las monta\u00f1as cuando un desv\u00edo alrededor de la cordillera o hacia otro destino podr\u00eda haber sido m\u00e1s seguro?<\/p>\n<p>La siguiente pregunta podr\u00eda ser, sabiendo que el tiempo era malo y teniendo tres helic\u00f3pteros en el viaje, \u00bfpor qu\u00e9 poner al presidente y al ministro de Asuntos Exteriores en el mismo avi\u00f3n?<\/p>\n<p>El accidente tambi\u00e9n revel\u00f3 la falta de preparaci\u00f3n de Ir\u00e1n para hacer frente a una calamidad de esta naturaleza.<\/p>\n<p>Parec\u00eda que no hab\u00eda escasez de personal, pero carec\u00edan de la tecnolog\u00eda adecuada.<\/p>\n<p>En mitad de la noche, mientras cientos, si no miles, de m\u00e9dicos, monta\u00f1eses, soldados, polic\u00edas e incluso el Cuerpo de \u00e9lite de la Guardia Revolucionaria rastreaban las escarpadas cumbres y los profundos barrancos, fue el dron turco AKINCI, que volaba en bucle por encima de las nubes, el primero en localizar rastros del helic\u00f3ptero.<\/p>\n<p>El presidente de Ir\u00e1n muri\u00f3 mientras ocupaba el cargo. Esto es lo que sigue<\/p>\n<p>Para una naci\u00f3n que fabrica, utiliza y exporta drones asesinos de largo alcance a pa\u00edses como Rusia para su guerra en Ucrania, y a actores no estatales como las milicias iraqu\u00edes y los hut\u00edes en Yemen -que en la actualidad tienen en jaque al comercio mar\u00edtimo mundial atacando barcos en el Mar Rojo- no parec\u00eda tener un simple dron de vigilancia capaz de realizar esta tarea.<\/p>\n<p>Poco antes de que AKINCI comenzara a grabar su patr\u00f3n de vigilancia sistem\u00e1tica en el cielo nocturno, Ir\u00e1n tambi\u00e9n hab\u00eda pedido a Turqu\u00eda y Rusia helic\u00f3pteros con capacidad de visi\u00f3n nocturna. Impl\u00edcitamente, si los ten\u00edan, no pod\u00edan hacerlos llegar lo suficientemente r\u00e1pido.<\/p>\n<p>Esta noche, de importancia aparentemente vital para Ir\u00e1n y su l\u00edder supremo, el ayatol\u00e1 Al\u00ed Jamenei, la proeza militar de Ir\u00e1n -proyectada a trav\u00e9s de su eje de apoderados en Medio Oriente y su aliado Rusia- parec\u00eda vac\u00eda.<\/p>\n<p>Al exministro de Asuntos Exteriores Zarif le gustar\u00eda que el mundo creyera que el n\u00facleo tecnol\u00f3gico de Ir\u00e1n ha sido vaciado por las sanciones estadounidenses, pero esa alegaci\u00f3n tambi\u00e9n est\u00e1 contaminada por la arrogancia.<\/p>\n<p>Si, como afirma, el helic\u00f3ptero del presidente fue v\u00edctima de la escasez de piezas de repuesto de calidad debido a las sanciones de EE.UU., \u00bfpor qu\u00e9 arriesgar la vida del presidente y del ministro de Asuntos Exteriores en una aeronave considerada potencialmente poco fiable? Qu\u00e9 otras posibilidades de transporte a\u00e9reo hab\u00eda, y si no hab\u00eda ninguna eso plantea la misma pregunta, por partida doble.<\/p>\n<p>Los presidentes de Ir\u00e1n no est\u00e1n ociosos, necesitan ir a sitios. La planificaci\u00f3n de mejores opciones podr\u00eda haberse convertido en una prioridad mayor. \u00bfAcaso la arrogancia entre el personal del presidente o en los escalones superiores del ej\u00e9rcito opt\u00f3 por confiar en el azar? Seg\u00fan Zarif, el mantenimiento del Bell 212 era un problema previsible.<\/p>\n<p>No ser\u00eda la primera vez que la arrogancia ahueca la l\u00f3gica, pero sin duda es la m\u00e1s tr\u00e1gica para los implicados.<\/p>\n<p>La iron\u00eda impl\u00edcita es que el propio Raisi fue uno de los art\u00edfices del aura de poder de Ir\u00e1n, s\u00f3lo para descubrir que estaba vac\u00eda cuando m\u00e1s la necesitaba.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Incluso antes de que el jefe del ej\u00e9rcito de Ir\u00e1n, Mohammad Bagheri, ordenara una investigaci\u00f3n sobre el accidente de helic\u00f3ptero que cost\u00f3 a la Rep\u00fablica Isl\u00e1mica la vida de dos de sus principales pol\u00edticos,\u00a0ya se estaba culpando a Estados Unidos. El cuerpo del presidente\u00a0Ebrahim Raisi\u00a0era sacado cuidadosamente del lugar del accidente mientras el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449623","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Incluso antes de que el jefe del ej\u00e9rcito de Ir\u00e1n, Mohammad Bagheri, ordenara una investigaci\u00f3n sobre el accidente de helic\u00f3ptero que cost\u00f3 a la Rep\u00fablica Isl\u00e1mica la vida de dos de sus principales pol\u00edticos,\u00a0ya se estaba culpando a Estados Unidos. El cuerpo del presidente\u00a0Ebrahim Raisi\u00a0era sacado cuidadosamente del lugar del accidente mientras el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T14:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada\",\"datePublished\":\"2024-05-21T14:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/\"},\"wordCount\":1140,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/\",\"name\":\"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-21T14:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada - Noticias","og_description":"(CNN) &#8212; Incluso antes de que el jefe del ej\u00e9rcito de Ir\u00e1n, Mohammad Bagheri, ordenara una investigaci\u00f3n sobre el accidente de helic\u00f3ptero que cost\u00f3 a la Rep\u00fablica Isl\u00e1mica la vida de dos de sus principales pol\u00edticos,\u00a0ya se estaba culpando a Estados Unidos. El cuerpo del presidente\u00a0Ebrahim Raisi\u00a0era sacado cuidadosamente del lugar del accidente mientras el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-21T14:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada","datePublished":"2024-05-21T14:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/"},"wordCount":1140,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","name":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-21T14:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Algunos en Ir\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\u00f3ptero en el que muri\u00f3 Raisi. La verdad puede ser m\u00e1s complicada","url":"http:\/\/noticiasya.com\/nacional\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/05\/21\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-21T14:03:47Z","datePublished":"2024-05-21T14:03:47Z","dateModified":"2024-05-21T14:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Algunos en Ir\\u00e1n afirman que las sanciones de EE.UU. causaron el accidente de helic\\u00f3ptero en el que muri\\u00f3 Raisi. La verdad puede ser m\\u00e1s complicada\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/21\\\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/21\\\/analisis-iran-sanciones-ee-uu-accidente-helicoptero-raisi-verdad-mas-complicada-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-21T14:03:47Z\",\"datePublished\":\"2024-05-21T14:03:47Z\",\"dateModified\":\"2024-05-21T14:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449616,"url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/21\/iran-ceremonias-funebres-presidente-ebrahim-raisi-investigaciones-trax\/","url_meta":{"origin":1449623,"position":0},"title":"Ir\u00e1n inicia d\u00edas de ceremonias f\u00fanebres por el presidente Ebrahim Raisi mientras los investigadores establecen las causas del accidente en el que muri\u00f3","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- Las ceremonias f\u00fanebres por el fallecido presidente de Ir\u00e1n Ebrahim Raisi comenzar\u00e1n este martes, tras su muerte en un accidente de helic\u00f3ptero, mientras las autoridades investigan las causas que causaron que la aeronave se estrellara contra la ladera de una remota monta\u00f1a en medio de la niebla el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449593,"url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/20\/helicoptero-presidente-iran-raisi-en-vivo-orix-2\/","url_meta":{"origin":1449623,"position":1},"title":"Muerte del presidente de Ir\u00e1n en un accidente de helic\u00f3ptero, en vivo: noticias, reacciones y m\u00e1s","author":"","date":"mayo 20, 2024","format":false,"excerpt":"\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientesEn esta foto facilitada por la Agencia de Noticias de la Rep\u00fablica Isl\u00e1mica IRNA el 19 de mayo de 2024 se muestra el helic\u00f3ptero que transporta al presidente de Ir\u00e1n, Ebrahim Raisi, despegando en la frontera iran\u00ed con Azerbaiy\u00e1n tras la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449590,"url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/19\/helicoptero-presidente-iran-raisi-en-vivo-orix\/","url_meta":{"origin":1449623,"position":2},"title":"Qu\u00e9 sabemos del accidente el helic\u00f3ptero del presidente de Ir\u00e1n, en vivo: noticias y desarrollos","author":"","date":"mayo 19, 2024","format":false,"excerpt":"\ud83d\udd04 Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientesEl helic\u00f3ptero que transportaba al presidente de Ir\u00e1n, Ebrahim Raisi, visto en el momento del despegue cerca de la frontera entre Ir\u00e1n y Azerbaiy\u00e1n el 19 de mayo. Esta fotograf\u00eda de terceros fue proporcionada por la Agencia de Noticias de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449599,"url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/20\/muerte-raisi-iran-medio-oriente-analisis-trax\/","url_meta":{"origin":1449623,"position":3},"title":"An\u00e1lisis: La muerte de Raisi llega en un momento complicado para Ir\u00e1n y el Medio Oriente","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- La muerte del presidente Ebrahim Raisi y del ministro de Asuntos Exteriores de Ir\u00e1n en un accidente de helic\u00f3ptero en una remota ladera de una monta\u00f1a se produce en un momento especialmente tenso en Medio Oriente (y para Ir\u00e1n a nivel interno).La guerra de Israel contra Hamas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449584,"url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/19\/quien-es-ebrahim-raisi-clerigo-conservador-juez-controversial-presidente-electo-iran-orix\/","url_meta":{"origin":1449623,"position":4},"title":"Qui\u00e9n es Ebrahim Raisi, el cl\u00e9rigo conservador y juez controversial que se convirti\u00f3 en presidente de Ir\u00e1n","author":"","date":"mayo 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Ebrahim Raisi, cl\u00e9rigo ultraconservador y exjefe judicial de Ir\u00e1n, fue electo presidente el 18 de junio de 2021 luego de que el Consejo de Guardianes vetara la participaci\u00f3n de los principales candidatos reformistas y centristas. \u00bfQui\u00e9n es exactamente Raisi?Pr\u00e1cticamente sin oposici\u00f3n, Raisi obtuvo casi 18 millones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472899,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/06\/ataques-central-electrica-iran-accidente-radiologico-trax\/","url_meta":{"origin":1449623,"position":5},"title":"Los ataques cerca de una central el\u00e9ctrica iran\u00ed podr\u00edan causar un accidente radiol\u00f3gico &#171;grave&#187;, afirma el OIEA","author":"","date":"abril 6, 2026","format":false,"excerpt":"El Organismo Internacional de Energ\u00eda At\u00f3mica (OIEA) declar\u00f3 este lunes que la actividad militar en curso cerca de la central nuclear iran\u00ed de Bushehr podr\u00eda causar un \u201cgrave accidente radiol\u00f3gico\u201d con posibles consecuencias m\u00e1s all\u00e1 de las fronteras del pa\u00eds.El domingo, un proyectil impact\u00f3 en una zona cercana a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449623"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449623\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}