{"id":1449650,"date":"2024-05-21T15:03:42","date_gmt":"2024-05-21T22:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/"},"modified":"2024-05-21T15:03:42","modified_gmt":"2024-05-21T22:03:42","slug":"ee-uu-rusia-arma-contraespacial-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","title":{"rendered":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada"},"content":{"rendered":"<p>(CNN) &#8212; EE.UU. considera probable que Rusia lanz\u00f3 la semana pasada un arma contraespacial que est\u00e1 cerca de un sat\u00e9lite gubernamental estadounidense en \u00f3rbita cercana y es capaz de atacarlo, declar\u00f3 el lunes en la ONU el embajador de Estados Unidos, Robert Wood.<\/p>\n<p>No es la primera vez que Rusia lanza un arma contraespacial, dise\u00f1ada para incapacitar o destruir sat\u00e9lites. Pero la \u00faltima vez que lo hizo fue en 2022, dijo Wood, que ejerce como representante alternativo de EE.UU. para Asuntos Pol\u00edticos Especiales en la ONU.<\/p>\n<p>El lanzamiento se produce en un momento en que Estados Unidos y sus aliados est\u00e1n cada vez m\u00e1s preocupados por los esfuerzos de Rusia para desarrollar un arma nuclear espacial capaz de destruir sat\u00e9lites comerciales y gubernamentales.<\/p>\n<p>&#171;El 16 de mayo, Rusia puso en \u00f3rbita terrestre baja un sat\u00e9lite que, seg\u00fan Estados Unidos, es probablemente un arma contraespacial capaz de atacar otros sat\u00e9lites en \u00f3rbita terrestre baja&#187;, declar\u00f3 Wood en declaraciones previas a la votaci\u00f3n de una resoluci\u00f3n del Consejo de Seguridad de la ONU redactada por Rusia sobre la seguridad en el espacio ultraterrestre. &#171;Rusia despleg\u00f3 esta nueva arma contraespacial en la misma \u00f3rbita que un sat\u00e9lite gubernamental estadounidense&#187;.<\/p>\n<p>Exclusiva: Rusia intenta desarrollar un arma nuclear espacial para destruir sat\u00e9lites con una onda de energ\u00eda masiva, seg\u00fan fuentes que conocen la informaci\u00f3n de inteligencia<\/p>\n<p>Wood a\u00f1adi\u00f3 que el lanzamiento del 16 de mayo &#171;sigue a anteriores lanzamientos de sat\u00e9lites rusos probablemente de sistemas contraespaciales a la \u00f3rbita terrestre baja en 2019 y 2022&#187;.<\/p>\n<p>El embajador calific\u00f3 el lanzamiento de &#171;preocupante&#187; y dijo que socava las afirmaciones de Rusia de que busca la seguridad en el espacio exterior. Un funcionario estadounidense declar\u00f3 por separado a CNN que EE.UU. preve\u00eda el lanzamiento desde hac\u00eda al menos varias semanas, y el Comando de Defensa Aeroespacial de Norteam\u00e9rica y el Comando Norte de EE.UU. lo siguieron en el momento en que se produjo, seg\u00fan un funcionario de Defensa.<\/p>\n<p>Rusia emiti\u00f3 al menos dos NOTAM (avisos a los aviadores) que se activaron el 16 de mayo indicando un posible lanzamiento espacial. Uno se refer\u00eda al lanzamiento propiamente dicho y el otro a la reentrada de un cohete espacial ruso en la costa de Baja California, M\u00e9xico.<\/p>\n<p>&#171;La buena noticia es que el NOTAM es la forma responsable y normal en que las naciones apoyan las actividades a\u00e9reas y mar\u00edtimas seguras&#187;, dijo el funcionario de defensa.<\/p>\n<p>Estados Unidos y sus aliados han estado trabajando para disuadir a Rusia de desarrollar un arma nuclear espacial, seg\u00fan inform\u00f3 anteriormente CNN. Si se desplegara, un arma de este tipo podr\u00eda destruir sat\u00e9lites creando una onda de energ\u00eda masiva al detonar, paralizando potencialmente una amplia franja de los sat\u00e9lites comerciales y gubernamentales de los que el mundo depende para hablar por tel\u00e9fono celular, pagar facturas y navegar por Internet.<\/p>\n<p>En abril, EE.UU. y Jap\u00f3n presentaron conjuntamente una resoluci\u00f3n del Consejo de Seguridad de la ONU en la que se ped\u00eda a los Estados miembros de la ONU que no desarrollaran armas nucleares basadas en el espacio, pero Rusia la vet\u00f3, algo que EE.UU. consider\u00f3 una se\u00f1al de que, en efecto, est\u00e1 persiguiendo un arma nuclear basada en el espacio.<\/p>\n<p>&#171;Como ya hemos se\u00f1alado anteriormente, Estados Unidos considera que Rusia est\u00e1 desarrollando un nuevo sat\u00e9lite portador de un dispositivo nuclear&#187;, declar\u00f3 el 24 de abril en un comunicado el asesor de Seguridad Nacional, Jake Sullivan. &#171;Hemos escuchado al presidente Putin decir p\u00fablicamente que Rusia no tiene intenci\u00f3n de desplegar armas nucleares en el espacio. Si ese fuera el caso, Rusia no habr\u00eda vetado esta resoluci\u00f3n&#187;.<\/p>\n<p>Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio<\/p>\n<p>El arma rusa est\u00e1 a\u00fan en fase de desarrollo y todav\u00eda no est\u00e1 en \u00f3rbita, han subrayado p\u00fablicamente funcionarios del gobierno de Biden. Pero si se utiliza, dicen los funcionarios, cruzar\u00eda un peligroso punto del Rubic\u00f3n en la historia de las armas nucleares.<\/p>\n<p>Rusia present\u00f3 su propia resoluci\u00f3n an\u00e1loga a principios de este mes, en la que ped\u00eda la prohibici\u00f3n &#171;para siempre&#187; del emplazamiento de armas en nuestro espacio. Pero Estados Unidos la vet\u00f3 el lunes porque &#171;no logra la sencilla tarea que nos propusimos hace varios meses: reafirmar las obligaciones b\u00e1sicas del Tratado sobre el Espacio Ultraterrestre y evitar una carrera armament\u00edstica nuclear en el espacio&#187;, declar\u00f3 Wood.<\/p>\n<p>El embajador de EE.UU. se mostr\u00f3 especialmente en desacuerdo con la petici\u00f3n de la resoluci\u00f3n de un mecanismo vinculante para prohibir cualquier arma basada en el espacio, afirmando que tal prohibici\u00f3n &#171;no puede verificarse&#187; y que la resoluci\u00f3n era un intento de Rusia &#171;de distraer la atenci\u00f3n mundial de su desarrollo de un nuevo sat\u00e9lite portador de un artefacto nuclear&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; EE.UU. considera probable que Rusia lanz\u00f3 la semana pasada un arma contraespacial que est\u00e1 cerca de un sat\u00e9lite gubernamental estadounidense en \u00f3rbita cercana y es capaz de atacarlo, declar\u00f3 el lunes en la ONU el embajador de Estados Unidos, Robert Wood. No es la primera vez que Rusia lanza un arma contraespacial, dise\u00f1ada [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449650","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; EE.UU. considera probable que Rusia lanz\u00f3 la semana pasada un arma contraespacial que est\u00e1 cerca de un sat\u00e9lite gubernamental estadounidense en \u00f3rbita cercana y es capaz de atacarlo, declar\u00f3 el lunes en la ONU el embajador de Estados Unidos, Robert Wood. No es la primera vez que Rusia lanza un arma contraespacial, dise\u00f1ada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T22:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada\",\"datePublished\":\"2024-05-21T22:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/\"},\"wordCount\":868,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/\",\"name\":\"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-21T22:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada - Noticias","og_description":"(CNN) &#8212; EE.UU. considera probable que Rusia lanz\u00f3 la semana pasada un arma contraespacial que est\u00e1 cerca de un sat\u00e9lite gubernamental estadounidense en \u00f3rbita cercana y es capaz de atacarlo, declar\u00f3 el lunes en la ONU el embajador de Estados Unidos, Robert Wood. No es la primera vez que Rusia lanza un arma contraespacial, dise\u00f1ada [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-21T22:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada","datePublished":"2024-05-21T22:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/"},"wordCount":868,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","name":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-21T22:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada","url":"http:\/\/noticiasya.com\/nacional\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-21T22:03:42Z","datePublished":"2024-05-21T22:03:42Z","dateModified":"2024-05-21T22:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. considera probable que Rusia lanz\\u00f3 un arma contraespacial la semana pasada\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/21\\\/ee-uu-rusia-arma-contraespacial-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/21\\\/ee-uu-rusia-arma-contraespacial-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-21T22:03:42Z\",\"datePublished\":\"2024-05-21T22:03:42Z\",\"dateModified\":\"2024-05-21T22:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459992,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/16\/pentagono-rusia-china-capacidades-militares-espacio-trax\/","url_meta":{"origin":1449650,"position":0},"title":"El Pent\u00e1gono monitorea de cerca a Rusia y China mientras prueban capacidades militares en el espacio","author":"","date":"marzo 16, 2025","format":false,"excerpt":"Funcionarios militares de Estados Unidos creen que Rusia y China est\u00e1n probando agresivamente nuevas capacidades espaciales ofensivas, al se\u00f1alar una serie de misiones de entrenamiento de sat\u00e9lites realizadas por ambos pa\u00edses en los \u00faltimos meses como evidencia creciente de un esfuerzo por militarizar el espacio exterior.Tan recientemente como la semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445548,"url":"https:\/\/noticiasya.com\/nacional\/2024\/02\/17\/exclusiva-rusia-intenta-desarrollar-un-arma-nuclear-espacial-para-destruir-satelites-con-una-onda-de-energia-masiva-segun-fuentes-que-conocen-la-informacion-de-inteligencia\/","url_meta":{"origin":1449650,"position":1},"title":"Exclusiva: Rusia intenta desarrollar un arma nuclear espacial para destruir sat\u00e9lites con una onda de energ\u00eda masiva, seg\u00fan fuentes que conocen la informaci\u00f3n de inteligencia","author":"","date":"febrero 17, 2024","format":false,"excerpt":"(CNN) -- Rusia est\u00e1 tratando de desarrollar un arma nuclear espacial que destruir\u00eda sat\u00e9lites al crear una onda de energ\u00eda masiva cuando se detona, lo que potencialmente podr\u00eda paralizar una amplia franja de los sat\u00e9lites comerciales y gubernamentales de los que el mundo depende para hablar por tel\u00e9fono celular, pagar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446203,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/02\/capacidades-militares-rusia-espacio-orix\/","url_meta":{"origin":1449650,"position":2},"title":"\u00bfArmas en el espacio? Estas son las capacidades militares de Rusia en la \u00f3rbita terrestre","author":"","date":"marzo 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00bfEst\u00e1 Rusia desarrollando armas nucleares para utilizar en el espacio? De acuerdo con fuentes del sector inteligencia de Estados Unidos, eso parece.\u00bfEs eso algo nuevo? Bueno, no tanto.En una exclusiva de CNN publicada a mediados de febrero, estas fuentes hablaron de un nuevo tipo de arma nuclear\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446444,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/04\/capacidades-militares-rusia-espacio-orix-2\/","url_meta":{"origin":1449650,"position":3},"title":"\u00bfArmas en el espacio? Estas son las capacidades militares de Rusia en la \u00f3rbita terrestre","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00bfEst\u00e1 Rusia desarrollando armas nucleares para utilizar en el espacio? De acuerdo con fuentes del sector inteligencia de Estados Unidos, eso parece.\u00bfEs eso algo nuevo? Bueno, no tanto.En una exclusiva de CNN publicada a mediados de febrero, estas fuentes hablaron de un nuevo tipo de arma nuclear\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448500,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","url_meta":{"origin":1449650,"position":4},"title":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Rusia vet\u00f3 este mi\u00e9rcoles una resoluci\u00f3n de las Naciones Unidas que propon\u00eda prohibir el uso de armas nucleares en el espacio exterior en medio de preocupaciones respaldadas por la inteligencia estadounidense de que Mosc\u00fa est\u00e9 tratando de desarrollar un dispositivo nuclear capaz de destruir sat\u00e9lites.El embajador ruso, Vassily\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446956,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/14\/putin-central-nuclear-espacio-rusia-trax\/","url_meta":{"origin":1449650,"position":5},"title":"Putin afirma que instalar una unidad nuclear en el espacio es una prioridad para Rusia","author":"","date":"marzo 14, 2024","format":false,"excerpt":"(CNN) -- El presidente de Rusia, Vladimir Putin, se\u00f1al\u00f3 este jueves a funcionarios del Gobierno que los proyectos espaciales, incluida la instalaci\u00f3n de una unidad de energ\u00eda nuclear en el espacio, son una prioridad y deben contar con la financiaci\u00f3n adecuada, seg\u00fan la agencia estatal de noticias TASS.Rusia \"tiene buenas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449650"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449650\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}