{"id":1449679,"date":"2024-05-22T15:03:38","date_gmt":"2024-05-22T22:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/"},"modified":"2024-05-22T15:03:38","modified_gmt":"2024-05-22T22:03:38","slug":"exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","title":{"rendered":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Ambra Battilana Gutierrez dice que durante a\u00f1os supo que la estaban silenciando.<\/p>\n<p>Corr\u00eda el a\u00f1o 2015 cuando la modelo italiana dice haber sido agredida por el entonces magnate del cine Harvey Weinstein durante una reuni\u00f3n de casting. Inmediatamente acudi\u00f3 a la polic\u00eda para denunciar lo sucedido, dando por hecho que las fuerzas del orden le ayudar\u00edan.<\/p>\n<p>Casi una d\u00e9cada despu\u00e9s, sigue buscando respuestas, no solo sobre su agresi\u00f3n, sino sobre lo que, seg\u00fan ella, son fallos del sistema de justicia penal y de c\u00f3mo se trata a las v\u00edctimas.<\/p>\n<p>&#171;Ten\u00eda 22 a\u00f1os, estaba en Nueva York, acababa de llegar. Ten\u00eda muy poco, mil d\u00f3lares, en mi cuenta bancaria y fui agredida por Harvey Weinstein. Lo denunci\u00e9 y luego me limit\u00e9 a tratar de seguir a la justicia y lo que me dijeron que hiciera&#187;, dijo Battilana Guti\u00e9rrez a CNN en una entrevista reciente.<\/p>\n<p>&#171;Ahora s\u00e9 que hab\u00eda mucha gente en mi contra&#187;, afirma.<\/p>\n<p>Los supuestos esfuerzos por silenciarla se han vuelto m\u00e1s claros para Battilana Gutierrez este mes, y no por nada que tenga que ver con Weinstein, sino por el juicio en curso contra el expresidente Donald Trump.<\/p>\n<p>Battilana Gutierrez dice que ve paralelismos estremecedores entre la supuesta conspiraci\u00f3n en torno a un pago de dinero por silencio relacionado con Trump y lo que le ocurri\u00f3 a ella.<\/p>\n<p>Durante el juicio de Trump, el &#171;rey de los tabloides&#187; David Pecker, que supervisaba American Media Inc, la empresa matriz de la influyente revista sensacionalista The National Enquirer, testific\u00f3 sobre la compra y supresi\u00f3n de historias negativas para ayudar a su amigo, Trump, a ganar la presidencia.<\/p>\n<p>El expresidente de Estados Unidos Donald Trump en el Tribunal Penal de Manhattan, Nueva York, el 16 de mayo. Cr\u00e9dito: Jeenah Moon\/Pool\/Reuters<\/p>\n<p>&#171;Le dije que cualquier cosa que escuchara en el mercado, si escuchaba algo negativo sobre usted o si escuchaba algo sobre mujeres vendiendo historias, se lo notificar\u00eda a Michael Cohen&#187;, testific\u00f3 Pecker que le dijo a Trump. &#171;Y entonces \u00e9l podr\u00eda hacer que las mataran en otra revista o que no se publicaran o que alguien tuviera que comprarlas&#187;.<\/p>\n<p>Dijo en el estrado que tambi\u00e9n cuidaba a otros hombres poderosos de los que era cercano, profesional o personalmente: hombres como Arnold Schwarzenegger, el agente de mega talentos Ari Emanuel y su hermano Rahm, quien renunci\u00f3 como primer jefe de gabinete del presidente Barack Obama para postularse y ganar la alcald\u00eda de Chicago.<\/p>\n<p>CNN puso en contacto con los representantes de Schwarzenegger, Ari y Rahm Emanuel para obtener sus comentarios.<\/p>\n<p>Pero otra figura poderosa en el mundo de Pecker que nunca sali\u00f3 a relucir en el juicio contra Trump fue Weinstein.<br \/>\n&#171;Ser\u00eda muy interesante ver si tiene que hablar sobre el juicio de Harvey Weinstein&#187;, dijo Battilana Gutierrez sobre Pecker.<\/p>\n<p>&#171;\u00bfQu\u00e9 quieres?&#187;<\/p>\n<p>Battilana Gutierrez dice que fue blanco del National Enquirer en una operaci\u00f3n de historias de &#171;atrapar y matar&#187; en 2015 despu\u00e9s de que le dijo a la polic\u00eda en la ciudad de Nueva York que Weinstein le manose\u00f3 los senos y le meti\u00f3 la mano en la falda durante una reuni\u00f3n de casting.<\/p>\n<p>Ella declar\u00f3 a CNN que recibi\u00f3 una oferta de US$ 150.000 de The National Enquirer en 2015 para comprar su historia. Ella rechaz\u00f3 la gran suma de dinero.<\/p>\n<p>&#171;The National Enquirer se puso en contacto conmigo y me hac\u00edan preguntas: &#8216;\u00bfQu\u00e9 quieres? &#8216;\u00bfQu\u00e9 quieres?&#8217; porque estaban tratando de comprar mi historia&#187;, dice Battilana Gutierrez. &#171;Yo respond\u00eda: &#8216;Nada&#8217;. Quer\u00eda contar mi historia, pero quer\u00eda confiar en alguien&#187;.<\/p>\n<p>Ambra Battilana Gutierrez, acusadora de Harvey Weinstein. Cr\u00e9dito: Natalia V. Osipova\/CNN<\/p>\n<p>Mientras intentaba dar a conocer su historia en 2015, de repente, se vio desprestigiada en las portadas de las revistas sensacionalistas.<\/p>\n<p>&#171;Me acusaron de faltar a la verdad y de ser una prostituta o de no ser una v\u00edctima perfecta porque soy modelo y trabajo en bikinis y lencer\u00eda. Es rid\u00edculo&#187;, afirma. &#171;Me destrozaron la vida porque los medios no pudieron comprarme. Vieron que no quer\u00eda que me silenciaran, que no quer\u00eda dinero y simplemente destruyeron mi credibilidad&#187;.<\/p>\n<p>Pecker y la empresa matriz de The National Enquirer no respondieron a la solicitud de comentarios de CNN. Pero durante el juicio de Trump, Pecker testific\u00f3 haber participado en pr\u00e1cticas de &#171;atrapar y matar&#187;, pagando por historias para que nunca salieran a la luz.<\/p>\n<p>Conclusiones del s\u00e9ptimo d\u00eda del juicio penal a Trump: salen a la luz t\u00e1cticas de tabloides<\/p>\n<p>Muchas de las circunstancias que rodean a Battilana Gutierrez ya fueron denunciadas por periodistas que ayudaron a destapar el caso Weinstein. Battilana Gutierrez ha hablado mucho con los medios de comunicaci\u00f3n como rostro prominente de la saga Weinstein, pero hasta esta conversaci\u00f3n con CNN, nunca hab\u00eda hablado en directo con los medios sobre muchos de estos detalles.<\/p>\n<p>No fueron solo los medios sensacionalistas en 2015 los que, seg\u00fan ella, intentaron silenciarla. Battilana Gutierrez dice a CNN que los abogados de Weinstein le ofrecieron hasta un mill\u00f3n de d\u00f3lares para firmar un acuerdo de no divulgaci\u00f3n, una vez que se enteraron de que estaba tratando de dar a conocer sus acusaciones.<\/p>\n<p>&#171;Sab\u00eda que intentaban ofrecerme US$ 100.000&#187;, dice Battilana Gutierrez, detallando los pormenores de las supuestas ofertas de acuerdo de Weinstein. &#171;Subieron a 300.000, 700.000, un mill\u00f3n de d\u00f3lares, y yo segu\u00ed rechazando todas las veces&#187;.<\/p>\n<p>El portavoz de Weinstein, Juda Engelmayer, dijo a CNN en un comunicado: &#171;Los abogados de la se\u00f1ora Gutierrez controlaron esas reuniones y establecieron los t\u00e9rminos de la misma&#187;.<\/p>\n<p>Engelmayer no respondi\u00f3 a las preguntas de CNN espec\u00edficamente sobre la relaci\u00f3n de Weinstein con Pecker, The National Enquirer y sus presuntos esfuerzos conjuntos para matar la historia de Battilana Gutierrez y plantar noticias negativas sobre ella en los medios sensacionalistas.<\/p>\n<p>Harvey Weinstein ante el tribunal el 9 de mayo. Cr\u00e9dito:\u00a0 Julia Nikhinson\/AP<\/p>\n<p>Pero su portavoz s\u00ed ha dicho que la reciente condena anulada de Weinstein ha &#171;abierto las puertas para que algunos vuelvan a estar en el foco, cuando pr\u00e1cticamente hab\u00eda desaparecido&#187;.<\/p>\n<p>&#171;Aunque est\u00e9 en prisi\u00f3n y condenado en Los \u00c1ngeles, el solo nombre de Harvey Weinstein parece seguir inspirando cobertura y atenci\u00f3n&#187;, dijo Engelmayer. Sobre Battilana Gutierrez, a\u00f1adi\u00f3: &#171;Harvey le desea lo mejor y espera \u00fanicamente felicidad y \u00e9xito para ella&#187;.<\/p>\n<p>Finalmente, Battilana Gutierrez firm\u00f3 un acuerdo de confidencialidad con el equipo legal de Weinstein. Dijo que sent\u00eda que no ten\u00eda otra opci\u00f3n, despu\u00e9s de que personas desconocidas se acercaran de forma aleatoria a su hermano en Italia preguntando por ella, y le preocupaba que la seguridad de su familia estuviera en peligro.<\/p>\n<p>El portavoz de Weinstein no respondi\u00f3 a la petici\u00f3n de CNN de que comentara las acusaciones de Battilana Gutierrez sobre el hecho de que su hermano fuera abordado en Italia, lo que, seg\u00fan ella, la asust\u00f3 para que finalmente firmara el acuerdo de confidencialidad.<\/p>\n<p>Battilana Gutierrez hace caso omiso de su acuerdo de confidencialidad para hablar en esta entrevista. Dice que es &#171;m\u00e1s importante&#187; compartir su verdad.<\/p>\n<p>En busca de justicia<\/p>\n<p>Desde el reportaje inicial de The New Yorker y The New York Times en 2017 que llev\u00f3 a su ca\u00edda, Weinstein ha sido acusado, condenado y sentenciado por delitos sexuales. En Nueva York, fue condenado por primera vez a 23 a\u00f1os de prisi\u00f3n tras ser declarado culpable de acto sexual criminal en primer grado y violaci\u00f3n en tercer grado, veredictos de culpabilidad que ahora han sido anulados por el Tribunal de Apelaciones de Nueva York. En Los \u00c1ngeles, fue condenado a otros 16 a\u00f1os de prisi\u00f3n por violaci\u00f3n y agresi\u00f3n sexual.<\/p>\n<p>Tribunal de apelaciones de Nueva York anula la condena de Harvey Weinstein por delitos sexuales<\/p>\n<p>En la sentencia de Weinstein en Nueva York, el juez James Burke dijo: &#171;Esta es una primera condena, pero no es un primer delito&#187;.<\/p>\n<p>Guti\u00e9rrez confirma ahora a CNN que fue una fuente an\u00f3nima para Ronan Farrow, que escribi\u00f3 para el New Yorker, y que le dio un audio de Weinstein en el que aparentemente admit\u00eda haber manoseado sus senos, que fue grabado durante una operaci\u00f3n encubierta de la polic\u00eda de Nueva York.<\/p>\n<p>Incluso con la grabaci\u00f3n, los fiscales no siguieron adelante con su caso, alegando que no hab\u00eda pruebas suficientes para una condena.<\/p>\n<p>A la derecha, el entonces fiscal del distrito de Manhattan, Cyrus Vance, Jr. en 2020. Cr\u00e9dito: Eduardo Mu\u00f1oz\/Reuters<\/p>\n<p>Cyrus Vance, fiscal de Manhattan en ese momento, dijo a CNN por correo electr\u00f3nico que asign\u00f3 a la jefa de la unidad de delitos sexuales para examinar el caso de Battilana Gutierrez y consider\u00f3 que ella llev\u00f3 a cabo &#171;una investigaci\u00f3n completa y detallada&#187; antes de recomendar en contra del enjuiciamiento por una serie de razones.<\/p>\n<p>&#171;Acept\u00e9 su recomendaci\u00f3n porque estaba personalmente familiarizado con su experiencia, juicio y compromiso en esta \u00e1rea de investigaciones criminales&#187;, dijo Vance.<\/p>\n<p>La Fiscal\u00eda de Manhattan declin\u00f3 hacer comentarios sobre la investigaci\u00f3n de Weinstein bajo el mandato de Vance, pero se\u00f1al\u00f3 que el actual fiscal Alvin Bragg est\u00e1 avanzando en un nuevo juicio contra Weinstein, despu\u00e9s de que su condena fuera anulada el mes pasado por el Tribunal de Apelaciones de Nueva York, una decisi\u00f3n que caus\u00f3 conmoci\u00f3n en las comunidades de supervivientes de agresiones sexuales y supuso un rev\u00e9s impresionante para el movimiento #MeToo.<\/p>\n<p>&#171;Como declaramos en el tribunal, volveremos a juzgar el caso contra Harvey Weinstein, e instamos a cualquier persona que haya sido v\u00edctima de agresi\u00f3n sexual a que nos llame&#187;, dijo un portavoz de la Fiscal\u00eda de Manhattan a CNN en respuesta a esta historia.<\/p>\n<p>El portavoz de Weinstein dijo a CNN: &#171;La Fiscal\u00eda conoc\u00eda todos los hechos y dej\u00f3 pasar este caso. Si hubieran cre\u00eddo que pod\u00edan perseguirlo, lo habr\u00edan hecho&#187;.<\/p>\n<p>Comprar la historia para &#171;enterrarla&#187;<\/p>\n<p>El mes pasado, un ex editor del National Enquirer public\u00f3 un ensayo en la revista New York Times Magazine, en el que comparte lo que afirma haber presenciado durante su tiempo en el tabloide, tanto en relaci\u00f3n con los esfuerzos de &#171;atrapar y matar&#187; tanto de Weinstein como de Trump. El reportero, Lachlan Cartwright, sostuvo que en un esfuerzo por desprestigiar a Battilana Gutierrez, los abogados de la empresa matriz del Enquirer, American Media Inc. (AMI), mantuvieron conversaciones con la Fiscal\u00eda de Manhattan.<\/p>\n<p>Cartwright insisti\u00f3 en esa afirmaci\u00f3n, diciendo a CNN: &#171;Me enter\u00e9 de que un abogado de alto nivel de AMI, en 2015, hab\u00eda estado en contacto con la Fiscal\u00eda de Manhattan y que esa persona hab\u00eda dado la vuelta al gui\u00f3n y hab\u00eda estado diciendo a la Fiscal\u00eda que Ambra estaba tratando de vender su historia al National Enquirer, que era todo lo contrario de lo que estaba pasando&#187;.<\/p>\n<p>Cartwright dijo a CNN que se enter\u00f3 de esto cuando sirvi\u00f3 como fuente an\u00f3nima para la investigaci\u00f3n de The New York Times sobre Weinstein. CNN no ha verificado de forma independiente la afirmaci\u00f3n de Cartwright, y Battilana Gutierrez dice que aunque no tiene conocimiento directo de si un abogado del Enquirer se puso en contacto con la Fiscal\u00eda de Manhattan, cree que una &#171;red muy complicada de personas estaban [estaba] trabajando juntas para destruirme&#187;.<\/p>\n<p>En su correo electr\u00f3nico a CNN, Vance no neg\u00f3 directamente la afirmaci\u00f3n de Cartwright, pero dijo: &#171;No tengo informaci\u00f3n que recuerde actualmente de que el National Enquirer o alguien que lo represente hablara con nuestra oficina sobre la venta de una historia al Enquirer&#187;.<\/p>\n<p>Cartwright afirma que, mientras trabajaba en el Enquirer, recibi\u00f3 un dato en 2015 sobre la denuncia policial de Battilana Guti\u00e9rrez en relaci\u00f3n con sus acusaciones contra Weinstein. Present\u00f3 la historia, que habr\u00eda sido una gran primicia en un mundo anterior al #MeToo, y se sorprendi\u00f3 cuando sus jefes pidieron comprarla, en lugar de informar sobre ella.<\/p>\n<p>David J. Pecker en 2017. Cr\u00e9dito: Mark Peterson\/Redux<\/p>\n<p>&#171;Tanto Harvey Weinstein como Donald Trump eran &#8216;Amigos de Pecker'&#187;, dijo Cartwright a CNN. &#171;La historia de Ambra Battilana es casi un &#8216;atrapar y matar&#8217; en el sentido de que creo que si ella hubiera aceptado que se vendiera su historia, no creo que la intenci\u00f3n habr\u00eda sido publicarla. Creo que la intenci\u00f3n era asegurarse de que no se publicara&#187;.<\/p>\n<p>En 2017, The New Yorker inform\u00f3 que National Enquirer comparti\u00f3 material in\u00e9dito con Weinstein sobre la acusaci\u00f3n de violaci\u00f3n de la actriz Rose McGowan, d\u00e1ndole un adelanto sobre las acusaciones que finalmente resultar\u00edan condenatorias para \u00e9l. En declaraciones a CNN, Cartwright confirm\u00f3 que durante su etapa en la revista, el editor jefe de Enquirer habl\u00f3 con Weinstein sobre McGowan.<\/p>\n<p>\u201cMe silenciaron por 20 a\u00f1os\u201d, dice Rose McGowan, tras esc\u00e1ndalo de Weinstein<\/p>\n<p>En el momento en que Battilana Gutierrez present\u00f3 su denuncia policial en 2015, The Weinstein Company ten\u00eda negocios con Pecker. Apenas unas semanas antes de la supuesta agresi\u00f3n de Weinstein a Battilana Gutierrez, las empresas de Weinstein y Pecker hab\u00edan firmado un acuerdo para crear un programa de televisi\u00f3n con el contenido del sitio web de AMI Radar Online. El programa nunca lleg\u00f3 a materializarse, pero la relaci\u00f3n, sin embargo, s\u00ed benefici\u00f3 a Weinstein.<\/p>\n<p>&#171;Eso significaba que Harvey Weinstein era una especie protegida&#187;, dijo Cartwright, y a\u00f1adi\u00f3: &#171;La gente dentro de American Media &#8230; estaba trabajando para ayudar a Harvey Weinstein y protegerlo y utilizando los recursos de American Media para hacerlo&#187;.<\/p>\n<p>Una oportunidad para testificar<\/p>\n<p>Casi una d\u00e9cada despu\u00e9s de que presentara por primera vez sus acusaciones contra Weinstein, Battilana Gutierrez sigue luchando por que se haga justicia, sobre todo porque la suerte de Weinstein en Nueva York sigue siendo una inc\u00f3gnita tras la anulaci\u00f3n de su condena y \u00e9l promete apelar su condena en Los \u00c1ngeles.<\/p>\n<p>&#171;Tengo un mont\u00f3n de preguntas sobre 2015 a las que nunca he tenido respuesta&#187;, dice.<\/p>\n<p>A trav\u00e9s del juicio por el pago de dinero por silencio de Trump y las continuas batallas legales de Weinstein, ella ve un tema com\u00fan: enormes esfuerzos para silenciar a las mujeres, con el fin de mantener a hombres influyentes en el poder.<\/p>\n<p>&#171;Nunca quise ser activista. Fue algo que simplemente me surgi\u00f3&#187;, dice. &#171;Simplemente sent\u00ed que no pod\u00eda cerrar los ojos cuando veo algo que no est\u00e1 bien&#187;.<\/p>\n<p>En la actualidad, Battilana Gutierrez forma parte de la junta directiva de Model Alliance, una organizaci\u00f3n sin fines de lucro con sede en Nueva York que trabaja para mejorar el trato a los trabajadores de la industria de la moda. Modelo en activo, afirma que en su sector sigue habiendo abusos, a pesar de los esfuerzos del movimiento #MeToo.<\/p>\n<p>Ambra Battilana Guti\u00e9rrez frente al Tribunal Penal de Manhattan en 2020. Cr\u00e9dito: Timothy A. Clary\/AFP\/Getty Images<\/p>\n<p>En 2022, tuvo la oportunidad de testificar sobre lo que dice que le sucedi\u00f3 en el juicio de Weinstein en Los \u00c1ngeles, no porque su caso en Nueva York llegara a ser procesado, sino porque los fiscales de Los \u00c1ngeles la trajeron como testigo de &#171;malos actos previos&#187;, con el fin de proporcionar m\u00e1s pruebas para ayudar a establecer un patr\u00f3n del supuesto comportamiento previo del magnate cinematogr\u00e1fico ca\u00eddo en desgracia. En ese juicio, el jurado escuch\u00f3 las grabaciones de Battilana Gutierrez con Weinstein.<\/p>\n<p>Poco despu\u00e9s de que se emitieran los veredictos en 2022, un miembro del jurado dijo a este periodista que le hab\u00eda impresionado especialmente la historia de Battilana Gutierrez y que habr\u00eda votado a favor de la condena si su experiencia hubiera estado directamente relacionada con una acusaci\u00f3n contra Weinstein.<\/p>\n<p>Cuando Battilana Gutierrez escuch\u00f3 la historia en la entrevista con CNN, se conmovi\u00f3 por todo lo que hab\u00eda pasado desde su primer encuentro con Weinstein.<\/p>\n<p>&#171;Todo mi deseo en 2015 era ser \u00fatil para alguien&#187;, dice ahora Battilana Gutierrez, llena de rabia y esperanza. &#171;Todos estos a\u00f1os que han pasado para m\u00ed, sabiendo que si tal vez hubiera podido (encontrar) a la persona adecuada para publicar esas grabaciones, no habr\u00eda perdido todo lo que perd\u00ed&#187;.<\/p>\n<p>Battilana Gutierrez dice a CNN que espera que el caso de Nueva York se vuelva a juzgar este oto\u00f1o, ya que el fiscal anunci\u00f3 su intenci\u00f3n de hacerlo. Y si la apelaci\u00f3n de Weinstein en Los \u00c1ngeles tiene \u00e9xito, dice que volver\u00eda a testificar.<\/p>\n<p>Dice que no dejar\u00e1 de buscar respuestas hasta que se haga justicia.<\/p>\n<p>&#171;\u00bfQui\u00e9n fue el responsable de que eso ocurriera? Porque no fue solo \u00e9l. S\u00e9 que hay m\u00e1s gente detr\u00e1s de \u00e9l que tiene puestos de poder que tambi\u00e9n estaba aprovechando&#187;.<\/p>\n<p>Y a\u00f1ade: &#171;Las cosas que son malas, las mentiras, siempre salen a la luz&#187;.<\/p>\n<p>&#8212; Jason Kravarik de CNN contribuy\u00f3 a este reportaje.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Ambra Battilana Gutierrez dice que durante a\u00f1os supo que la estaban silenciando. Corr\u00eda el a\u00f1o 2015 cuando la modelo italiana dice haber sido agredida por el entonces magnate del cine Harvey Weinstein durante una reuni\u00f3n de casting. Inmediatamente acudi\u00f3 a la polic\u00eda para denunciar lo sucedido, dando por hecho que las fuerzas del orden [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449679","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Ambra Battilana Gutierrez dice que durante a\u00f1os supo que la estaban silenciando. Corr\u00eda el a\u00f1o 2015 cuando la modelo italiana dice haber sido agredida por el entonces magnate del cine Harvey Weinstein durante una reuni\u00f3n de casting. Inmediatamente acudi\u00f3 a la polic\u00eda para denunciar lo sucedido, dando por hecho que las fuerzas del orden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-22T22:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos\",\"datePublished\":\"2024-05-22T22:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/\"},\"wordCount\":2891,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/\",\"name\":\"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-22T22:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos - Noticias","og_description":"(CNN) &#8212;\u00a0Ambra Battilana Gutierrez dice que durante a\u00f1os supo que la estaban silenciando. Corr\u00eda el a\u00f1o 2015 cuando la modelo italiana dice haber sido agredida por el entonces magnate del cine Harvey Weinstein durante una reuni\u00f3n de casting. Inmediatamente acudi\u00f3 a la polic\u00eda para denunciar lo sucedido, dando por hecho que las fuerzas del orden [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-22T22:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/"},"author":{"name":"","@id":""},"headline":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos","datePublished":"2024-05-22T22:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/"},"wordCount":2891,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","name":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-22T22:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos","url":"http:\/\/noticiasya.com\/nacional\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/05\/22\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-22T22:03:38Z","datePublished":"2024-05-22T22:03:38Z","dateModified":"2024-05-22T22:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EXCLUSIVA | Ella dice que Harvey Weinstein la agredi\\u00f3. Ahora encuentra similitudes entre su caso y el juicio de Trump por sobornos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/22\\\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/22\\\/exclusiva-denunciante-harvey-weinstein-juicio-trump-silencio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-22T22:03:38Z\",\"datePublished\":\"2024-05-22T22:03:38Z\",\"dateModified\":\"2024-05-22T22:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452558,"url":"https:\/\/noticiasya.com\/nacional\/2024\/09\/09\/hospitalizan-emergencia-harvey-weinstein-cirugia-corazon-trax\/","url_meta":{"origin":1449679,"position":0},"title":"Hospitalizan de emergencia a Harvey Weinstein para una cirug\u00eda del coraz\u00f3n","author":"","date":"septiembre 9, 2024","format":false,"excerpt":"(CNN) -- Harvey Weinstein fue \"trasladado de emergencia\" al Hospital Bellevue de Nueva York el domingo por la noche \"debido a varias afecciones m\u00e9dicas\", seg\u00fan los representantes del desacreditado exproductor de cine.\"Podemos confirmar que el se\u00f1or Weinstein fue sometido a un procedimiento y cirug\u00eda en su coraz\u00f3n hoy\", dijeron el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448614,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/27\/harvey-weinstein-trasladado-pabellon-bellevue-hospital-trax\/","url_meta":{"origin":1449679,"position":1},"title":"Harvey Weinstein fue trasladado al pabell\u00f3n de prisi\u00f3n del Bellevue Hospital por razones m\u00e9dicas, seg\u00fan su abogado y registros en l\u00ednea","author":"","date":"abril 27, 2024","format":false,"excerpt":"(CNN) -- Harvey Weinstein, el poderoso productor de Hollywood cuya ca\u00edda fue un s\u00edmbolo del movimiento #MeToo, ha sido trasladado del Centro Correccional Mohawk en Rome, Nueva York, al pabell\u00f3n de prisi\u00f3n del Hospital Bellevue (BHPW), seg\u00fan registros en l\u00ednea y su abogado.\"Est\u00e1 en Bellevue por razones m\u00e9dicas\", dijo este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448519,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/25\/denunciantes-harvey-weinstein-nuevo-juicio-anulacion-condena-trax\/","url_meta":{"origin":1449679,"position":2},"title":"Denunciantes de Harvey Weinstein quieren un nuevo juicio tras anulaci\u00f3n de condena por violaci\u00f3n y agresi\u00f3n","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Cuando el productor de Hollywood Harvey Weinstein fue declarado culpable de dos delitos sexuales en febrero de 2020, la condena fue aclamada como un momento hist\u00f3rico en el movimiento #MeToo.Ahora, m\u00e1s de cuatro a\u00f1os despu\u00e9s, el fallo de la Corte de Apelaciones de Nueva York que anula esa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443256,"url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/06\/en-la-tercera-tanda-de-documentos-del-caso-epstein-figura-una-llamada-de-harvey-weinstein-mas-hombres-famosos-y-detalles-inquietantes\/","url_meta":{"origin":1449679,"position":3},"title":"En la tercera tanda de documentos del caso Epstein figura una llamada de Harvey Weinstein, m\u00e1s hombres famosos y detalles inquietantes","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN) -- La tercera ronda de documentos de una demanda relacionada con Jeffrey Epstein, el pederasta convicto que muri\u00f3 en la c\u00e1rcel antes de poder enfrentar un juicio por cargos federales de tr\u00e1fico sexual, se hizo p\u00fablica este viernes.La publicaci\u00f3n de este viernes ten\u00eda m\u00e1s de mil p\u00e1ginas, y llega\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455286,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/21\/a-harvey-weinstein-le-diagnosticaron-cancer-segun-fuentes-trax\/","url_meta":{"origin":1449679,"position":4},"title":"A Harvey Weinstein le diagnosticaron c\u00e1ncer, seg\u00fan fuentes","author":"","date":"octubre 21, 2024","format":false,"excerpt":"(CNN) --\u00a0 A Harvey Weinstein le diagnosticaron c\u00e1ncer de huesos, dijo a CNN una fuente cercana al productor encarcelado.El diagn\u00f3stico espec\u00edfico de Weinstein es leucemia mieloide cr\u00f3nica, una forma de c\u00e1ncer de la m\u00e9dula \u00f3sea, dice la fuente, y agrega que est\u00e1 recibiendo tratamiento en Rikers Island en Nueva York.Juda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447395,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/26\/tercera-ronda-documentos-jeffrey-epstein-trax\/","url_meta":{"origin":1449679,"position":5},"title":"En la tercera tanda de documentos del caso Epstein figura una llamada de Harvey Weinstein, m\u00e1s hombres famosos y detalles inquietantes","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- La tercera ronda de documentos de una demanda relacionada con Jeffrey Epstein, el pederasta convicto que muri\u00f3 en la c\u00e1rcel antes de poder enfrentar un juicio por cargos federales de tr\u00e1fico sexual, se hizo p\u00fablica este viernes.La publicaci\u00f3n de este viernes ten\u00eda m\u00e1s de mil p\u00e1ginas, y llega\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449679"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449679\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}