{"id":1449950,"date":"2024-06-03T02:03:48","date_gmt":"2024-06-03T09:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/"},"modified":"2024-06-03T02:03:48","modified_gmt":"2024-06-03T09:03:48","slug":"cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/","title":{"rendered":"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre"},"content":{"rendered":"<p>(CNN) &#8212; Las Fuerzas de Defensa de Israel han localizado el cuerpo del param\u00e9dico israel\u00ed Dolev Yehud, quien, seg\u00fan dicen, fue asesinado por combatientes de Hamas el 7 de octubre en el kibutz Nir Oz.<\/p>\n<p>En una declaraci\u00f3n de este lunes, las FDI dijeron que tras \u201cun an\u00e1lisis exhaustivo realizado por las FDI en coordinaci\u00f3n con expertos antropol\u00f3gicos\u201d, se identific\u00f3 el cuerpo de Yehud.<\/p>\n<p>Yehud, que ten\u00eda 35 a\u00f1os, era param\u00e9dico de los servicios m\u00e9dicos de emergencia voluntarios israel\u00edes, United Hatzalah, y del servicio nacional de emergencia m\u00e9dica, desastres, ambulancias y banco de sangre del pa\u00eds, Magen David Adom (MDA).<\/p>\n<p>El kibutz Nir Oz fue uno de los varios kibutzim que sufrieron la peor parte del ataque de Ham\u00e1s el 7 de octubre, con muchos residentes tomados como rehenes.<\/p>\n<p>Melissa Bell de CNN habl\u00f3 con el padre de Dolev, Yechiel Yehud, en abril de este a\u00f1o, quien dijo que Dolev fue visto por \u00faltima vez saliendo del refugio con su esposa embarazada y sus tres hijos. En el momento de la entrevista, Yechiel cre\u00eda que Dolev hab\u00eda sido secuestrado por Ham\u00e1s y le dijo a Bell que le preocupaba que su hijo no tuviera sus medicamentos.<\/p>\n<p>La hermana de Dolev, Arbel, de 28 a\u00f1os, tampoco ha sido vista desde el 7 de octubre. Todav\u00eda aparece como desaparecida en el Foro de familias de rehenes.<\/p>\n<p>El Foro de Familias Rehenes expres\u00f3 su \u201cprofundo dolor\u201d al conocer la noticia, precisando que el funeral est\u00e1 previsto para el martes. Tambi\u00e9n pidieron a los medios que &#171;honren la privacidad de la familia y se abstengan de contactarlos durante este per\u00edodo de luto&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Las Fuerzas de Defensa de Israel han localizado el cuerpo del param\u00e9dico israel\u00ed Dolev Yehud, quien, seg\u00fan dicen, fue asesinado por combatientes de Hamas el 7 de octubre en el kibutz Nir Oz. En una declaraci\u00f3n de este lunes, las FDI dijeron que tras \u201cun an\u00e1lisis exhaustivo realizado por las FDI en coordinaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449950","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Las Fuerzas de Defensa de Israel han localizado el cuerpo del param\u00e9dico israel\u00ed Dolev Yehud, quien, seg\u00fan dicen, fue asesinado por combatientes de Hamas el 7 de octubre en el kibutz Nir Oz. En una declaraci\u00f3n de este lunes, las FDI dijeron que tras \u201cun an\u00e1lisis exhaustivo realizado por las FDI en coordinaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T09:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre\",\"datePublished\":\"2024-06-03T09:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/\",\"name\":\"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-03T09:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre - Noticias","og_description":"(CNN) &#8212; Las Fuerzas de Defensa de Israel han localizado el cuerpo del param\u00e9dico israel\u00ed Dolev Yehud, quien, seg\u00fan dicen, fue asesinado por combatientes de Hamas el 7 de octubre en el kibutz Nir Oz. En una declaraci\u00f3n de este lunes, las FDI dijeron que tras \u201cun an\u00e1lisis exhaustivo realizado por las FDI en coordinaci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-03T09:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/"},"author":{"name":"","@id":""},"headline":"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre","datePublished":"2024-06-03T09:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/","name":"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-03T09:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las FDI localizan el cuerpo del param\u00e9dico israel\u00ed muerto el 7 de octubre","url":"http:\/\/noticiasya.com\/nacional\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/06\/03\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-03T09:03:48Z","datePublished":"2024-06-03T09:03:48Z","dateModified":"2024-06-03T09:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las FDI localizan el cuerpo del param\\u00e9dico israel\\u00ed muerto el 7 de octubre\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/06\\\/03\\\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/06\\\/03\\\/cuerpo-paramedico-israeli-murio-7-de-octubre-localizado-por-fdi-kibutz-nir-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-03T09:03:48Z\",\"datePublished\":\"2024-06-03T09:03:48Z\",\"dateModified\":\"2024-06-03T09:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461239,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/15\/avion-israeli-bomba-cerca-comunidad-frontera-gaza-trax\/","url_meta":{"origin":1449950,"position":0},"title":"Avi\u00f3n israel\u00ed lanza bomba cerca de comunidad en la frontera con Gaza por &#171;falla t\u00e9cnica&#187;, seg\u00fan las FDI","author":"","date":"abril 15, 2025","format":false,"excerpt":"Un avi\u00f3n de combate israel\u00ed lanz\u00f3 una bomba cerca de una comunidad israel\u00ed en la frontera de Gaza el martes por la noche como resultado de lo que las Fuerzas de Defensa de Israel (FDI) llamaron un \u201cfallo t\u00e9cnico\u201d.La bomba cay\u00f3 cerca del kibutz Nir Yithzak, adyacente al sur de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463304,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/07\/recuperan-cuerpo-rehen-tailandes-gaza-trax\/","url_meta":{"origin":1449950,"position":1},"title":"Recuperan cuerpo de reh\u00e9n tailand\u00e9s del sur de Gaza en operaci\u00f3n militar","author":"","date":"junio 7, 2025","format":false,"excerpt":"El cuerpo de Nattapong Pinta, un reh\u00e9n tailand\u00e9s secuestrado con vida durante los atentados del 7 de octubre, fue recuperado del sur de Gaza en una operaci\u00f3n militar este viernes, seg\u00fan un comunicado de las Fuerzas de Defensa de Israel (FDI) y el servicio de seguridad Shin Bet.El anuncio se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449963,"url":"https:\/\/noticiasya.com\/nacional\/2024\/06\/03\/fdi-cuatro-rehenes-israelies-gaza-muertos-trax\/","url_meta":{"origin":1449950,"position":2},"title":"Las FDI notifican a las familias de cuatro rehenes israel\u00edes retenidos en Gaza que &#171;ya no est\u00e1n vivos&#187;","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN) -- Las Fuerzas de Defensa de Israel dicen que sus representantes informaron a las familias de cuatro rehenes retenidos en Gaza \"que ya no est\u00e1n vivos\".Las FDI dijeron que hab\u00edan comunicado a las familias de Haim Perry, Yoram Metzger, Amiram Cooper y Nadav Popplewell \"que fueron brutalmente secuestrados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447796,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/06\/cuerpo-rehen-israel-hamas-rescatado-trax\/","url_meta":{"origin":1449950,"position":3},"title":"Devuelven a su familia el cuerpo de reh\u00e9n israel\u00ed despu\u00e9s de ser recuperado durante la noche, dice Israel","author":"","date":"abril 6, 2024","format":false,"excerpt":"(CNN) -- El cuerpo de un reh\u00e9n israel\u00ed, que muri\u00f3 mientras estaba cautivo por el grupo terrorista Jihad Isl\u00e1mica, fue devuelto a la familia, dijo este s\u00e1bado el Ej\u00e9rcito israel\u00ed.El cuerpo de Elad Katzir fue rescatado durante la noche en Khan Yunis y devuelto a su familia en Israel tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463328,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/07\/israel-mato-lider-grupo-militante-palestino-ataque-trax\/","url_meta":{"origin":1449950,"position":4},"title":"Israel afirma haber matado al l\u00edder del grupo militante palestino que particip\u00f3 en el ataque del 7 de octubre","author":"","date":"junio 7, 2025","format":false,"excerpt":"Las fuerzas israel\u00edes aseguran haber matado al l\u00edder de un grupo militante palestino que particip\u00f3 en los ataques del 7 de octubre de 2023 en el sur de Israel.Asaad Abu Sharia, quien dirigi\u00f3 el Movimiento Muyahid\u00edn Palestino y su brazo armado, las Brigadas Muyahidines, muri\u00f3 en una operaci\u00f3n conjunta con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463827,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/22\/recuperan-gazacuerpos-soldado-israeli-dos-civiles-secuestrados-trax\/","url_meta":{"origin":1449950,"position":5},"title":"Recuperan en Gaza los cuerpos de un soldado israel\u00ed y dos civiles secuestrados","author":"","date":"junio 22, 2025","format":false,"excerpt":"Los cuerpos de un soldado de las Fuerzas de Defensa de Israel (FDI) y dos civiles que murieron durante los ataques liderados por Hamas el 7 de octubre fueron recuperados en Gaza durante una operaci\u00f3n militar de rescate de rehenes.En una operaci\u00f3n especial llevada a cabo por la Agencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449950"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449950\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}