{"id":1458822,"date":"2025-02-17T04:03:48","date_gmt":"2025-02-17T12:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/"},"modified":"2025-02-17T04:03:48","modified_gmt":"2025-02-17T12:03:48","slug":"un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/","title":{"rendered":"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei"},"content":{"rendered":"<p>Alan Boryszanski, fundador de Cryptomate, una empresa crypto nacida en Argentina y que, seg\u00fan indica, tiene como objetivo impulsar a las empresas a la econom\u00eda criptogr\u00e1fica.<\/p>\n<p>En este marco, se refiri\u00f3 a la situaci\u00f3n generada por la promoci\u00f3n que hizo el presidente Javier Milei de un proyecto a trav\u00e9s de de su cuenta de X y que despu\u00e9s retir\u00f3 su apoyo al proyecto, un per\u00edodo en el cual la criptomoneda registr\u00f3 un r\u00e1pido aumento en su cotizaci\u00f3n y luego se desplom\u00f3 causando p\u00e9rdidas para miles de inversores, seg\u00fan se pudo observar en los sitios de aplicaciones de trading.<\/p>\n<p>En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201choy en d\u00eda quiz\u00e1s el prisma lo ve como algo negativo, pero en el largo plazo es algo positivo para la industria porque genera conciencia de lo bueno y lo malo, lo sucio y lo limpio de la tecnolog\u00eda e interioriza a las personas de que se puede hacer cosas con esto, que no es solamente un activo o una tecnolog\u00eda que viene a fomentar especulaciones, sino que tambi\u00e9n puede trascender otros tipos de aplicabilidad\u201d.<\/p>\n<p>El especialista consider\u00f3 que \u201chab\u00eda la intencionalidad de generar un proyecto, se hizo una ingenier\u00eda social para con el c\u00edrculo cercano del presidente, para atraerlo a comentar que este proyecto iba a salir a la luz, iba a desarrollarse con un impacto en Argentina, entiendo que el c\u00edrculo del presidente entendi\u00f3 que era un proyecto oneroso, que pod\u00eda ser beneficioso y por lo cual surgi\u00f3 ese tweet pocos minutos despu\u00e9s del lanzamiento de esa moneda\u201d.<\/p>\n<p>En este sentido, aclar\u00f3 que \u201ccuando sale ese tipo de monedas, que de vuelta es una subcategor\u00eda dentro del mundo de los activos digitales, que son memecoins, que son expresiones o voces traducidas en el mundo digital que tienen una contraparte de valor monetario, que te dice qu\u00e9 tan fuerte es. Cuando sali\u00f3 el token de Donald Trump, antes de que fuera presidente, mostraba el impulso que ten\u00eda su persona y su nuevo gobierno\u201d.<\/p>\n<p>Detall\u00f3 que \u201chay otros memecoins que hablan de otras cosas, son expresiones que la sociedad valida con su dinero. Ese tipo de tokens requieren de, en sus primeras etapas, lo que se llama armadores de mercado. Cuando es un token que tiene que salir a la luz, primero tiene que haber una contraparte que levante la mano y diga yo vendo, yo compro a tal precio\u201d.<\/p>\n<p>Alan Boryszanski analiz\u00f3 que \u201ca sabiendas que iba a haber un tweet del presidente, los hacedores de mercado lo que hicieron fue colocar grandes cantidades de liquidez en el proyecto, como para que eso haga que todas las partes que quieran participar puedan encontrar esa pata vendedora conscientemente. Al momento que, a entender de los hacedores de mercado, se lleg\u00f3 a un precio que hac\u00eda queno hab\u00eda viabilidad, no hab\u00eda necesidad de seguir avanzando en una cotizaci\u00f3n mayor o no hab\u00eda liquidez para afrontar un precio mayor, lo que hicieron fue retirar su porci\u00f3n inicial, recubrir su riesgo, porque ellos lo hacen con el token de Javier Milei\u201d.<\/p>\n<p>Explic\u00f3 que \u201cpueden ser 500 proyectos al mismo tiempo, retienen su liquidez inicial, toman su ganancia, seg\u00fan los t\u00e9rminos y condiciones del proyecto, tambi\u00e9n asignar\u00e1n la proporci\u00f3n que le corresponde a cada participante y seguir\u00e1n con el siguiente\u201d.<\/p>\n<p>Detall\u00f3 que es \u201clo que se denomin\u00f3 el pump and dump, que se impuls\u00f3 el proyecto hasta un punto elevado de valorizaci\u00f3n internacional, que tambi\u00e9n le pas\u00f3 el token de Trump, que tambi\u00e9n le pas\u00f3 el token de Melania Trump, que tambi\u00e9n le pas\u00f3 al Pepecoin, que es una moneda divertida que estuvo ah\u00ed dando vueltas\u201d.<\/p>\n<p>El fundador de Cryptomate remarc\u00f3 que  \u201csi la liquidez que se extrajo y la ganancia que se extrajo se usa para el prop\u00f3sito inicial del proyecto, entonces estamos hablando, estamos discutiendo sobre cosas que nunca hubo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alan Boryszanski, fundador de Cryptomate, una empresa crypto nacida en Argentina y que, seg\u00fan indica, tiene como objetivo impulsar a las empresas a la econom\u00eda criptogr\u00e1fica. En este marco, se refiri\u00f3 a la situaci\u00f3n generada por la promoci\u00f3n que hizo el presidente Javier Milei de un proyecto a trav\u00e9s de de su cuenta de X [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458822","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei - Noticias\" \/>\n<meta property=\"og:description\" content=\"Alan Boryszanski, fundador de Cryptomate, una empresa crypto nacida en Argentina y que, seg\u00fan indica, tiene como objetivo impulsar a las empresas a la econom\u00eda criptogr\u00e1fica. En este marco, se refiri\u00f3 a la situaci\u00f3n generada por la promoci\u00f3n que hizo el presidente Javier Milei de un proyecto a trav\u00e9s de de su cuenta de X [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T12:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei\",\"datePublished\":\"2025-02-17T12:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/\"},\"wordCount\":711,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/\",\"name\":\"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-17T12:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/","og_locale":"es_ES","og_type":"article","og_title":"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei - Noticias","og_description":"Alan Boryszanski, fundador de Cryptomate, una empresa crypto nacida en Argentina y que, seg\u00fan indica, tiene como objetivo impulsar a las empresas a la econom\u00eda criptogr\u00e1fica. En este marco, se refiri\u00f3 a la situaci\u00f3n generada por la promoci\u00f3n que hizo el presidente Javier Milei de un proyecto a trav\u00e9s de de su cuenta de X [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/","og_site_name":"Noticias","article_published_time":"2025-02-17T12:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/"},"author":{"name":"","@id":""},"headline":"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei","datePublished":"2025-02-17T12:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/"},"wordCount":711,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/","url":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/","name":"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-17T12:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un especialista en criptomoneda analiz\u00f3 la pol\u00e9mica por el proyecto que se desplom\u00f3 luego de ser presentado por Javier Milei","url":"http:\/\/noticiasya.com\/nacional\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/02\/17\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-17T12:03:48Z","datePublished":"2025-02-17T12:03:48Z","dateModified":"2025-02-17T12:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un especialista en criptomoneda analiz\\u00f3 la pol\\u00e9mica por el proyecto que se desplom\\u00f3 luego de ser presentado por Javier Milei\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/17\\\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/17\\\/un-especialista-en-criptomoneda-analizo-la-polemica-por-el-proyecto-que-se-desplomo-luego-de-ser-presentado-por-javier-milei\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-17T12:03:48Z\",\"datePublished\":\"2025-02-17T12:03:48Z\",\"dateModified\":\"2025-02-17T12:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458808,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/16\/milei-controversia-criptomoneda-libra-orix\/","url_meta":{"origin":1458822,"position":0},"title":"Milei en medio de una controversia tras promocionar una criptomoneda cuyo valor subi\u00f3 y se desplom\u00f3. \u00bfQu\u00e9 pas\u00f3 con $LIBRA?","author":"","date":"febrero 16, 2025","format":false,"excerpt":"El presidente de Argentina, Javier Milei, se encuentra en medio de una tormenta pol\u00edtica que incluye pedidos de juicio pol\u00edtico en su contra, despu\u00e9s de promocionar en la tarde del viernes un activo digital a trav\u00e9s de su cuenta de X. Horas despu\u00e9s, el primer mandatario retir\u00f3 su apoyo al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460973,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/08\/comision-legislativa-investigar-milei-criptoescandalo-libra-orix\/","url_meta":{"origin":1458822,"position":1},"title":"Aprueban una comisi\u00f3n legislativa para investigar a Milei y el criptoesc\u00e1ndalo $LIBRA","author":"","date":"abril 8, 2025","format":false,"excerpt":"La C\u00e1mara de Diputados de Argentina aprob\u00f3 este martes crear una comisi\u00f3n para investigar en el Congreso el caso de la criptomoneda $LIBRA, que desat\u00f3 un esc\u00e1ndalo que involucr\u00f3 al presidente Javier Milei.El proyecto tuvo 128 votos a favor, 93 en contra (incluidos los del oficialismo y algunos de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458885,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/18\/mileio-defiende-tuit-criptomonedas-argentina-trax\/","url_meta":{"origin":1458822,"position":2},"title":"Milei defiende su tuit sobre criptomonedas tras la ca\u00edda y compara p\u00e9rdidas con apuestas","author":"","date":"febrero 18, 2025","format":false,"excerpt":"El presidente de Argentina Javier Milei se defendi\u00f3 tras promover una criptomoneda cuyo valor se desplom\u00f3 a las pocas horas de su lanzamiento, comparando a quienes invirtieron en el token despu\u00e9s de su respaldo con los jugadores de los casinos.\u201cLa realidad es que si vos vas al casino y pierd\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458948,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/dilema-milei-escandalo-libra-criptomoneda-analisis-orix\/","url_meta":{"origin":1458822,"position":3},"title":"AN\u00c1LISIS | El dilema de Milei ante el esc\u00e1ndalo $Libra: \u00bfquedar como ingenuo o como c\u00f3mplice?","author":"","date":"febrero 19, 2025","format":false,"excerpt":"El esc\u00e1ndalo de la criptomoneda $LIBRA dej\u00f3 en una situaci\u00f3n muy comprometedora al presidente de Argentina, Javier Milei: quedar como aparente c\u00f3mplice de la promoci\u00f3n de un activo digital que subi\u00f3 vertiginosamente para desplomarse a las pocas horas (dejando a miles de inversores damnificados tras su recomendaci\u00f3n y a unos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458833,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/17\/que-tipo-de-criptomoneda-es-la-que-promociono-milei\/","url_meta":{"origin":1458822,"position":4},"title":"\u00bfQu\u00e9 tipo de criptomoneda es la que promocion\u00f3 Milei?","author":"","date":"febrero 17, 2025","format":false,"excerpt":"Juli\u00e1n Colombo, CEO de Bitso, habl\u00f3 este lunes en CNN Radio sobre c\u00f3mo funciona el mundo de las criptomonedas, la variedad de monedas digitales que existe en el mundo y las reacciones en el sector luego de la controversia que tuvo en el centro de la escena al presidente Javier\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458775,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/15\/damian-di-pace-analizo-la-inflacion-de-enero-y-la-polemica-por-la-criptomoneda-recomendada-por-javier-milei\/","url_meta":{"origin":1458822,"position":5},"title":"Dami\u00e1n Di Pace analiz\u00f3 la inflaci\u00f3n de enero y la pol\u00e9mica por la criptomoneda recomendada por Javier Milei","author":"","date":"febrero 15, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Dami\u00e1n Di Pace, economista, habl\u00f3 este s\u00e1bado con Hern\u00e1n Harris en De Ida y Vuelta sobre el dato de inflaci\u00f3n de enero y la controversia generada por la criptomoneda que recomend\u00f3 el presidente Javier Milei.Di Pace explic\u00f3 que \u201csi baja la canasta b\u00e1sica total, tambi\u00e9n baja\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1458822"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458822\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1458822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1458822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1458822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}