{"id":1458851,"date":"2025-02-17T21:03:49","date_gmt":"2025-02-18T05:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/"},"modified":"2025-02-17T21:03:49","modified_gmt":"2025-02-18T05:03:49","slug":"costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/","title":{"rendered":"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU."},"content":{"rendered":"<p>La Presidencia de Costa Rica anunci\u00f3 este lunes que acord\u00f3 colaborar con el Gobierno de Estados Unidos para recibir a 200 migrantes de diversas nacionalidades deportados por EE.UU., para despu\u00e9s enviarlos a sus lugares de origen (pa\u00edses del centro de Asia y de la India).<\/p>\n<p>En un comunicado, el Gobierno costarricense anunci\u00f3 que este mi\u00e9rcoles recibir\u00e1 al grupo, y que el proceso es completamente financiado por Estados Unidos, bajo la supervisi\u00f3n de la Organizaci\u00f3n Internacional para las Migraciones (OIM).<\/p>\n<p>\u201cCosta Rica continuar\u00e1 siendo un referente mundial en temas humanitarios\u201d, se\u00f1al\u00f3.<\/p>\n<p>Esta colaboraci\u00f3n se da en el marco de la campa\u00f1a del Gobierno del presidente Donald Trump contra la inmigraci\u00f3n indocumentada, con redadas y deportaciones masivas. A inicios de mes, el secretario de Estado de EE.UU., Marco Rubio, firm\u00f3 en El Salvador un acuerdo para admitir en el pa\u00eds y alojar en una megaprisi\u00f3n a criminales convictos en Estados Unidos, a cambio de una contraprestaci\u00f3n, sin importar sus nacionalidades.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidencia de Costa Rica anunci\u00f3 este lunes que acord\u00f3 colaborar con el Gobierno de Estados Unidos para recibir a 200 migrantes de diversas nacionalidades deportados por EE.UU., para despu\u00e9s enviarlos a sus lugares de origen (pa\u00edses del centro de Asia y de la India). En un comunicado, el Gobierno costarricense anunci\u00f3 que este mi\u00e9rcoles [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458851","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Presidencia de Costa Rica anunci\u00f3 este lunes que acord\u00f3 colaborar con el Gobierno de Estados Unidos para recibir a 200 migrantes de diversas nacionalidades deportados por EE.UU., para despu\u00e9s enviarlos a sus lugares de origen (pa\u00edses del centro de Asia y de la India). En un comunicado, el Gobierno costarricense anunci\u00f3 que este mi\u00e9rcoles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T05:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU.\",\"datePublished\":\"2025-02-18T05:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/\"},\"wordCount\":201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/\",\"name\":\"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-18T05:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU. - Noticias","og_description":"La Presidencia de Costa Rica anunci\u00f3 este lunes que acord\u00f3 colaborar con el Gobierno de Estados Unidos para recibir a 200 migrantes de diversas nacionalidades deportados por EE.UU., para despu\u00e9s enviarlos a sus lugares de origen (pa\u00edses del centro de Asia y de la India). En un comunicado, el Gobierno costarricense anunci\u00f3 que este mi\u00e9rcoles [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2025-02-18T05:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU.","datePublished":"2025-02-18T05:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/"},"wordCount":201,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/","name":"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-18T05:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Costa Rica acepta recibir y repatriar a 200 migrantes asi\u00e1ticos deportados por EE.UU.","url":"http:\/\/noticiasya.com\/nacional\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/02\/17\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-18T05:03:49Z","datePublished":"2025-02-18T05:03:49Z","dateModified":"2025-02-18T05:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Costa Rica acepta recibir y repatriar a 200 migrantes asi\\u00e1ticos deportados por EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/17\\\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/17\\\/costa-rica-recibir-repatriar-200-migrantes-asiaticos-deportados-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-18T05:03:49Z\",\"datePublished\":\"2025-02-18T05:03:49Z\",\"dateModified\":\"2025-02-18T05:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458952,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/costa-rica-albergar-migrantes-asiaticos-deportados-eeuu-orix\/","url_meta":{"origin":1458851,"position":0},"title":"Costa Rica prev\u00e9 albergar hasta 6 semanas a los 200 migrantes asi\u00e1ticos deportados por EE.UU.; entre ellos hay 50 ni\u00f1os","author":"","date":"febrero 19, 2025","format":false,"excerpt":"El presidente de Costa Rica, Rodrigo Chaves, dijo este mi\u00e9rcoles que prev\u00e9n albergar entre tres y seis semanas en un centro de procesamiento al grupo de 200 personas de nacionalidades asi\u00e1ticas deportadas por Estados Unidos, entre quienes hay unos 50 ni\u00f1os.El mandatario explic\u00f3 durante un evento en Punta Arenas que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459003,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/20\/vuelo-135-migrantes-deportados-llega-costa-rica-orix\/","url_meta":{"origin":1458851,"position":1},"title":"Vuelo con 135 migrantes deportados por EE.UU. llega a Costa Rica","author":"","date":"febrero 20, 2025","format":false,"excerpt":"Un vuelo con 135 migrantes de diversos pa\u00edses deportados por Estados Unidos aterriz\u00f3 este jueves en San Jos\u00e9, Costa Rica, para continuar su proceso de repatriaci\u00f3n.A bordo de un vuelo ch\u00e1rter, los migrantes llegaron al Aeropuerto Internacional Juan Santamar\u00eda para despu\u00e9s ser trasladados en autobuses al Centro de Atenci\u00f3n Temporal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459060,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/21\/defensoria-costa-rica-deportados-malos-tratos-orix\/","url_meta":{"origin":1458851,"position":2},"title":"La Defensor\u00eda de Costa Rica se\u00f1ala &#171;fallas&#187; en atenci\u00f3n a deportados por EE.UU.; el Gobierno niega malos tratos","author":"","date":"febrero 21, 2025","format":false,"excerpt":"La Defensor\u00eda de los Habitantes de Costa Rica dijo este viernes que observ\u00f3 fallas en la atenci\u00f3n que las autoridades del pa\u00eds centroamericano dieron al grupo de 135 migrantes de varias nacionalidades \u2015principalmente de pa\u00edses asi\u00e1ticos\u2015 que lleg\u00f3 este jueves tras ser deportado por Estados Unidos. El Ministerio de Seguridad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462910,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/28\/hrw-trato-injusto-deportados-costa-rica-orix\/","url_meta":{"origin":1458851,"position":3},"title":"Human Rights Watch denuncia trato &#171;injusto&#187; contra deportados de EE.UU. a Costa Rica","author":"","date":"mayo 28, 2025","format":false,"excerpt":"La organizaci\u00f3n no gubernamental Human Rights Watch (HRW) denunci\u00f3 en un informe que los 200 migrantes deportados por Estados Unidos hacia Costa Rica en febrero fueron expulsados \u201cinjustamente\u201d, y que las autoridades del pa\u00eds centroamericano los detuvieron durante dos meses y les \u201ctransmitieron mensajes contradictorios sobre su futuro\u201d.\u201cDurante m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460855,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/04\/migrantes-china-deportados-ee-uu-refugio-costa-rica-orix\/","url_meta":{"origin":1458851,"position":4},"title":"Migrantes de China deportados por EE.UU. comienzan proceso de refugio en Costa Rica","author":"","date":"abril 4, 2025","format":false,"excerpt":"Costa Rica otorg\u00f3 la condici\u00f3n de solicitantes de refugio a 16 migrantes de nacionalidad china deportados por Estados Unidos el 20 y el 26 de febrero pasado, inform\u00f3 este viernes la Direcci\u00f3n General de Migraci\u00f3n y Extranjer\u00eda de la naci\u00f3n centroamericana.El grupo forma parte de 200 personas deportadas por Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459505,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/04\/migrantes-deportados-eeuu-costa-rica-retorno-voluntario-orix\/","url_meta":{"origin":1458851,"position":5},"title":"Grupo de migrantes deportados por EE.UU. sale de Costa Rica en &#171;retorno voluntario&#187;, dice el Gobierno","author":"","date":"marzo 4, 2025","format":false,"excerpt":"La direcci\u00f3n de Migraci\u00f3n y Extranjer\u00eda de Costa Rica inform\u00f3 que este martes se concret\u00f3 el \u201cretorno voluntario\u201d de dos migrantes de Azerbaiy\u00e1n, que forman parte del primer grupo de 200 personas deportadas por Estados Unidos el 20 y el 26 de febrero.La Oficina de Prensa del Ministerio de Seguridad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1458851"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458851\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1458851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1458851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1458851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}