{"id":1458871,"date":"2025-02-18T11:03:42","date_gmt":"2025-02-18T19:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/"},"modified":"2025-02-18T11:03:42","modified_gmt":"2025-02-18T19:03:42","slug":"andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/","title":{"rendered":"Andr\u00e9s Malamud: &#171;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&#187;"},"content":{"rendered":"<p><strong>Andr\u00e9s Malamud<\/strong>, polit\u00f3logo argentino, convers\u00f3 este martes en CNN Radio con Pepe Gil Vidal y Mariana Airas sobre el esc\u00e1ndalo del presidente Javier Milei con la criptomoneda $LIBRA y dijo que el impacto negativo \u201cno est\u00e1 en los mercados ni en el electorado, sino en la propia pol\u00edtica\u201d.<\/p>\n<p>En el programa <em>Regreso CNN,<\/em> adem\u00e1s, Malamud indic\u00f3 que el presidente \u201choy est\u00e1 desaprovechando el mundo digital por el r\u00e9cord de negatividad. Hasta ahora en los mercados no tuvo ning\u00fan impacto serio y seguramente no suceda en t\u00e9rminos electorales. <strong>Pero genera desconfianza en los olfateadores de la pol\u00edtica y puede traerle problemas en el Congreso\u201d.<\/strong><\/p>\n<p>Seg\u00fan Malamud, <strong>\u201cesto es Milei versus Milei. Hoy la pol\u00edtica es un desierto y \u00e9l se hace da\u00f1o a s\u00ed mismo\u201d.<\/strong><\/p>\n<p>\u201c<strong>Nadie lo obligaba a hacer el discurso en Davos o a difundir una estafa.<\/strong> Y mucho menos dejar en evidencia el pacto con el periodista que lo entrevist\u00f3\u201d, relat\u00f3 el especialista sobre las \u00faltimas exposiciones que generaron pol\u00e9mica con el primer mandatario en el centro de la escena.<\/p>\n<p>En este sentido, Malamud expres\u00f3 que en este caso \u201cfall\u00f3 el economista y fall\u00f3 el mago de la pol\u00edtica. Hay que ver c\u00f3mo se reconfigura todo esto\u201d.<\/p>\n<p><strong>Finalmente, el experto aclar\u00f3 que \u201cesto que sucedi\u00f3 es un antes y un despu\u00e9s para el gobierno; veremos c\u00f3mo procesa esta crisis\u201d<\/strong><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andr\u00e9s Malamud, polit\u00f3logo argentino, convers\u00f3 este martes en CNN Radio con Pepe Gil Vidal y Mariana Airas sobre el esc\u00e1ndalo del presidente Javier Milei con la criptomoneda $LIBRA y dijo que el impacto negativo \u201cno est\u00e1 en los mercados ni en el electorado, sino en la propia pol\u00edtica\u201d. En el programa Regreso CNN, adem\u00e1s, Malamud [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458871","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Andr\u00e9s Malamud: &quot;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andr\u00e9s Malamud: &quot;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Andr\u00e9s Malamud, polit\u00f3logo argentino, convers\u00f3 este martes en CNN Radio con Pepe Gil Vidal y Mariana Airas sobre el esc\u00e1ndalo del presidente Javier Milei con la criptomoneda $LIBRA y dijo que el impacto negativo \u201cno est\u00e1 en los mercados ni en el electorado, sino en la propia pol\u00edtica\u201d. En el programa Regreso CNN, adem\u00e1s, Malamud [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T19:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Andr\u00e9s Malamud: &#171;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&#187;\",\"datePublished\":\"2025-02-18T19:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/\",\"name\":\"Andr\u00e9s Malamud: \\\"Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-18T19:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Andr\u00e9s Malamud: &#171;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Andr\u00e9s Malamud: \"Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/","og_locale":"es_ES","og_type":"article","og_title":"Andr\u00e9s Malamud: \"Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis\" - Noticias","og_description":"Andr\u00e9s Malamud, polit\u00f3logo argentino, convers\u00f3 este martes en CNN Radio con Pepe Gil Vidal y Mariana Airas sobre el esc\u00e1ndalo del presidente Javier Milei con la criptomoneda $LIBRA y dijo que el impacto negativo \u201cno est\u00e1 en los mercados ni en el electorado, sino en la propia pol\u00edtica\u201d. En el programa Regreso CNN, adem\u00e1s, Malamud [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/","og_site_name":"Noticias","article_published_time":"2025-02-18T19:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/"},"author":{"name":"","@id":""},"headline":"Andr\u00e9s Malamud: &#171;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&#187;","datePublished":"2025-02-18T19:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/","url":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/","name":"Andr\u00e9s Malamud: \"Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-18T19:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Andr\u00e9s Malamud: &#171;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Andr\u00e9s Malamud: &#171;Esto es un antes y un despu\u00e9s; veremos c\u00f3mo procesa el gobierno esta crisis&#187;","url":"http:\/\/noticiasya.com\/nacional\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/02\/18\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-18T19:03:42Z","datePublished":"2025-02-18T19:03:42Z","dateModified":"2025-02-18T19:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Andr\\u00e9s Malamud: &#171;Esto es un antes y un despu\\u00e9s; veremos c\\u00f3mo procesa el gobierno esta crisis&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/18\\\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/18\\\/andres-malamud-esto-es-un-antes-y-un-despues-veremos-como-procesa-el-gobierno-esta-crisis\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-18T19:03:42Z\",\"datePublished\":\"2025-02-18T19:03:42Z\",\"dateModified\":\"2025-02-18T19:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458841,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/17\/carlos-malamud-fue-el-primer-gran-error-de-milei\/","url_meta":{"origin":1458871,"position":0},"title":"Carlos Malamud: &#171;Fue el primer gran error de Milei&#187;","author":"","date":"febrero 17, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Carlos Malamud, historiador y catedr\u00e1tico del Real Instituto Elcano de Madrid, dialog\u00f3 este lunes con CNN Radio tras la pol\u00e9mica generada con el tuit de Javier Milei al recomendar una criptomoneda.En Regreso CNN, con Pepe Gil Vidal y Mariana Arias, el analista sostuvo que \u201cel presidente,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458200,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/04\/andres-malamud-el-kirchnerismo-ya-casi-no-tiene-existencia-electoral-a-nivel-nacional\/","url_meta":{"origin":1458871,"position":1},"title":"Andr\u00e9s Malamud: &#171;El kirchnerismo ya casi no tiene existencia electoral a nivel nacional&#187;","author":"","date":"febrero 4, 2025","format":false,"excerpt":"Andr\u00e9s Malamud, analista pol\u00edtico, se refiri\u00f3 al momento pol\u00edtico del pa\u00eds y el futuro de cara a las elecciones legislativas de este a\u00f1o.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cel presidencialismo funciona con un gobierno que ordena y la oposici\u00f3n que desordena. Siempre que hay situaciones intermedias en el presidencialismo pasa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448489,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/24\/analisis-impacto-marcha-universitaria-argentina-gobierno-milei-orix\/","url_meta":{"origin":1458871,"position":2},"title":"An\u00e1lisis | El impacto de la masiva marcha universitaria en Argentina para el gobierno de Milei","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Llegar a la hist\u00f3rica Plaza de Mayo, en el centro de Buenos Aires, fue una tarea casi imposible. Cuadras y cuadras de manifestantes, entre ellos estudiantes, profesores y egresados, se sumaron a una protesta que denunci\u00f3 el ajuste presupuestario en las universidades p\u00fablicas de Argentina.Una multitud llen\u00f3 Avenida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466223,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/07\/denuncias-corrupcion-karina-milei-previo-elecciones-buenos-aires-orix\/","url_meta":{"origin":1458871,"position":3},"title":"Denuncias de corrupci\u00f3n salpican a Karina Milei previo a elecciones cruciales en la provincia de Buenos Aires","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"Una canci\u00f3n sobre la hermana del presidente Javier Milei se volvi\u00f3 viral en Argentina. Se escucha en videos de redes sociales, programas de radio e incluso en el Congreso de la Naci\u00f3n. La parodia utiliza la melod\u00eda de la reconocida canci\u00f3n cubana \u201cGuantanamera\u201d, pero con una nueva letra con tono\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459448,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/03\/sebastian-galiani-el-programa-economico-tiene-dos-grandes-preguntas-por-resolver\/","url_meta":{"origin":1458871,"position":4},"title":"Sebasti\u00e1n Galiani: &#171;El programa econ\u00f3mico tiene dos grandes preguntas por resolver&#187;","author":"","date":"marzo 3, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 El economista y profesor de la Universidad de Maryland, Sebasti\u00e1n Galiani, dialog\u00f3 este lunes con CNN Radio sobre el rumbo de la econom\u00eda argentina durante el gobierno de Javier Milei.En el programa CNN Econom\u00eda y Actualidad, conducido por Julieta Tarr\u00e9s, Galiani sostuvo que \u201cel gobierno ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458867,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/18\/jaime-rosemberg-el-gobierno-esta-intentando-cerrar-el-episodio-cripto\/","url_meta":{"origin":1458871,"position":5},"title":"La columna de Jaime Rosemberg: el intento del gobierno de &#171;cerrar el episodio cripto&#187; y el plan de la oposici\u00f3n","author":"","date":"febrero 18, 2025","format":false,"excerpt":"El periodista y columnista de CNN Radio Jaime Rosemberg habl\u00f3 este martes en CNN Radio sobre el impacto pol\u00edtico del esc\u00e1ndalo de Javier Milei con la criptomoneda $LIBRA, la intenci\u00f3n de la oposici\u00f3n y la estrategia del oficialismo para desactivar el tema.\u201cEl gobierno est\u00e1 intentando cerrar el episodio cripto con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1458871"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458871\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1458871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1458871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1458871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}