{"id":1458945,"date":"2025-02-19T17:03:50","date_gmt":"2025-02-20T01:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/"},"modified":"2025-02-19T17:03:50","modified_gmt":"2025-02-20T01:03:50","slug":"que-podria-ganar-doge-acceder-datos-seguridad-social-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","title":{"rendered":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social"},"content":{"rendered":"<p>Cuando la gente piensa en la seguridad social, generalmente piensa en los beneficios mensuales para los aproximadamente 69 millones de jubilados, trabajadores discapacitados, dependientes y sobrevivientes que los reciben hoy.<\/p>\n<p>Pero la noticia de que miembros del Departamento de Eficiencia Gubernamental (DOGE) est\u00e1n <a href=\"https:\/\/www.cnn.com\/2025\/02\/17\/politics\/social-security-head-steps-down-doge-access\/index.html\">buscando acceso<\/a> a los sistemas de datos de la Administraci\u00f3n del Seguro Social deber\u00eda evocar pensamientos de datos sobre cientos de millones de personas.<\/p>\n<p>\u00bfPor qu\u00e9? Porque los m\u00faltiples sistemas de datos de la SSA contienen una gran cantidad de informaci\u00f3n personal sobre la mayor\u00eda de las personas que viven en Estados Unidos hoy en d\u00eda, as\u00ed como sobre aquellas que han fallecido a lo largo de los a\u00f1os.<\/p>\n<p>Son datos que van \u201cdesde la cuna hasta la tumba\u201d, dijo Kathleen Romig, quien trabaj\u00f3 en la SSA, primero como analista de pol\u00edticas de jubilaci\u00f3n y m\u00e1s recientemente como asesora principal en la Oficina del Comisionado.<\/p>\n<p>DOGE fue creado unilateralmente por el presidente Donald Trump con el objetivo de \u201cmodernizar la tecnolog\u00eda y el software federales para maximizar la eficiencia y la productividad gubernamentales\u201d, seg\u00fan su decreto. Hasta la fecha, el grupo ha <a href=\"https:\/\/www.cnn.com\/2025\/02\/04\/politics\/musk-washington-chaos\/index.html\">causado caos<\/a> e intimidaci\u00f3n en varias agencias federales en las que ha intentado <a href=\"https:\/\/www.cnn.com\/2025\/02\/06\/politics\/elon-musk-treasury-department-payment-system\/index.html\">tomar el control y cerrar<\/a> varios tipos de gastos.<\/p>\n<p>Tambi\u00e9n es objeto de varias demandas <a href=\"https:\/\/www.cnn.com\/2025\/02\/18\/politics\/doge-temporary-restraining-order-chutkan\/index.html\">que cuestionan su derecho legal<\/a> a acceder en masa a los datos personales de los estadounidenses en sistemas inform\u00e1ticos gubernamentales altamente restringidos y a despedir a grupos de trabajadores federales como lo ha hecho.<\/p>\n<p>Esta es solo una lista parcial de los datos que los sistemas del SSA probablemente tienen sobre usted: su nombre, n\u00famero de seguridad social, fecha y lugar de nacimiento, g\u00e9nero, direcciones, estado civil y parental, nombres de sus padres, ingresos de por vida, informaci\u00f3n de cuenta bancaria, estado de inmigraci\u00f3n y autorizaci\u00f3n de trabajo, condiciones de salud si solicita beneficios por discapacidad y uso de Medicare despu\u00e9s de cierta edad, que el SSA puede verificar peri\u00f3dicamente para determinar si todav\u00eda est\u00e1 vivo.<\/p>\n<p>Tambi\u00e9n se pueden obtener o comparar otros tipos de informaci\u00f3n personal a trav\u00e9s de los acuerdos de intercambio de datos de la SSA con el IRS y el Departamento de Salud y Servicios Humanos. Tambi\u00e9n se puede recopilar informaci\u00f3n sobre sus activos y condiciones de vida si solicita <a href=\"https:\/\/www.ssa.gov\/ssi\/text-over-ussi.htm\">el Ingreso de Seguridad Suplementario (SSI)<\/a>, que est\u00e1 destinado a ayudar a las personas con ingresos muy limitados.<\/p>\n<p>Al igual que los <a href=\"https:\/\/www.cnn.com\/2025\/02\/18\/economy\/doge-irs-data-tax-filers-risk\/index.html\">sistemas de datos del IRS<\/a> a los que DOGE tambi\u00e9n ha buscado acceso, los sistemas de la SSA son antiguos, complejos, est\u00e1n interconectados y funcionan con un lenguaje de programaci\u00f3n desarrollado hace d\u00e9cadas. Si se hace un cambio en un sistema, se puede hacer fracasar otro si no se sabe lo que se est\u00e1 haciendo, dijo Romig, quien ahora es director de pol\u00edticas de Seguridad Social y discapacidad en el liberal Centro de Presupuesto y Prioridades Pol\u00edticas.<\/p>\n<p>Y, al igual que en el IRS, existe la preocupaci\u00f3n de que si los miembros del equipo DOGE obtienen acceso a los sistemas de la SSA y buscan realizar cambios directamente o a trav\u00e9s de un empleado de la SSA, podr\u00edan causar errores t\u00e9cnicos o basar sus decisiones en interpretaciones incorrectas de los datos.<\/p>\n<p>Por ejemplo, el multimillonario CEO Elon Musk, que dirige DOGE, <a href=\"https:\/\/www.cnn.com\/2025\/02\/18\/politics\/trump-musk-social-security-payments-what-matters\/index.html\">afirm\u00f3 incorrectamente<\/a> que la SSA est\u00e1 realizando pagos a millones de personas fallecidas. Su afirmaci\u00f3n parece basarse en la llamada lista Numident, que es una recopilaci\u00f3n limitada de datos personales, dijo Romig. La lista incluye nombres, n\u00fameros de la Seguridad Social y las fechas de nacimiento y muerte de una persona. Pero la lista Numident no refleja las fechas de muerte de 18,9 millones de personas que nacieron en 1920 o antes.<\/p>\n<p>Ese es un problema conocido, que el inspector general de la Seguridad Social en un <a href=\"https:\/\/oig.ssa.gov\/assets\/uploads\/a-06-21-51022.pdf\">informe<\/a> de 2023 ya ha recomendado que la agencia corrija. Ese mismo informe, sin embargo, tambi\u00e9n se\u00f1al\u00f3 que \u201ccasi ninguno de los 18,9 millones de titulares de n\u00fameros recibe actualmente pagos de la SSA\u201d.<\/p>\n<p>Y tomar decisiones basadas en interpretaciones err\u00f3neas podr\u00eda crear problemas reales para las personas.<\/p>\n<p>Por ejemplo, dijo Romig, hay distintos tipos de n\u00fameros de Seguridad Social asignados: por ejemplo, para ciudadanos estadounidenses, para no ciudadanos con autorizaci\u00f3n de trabajo y para personas con visas de estudiante que no tienen autorizaci\u00f3n de trabajo. Pero el estatus de una persona puede cambiar con el tiempo. Por ejemplo, alguien con una visa de estudiante puede eventualmente obtener autorizaci\u00f3n de trabajo. Pero es responsabilidad de la persona actualizar a la SSA sobre su estatus.<\/p>\n<p>Si no lo hace de inmediato o tal vez ni siquiera durante a\u00f1os, las listas en los sistemas de la SSA pueden no estar completamente actualizadas. Por lo tanto, es f\u00e1cil ver c\u00f3mo una nueva entidad como DOGE, que no est\u00e1 familiarizada con la complejidad de los procesos de la Seguridad Social, podr\u00eda tomar una decisi\u00f3n r\u00e1pida que afecte a un grupo particular de personas en una lista que puede no estar actualizada.<\/p>\n<p>Charles Blahous, estratega de investigaci\u00f3n del Mercatus Center de la Universidad George Mason, ha sido uno de los principales defensores de la soluci\u00f3n del d\u00e9ficit de financiaci\u00f3n a largo plazo de la Seguridad Social y est\u00e1 totalmente a favor de erradicar el despilfarro, el fraude y el abuso.<\/p>\n<p>Pero, se\u00f1al\u00f3 Blahous, \u201clas mejores estimaciones de los pagos indebidos en la Seguridad Social son de menos del 1% de los desembolsos del programa. Me preocupa que esta conversaci\u00f3n en particular est\u00e9 alimentando profundas impresiones err\u00f3neas sobre la Seguridad Social y los desaf\u00edos de pol\u00edtica que la rodean\u201d.<\/p>\n<p>Los sistemas de datos de la SSA est\u00e1n almacenados en salas cerradas, y el acceso para ver (y mucho menos modificar) la informaci\u00f3n que contienen ha sido siempre estrictamente limitado, dijo Romig, se\u00f1alando que le tomaron las huellas digitales y tuvo que pasar una verificaci\u00f3n de antecedentes antes de que se le permitiera ver los datos para su investigaci\u00f3n mientras estaba en la agencia y solo pod\u00edan ser datos que no tuvieran informaci\u00f3n de identificaci\u00f3n personal.<\/p>\n<p>Dada la variedad de datos personales disponibles, tambi\u00e9n hay una serie de leyes federales de privacidad y otras leyes que limitan el uso y la difusi\u00f3n de dicha informaci\u00f3n.<\/p>\n<p>Estas leyes tienen como objetivo evitar no s\u00f3lo el uso indebido o la filtraci\u00f3n de datos por parte de individuos, sino tambi\u00e9n el abuso de poder por parte del gobierno, seg\u00fan el Centro para la Democracia y la Tecnolog\u00eda.<\/p>\n<p>Durante el fin de semana, la comisionada interina de la SSA, Michelle King, ejecutiva de servicio de larga trayectoria en la agencia, renunci\u00f3 despu\u00e9s de que miembros del personal de DOGE intentaran acceder a registros gubernamentales confidenciales. En su lugar, el empleado de la SSA, Lee Dudek, fue nombrado director interino.<\/p>\n<p>Dudek emiti\u00f3 una <a href=\"https:\/\/www.ssa.gov\/news\/press\/releases\/2025\/#2025-02-19\">declaraci\u00f3n<\/a> sobre el \u201cCompromiso de la SSA con la transparencia de la agencia y la protecci\u00f3n de los beneficios y la informaci\u00f3n\u201d alrededor del mediod\u00eda del mi\u00e9rcoles. \u201cMi primera llamada como Comisionado interino fue a nuestra Oficina del Inspector General (OIG) para brindarles la oportunidad de supervisar y revisar todas y cada una de las actividades de la agencia, incluidas mis acciones pasadas, presentes y futuras\u201d, dijo.<\/p>\n<p>Trump ya <a href=\"https:\/\/www.cnn.com\/2025\/02\/12\/politics\/inspector-general-lawsuit-fired-trump\/index.html\">despidi\u00f3 a varios inspectores generales de agencias<\/a>, incluido Hannibal Ware, que se desempe\u00f1aba como inspector general interino de la SSA <a href=\"https:\/\/oig.ssa.gov\/news-releases\/2024-09-30-inspector-general-hannibal-%E2%80%9Cmike%E2%80%9D-ware-designated-as-acting-inspector-general-for-social-security-administration-office-of-inspector-general\/\">desde el oto\u00f1o.<\/a> Esos despidos son objeto de una demanda. La Oficina del Inspector General le dijo a CNN que Michelle Anderson, inspectora general adjunta, actualmente desempe\u00f1a las funciones de inspectora general de la Administraci\u00f3n del Seguro Social.<\/p>\n<p>Dudek tambi\u00e9n se\u00f1al\u00f3 en su declaraci\u00f3n que el personal de DOGE: a) \u201cno puede realizar cambios en los sistemas de la agencia, pagos de beneficios u otra informaci\u00f3n\u201d; b) \u201csolo tiene acceso de lectura\u201d a los datos; c) \u201cno tiene acceso a datos relacionados con una orden de restricci\u00f3n temporal ordenada por un tribunal, actual o futura\u201d; y d) \u201cdebe cumplir con la ley y si viola la ley ser\u00e1 remitido al Departamento de Justicia para un posible procesamiento\u201d.<\/p>\n<p><em>Alayna Treene de CNN contribuy\u00f3 a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando la gente piensa en la seguridad social, generalmente piensa en los beneficios mensuales para los aproximadamente 69 millones de jubilados, trabajadores discapacitados, dependientes y sobrevivientes que los reciben hoy. Pero la noticia de que miembros del Departamento de Eficiencia Gubernamental (DOGE) est\u00e1n buscando acceso a los sistemas de datos de la Administraci\u00f3n del Seguro [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458945","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando la gente piensa en la seguridad social, generalmente piensa en los beneficios mensuales para los aproximadamente 69 millones de jubilados, trabajadores discapacitados, dependientes y sobrevivientes que los reciben hoy. Pero la noticia de que miembros del Departamento de Eficiencia Gubernamental (DOGE) est\u00e1n buscando acceso a los sistemas de datos de la Administraci\u00f3n del Seguro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-20T01:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social\",\"datePublished\":\"2025-02-20T01:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/\"},\"wordCount\":1452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/\",\"name\":\"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-20T01:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social - Noticias","og_description":"Cuando la gente piensa en la seguridad social, generalmente piensa en los beneficios mensuales para los aproximadamente 69 millones de jubilados, trabajadores discapacitados, dependientes y sobrevivientes que los reciben hoy. Pero la noticia de que miembros del Departamento de Eficiencia Gubernamental (DOGE) est\u00e1n buscando acceso a los sistemas de datos de la Administraci\u00f3n del Seguro [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","og_site_name":"Noticias","article_published_time":"2025-02-20T01:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/"},"author":{"name":"","@id":""},"headline":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social","datePublished":"2025-02-20T01:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/"},"wordCount":1452,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","url":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","name":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-20T01:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qu\u00e9 podr\u00eda ganar DOGE al acceder a sus datos de seguridad social","url":"http:\/\/noticiasya.com\/nacional\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/02\/19\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-20T01:03:50Z","datePublished":"2025-02-20T01:03:50Z","dateModified":"2025-02-20T01:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qu\\u00e9 podr\\u00eda ganar DOGE al acceder a sus datos de seguridad social\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/19\\\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/19\\\/que-podria-ganar-doge-acceder-datos-seguridad-social-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-20T01:03:50Z\",\"datePublished\":\"2025-02-20T01:03:50Z\",\"dateModified\":\"2025-02-20T01:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463310,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/07\/doge-datos-seguro-social-trax\/","url_meta":{"origin":1458945,"position":0},"title":"El DOGE acaba de recibir luz verde para acceder a tus datos del Seguro Social. \u00bfQu\u00e9 significa?","author":"","date":"junio 7, 2025","format":false,"excerpt":"Cuando la gente piensa en el Seguro Social, normalmente piensa en los beneficios mensuales para los aproximadamente 69 millones de jubilados, trabajadores con discapacidad, dependientes y sobrevivientes que los reciben hoy en d\u00eda.Pero los esfuerzos realizados este a\u00f1o por el Departamento de Eficiencia Gubernamental (DOGE, por sus siglas en ingl\u00e9s)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460205,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/20\/jueza-bloquea-doge-informacion-seguridad-social-trax\/","url_meta":{"origin":1458945,"position":1},"title":"Una jueza bloquea a DOGE de acceder a datos sensibles de Seguridad Social","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Una jueza federal bloque\u00f3 este jueves a la Administraci\u00f3n del Seguro Social (SSA, por sus siglas en ingl\u00e9s) de dar acceso a miembros del Departamento de Eficiencia Gubernamental (DOGE, por sus siglas en ingl\u00e9s) a datos de la agencia que contienen informaci\u00f3n personal identificable de individuos.En una contundente opini\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461908,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/02\/trump-disputa-doge-datos-seguro-social-corte-suprema-trax\/","url_meta":{"origin":1458945,"position":2},"title":"Trump lleva la disputa de DOGE sobre el acceso a los datos del Seguro Social a la Corte Suprema","author":"","date":"mayo 2, 2025","format":false,"excerpt":"El Gobierno del presidente Donald Trump inst\u00f3 este viernes a la Corte Suprema a permitir que el Departamento de Eficiencia Gubernamental (DOGE, por sus siglas en ingl\u00e9s) de Elon Musk acceda a los datos de la Administraci\u00f3n del Seguro Social (SSA, por sus siglas en ingl\u00e9s) sobre cientos de millones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463287,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/06\/corte-suprema-restablece-acceso-doge-datos-seguro-social-trax\/","url_meta":{"origin":1458945,"position":3},"title":"La Corte Suprema restablece el acceso de DOGE a datos sensibles del Seguro Social","author":"","date":"junio 6, 2025","format":false,"excerpt":"La Corte Suprema levant\u00f3 este viernes una orden de un tribunal inferior que imped\u00eda a la Administraci\u00f3n del Seguro Social otorgar acceso a datos sensibles de la agencia a afiliados del Departamento de Eficiencia Gubernamental (DOGE).El fallo, considerado una victoria para el Gobierno de Trump, permite que DOGE acceda a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461626,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/25\/doge-base-maestra-acelerar-deportaciones-trax\/","url_meta":{"origin":1458945,"position":4},"title":"El DOGE construye una base de datos maestra para aplicar la ley inmigratoria, dicen fuentes","author":"","date":"abril 25, 2025","format":false,"excerpt":"Los empleados del Departamento de Eficiencia Gubernamental (DOGE, por sus siglas en ingl\u00e9s), de Elon Musk, est\u00e1n construyendo una base de datos maestra para acelerar la aplicaci\u00f3n de la ley de inmigraci\u00f3n y las deportaciones al combinar datos sensibles de todo el Gobierno federal, seg\u00fan m\u00faltiples fuentes familiarizadas con los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462883,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/28\/juez-doge-acceso-sistemas-pago-sensibles-tesoro-trax\/","url_meta":{"origin":1458945,"position":5},"title":"Juez dictamina que DOGE puede acceder a sistemas de pago sensibles del Tesoro","author":"","date":"mayo 28, 2025","format":false,"excerpt":"El Departamento de Eficiencia Gubernamental de la administraci\u00f3n Trump ahora puede acceder a sistemas sensibles del Departamento del Tesoro que controlan billones de d\u00f3lares en pagos y contienen informaci\u00f3n privada de millones de estadounidenses, dictamin\u00f3 este martes un juez federal.La jueza de distrito estadounidense Jeannette Vargas dijo en su fallo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1458945"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458945\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1458945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1458945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1458945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}