{"id":1458954,"date":"2025-02-19T19:03:50","date_gmt":"2025-02-20T03:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/"},"modified":"2025-02-19T19:03:50","modified_gmt":"2025-02-20T03:03:50","slug":"sao-paulo-brasil-emergencia-salud-dengue-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","title":{"rendered":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue"},"content":{"rendered":"<p>El Gobierno de Sao Paulo, Brasil, declar\u00f3 este mi\u00e9rcoles emergencia de salud p\u00fablica debido a la cifra de casos de dengue registrados en el estado en lo que va del a\u00f1o.<\/p>\n<p>El Ejecutivo local inform\u00f3 en su cuenta de X y a trav\u00e9s de su agencia oficial de noticias que la declaratoria incluye medidas como un aumento de 20% a los recursos para la atenci\u00f3n de la enfermedad en hospitales, la inversi\u00f3n del equivalente a unos US$ 524.000 en equipos de fumigaci\u00f3n para combatir al mosquito <em>Aedes aegypti<\/em> \u2014principal vector transmisor del virus causante del dengue\u2014 y la adquisici\u00f3n de 32 millones de art\u00edculos \u2014como sueros y medicamentos\u2014 para ayudar a los municipios.<\/p>\n<p>Este a\u00f1o se han registrado 124.038 casos y 113 muertes por dengue, agreg\u00f3 el Gobierno. Por su parte, el Ministerio de Salud federal tiene registro del mismo n\u00famero de fallecimientos en el estado, aunque tiene contabilizados 205.163 casos.<\/p>\n<p>De acuerdo con las cifras del Ministerio, los casos en Sao Paulo son el 58% de los 352.020 registrados en todo Brasil en lo que va de 2025. En tanto, la cifra de muertes equivale al 77% del total nacional, que asciende a 146.<\/p>\n<p>En 2024, un a\u00f1o en el que <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/07\/salud\/america-dengue-alza-2024-175-73-orix\">se observ\u00f3 un incremento del dengue en Am\u00e9rica<\/a>, Brasil fue el pa\u00eds del continente con m\u00e1s casos y fallecimientos por dengue. Seg\u00fan el Ministerio, hubo 6 millones 613.730 casos y 6.216 decesos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Sao Paulo, Brasil, declar\u00f3 este mi\u00e9rcoles emergencia de salud p\u00fablica debido a la cifra de casos de dengue registrados en el estado en lo que va del a\u00f1o. El Ejecutivo local inform\u00f3 en su cuenta de X y a trav\u00e9s de su agencia oficial de noticias que la declaratoria incluye medidas como [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458954","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Sao Paulo, Brasil, declar\u00f3 este mi\u00e9rcoles emergencia de salud p\u00fablica debido a la cifra de casos de dengue registrados en el estado en lo que va del a\u00f1o. El Ejecutivo local inform\u00f3 en su cuenta de X y a trav\u00e9s de su agencia oficial de noticias que la declaratoria incluye medidas como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-20T03:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue\",\"datePublished\":\"2025-02-20T03:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/\"},\"wordCount\":262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/\",\"name\":\"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-20T03:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue - Noticias","og_description":"El Gobierno de Sao Paulo, Brasil, declar\u00f3 este mi\u00e9rcoles emergencia de salud p\u00fablica debido a la cifra de casos de dengue registrados en el estado en lo que va del a\u00f1o. El Ejecutivo local inform\u00f3 en su cuenta de X y a trav\u00e9s de su agencia oficial de noticias que la declaratoria incluye medidas como [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","og_site_name":"Noticias","article_published_time":"2025-02-20T03:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/"},"author":{"name":"","@id":""},"headline":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue","datePublished":"2025-02-20T03:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/"},"wordCount":262,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","url":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","name":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-20T03:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Sao Paulo, Brasil, declara emergencia de salud p\u00fablica por dengue","url":"http:\/\/noticiasya.com\/nacional\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/02\/19\/sao-paulo-brasil-emergencia-salud-dengue-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-20T03:03:50Z","datePublished":"2025-02-20T03:03:50Z","dateModified":"2025-02-20T03:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Sao Paulo, Brasil, declara emergencia de salud p\\u00fablica por dengue\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/19\\\/sao-paulo-brasil-emergencia-salud-dengue-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/19\\\/sao-paulo-brasil-emergencia-salud-dengue-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-20T03:03:50Z\",\"datePublished\":\"2025-02-20T03:03:50Z\",\"dateModified\":\"2025-02-20T03:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1445077,"url":"https:\/\/noticiasya.com\/nacional\/2024\/02\/08\/rio-de-janeiro-declara-emergencia-de-salud-por-dengue-mientras-brasil-se-prepara-para-el-carnaval\/","url_meta":{"origin":1458954,"position":0},"title":"R\u00edo de Janeiro declara emergencia de salud por dengue, mientras Brasil se prepara para el carnaval","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) -- El alcalde de\u00a0 R\u00edo de Janeiro, en Brasil, Eduardo Paes, declar\u00f3 el estado de emergencia de salud p\u00fablica debido a una epidemia de dengue, report\u00f3 CNN Brasil, afiliada de CNN.El aumento en los casos de dengue ocurre mientras R\u00edo de Janeiro y todo el pa\u00eds se preparan para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447503,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/28\/puerto-rico-emergencia-salud-dengue-trax\/","url_meta":{"origin":1458954,"position":1},"title":"Puerto Rico declara emergencia de salud p\u00fablica luego de m\u00e1s de 500 casos de dengue en 2024","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN) -- Puerto Rico declar\u00f3 la emergencia de salud p\u00fablica debido al creciente n\u00famero de casos de dengue.El secretario de Salud de Puerto Rico, Carlos Mellado, dijo que el departamento de salud ha registrado 549 casos de dengue en lo que va del a\u00f1o, superando con creces las cifras hist\u00f3ricas.\u201cNuestros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448289,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/19\/casos-dengue-superan-52-millones-en-america-trax\/","url_meta":{"origin":1458954,"position":2},"title":"Los casos de dengue superan los 5,2 millones en Am\u00e9rica; el brote supera el r\u00e9cord anual, advierte la OPS","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN) -- Los casos de dengue est\u00e1n aumentando en Am\u00e9rica. El n\u00famero de casos reportados esta semana superaron los 5,2 millones, por encima del r\u00e9cord anual establecido en 2023, de acuerdo con la Organizaci\u00f3n Panamericana de la Salud (OPS).Ashley Baldwin, portavoz de la OPS, le dijo a CNN el jueves\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447012,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/15\/crece-epidemia-dengue-brasil-casos-orix\/","url_meta":{"origin":1458954,"position":3},"title":"Crece la epidemia de dengue en Brasil: los casos registrados en lo que va de 2024 ya superan a los de todo 2023","author":"","date":"marzo 15, 2024","format":false,"excerpt":"(CNN) -- La epidemia de dengue aumenta en Brasil, donde el n\u00famero de casos registrados en lo que va de 2024 ya super\u00f3 el registrado durante todo 2023, de acuerdo con las cifras del Ministerio de Salud del pa\u00eds sudamericano.En las primeras 10 semanas de este a\u00f1o, el Ministerio contabiliz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446004,"url":"https:\/\/noticiasya.com\/nacional\/2024\/02\/25\/dengue-america-que-pasa-protegerse-orix\/","url_meta":{"origin":1458954,"position":4},"title":"\u00bfQu\u00e9 est\u00e1 pasando con el dengue en Am\u00e9rica y c\u00f3mo protegerse?","author":"","date":"febrero 25, 2024","format":false,"excerpt":"(CNN) -- Los casos de dengue en Am\u00e9rica han registrado un \u201caumento exponencial\u201d en 2024, por lo que los pa\u00edses deben reforzar la vigilancia, la prevenci\u00f3n y la atenci\u00f3n de las personas enfermas y las acciones de control del mosquito Aedes aegypti (principal vector transmisor), de acuerdo con la m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456350,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/07\/america-dengue-alza-2024-175-73-orix\/","url_meta":{"origin":1458954,"position":5},"title":"Am\u00e9rica suma 12,6 millones de casos de dengue en 2024, un alza de 175,73% en comparaci\u00f3n con el a\u00f1o anterior","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"A menos de un mes de que termine 2024, los casos de dengue en Am\u00e9rica suman 12.669.716, un incremento de 175,73% en comparaci\u00f3n a los que se registraron en todo 2023, de acuerdo con la plataforma de la Organizaci\u00f3n Mundial de la Salud (OMS) y la Organizaci\u00f3n Panamericana de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1458954"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458954\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1458954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1458954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1458954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}