{"id":1458955,"date":"2025-02-19T19:03:50","date_gmt":"2025-02-20T03:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/"},"modified":"2025-02-19T19:03:50","modified_gmt":"2025-02-20T03:03:50","slug":"petro-nombra-a-militar-ministro-de-defensa-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/","title":{"rendered":"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia"},"content":{"rendered":"<p>El presidente de Colombia, Gustavo Petro, anunci\u00f3 este mi\u00e9rcoles que el nuevo ministro de Defensa, en reemplazo de Iv\u00e1n Vel\u00e1squez, ser\u00e1 el general Pedro S\u00e1nchez. El alto oficial es recordado por su rol protag\u00f3nico en la b\u00fasqueda y rescate de los cuatro ni\u00f1os ind\u00edgenas que permanecieron perdidos durante 40 d\u00edas tras el accidente de una avioneta en junio de 2023, en las selvas del sur del pa\u00eds.<\/p>\n<p>\u201cLogramos resistir 30 d\u00edas con tropas en el territorio y con ind\u00edgenas en el territorio, conviviendo, y salvamos ni\u00f1os y ni\u00f1as. Mientras generales mataban ni\u00f1os en Palestina, generales salvaban ni\u00f1os en las selvas colombianas y por eso he querido que el pr\u00f3ximo ministro de la Defensa (\u2026) sea el general Pedro S\u00e1nchez\u201d, sostuvo el mandatario en un foro con gobernadores de todo el pa\u00eds en la ciudad de Villa de Leiva.<\/p>\n<p>El nombramiento, sin embargo, rompe la tradici\u00f3n por la cual ese cargo lo ocupa un civil.<\/p>\n<p>La costumbre comenz\u00f3 hace m\u00e1s de 30 a\u00f1os cuando, tras la aprobaci\u00f3n de la Constituci\u00f3n pol\u00edtica de Colombia de 1991, se inici\u00f3 la transici\u00f3n al nombramiento de ministros de Defensa civiles. El primero de ellos fue Fernando Botero en 1994, durante el Gobierno de Ernesto Samper. Desde entonces, solamente ha habido algunas excepciones cuando los generales Fredy Padilla de Le\u00f3n, en 2009, y Luis Fernando Navarro, en 2019 y 2021, ocuparon el puesto como encargados por breves per\u00edodos.<\/p>\n<p>\u201cEl general S\u00e1nchez es un militar \u00edntegro. Pero, primero, el presidente ha roto con la tradici\u00f3n civilista de que un militar activo no sea ministro de Defensa y, segundo, y muy delicado, que por cuestiones de \u00e9tica militar todos los oficiales m\u00e1s antiguos que \u00e9l o con mayor rango, seguramente se retirar\u00e1n, con lo que el pa\u00eds, en medio de la crisis de seguridad que vive, podr\u00eda perder a altos oficiales con experiencia y entrenamiento. Compleja situaci\u00f3n\u201d, sostuvo el periodista y analista de Caracol Radio, Gustavo G\u00f3mez, en su cuenta en la red social X.<\/p>\n<p>Varios analistas y expertos en temas de seguridad nacional han mostrado su preocupaci\u00f3n por este cambio en la conducci\u00f3n del ministerio de Defensa. \u201cUno de los grandes reclamos hist\u00f3ricos de la izquierda, en la que militaba <a href=\"https:\/\/x.com\/petrogustavo\">@petrogustavo<\/a>, era que el ministerio de Defensa fuera encabezado por un civil. Es una garant\u00eda de control de la fuerza p\u00fablica a la que ahora el presidente renuncia. Retroceso de tres d\u00e9cadas. En fin\u201d, sostuvo en X el analista pol\u00edtico H\u00e9ctor Riveros.<\/p>\n<p>Petro a\u00fan no se ha pronunciado p\u00fablicamente por estas cr\u00edticas. CNN solicit\u00f3 comentarios a la Presidencia de Colombia y espera respuesta.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Colombia, Gustavo Petro, anunci\u00f3 este mi\u00e9rcoles que el nuevo ministro de Defensa, en reemplazo de Iv\u00e1n Vel\u00e1squez, ser\u00e1 el general Pedro S\u00e1nchez. El alto oficial es recordado por su rol protag\u00f3nico en la b\u00fasqueda y rescate de los cuatro ni\u00f1os ind\u00edgenas que permanecieron perdidos durante 40 d\u00edas tras el accidente de una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1458955","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petro nombra a militar activo como nuevo ministro de Defensa de Colombia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Colombia, Gustavo Petro, anunci\u00f3 este mi\u00e9rcoles que el nuevo ministro de Defensa, en reemplazo de Iv\u00e1n Vel\u00e1squez, ser\u00e1 el general Pedro S\u00e1nchez. El alto oficial es recordado por su rol protag\u00f3nico en la b\u00fasqueda y rescate de los cuatro ni\u00f1os ind\u00edgenas que permanecieron perdidos durante 40 d\u00edas tras el accidente de una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-20T03:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia\",\"datePublished\":\"2025-02-20T03:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/\"},\"wordCount\":491,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/\",\"name\":\"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-02-20T03:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia - Noticias","og_description":"El presidente de Colombia, Gustavo Petro, anunci\u00f3 este mi\u00e9rcoles que el nuevo ministro de Defensa, en reemplazo de Iv\u00e1n Vel\u00e1squez, ser\u00e1 el general Pedro S\u00e1nchez. El alto oficial es recordado por su rol protag\u00f3nico en la b\u00fasqueda y rescate de los cuatro ni\u00f1os ind\u00edgenas que permanecieron perdidos durante 40 d\u00edas tras el accidente de una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/","og_site_name":"Noticias","article_published_time":"2025-02-20T03:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/"},"author":{"name":"","@id":""},"headline":"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia","datePublished":"2025-02-20T03:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/"},"wordCount":491,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/","url":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/","name":"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-02-20T03:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia","url":"http:\/\/noticiasya.com\/nacional\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/02\/19\/petro-nombra-a-militar-ministro-de-defensa-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-02-20T03:03:50Z","datePublished":"2025-02-20T03:03:50Z","dateModified":"2025-02-20T03:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Petro nombra a militar activo como nuevo ministro de Defensa de Colombia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/19\\\/petro-nombra-a-militar-ministro-de-defensa-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/02\\\/19\\\/petro-nombra-a-militar-ministro-de-defensa-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-02-20T03:03:50Z\",\"datePublished\":\"2025-02-20T03:03:50Z\",\"dateModified\":\"2025-02-20T03:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458987,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/20\/ministro-defensa-pedro-sanchez-retiro-fuerza-aerea-orix\/","url_meta":{"origin":1458955,"position":0},"title":"Ministro designado de Defensa de Colombia, Pedro S\u00e1nchez, anuncia retiro de la Fuerza A\u00e9rea para asumir el cargo como civil","author":"","date":"febrero 20, 2025","format":false,"excerpt":"El ministro designado de Defensa de Colombia, Pedro S\u00e1nchez, anunci\u00f3 este jueves que inici\u00f3 el proceso de retiro de la Fuerza A\u00e9rea, donde ostentaba el rango de general, para asumir el cargo preservando su \u201cnaturaleza civil\u201d, algo que hab\u00eda despertado preocupaci\u00f3n de varios expertos en seguridad nacional.\u201cAcabo de radicar la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459038,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/21\/pedro-sanchez-ministro-defensa-colombia-orix\/","url_meta":{"origin":1458955,"position":1},"title":"Qui\u00e9n es Pedro S\u00e1nchez, ministro de Defensa designado de Colombia y por qu\u00e9 fue su nombramiento caus\u00f3 pol\u00e9mica","author":"","date":"febrero 21, 2025","format":false,"excerpt":"Pedro Arnulfo S\u00e1nchez, quien hasta este jueves era brigadier general activo de la Fuerza A\u00e9rea de Colombia, ser\u00e1 el nuevo ministro de Defensa, seg\u00fan la instrucci\u00f3n del mi\u00e9rcoles del presidente Gustavo Petro. S\u00e1nchez, reconocido por liderar el rescate de cuatro menores ind\u00edgenas desaparecidos en la selva durante 40 d\u00edas tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468230,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/11\/petro-lanza-operativo-ivan-mordisco-orix\/","url_meta":{"origin":1458955,"position":2},"title":"Petro lanza una ofensiva militar contra alias &#171;Iv\u00e1n Mordisco&#187;","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, anunci\u00f3 este lunes que orden\u00f3 \u201cuna ofensiva militar en el Guaviare\u201d, zona selv\u00e1tica del sureste del pa\u00eds, contra alias \u201cIv\u00e1n Mordisco\u201d, jefe de las disidencias de las FARC.\u201cOfensiva militar contra Iv\u00e1n Mordisco en el Guaviare. He ordenado el bombardeo y la disoluci\u00f3n militar del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462666,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/21\/colombia-lyan-hortua-secuestrado-liberacion-farc-orix\/","url_meta":{"origin":1458955,"position":3},"title":"Liberan en Colombia al ni\u00f1o Lyan Hort\u00faa, presuntamente secuestrado por disidencias de las FARC","author":"","date":"mayo 21, 2025","format":false,"excerpt":"El ni\u00f1o Lyan Hort\u00faa, quien presuntamente fue secuestrado el 3 de mayo en el municipio de Jamund\u00ed por disidencias de la guerrilla de las Fuerzas Armadas Revolucionarias de Colombia (FARC), fue liberado este mi\u00e9rcoles y se encuentra bien, inform\u00f3 la Defensor\u00eda del Pueblo del pa\u00eds sudamericano.El menor, de 11 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460475,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/26\/ataque-explosivos-motocicleta-cauca-colombia-orix\/","url_meta":{"origin":1458955,"position":4},"title":"Un ataque con explosivos en una motocicleta deja 11 heridos en el Cauca, Colombia","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Un ataque con explosivos instalados en una motocicleta dej\u00f3 heridas a 11 personas en el departamento del Cauca, en el suroccidente de Colombia, inform\u00f3 este mi\u00e9rcoles la Polic\u00eda Nacional del pa\u00eds sudamericano.De los 11 heridos, 10 son civiles y el otro es un polic\u00eda, dijo la instituci\u00f3n en un reporte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468313,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/13\/petro-bombardeo-disidencias-farc-frontera-venezuela-orix\/","url_meta":{"origin":1458955,"position":5},"title":"Petro ordena bombardeo contra un jefe de las disidencias de las FARC en la frontera con Venezuela","author":"","date":"noviembre 13, 2025","format":false,"excerpt":"Las Fuerzas Militares de Colombia realizaron este jueves un bombardeo en el departamento de Arauca, ubicado en la frontera con Venezuela, contra un grupo de disidentes de las Fuerzas Armadas Revolucionarias de Colombia (FARC) bajo el mando de alias \u201cIv\u00e1n Mordisco\u201d, en una operaci\u00f3n ordenada por el presidente Gustavo Petro.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1458955"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1458955\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1458955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1458955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1458955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}