{"id":1464966,"date":"2025-07-30T05:03:43","date_gmt":"2025-07-30T12:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/"},"modified":"2025-07-30T05:03:43","modified_gmt":"2025-07-30T12:03:43","slug":"tsunami-que-hacer-durante-despues-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/","title":{"rendered":"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami?"},"content":{"rendered":"<p><strong>(CNN) \u2013<\/strong> Comienza con un sonido rugiente, no muy diferente al de un tren de carga o al de un Boeing 747 al despegar.<\/p>\n<p>Luego, un muro de agua, con una fuerza inimaginable, capaz de derribar un edificio entero en segundos.<\/p>\n<p>Si sobrevives al golpe inicial, ahora te enfrentas a un implacable embate de ola tras ola, y como en una m\u00e1quina de pinball, eres golpeado por escombros, \u00e1rboles arrancados de ra\u00edz y autom\u00f3viles que comparten la misma trayectoria violenta que t\u00fa.<\/p>\n<p>Quienes han vivido un tsunami describen una situaci\u00f3n casi insuperable.<\/p>\n<p>\u201cLa primera ola parec\u00eda como una pared blanca que ven\u00eda hacia ti, y el sonido\u2026 eran solo gritos por todas partes y el sonido de un choque\u2026 el agua segu\u00eda llegando y llegando\u201d, <a href=\"http:\/\/www.cnn.com\/2004\/WORLD\/asiapcf\/12\/29\/tsunami.survivors\/index.html?eref=sitesearch\">dijo a CNN un sobreviviente de un tsunami.<\/a><\/p>\n<p>Entonces, \u00bfc\u00f3mo sobreviven las personas a una de las fuerzas m\u00e1s letales de la Madre Naturaleza?<\/p>\n<p>Los tsunamis son olas gigantes provocadas por cualquier cosa que altere el oc\u00e9ano, incluidos terremotos o erupciones volc\u00e1nicas bajo el mar, por lo que la primera se\u00f1al puede ser un temblor de la Tierra o un r\u00e1pido ascenso o descenso de las aguas del oc\u00e9ano.<\/p>\n<p>No esperes una advertencia. Corre.<\/p>\n<p>Para las personas que viven en zonas costeras bajas, un tsunami podr\u00eda llegar apenas minutos despu\u00e9s de un terremoto, demasiado r\u00e1pido para que se difundan las advertencias oficiales.<\/p>\n<p>\u201cDe manera similar a la marejada cicl\u00f3nica de un hurac\u00e1n, si est\u00e1s en la playa cuando llega un tsunami, no sobrevivir\u00edas\u201d, dijo el meteor\u00f3logo de CNN Brandon Miller.<\/p>\n<p>La fuerza del agua, as\u00ed como todas las turbulencias y corrientes internas, ser\u00eda demasiado fuerte. Un tsunami de 1,8 a 3 metros, aunque no parezca enorme, ser\u00eda extremadamente da\u00f1ino y podr\u00eda alcanzar grandes distancias, dependiendo de la elevaci\u00f3n de la costa, dijo Miller.<\/p>\n<p>A veces puede ser imposible evitar un tsunami.<\/p>\n<p>Si est\u00e1 atrapado o no puede evacuar a un terreno m\u00e1s alto, el siguiente paso es encontrar un refugio vertical resistente.<\/p>\n<p>Esto no es ideal ya que la propia estructura podr\u00eda colapsar, pero si es su \u00fanica opci\u00f3n, dir\u00edjase al punto m\u00e1s alto posible.<\/p>\n<p>En \u00e1reas con mayor amenaza de tsunami, es posible que vea edificios o rutas de escape marcados con el s\u00edmbolo internacional de tsunami; s\u00edgalos.<\/p>\n<p>Si usted es arrastrado por una corriente turbulenta, lo mejor que puede hacer es aferrarse a algo que flote, como una puerta o el tronco de un \u00e1rbol.<\/p>\n<p>\u201cMe salv\u00e9 agarr\u00e1ndome al techo, pero mi esposa fue arrastrada\u201d, <a href=\"http:\/\/www.cnn.com\/2011\/WORLD\/asiapcf\/03\/13\/japan.rescues\/\">dijo un hombre<\/a> que sobrevivi\u00f3 al mortal tsunami de 2011 en Jap\u00f3n.<\/p>\n<p>No regrese a las zonas costeras hasta que las autoridades declaren que la amenaza de tsunami ha terminado.<\/p>\n<p>Preste mucha atenci\u00f3n a su sistema de alerta local (anuncios de radio, sitios web oficiales, cuentas de redes sociales y alertas de emergencia de tel\u00e9fonos celulares) y siga los consejos.<\/p>\n<p>Los tsunamis pueden durar horas, as\u00ed que use el sentido com\u00fan.<\/p>\n<p>Durante el tsunami del oc\u00e9ano \u00cdndico de 2004, el m\u00e1s devastador registrado, muchas personas murieron cuando regresaron a la playa para ver c\u00f3mo el oc\u00e9ano se retiraba y dejaba al descubierto el lecho marino.<\/p>\n<p>Un oc\u00e9ano que retrocede r\u00e1pidamente es un fen\u00f3meno que generalmente precede a una ola asesina, seg\u00fan <a href=\"http:\/\/tsunami.noaa.gov\/\">la NOAA<\/a>.<\/p>\n<p>Revise si usted y los dem\u00e1s est\u00e1n lesionados. Brinde primeros auxilios a las personas lesionadas o atrapadas, ya que podr\u00eda encontrarse en una zona temporalmente inaccesible para la asistencia de emergencia.<\/p>\n<p>No vuelva a entrar a los edificios hasta que se haya comprobado su integridad estructural. Las aguas de un tsunami, al igual que las inundaciones, pueden socavar los cimientos de un edificio y provocar grietas en los pisos o el derrumbe de las paredes.<\/p>\n<p>Los cad\u00e1veres, las tuber\u00edas de alcantarillado destruidas, los suministros de agua dulce contaminados y los cables el\u00e9ctricos ca\u00eddos crean los mayores riesgos para la salud mucho despu\u00e9s de que retrocedan las aguas del tsunami.<\/p>\n<p>Siempre es una buena idea estar equipado para cualquier desastre con un plan de evacuaci\u00f3n para usted y su familia y un <a href=\"http:\/\/www.redcross.org\/get-help\/prepare-for-emergencies\/be-red-cross-ready\/get-a-kit\">kit de preparaci\u00f3n para emergencias<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013 Comienza con un sonido rugiente, no muy diferente al de un tren de carga o al de un Boeing 747 al despegar. Luego, un muro de agua, con una fuerza inimaginable, capaz de derribar un edificio entero en segundos. Si sobrevives al golpe inicial, ahora te enfrentas a un implacable embate de ola [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464966","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013 Comienza con un sonido rugiente, no muy diferente al de un tren de carga o al de un Boeing 747 al despegar. Luego, un muro de agua, con una fuerza inimaginable, capaz de derribar un edificio entero en segundos. Si sobrevives al golpe inicial, ahora te enfrentas a un implacable embate de ola [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T12:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami?\",\"datePublished\":\"2025-07-30T12:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/\"},\"wordCount\":747,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/\",\"name\":\"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-30T12:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami? - Noticias","og_description":"(CNN) \u2013 Comienza con un sonido rugiente, no muy diferente al de un tren de carga o al de un Boeing 747 al despegar. Luego, un muro de agua, con una fuerza inimaginable, capaz de derribar un edificio entero en segundos. Si sobrevives al golpe inicial, ahora te enfrentas a un implacable embate de ola [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-30T12:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami?","datePublished":"2025-07-30T12:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/"},"wordCount":747,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/","name":"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-30T12:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 hacer durante y despu\u00e9s de un tsunami?","url":"http:\/\/noticiasya.com\/nacional\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/07\/30\/tsunami-que-hacer-durante-despues-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-30T12:03:43Z","datePublished":"2025-07-30T12:03:43Z","dateModified":"2025-07-30T12:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 hacer durante y despu\\u00e9s de un tsunami?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/30\\\/tsunami-que-hacer-durante-despues-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/30\\\/tsunami-que-hacer-durante-despues-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-30T12:03:43Z\",\"datePublished\":\"2025-07-30T12:03:43Z\",\"dateModified\":\"2025-07-30T12:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1443004,"url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/01\/que-es-un-tsunami-y-por-que-puede-ser-tan-peligroso\/","url_meta":{"origin":1464966,"position":0},"title":"\u00bfQu\u00e9 es un tsunami y por qu\u00e9 puede ser tan peligroso?","author":"","date":"enero 1, 2024","format":false,"excerpt":"(CNN) -- Los tsunamis se forman por un desplazamiento de agua causado por un deslizamiento de tierra, un terremoto, una erupci\u00f3n volc\u00e1nica o un deslizamiento del l\u00edmite entre dos de las placas tect\u00f3nicas de la tierra (que son placas de roca de 15 a 200 metros de espesor que apoyan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456299,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/05\/sismo-magnitud-7-0-norte-california-trax\/","url_meta":{"origin":1464966,"position":1},"title":"Fuerte sismo de magnitud 7,0 sacude el norte de California","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"Se emitieron advertencias de tsunami para partes de las costas del norte de California y Oregon despu\u00e9s de que un sismo de magnitud 7,0 sacudiera la costa de California.El sismo ocurri\u00f3 a las 10:44 a.m. PT a unos 96,5 kil\u00f3metros al suroeste de Ferndale, California, de acuerdo con el Servicio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455481,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/31\/vecinos-valencia-rehacen-vidas-tras-dana-orix\/","url_meta":{"origin":1464966,"position":2},"title":"Vecinos de Valencia rehacen sus vidas tras el paso de la DANA: &#171;Vi una ola de fango, como un tsunami\u201d","author":"","date":"octubre 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Han pasado casi 48 horas desde que el r\u00edo Magro, afluente del r\u00edo J\u00facar, desbordara en varios puntos de su recorrido debido a las lluvias torrenciales que han azotado la provincia de Valencia.En Utiel, una de las localidades que m\u00e1s han sufrido la crecida descomunal del cauce,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464960,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/29\/alertas-tsunami-terremoto-costa-oriental-rusia-trax\/","url_meta":{"origin":1464966,"position":3},"title":"Activan alertas de tsunami para partes de Rusia y Jap\u00f3n tras un fuerte sismo","author":"","date":"julio 29, 2025","format":false,"excerpt":"Se emitieron alertas de tsunami para partes de Rusia y Jap\u00f3n tras un enorme terremoto de magnitud 8,7 que sacudi\u00f3 el mi\u00e9rcoles la remota y escasamente poblada costa oriental de Rusia.El sismo ocurri\u00f3 a unos 136 kil\u00f3metros de Petropavlovsk-Kamchatsky, Rusia, a una profundidad de 19 kil\u00f3metros, de acuerdo con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451509,"url":"https:\/\/noticiasya.com\/nacional\/2024\/07\/30\/foto-surf-gabriel-medina-ola-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1464966,"position":4},"title":"La foto viral del surfista brasile\u00f1o Gabriel Medina tras un (casi) 10 perfecto en los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN) -- Fue una celebraci\u00f3n para la posteridad, o al menos para la fama viral.El surfista brasile\u00f1o Gabriel Medina se enfrentaba al japon\u00e9s Kanoa Igarashi, el hombre que lo hab\u00eda vencido en los Juegos Ol\u00edmpicos de Tokio, y buscaba que esta vez la historia fuera diferente.El brasile\u00f1o no solo consigui\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464118,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/01\/torre-eiffel-cerrada-calor-temperaturas-europa-trax\/","url_meta":{"origin":1464966,"position":5},"title":"La Torre Eiffel est\u00e1 cerrada a los turistas por el calor mientras las altas temperaturas azotan a Europa","author":"","date":"julio 1, 2025","format":false,"excerpt":"Una ola de calor en el mar Mediterr\u00e1neo se est\u00e1 combinando con una poderosa c\u00fapula de altas temperaturas que hacen que Europa est\u00e9 sofocada.Es un patr\u00f3n que aparece con frecuencia a medida que el planeta se calienta: la influencia de las olas de calor marinas del Mediterr\u00e1neo ha sido m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1464966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1464966"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1464966\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1464966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1464966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1464966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}