{"id":1464971,"date":"2025-07-30T09:03:49","date_gmt":"2025-07-30T16:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/"},"modified":"2025-07-30T09:03:49","modified_gmt":"2025-07-30T16:03:49","slug":"largo-expediente-historias-falsas-donald-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/","title":{"rendered":"El largo expediente de historias falsas de Donald Trump"},"content":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fx.com%2Fatrupar%2Fstatus%2F1949824210173313371&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921345862%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=TIctoar4kqiM0ZOgYqwg%2Fgd8vCLvRhy3T0hEXzOMZvk%3D&#038;reserved=0\">cont\u00f3 el lunes una historia<\/a> sobre c\u00f3mo \u201chizo una predicci\u00f3n correcta\u201d sobre el resultado del refer\u00e9ndum del brexit, de 2016, en el Reino Unido, mientras visitaba su campo de golf en Escocia \u201cel d\u00eda antes de la votaci\u00f3n\u201d.<\/p>\n<p>\u201c\u00bfRecuerdan?\u201d, les pregunt\u00f3 a los periodistas.<\/p>\n<p>No pod\u00edan recordarlo. No sucedi\u00f3.<\/p>\n<p>En realidad, Trump visit\u00f3 Escocia <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2016%2F06%2F24%2Fpolitics%2Fdonald-trump-scotland-news-conference&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921367213%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=lY5zHpaRwXllILPuFJYBI1f%2BKfqQS6smdhThNJi5ROA%3D&#038;reserved=0\">el d\u00eda despu\u00e9s<\/a> del refer\u00e9ndum del brexit, <a href=\"https:\/\/www.nytimes.com\/2025\/07\/26\/world\/europe\/trump-brexit-scotland-uk.html\">no el d\u00eda antes<\/a>. Y aunque <a href=\"https:\/\/www.cnbc.com\/2016\/03\/24\/trump-migration-craziness-will-push-uk-out-of-eu.html\">s\u00ed dijo<\/a>, unos tres meses antes, que pensaba que el Reino Unido finalmente saldr\u00eda de la Uni\u00f3n Europea, no hizo predicciones p\u00fablicas en una <a href=\"https:\/\/www.foxbusiness.com\/politics\/trump-u-k-should-get-out-of-eu\">entrevista<\/a> el d\u00eda antes de la votaci\u00f3n; dijo que personalmente estaba a favor del brexit, pero tambi\u00e9n que \u201cno creo que nadie deba escucharme porque realmente no me he centrado mucho en eso\u201d.<\/p>\n<p>La historia imaginaria de Trump sobre estos eventos de hace nueve a\u00f1os podr\u00eda considerarse trivial en comparaci\u00f3n con sus mentiras sobre temas urgentes como <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/23\/eeuu\/cnn-verifica-afirmaciones-falsas-trump-inflacion-trax\">la inflaci\u00f3n<\/a> y <a href=\"https:\/\/www.cnn.com\/2025\/06\/16\/politics\/g7-trump-lies-canada-ukraine\">la guerra en Ucrania<\/a>. Pero es parte de un patr\u00f3n: una <a href=\"https:\/\/www.cnn.com\/videos\/politics\/2020\/09\/18\/trump-rewrites-covid-19-history-facts-first-vf-dp-orig.cnn\">larga<\/a> <a href=\"https:\/\/www.cnn.com\/2024\/06\/02\/politics\/fact-check-trump-false-claim-lock-up-hillary-clinton\/index.html\">serie<\/a> de relatos igualmente fabricados del presidente sobre su propia historia y la historia mundial.<\/p>\n<p>Y el patr\u00f3n tiene un prop\u00f3sito. Las historias de Trump buscan exagerar su visi\u00f3n y conocimiento sobre asuntos nacionales y extranjeros, embellecer su biograf\u00eda y su historial en el cargo, y minimizar a sus oponentes pol\u00edticos.<\/p>\n<p>Las historias suelen ser coloridas aunque sean falsas. La ficci\u00f3n hist\u00f3rica de Trump est\u00e1 salpicada de detalles v\u00edvidos y citas inventadas, todo para hacerlas parecer aut\u00e9nticas y lograr que queden grabadas en la mente de los votantes.<\/p>\n<p>Un funcionario de la Casa Blanca, que respondi\u00f3 a las preguntas de CNN bajo condici\u00f3n de anonimato, se\u00f1al\u00f3 que Trump predijo correctamente el brexit y luego dijo: \u201c\u00c9l estaba en Escocia antes de la votaci\u00f3n\u201d. El funcionario no reconoci\u00f3 que, contrariamente a lo que Trump afirm\u00f3 el lunes y ha asegurado durante a\u00f1os, \u00e9l no estaba all\u00ed el d\u00eda antes de la votaci\u00f3n del brexit y no hizo una predicci\u00f3n ese d\u00eda.<\/p>\n<p>Aqu\u00ed hay una verificaci\u00f3n de hechos de otros ocho ejemplos de historias falsas de Trump sobre el pasado, tan solo en los \u00faltimos dos meses:<\/p>\n<ul>\n<li>Su afirmaci\u00f3n falsa de que emiti\u00f3 una advertencia de \u201cno entren\u201d contra la invasi\u00f3n de Iraq de 2003.<\/li>\n<li>Su historia falsa sobre una supuesta conversaci\u00f3n con su difunto t\u00edo sobre el <em>Unabomber<\/em>.<\/li>\n<li>Su afirmaci\u00f3n falsa de que fue la persona que despleg\u00f3 la Guardia Nacional durante los disturbios civiles en Minneapolis, en 2020.<\/li>\n<li>Su afirmaci\u00f3n falsa de que firm\u00f3 una ley, en 2020, para imponer sentencias autom\u00e1ticas de 10 a\u00f1os de prisi\u00f3n a personas que da\u00f1en monumentos.<\/li>\n<li>Su afirmaci\u00f3n falsa de que estaba siendo sarc\u00e1stico cuando prometi\u00f3 repetidamente poner fin a la guerra de Rusia en Ucrania dentro de las 24 horas posteriores a su regreso al cargo.<\/li>\n<li>Su afirmaci\u00f3n falsa de que la Uni\u00f3n Europea fue creada para aprovecharse de Estados Unidos.<\/li>\n<li>Su afirmaci\u00f3n falsa de que los aranceles se impusieron solo despu\u00e9s de la Gran Depresi\u00f3n, y no durante ella.<\/li>\n<li>Su afirmaci\u00f3n falsa de que Corea del Sur convenci\u00f3 al expresidente de EE.UU. Joe Biden de permitirle dejar de hacer cualquier pago para compartir el costo de la presencia militar estadounidense all\u00ed.<\/li>\n<\/ul>\n<p>Trump, promocionando su destreza en pol\u00edtica exterior, ha estado afirmando falsamente <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2019%2F10%2F29%2Fpolitics%2Ffact-check-trump-false-claim-opposed-iraq-invasion&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921670200%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=6TI4Lu6GXapjyLXc%2BxM1D2AGvZ1HAOt%2BLRoh%2F3bvtAQ%3D&#038;reserved=0\">durante a\u00f1os<\/a> que advirti\u00f3 de manera p\u00fablica a Estados Unidos de no invadir Iraq en 2003. <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-press-gaggle-after-air-force-one-arrival-june-20-2025%2F%2316&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921683847%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=66oFs3ipD%2Bq%2FJOoLOaIw%2BLvGsfVhcPOaH03YwxR2%2BcU%3D&#038;reserved=0\">Lo volvi\u00f3 a hacer<\/a> en comentarios a periodistas en junio: \u201cLo dije fuerte y claro, pero era un civil, aunque supongo que recib\u00ed mucha publicidad, pero me opon\u00eda mucho a la guerra de Iraq. Y de hecho dije: \u2018No entren, no entren, no entren\u2019. Pero dije: \u2018Si van a entrar, qu\u00e9dense con el petr\u00f3leo\u2019. Pero no lo hicieron\u201d.<\/p>\n<p>Palabras muy firmes. Excepto que Trump no las pronunci\u00f3.<\/p>\n<p><a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2019%2F10%2F29%2Fpolitics%2Ffact-check-trump-false-claim-opposed-iraq-invasion%2Findex.html&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921697365%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=3SeXObE7%2BuVtAyonh2FQh65CozUOI61gElzTJ7L3faU%3D&#038;reserved=0\">No hay constancia<\/a> de que Trump haya emitido ninguna advertencia p\u00fablica de este tipo antes de la invasi\u00f3n de 2003. Cuando el locutor de radio <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Ffactba.se%2Ftranscript%2Fdonald-trump-interview-howard-stern-show-september-11-2002&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921710919%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=8a6TMuwveKP9w3YvT%2BgerMMNibzP2L8vQHWvWzUiVNY%3D&#038;reserved=0\">Howard Stern le pregunt\u00f3 a Trump, en septiembre de 2002<\/a>, si estaba \u201ca favor de invadir Iraq\u201d, Trump dijo: \u201cS\u00ed, creo que s\u00ed. Ojal\u00e1 la primera vez se hubiera hecho correctamente\u201d. Trump no expres\u00f3 una opini\u00f3n firme sobre la guerra en <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Ffactba.se%2Ftranscript%2Fdonald-trump-interview-fox-neil-cavuto-january-28-2003&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921724116%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=XoKVLAoWah%2FK23aoLDDvL%2B7mfBOwicuCfiVd9UqMeog%3D&#038;reserved=0\">una entrevista en Fox, en enero de 2003<\/a>, diciendo que \u201co atacas o no atacas\u201d y que el entonces presidente George W. Bush \u201ctiene que hacer algo o no hacer nada, tal vez\u201d.<\/p>\n<p>Trump comenz\u00f3 a expresar p\u00fablicamente pensamientos cr\u00edticos sobre la guerra poco despu\u00e9s de que comenzara, en 2003, y luego se convirti\u00f3 en un opositor expl\u00edcito, en 2004. De hecho, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.esquire.com%2Fnews-politics%2Fvideos%2Fa47684%2Ftrump-iraq-war%2F&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921738254%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=MusXM%2F8gzRMl3FKKGJmwSV3rcd8BLlzfbCo59p7bHD8%3D&#038;reserved=0\">recibi\u00f3 bastante<\/a> publicidad por ese comentario, pero fue una cr\u00edtica posterior a la invasi\u00f3n, no una cr\u00edtica previa, como \u00e9l sigue diciendo que fue.<\/p>\n<p>Al pregunt\u00e1rsele sobre esta afirmaci\u00f3n falsa, el funcionario de la Casa Blanca respondi\u00f3: \u201cDijo que estaba en contra\u201d. Sin embargo, Trump fue m\u00e1s all\u00e1 que simplemente afirmar que estaba en contra de la invasi\u00f3n; asegur\u00f3 haber realizado comentarios p\u00fablicos espec\u00edficos antes de la invasi\u00f3n que en realidad nunca hizo.<\/p>\n<p>Trump <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-speech-campaign-rally-gastonia-north-carolina-november-2-2024%2F%23138&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921765621%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=E4cyHfR2Jiygg6FeqXt2EEzy%2FUR3tlkqLeVjjw5dTwc%3D&#038;reserved=0\">ha mencionado<\/a> <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-speech-political-rally-las-vegas-nevada-january-27-2024%2F%2364&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921752274%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Cq5CVrghBbTW7a5TYe05v25jm3ziw%2BUzqFa40%2Bn%2Byvg%3D&#038;reserved=0\">repetidamente<\/a> a su difunto t\u00edo John Trump, un profesor de larga trayectoria en el Instituto Tecnol\u00f3gico de Massachusetts (MIT, por sus siglas en ingl\u00e9s), como prueba de su propia inteligencia y sus buenos \u201c<a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-speech-political-rally-las-vegas-nevada-january-27-2024%2F%2364&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921778915%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=mUeInhIfE6prWcBkQpg4JE4Rt0790VHVASF9BSKXjEw%3D&#038;reserved=0\">genes<\/a>\u201d. En un <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-remarks-pennsylvania-energy-innovation-summit-pittsburgh-july-15-2025%2F&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921792214%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=fkeg%2FWYvjky5GIlbma8sgTiv7B6gKXHH%2BNEOkLwHILI%3D&#038;reserved=0\">evento<\/a> sobre energ\u00eda e innovaci\u00f3n antes este mes, dijo que necesitaba \u201cpresumir\u201d de la inteligencia de su t\u00edo, y luego invent\u00f3 una historia que lo relacionaba de manera v\u00edvida, pero incorrecta con el difunto terrorista <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.fbi.gov%2Fhistory%2Ffamous-cases%2Funabomber&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921805857%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=fLPg%2Fjyfg0wsvoCHpvnPoEeuuXOlh1SfwQKKMDCUiyw%3D&#038;reserved=0\"><em>Unabomber<\/em><\/a>, Theodore \u201cTed\u201d Kaczynski.<\/p>\n<p>\u201cKaczynski fue uno de sus estudiantes\u201d, dijo Trump, y luego continu\u00f3 hablando de haberle preguntado a su t\u00edo c\u00f3mo era Kaczynski. \u201cLe dije: \u2018\u00bfQu\u00e9 tipo de estudiante era, t\u00edo John?\u2019 Dr. John Trump. Le dije: \u2018\u00bfQu\u00e9 tipo de estudiante?\u2019. Y entonces \u00e9l dijo: \u2018En serio, bueno\u2019. Dijo: \u2018Correg\u00eda, iba corrigiendo a todo el mundo\u2019\u201d.<\/p>\n<p>Este supuesto intercambio no pudo haber ocurrido. Aparte de que el MIT <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F07%2F16%2Fpolitics%2Ffact-check-trump-uncle-unabomber&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921819310%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=dBRdbiHMEU91JTmUKOuunFzqOB%2FLwRnKU9tksLF9RQg%3D&#038;reserved=0\">dice<\/a> que no tiene informaci\u00f3n que sugiera que Kaczynski haya asistido alguna vez al MIT (fue a la cercana Harvard), el t\u00edo del presidente <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.nytimes.com%2F1985%2F02%2F26%2Fus%2Fjohn-trump-dies-engineer-was-78.html&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921832740%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=eHha5AepCWYgWd5m8Z77e83OnuVAEJo5zaJLhsdOoDU%3D&#038;reserved=0\">muri\u00f3 en 1985<\/a>, m\u00e1s de una d\u00e9cada antes de que Kaczynski fuera identificado p\u00fablicamente como el <em>Unabomber,<\/em> <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fabcnews.go.com%2FUS%2Funabomber-evaded-capture-20-years-americas-prolific-bomber%2Fstory%3Fid%3D58738943&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921846753%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=P8ugxgGmQJIiYAKxcDxo1iUF9Si%2BkOEQnDNeayCtqo0%3D&#038;reserved=0\">en 1996<\/a>. Dado que Kaczynski hab\u00eda vivido durante a\u00f1os como un ermita\u00f1o en la naturaleza, no hay ninguna raz\u00f3n aparente por la que Donald Trump habr\u00eda estado pregunt\u00e1ndole a alguien sobre Kaczynski en 1985 o antes.<\/p>\n<p>La Casa Blanca ni siquiera intent\u00f3 defender esta historia ni bajo condici\u00f3n de anonimato.<\/p>\n<p>Trump, atacando a un prominente oponente dem\u00f3crata, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-speech-250th-anniversary-army-fort-liberty-north-carolina-june-10-2025%2F%2360&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921860943%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=8GKk%2FnmR8Mi68lOQXP6liauUbyUUdvT265SkLeZJJvA%3D&#038;reserved=0\">les dijo a miembros de las fuerzas armadas en un discurso en Fort Bragg, en junio<\/a>, que \u201cnunca olvidar\u00e9\u201d lo que sucedi\u00f3 con el gobernador de Minnesota, Tim Walz, tras el homicidio de George Floyd, en Minneapoli,s en 2020: \u201cEsa ciudad estaba ardiendo, Minneapolis se estaba incendiando, iba a quedar arrasada, y \u00e9l no llamaba a la Guardia. Y esper\u00e9 mucho tiempo, y yo llam\u00e9 a la Guardia, y la salv\u00e9\u201d.<\/p>\n<p>Sea lo que sea que Trump recuerde, eso no es lo que pas\u00f3. En realidad, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2024%2F07%2F28%2Fpolitics%2Ffact-check-minnesota-trump-speech-national-guard&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921874591%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=xXRvWJBwMKIPG7qqo7I1Mi5sPhBKg4hJDAGt7loGJog%3D&#038;reserved=0\">Walz, no Trump, fue quien despleg\u00f3 la Guardia Nacional de Minnesota<\/a>, m\u00e1s de siete horas antes de que Trump amenazara p\u00fablicamente con desplegar la Guardia \u00e9l mismo. Si bien muchos republicanos y algunos dem\u00f3cratas criticaron a Walz por no enviar la Guardia m\u00e1s r\u00e1pido, es indiscutible que Walz, no Trump, fue quien finalmente lo hizo.<\/p>\n<p>El funcionario de la Casa Blanca dijo que Walz activ\u00f3 la Guardia \u201csolo\u201d despu\u00e9s de que Trump se lo instara. Eso es una aceptaci\u00f3n impl\u00edcita de que Trump estaba equivocado al decir que fue \u00e9l quien activ\u00f3 la Guardia, y la declaraci\u00f3n del funcionario tambi\u00e9n es incorrecta. Walz activ\u00f3 la Guardia <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2020%2F07%2F01%2Fpolitics%2Ffact-check-trump-walz-minnesota-national-guard&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921887979%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=c%2BriDFl4hjadlI%2BvxvZ8g8DsSUF0UFw8Euxq3%2FRdAso%3D&#038;reserved=0\">antes de hablar con Trump<\/a> sobre el asunto y antes de la declaraci\u00f3n p\u00fablica de Trump.<\/p>\n<p>Trump cont\u00f3 otra historia dram\u00e1tica, pero falsa, sobre su respuesta a las protestas de 2020 durante un <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-speech-salute-to-america-des-moines-iowa-july-3-2025\/#125\">discurso<\/a> en Iowa, anteriormente este mes.<\/p>\n<p>Trump dijo que, mientras los manifestantes marchaban hacia el monumento a Jefferson intentando derribar una estatua de Thomas Jefferson, \u201cfirmamos una ley\u201d \u2014\u201cuna ley antigua de 1909\u201d\u2014 que \u201cestablec\u00eda que si tan solo tocas un monumento o una estatua, vas a la c\u00e1rcel por un periodo de 10 a\u00f1os. Sin excepciones\u201d. Afirm\u00f3 que realiz\u00f3 una conferencia de prensa en medio de la marcha diciendo que cualquiera que toque un monumento \u201cva inmediatamente a la c\u00e1rcel por un periodo de 10 a\u00f1os\u201d, y entonces \u201cesa marcha se dispers\u00f3 tan r\u00e1pido\u201d.<\/p>\n<p>\u201c\u00bfRecuerdan esa noche? Fue una locura\u201d, pregunt\u00f3 Trump durante su narraci\u00f3n.<\/p>\n<p>Nadie podr\u00eda recordar esa noche porque no ocurri\u00f3. Trump <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2020%2F10%2F19%2Fpolitics%2Ffact-check-trump-dishonest-weekend-florida-michigan-georgia-wisconsin&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921918520%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=jorPbcTtWiRRcIIZntPvxSeTHwxBwpKpXJojj0J23kM%3D&#038;reserved=0\">no firm\u00f3<\/a> ninguna \u201cley\u201d sobre sanciones por da\u00f1os a monumentos, no hizo nada para imponer sentencias de c\u00e1rcel r\u00e1pidas o autom\u00e1ticas de 10 a\u00f1os a quienes da\u00f1en monumentos, y la pol\u00edtica que anunci\u00f3 en junio de 2020 no dispers\u00f3 de repente una marcha activa hacia el monumento a Jefferson.<\/p>\n<p>Lo que realmente sucedi\u00f3: Trump <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2020%2F06%2F26%2Fpolitics%2Ftrump-signs-monuments-executive-order&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921932311%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=5OXz6QUB%2Fki0pZbIs78JR6SaVG0Gr1yPJGv5w8HE3%2FM%3D&#038;reserved=0\">anunci\u00f3<\/a> que hab\u00eda emitido un <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Ftrumpwhitehouse.archives.gov%2Fpresidential-actions%2Fexecutive-order-protecting-american-monuments-memorials-statues-combating-recent-criminal-violence%2F&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921945948%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Ksve6QvcbVTCdN0QT2JRizyHZ%2FEhfcVzDSKUGTGVPOY%3D&#038;reserved=0\">decreto<\/a> que instru\u00eda al secretario de Justicia a dar prioridad a las investigaciones y procesamientos de personas que da\u00f1aran monumentos propiedad del Gobierno y a procesar a los infractores \u201cen la mayor medida posible\u201d permitida por la ley federal vigente, la cual establec\u00eda una sentencia m\u00e1xima \u2014no inmediata ni obligatoria\u2014 de 10 a\u00f1os en prisi\u00f3n. No est\u00e1 claro cu\u00e1l fue el impacto, si es que tuvo alguno, de este anuncio en las protestas que siguieron al homicidio de Floyd.<\/p>\n<p>Cuando un reportero le record\u00f3 a Trump en una <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-press-conference-nato-summit-the-hague-netherlands-june-25-2025%2F&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921959583%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=yqOyUwoODSQCnc%2B8JxAYKit9eeQXc21ZmLl4EzwNfh8%3D&#038;reserved=0\">conferencia de prensa<\/a> en junio que \u00e9l hab\u00eda prometido anteriormente terminar la guerra de Rusia contra Ucrania en \u201c24 horas\u201d, pero despu\u00e9s dijo que hablaba sarc\u00e1sticamente, Trump dijo: \u201cPor supuesto que fue sarc\u00e1stico\u201d.<\/p>\n<p>Pero claramente no fue sarc\u00e1stico. Cuando Trump afirm\u00f3 en abril que hab\u00eda hecho la promesa \u201cen broma\u201d, <a href=\"https:\/\/www.cnn.com\/2025\/04\/25\/politics\/fact-check-trump-ukraine-war\">CNN encontr\u00f3 53 ejemplos<\/a> en los que prometi\u00f3 durante la campa\u00f1a, en un tono, manera y contexto completamente serios, que pondr\u00eda fin a la guerra ya sea dentro de las 24 horas tras regresar a la Casa Blanca o incluso antes, como presidente electo.<\/p>\n<p>Cuando CNN pregunt\u00f3 a la Casa Blanca sobre esta afirmaci\u00f3n falsa, la portavoz Anna Kelly respondi\u00f3 oficialmente con un comentario que no abordaba directamente la veracidad de la declaraci\u00f3n. \u201cRusia y Ucrania est\u00e1n teniendo negociaciones directas por primera vez en a\u00f1os gracias al liderazgo del presidente Trump\u201d, dijo Kelly.<\/p>\n<p>Trump ocasionalmente ofrece lecciones sobre historia mundial para reforzar sus argumentos contempor\u00e1neos. Pero esas lecciones a veces han sido falsas. En junio, por ejemplo, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-remarks-foreign-ministers-democratic-republic-congo-rwanda-june-27-2025%2F%23234&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082921986880%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=BzfSYnkB0RUCCRHTLHSdcR5prNKnbHiP4gITvWGQHWM%3D&#038;reserved=0\">dijo<\/a> al hablar de sus negociaciones comerciales con la Uni\u00f3n Europea: \u201cLa UE fue formada para aprovecharse de Estados Unidos en el comercio. Para eso fue formada\u201d.<\/p>\n<p>Expertos en la historia de la UE han dicho anteriormente a CNN que esta afirmaci\u00f3n de Trump es \u201cabsurda\u201d y \u201cno podr\u00eda ser m\u00e1s err\u00f3nea o inexacta\u201d, se\u00f1alando que los presidentes estadounidenses apoyaron de manera continua los esfuerzos de integraci\u00f3n europea que ten\u00edan como objetivo estabilizar el continente y promover la prosperidad.<\/p>\n<p>Trump ha hecho de los aranceles una de sus herramientas pol\u00edticas distintivas. Durante una <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Frollcall.com%2Ffactbase%2Ftrump%2Ftranscript%2Fdonald-trump-remarks-cabinet-meeting-july-8-2025%2F&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082922014218%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Kc7a9q0Lsbt5rH%2FNPySL%2Bs8LI36rmtQP7d22KAWXkXU%3D&#038;reserved=0\">reuni\u00f3n del gabinete<\/a> a comienzos de este mes, los defendi\u00f3 con una historia sumamente distorsionada sobre su papel en la Gran Depresi\u00f3n, afirmando err\u00f3neamente que los aranceles se restablecieron \u201cdespu\u00e9s de la Depresi\u00f3n\u201d, no durante ella.<\/p>\n<p>Trump dijo: \u201cNo hab\u00eda un sistema de impuestos sobre la renta\u2026 en 1913, eso regres\u00f3, y funcion\u00f3 bien por un tiempo, y luego vino la Gran Depresi\u00f3n. Y despu\u00e9s intentaron restablecer los aranceles. Pero el asunto completo era, sabes, esto fue despu\u00e9s de la Depresi\u00f3n. Fue uno de los grandes conceptos err\u00f3neos como suelen decir. \u2018Oh, pero fue durante la\u2019\u2026 no. El pa\u00eds tuvo una Gran Depresi\u00f3n, y luego despu\u00e9s de la Depresi\u00f3n, despu\u00e9s, mucho despu\u00e9s de que comenzara, restablecieron los aranceles para ver si pod\u00edan salvar la situaci\u00f3n. Pero realmente les tom\u00f3 25 a\u00f1os, \u00bfno lo crees?, unos 25 a\u00f1os para salir de la Gran Depresi\u00f3n. Mucha gente no entiende eso\u201d.<\/p>\n<p>Completamente err\u00f3neo.<\/p>\n<p>Estados Unidos impuso importantes aranceles cerca del comienzo de la Gran Depresi\u00f3n, a trav\u00e9s de la <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.senate.gov%2Fartandhistory%2Fhistory%2Fminute%2FSenate_Passes_Smoot_Hawley_Tariff.htm&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082922027731%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=jV7ODk5v2mhiIDSyKK2c6w%2Fs7ks18as54Gi9bYHbLw8%3D&#038;reserved=0\">Ley de Aranceles Smoot-Hawley de 1930<\/a>; se piensa ampliamente que <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.britannica.com%2Ftopic%2FSmoot-Hawley-Tariff-Act&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082922041432%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=G1tSj%2Br7OGx5E3sni689wtBjKTdAbI0k0mIJfDxgoIo%3D&#038;reserved=0\">contribuyeron a profundizar la Depresi\u00f3n<\/a>, que comenz\u00f3 en 1929 y generalmente se considera que dur\u00f3 hasta 1939. Y aunque la historia econ\u00f3mica siempre puede debatirse, no hay base razonable para la afirmaci\u00f3n de que tom\u00f3 25 a\u00f1os \u201csalir de\u201d la Gran Depresi\u00f3n; la Segunda Guerra Mundial, de 1939 a 1945, sirvi\u00f3 como un <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fprospect.org%2Fhealth%2Fway-won-america-s-economic-breakthrough-world-war-ii%2F&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082922058715%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=RiDcmZ8DYDdYt5%2B6Y4vkP20aMyFcTM78Wpht%2FbThb7I%3D&#038;reserved=0\">gran impulso para la econom\u00eda estadounidense<\/a>.<\/p>\n<p>En la misma reuni\u00f3n del gabinete, Trump repiti\u00f3 una <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F04%2F09%2Fpolitics%2Ffact-check-biden-south-korea-trump%2Findex.html&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082922072464%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=4XAOtEfOzPnQPAHFiLRuGrf8a7%2BKvwu%2BWfebZHId098%3D&#038;reserved=0\">historia falsa<\/a> sobre c\u00f3mo supuestamente Corea del Sur persuadi\u00f3 a Biden para que le permitiera abandonar completamente los pagos que hab\u00eda estado haciendo para ayudar a cubrir el costo de la presencia militar estadounidense en Corea del Sur, diciendo: \u201c\u00bfY saben lo que hizo Biden? Probablemente fueron con \u00e9l y le dijeron: \u2018Miren, Trump nos trat\u00f3 terriblemente y no deber\u00edamos estar pagando nada\u2019, y \u00e9l lo redujo a nada\u201d.<\/p>\n<p>De hecho, la administraci\u00f3n de Biden firm\u00f3 dos acuerdos de reparto de costos con Corea del Sur, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2021%2F03%2F07%2Fpolitics%2Fus-south-korea-cost-sharing-troops%2Findex.html&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082922086402%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=1aWeyu2F1%2Fpg8ZDgXH3%2FhryKLcodq0oiWIwmmvS6l24%3D&#038;reserved=0\">uno en 2021<\/a> y <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2024%2F10%2F04%2Fpolitics%2Fus-forces-south-korea-cost-sharing-agreement%2Findex.html&#038;data=05%7C02%7Csteven.nannes%40cnn.com%7C04104c630a604fd4d4ef08ddcec88c1c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638894082922099925%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=4YOYoAKsdE%2BcgfgQvnFYpwR0%2BD5QMwvTNZN5%2BGfqHnk%3D&#038;reserved=0\">otro en 2024<\/a>, que incluyeron aumentos del gasto surcoreano; es decir, Corea del Sur acept\u00f3 dos veces pagar m\u00e1s de lo que pag\u00f3 durante el primer mandato de Trump.<\/p>\n<p>El funcionario de la Casa Blanca afirm\u00f3 que \u201cel presidente Trump tiene raz\u00f3n\u201d porque Biden negoci\u00f3 acuerdos \u201cmalos\u201d que aseguraron pagos \u201cmucho m\u00e1s bajos\u201d de los que Trump habr\u00eda conseguido. Pero esa defensa contradice la afirmaci\u00f3n falsa de Trump de que Biden acord\u00f3 permitir que no se hicieran pagos en absoluto.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, cont\u00f3 el lunes una historia sobre c\u00f3mo \u201chizo una predicci\u00f3n correcta\u201d sobre el resultado del refer\u00e9ndum del brexit, de 2016, en el Reino Unido, mientras visitaba su campo de golf en Escocia \u201cel d\u00eda antes de la votaci\u00f3n\u201d. \u201c\u00bfRecuerdan?\u201d, les pregunt\u00f3 a los periodistas. No pod\u00edan recordarlo. No [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464971","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El largo expediente de historias falsas de Donald Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El largo expediente de historias falsas de Donald Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos, Donald Trump, cont\u00f3 el lunes una historia sobre c\u00f3mo \u201chizo una predicci\u00f3n correcta\u201d sobre el resultado del refer\u00e9ndum del brexit, de 2016, en el Reino Unido, mientras visitaba su campo de golf en Escocia \u201cel d\u00eda antes de la votaci\u00f3n\u201d. \u201c\u00bfRecuerdan?\u201d, les pregunt\u00f3 a los periodistas. No pod\u00edan recordarlo. No [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T16:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El largo expediente de historias falsas de Donald Trump\",\"datePublished\":\"2025-07-30T16:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/\"},\"wordCount\":2420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/\",\"name\":\"El largo expediente de historias falsas de Donald Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-30T16:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El largo expediente de historias falsas de Donald Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El largo expediente de historias falsas de Donald Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El largo expediente de historias falsas de Donald Trump - Noticias","og_description":"El presidente de Estados Unidos, Donald Trump, cont\u00f3 el lunes una historia sobre c\u00f3mo \u201chizo una predicci\u00f3n correcta\u201d sobre el resultado del refer\u00e9ndum del brexit, de 2016, en el Reino Unido, mientras visitaba su campo de golf en Escocia \u201cel d\u00eda antes de la votaci\u00f3n\u201d. \u201c\u00bfRecuerdan?\u201d, les pregunt\u00f3 a los periodistas. No pod\u00edan recordarlo. No [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-30T16:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/"},"author":{"name":"","@id":""},"headline":"El largo expediente de historias falsas de Donald Trump","datePublished":"2025-07-30T16:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/"},"wordCount":2420,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/","name":"El largo expediente de historias falsas de Donald Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-30T16:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El largo expediente de historias falsas de Donald Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El largo expediente de historias falsas de Donald Trump","url":"http:\/\/noticiasya.com\/nacional\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/07\/30\/largo-expediente-historias-falsas-donald-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-30T16:03:49Z","datePublished":"2025-07-30T16:03:49Z","dateModified":"2025-07-30T16:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El largo expediente de historias falsas de Donald Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/30\\\/largo-expediente-historias-falsas-donald-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/30\\\/largo-expediente-historias-falsas-donald-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-30T16:03:49Z\",\"datePublished\":\"2025-07-30T16:03:49Z\",\"dateModified\":\"2025-07-30T16:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464869,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/26\/trump-escocia-golf-escandalo-epstein-trax\/","url_meta":{"origin":1464971,"position":0},"title":"Trump huye de las controversias en Washington en un viaje a Escocia con mucho golf","author":"","date":"julio 26, 2025","format":false,"excerpt":"Huyendo de la agobiante humedad de Washington y de las constantes preguntas sobre las acaloradas pol\u00e9micas, el presidente Donald Trump vuelve a refugiarse el fin de semana en sus clubes de golf, esta vez a m\u00e1s de 5.000 kil\u00f3metros de distancia, en Escocia.Aunque la Casa Blanca calific\u00f3 su viaje de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464859,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/25\/trump-niega-saber-nombre-archivos-epstein-trax\/","url_meta":{"origin":1464971,"position":1},"title":"Trump niega saber sobre su inclusi\u00f3n en los archivos de Epstein, a pesar de haber sido informado en mayo","author":"","date":"julio 25, 2025","format":false,"excerpt":"El presidente Donald Trump neg\u00f3 nuevamente que le hayan dicho que su nombre aparec\u00eda en archivos relacionados con el caso de Jeffrey Epstein, a pesar de los informes de CNN y otros medios de que la secretaria de Justicia, Pam Bondi, le inform\u00f3 sobre el asunto en mayo.\u201cNo, nunca, nunca\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459677,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/08\/hombre-bandera-palestina-big-ben-manifestantes-campo-golf-trump-trax\/","url_meta":{"origin":1464971,"position":2},"title":"Hombre con una bandera palestina escala el Big Ben de Londres luego de que manifestantes atacaran un campo de golf de Trump","author":"","date":"marzo 8, 2025","format":false,"excerpt":"Los servicios de emergencia tuvieron que acudir este s\u00e1bado al Palacio de Westminster de Londres despu\u00e9s de que un hombre que portaba una bandera palestina escalara la Torre Elizabeth, conocida popularmente como \u201cBig Ben\u201d.El hombre, que iba descalzo y vestido totalmente de negro, se aferr\u00f3 precariamente al lateral de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469308,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/16\/trump-compromiso-donald-trump-jr-bettina-anderson-trax\/","url_meta":{"origin":1464971,"position":3},"title":"Trump anuncia el compromiso de Donald Trump Jr. durante una fiesta navide\u00f1a en la Casa Blanca","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"El hijo mayor del presidente, Donald Trump Jr., est\u00e1 comprometido con la socialit\u00e9 de Palm Beach Bettina Anderson, confirm\u00f3 a CNN un portavoz de Trump Jr.El presidente Donald Trump anunci\u00f3 el compromiso la noche del lunes durante una fiesta navide\u00f1a en la Casa Blanca.El anuncio volvi\u00f3 a poner el foco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470747,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/02\/trump-criticas-grammys-epstein-y-groenlandia-trax\/","url_meta":{"origin":1464971,"position":4},"title":"Donald Trump responde a las cr\u00edticas en los Grammys sobre Epstein y Groenlandia","author":"","date":"febrero 2, 2026","format":false,"excerpt":"El presidente Donald Trump respondi\u00f3 a las cr\u00edticas del domingo por parte del presentador de los Grammy, Trevor Noah, sobre su amistad con el delincuente sexual convicto y financiero ca\u00eddo en desgracia Jeffrey Epstein.\u201cNoah dijo, INCORRECTAMENTE sobre m\u00ed, que Donald Trump y Bill Clinton pasaron tiempo en la Isla Epstein.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455055,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/12\/muere-alex-salmond-figura-movimiento-independentista-escocia-trax\/","url_meta":{"origin":1464971,"position":5},"title":"Muere a los 69 a\u00f1os Alex Salmond, figura destacada del movimiento independentista de Escocia","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN) -- El ex primer ministro de Escocia Alex Salmond muri\u00f3 a los 69 a\u00f1os, seg\u00fan declaraciones de los principales partidos pol\u00edticos de Escocia y medios de comunicaci\u00f3n del Reino Unido.Salmond enferm\u00f3 mientras estaba en Macedonia del Norte, seg\u00fan informes de los medios brit\u00e1nicos.\u201cNunca podr\u00e9 agradecerle a Alex todas sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1464971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1464971"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1464971\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1464971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1464971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1464971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}