{"id":1464984,"date":"2025-07-30T16:03:46","date_gmt":"2025-07-30T23:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/"},"modified":"2025-07-30T16:03:46","modified_gmt":"2025-07-30T23:03:46","slug":"testimonios-jurado-investigador-caso-epstein-maxwell-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/","title":{"rendered":"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades"},"content":{"rendered":"<p>Las transcripciones del jurado investigador que el Departamento de Justicia est\u00e1 pidiendo que se revelen de su investigaci\u00f3n sobre el delincuente sexual convicto Jeffrey Epstein y su asociada Ghislaine Maxwell incluyen el testimonio de solo dos testigos, ambos funcionarios encargados de hacer cumplir la ley, seg\u00fan un memorando del Departamento de Justicia presentado el martes por la noche.<\/p>\n<p>Esta revelaci\u00f3n plantea nuevas dudas sobre si el intento del Gobierno de Trump por desclasificar ese material confidencial ser\u00e1 suficiente para responder a la demanda de mayor transparencia en torno a la investigaci\u00f3n sobre Epstein.<\/p>\n<p>A comienzos de este mes, el Departamento de Justicia present\u00f3 una solicitud para desclasificar las transcripciones de los jurados investigadores en el caso de Jeffrey Epstein en Nueva York y Florida.<\/p>\n<p>La secretaria de Justicia Pam Bondi y el subsecretario de Justicia Todd Blanche presentaron personalmente la inusual petici\u00f3n, citando \u201cel inter\u00e9s p\u00fablico en el trabajo de investigaci\u00f3n realizado por el Departamento de Justicia y la Oficina Federal de Investigaciones sobre Epstein\u2026\u201d. La medida se produjo en medio de una fuerte reacci\u00f3n por el incumplimiento del Departamento a su promesa de divulgar m\u00e1s materiales relacionados con Epstein.<\/p>\n<p>La solicitud en Florida fue r\u00e1pidamente denegada, pero el juez Richard Berman en Nueva York pidi\u00f3 m\u00e1s detalles espec\u00edficos sobre por qu\u00e9 deb\u00eda divulgarse esa informaci\u00f3n antes de emitir un fallo.<\/p>\n<p>El martes por la noche, el Departamento de Justicia present\u00f3 su respuesta ante el tribunal. \u201cEn este caso, el paso del tiempo no ha disminuido el inter\u00e9s p\u00fablico en estos casos\u201d, escribi\u00f3 Jay Clayton, fiscal interino del distrito sur de Nueva York.<\/p>\n<p>El <a href=\"https:\/\/www.documentcloud.org\/documents\/26036915-doj-filing-on-epstein-grand-jury-details\/\">memorando<\/a> revel\u00f3 informaci\u00f3n hasta ahora desconocida sobre los testigos que comparecieron ante el jurado investigador.<\/p>\n<p>\u201cEn este caso, hubo un testigo \u2014un agente del FBI\u2014 durante las audiencias del jurado investigador sobre Epstein. Hubo dos testigos \u2014el mismo agente del FBI y un detective del Departamento de Polic\u00eda de Nueva York (NYPD), que era parte del grupo de trabajo sobre explotaci\u00f3n infantil y trata de personas del FBI\u2014 durante las audiencias del jurado investigador sobre Maxwell\u201d, se\u00f1al\u00f3 el documento.<\/p>\n<p>El Departamento de Justicia reiter\u00f3 que las v\u00edctimas testificaron durante el juicio, pero que ante el jurado investigador sus declaraciones fueron le\u00eddas por los investigadores.<\/p>\n<p>\u201cMuchas de las v\u00edctimas cuyas declaraciones sobre Epstein y Maxwell fueron objeto del testimonio ante el jurado investigador declararon en el juicio de forma coherente con los relatos presentados por un agente del FBI y un detective del Departamento de Polic\u00eda de Nueva York (\u2018NYPD\u2019) ante el jurado investigador, y algunas tambi\u00e9n han hecho p\u00fablicos esos relatos durante litigios civiles\u201d, escribi\u00f3 el Departamento.<\/p>\n<p>La muerte de Epstein en 2019, mientras esperaba juicio, fue catalogada como suicidio. Maxwell fue condenada en 2021 y sentenciada a 20 a\u00f1os de prisi\u00f3n. La semana pasada se reuni\u00f3 con Blanche para responder a nuevas preguntas sobre la investigaci\u00f3n, aunque se desconoce qu\u00e9 le dijo al Gobierno o c\u00f3mo podr\u00eda afectar su caso.<\/p>\n<p>El juez Berman dio plazo hasta el 5 de agosto a las v\u00edctimas y al representante de Epstein para que se pronuncien sobre la solicitud del Departamento. Indic\u00f3 que tomar\u00e1 una decisi\u00f3n \u201ccon prontitud\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las transcripciones del jurado investigador que el Departamento de Justicia est\u00e1 pidiendo que se revelen de su investigaci\u00f3n sobre el delincuente sexual convicto Jeffrey Epstein y su asociada Ghislaine Maxwell incluyen el testimonio de solo dos testigos, ambos funcionarios encargados de hacer cumplir la ley, seg\u00fan un memorando del Departamento de Justicia presentado el martes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464984","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las transcripciones del jurado investigador que el Departamento de Justicia est\u00e1 pidiendo que se revelen de su investigaci\u00f3n sobre el delincuente sexual convicto Jeffrey Epstein y su asociada Ghislaine Maxwell incluyen el testimonio de solo dos testigos, ambos funcionarios encargados de hacer cumplir la ley, seg\u00fan un memorando del Departamento de Justicia presentado el martes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T23:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades\",\"datePublished\":\"2025-07-30T23:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/\"},\"wordCount\":583,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/\",\"name\":\"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-30T23:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades - Noticias","og_description":"Las transcripciones del jurado investigador que el Departamento de Justicia est\u00e1 pidiendo que se revelen de su investigaci\u00f3n sobre el delincuente sexual convicto Jeffrey Epstein y su asociada Ghislaine Maxwell incluyen el testimonio de solo dos testigos, ambos funcionarios encargados de hacer cumplir la ley, seg\u00fan un memorando del Departamento de Justicia presentado el martes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-30T23:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/"},"author":{"name":"","@id":""},"headline":"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades","datePublished":"2025-07-30T23:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/"},"wordCount":583,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/","name":"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-30T23:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\u00fan autoridades","url":"http:\/\/noticiasya.com\/nacional\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/07\/30\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-30T23:03:46Z","datePublished":"2025-07-30T23:03:46Z","dateModified":"2025-07-30T23:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Testimonios del jurado investigador en el caso de Epstein y Maxwell incluyen solo dos testigos, seg\\u00fan autoridades\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/30\\\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/30\\\/testimonios-jurado-investigador-caso-epstein-maxwell-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-30T23:03:46Z\",\"datePublished\":\"2025-07-30T23:03:46Z\",\"dateModified\":\"2025-07-30T23:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468663,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/24\/departamento-justicia-solicitud-transcripciones-jurado-investigador-epstein-trax\/","url_meta":{"origin":1464984,"position":0},"title":"Departamento de Justicia renueva solicitud para liberar las transcripciones del jurado investigador relacionadas con Epstein","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"El Departamento de Justicia renov\u00f3 su solicitud a jueces federales en Nueva York para desclasificar las transcripciones del jurado investigador relacionadas con Jeffrey Epstein y su c\u00f3mplice Ghislaine Maxwell, tras la aprobaci\u00f3n la semana pasada de la ley que exige la publicaci\u00f3n de archivos relacionados con Epstein.Los jueces que supervisan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465387,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/11\/maxwell-jurado-investigador-trump-trax\/","url_meta":{"origin":1464984,"position":1},"title":"Juez rechaza solicitud de la administraci\u00f3n Trump para revelar material del jurado investigador en el caso Ghislaine Maxwell","author":"","date":"agosto 11, 2025","format":false,"excerpt":"Un juez federal rechaz\u00f3 la solicitud de la administraci\u00f3n Trump de desclasificar el material del jurado investigador en el caso de tr\u00e1fico sexual de Ghislaine Maxwell.El Departamento de Justicia ha solicitado que sea hagan p\u00fablicos el testimonio y las pruebas de ese jurado de los casos que involucran a Jeffrey\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465076,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/02\/casa-blanca-cobertura-caso-epstein-trax\/","url_meta":{"origin":1464984,"position":2},"title":"La Casa Blanca sigue de cerca la cobertura del caso Epstein y no logra hacer que desaparezca","author":"","date":"agosto 2, 2025","format":false,"excerpt":"El presidente Donald Trump ha suplicado a su base que deje de pensar en Jeffrey Epstein. Pero, 25 d\u00edas despu\u00e9s de que su Departamento de Justicia declarara que no ten\u00eda nada m\u00e1s que decir sobre el delincuente sexual convicto, la presi\u00f3n para que se tomen medidas contin\u00faa.Algunos funcionarios reconocen, al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469149,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/10\/juez-revelar-registros-judiciales-jeffrey-epstein-trax\/","url_meta":{"origin":1464984,"position":3},"title":"Un tercer juez federal concede una solicitud para divulgar los registros judiciales relacionados con Jeffrey Epstein","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"Un juez federal aprob\u00f3 este mi\u00e9rcoles la desclasificaci\u00f3n de documentos de la investigaci\u00f3n y el procesamiento penal del acusado de tr\u00e1fico sexual Jeffrey Epstein.La decisi\u00f3n del juez de Manhattan, Richard M. Berman, se anunci\u00f3 un d\u00eda despu\u00e9s de que otro juez de Nueva York aprobara la divulgaci\u00f3n de registros en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464865,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/25\/que-son-archivos-epstein-que-contienen-trax\/","url_meta":{"origin":1464984,"position":4},"title":"\u00bfQu\u00e9 son los archivos de Epstein y qu\u00e9 contienen? Esto sabemos","author":"","date":"julio 25, 2025","format":false,"excerpt":"Fiscales federales reunieron millones de registros durante la investigaci\u00f3n y el proceso judicial por tr\u00e1fico sexual contra Jeffrey Epstein y su c\u00f3mplice y expareja, Ghislaine Maxwell.La pregunta sobre qu\u00e9 contienen realmente esos documentos \u2014y si el p\u00fablico podr\u00e1 verlos alguna vez\u2014 se ha vuelto central en una creciente crisis de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468636,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/23\/desclasificar-testimonio-jurado-investigador-caso-epstein-florida-trax\/","url_meta":{"origin":1464984,"position":5},"title":"El Departamento de Justicia vuelve a pedir a un juez que desclasifique el testimonio del jurado investigador sobre Epstein","author":"","date":"noviembre 23, 2025","format":false,"excerpt":"El Departamento de Justicia solicit\u00f3 a un juez federal en Florida que reconsidere desclasificar los materiales del jurado investigador relacionados con una investigaci\u00f3n sobre Jeffrey Epstein, debido a que la agencia enfrenta un plazo impuesto por el Congreso para publicar todos los documentos relacionados con el acusado de tr\u00e1fico sexual\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1464984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1464984"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1464984\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1464984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1464984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1464984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}