{"id":1465012,"date":"2025-07-31T13:03:43","date_gmt":"2025-07-31T20:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/"},"modified":"2025-07-31T13:03:43","modified_gmt":"2025-07-31T20:03:43","slug":"papa-evoluciono-tomate-silvestre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/","title":{"rendered":"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos"},"content":{"rendered":"<p>La humilde papa moderna, domesticada por primera vez hace unos 10.000 a\u00f1os, surgi\u00f3 en la cordillera de Los Andes antes de convertirse en un cultivo clave del que depende el mundo. Sin embargo, debido a que las plantas no se conservan bien en el registro f\u00f3sil, su linaje ha permanecido en gran medida en el misterio.<\/p>\n<p>Ahora, un equipo de bi\u00f3logos evolutivos y cient\u00edficos gen\u00f3micos ha rastreado los or\u00edgenes de este alimento b\u00e1sico a base de almid\u00f3n hasta un encuentro casual hace millones de a\u00f1os con un pariente vegetal inesperado: el tomate.<\/p>\n<p>Los investigadores analizaron 450 genomas de especies de papas cultivadas y silvestres, y los genes revelaron que un antiguo ancestro de la planta de tomate silvestre se cruz\u00f3 naturalmente con una planta parecida a la papa llamada Etuberosum hace 9 millones de a\u00f1os o, mejor dicho, se volvi\u00f3 a encontrar, ya que ambas plantas se separaron originalmente de una planta ancestral com\u00fan hace unos 14 millones de a\u00f1os, seg\u00fan un estudio publicado este jueves en la revista <a href=\"https:\/\/www.cell.com\/cell\/fulltext\/S0092-8674(25)00736-6\">Cell<\/a>.<\/p>\n<p>Si bien ni los tomates ni los etuberosums ten\u00edan la capacidad de producir tub\u00e9rculos (la parte comestible y alargada de plantas domesticadas como la papa, el \u00f1ame y la malanga, que crecen bajo tierra), la planta h\u00edbrida resultante s\u00ed lo hizo. Los tub\u00e9rculos evolucionaron como una forma innovadora para que la planta de papa almacenara nutrientes bajo tierra a medida que el clima y el ambiente de Los Andes se volv\u00edan m\u00e1s fr\u00edos y, una vez cultivados, se convirtieron en un pilar de la dieta humana. Actualmente existen m\u00e1s de 100 especies silvestres de papa que tambi\u00e9n producen tub\u00e9rculos, aunque no todas son comestibles debido a que algunas contienen toxinas.<\/p>\n<p>\u201cLa evoluci\u00f3n de un tub\u00e9rculo otorg\u00f3 a las papas una enorme ventaja en entornos hostiles, impulsando una explosi\u00f3n de nuevas especies y contribuyendo a la rica diversidad de papas que vemos y de las que dependemos hoy\u201d, declar\u00f3 en un comunicado el coautor del estudio, Sanwen Huang, presidente de la Academia China de Ciencias Agr\u00edcolas Tropicales y profesor del Instituto de Gen\u00f3mica Agr\u00edcola de Shenzhen, perteneciente a la Academia China de Ciencias Agr\u00edcolas. \u201cPor fin hemos resuelto el misterio del origen de las papas\u201d.<\/p>\n<p>Los cient\u00edficos tambi\u00e9n han descifrado qu\u00e9 genes aport\u00f3 cada planta para la creaci\u00f3n de tub\u00e9rculos. Comprender c\u00f3mo se originaron y evolucionaron las papas podr\u00eda, en \u00faltima instancia, ayudar a los cient\u00edficos a desarrollar papas m\u00e1s resilientes, resistentes a enfermedades y a las condiciones clim\u00e1ticas cambiantes.<\/p>\n<p>Las papas, los tomates y los etuberosum pertenecen al g\u00e9nero Solanum, que incluye unas 1.500 especies y es el g\u00e9nero m\u00e1s grande de la familia de las solan\u00e1ceas. A simple vista, las plantas de papa parecen casi id\u00e9nticas a las etuberosum, lo que inicialmente llev\u00f3 a los cient\u00edficos a pensar que eran hermanas con un ancestro com\u00fan, seg\u00fan el coautor del estudio JianQuan Liu, profesor de la Facultad de Ecolog\u00eda de la Universidad de Lanzhou en Gansu, China.<\/p>\n<p>Los etuberosums incluyen solo tres especies y, si bien las plantas tienen flores y hojas similares a las de las plantas de papa, no producen tub\u00e9rculos.<\/p>\n<p>\u201cLos etuberosums son algo especial\u201d, declar\u00f3 a CNN la Dra. Sandy Knapp, coautora del estudio y bot\u00e1nica investigadora del Museo de Historia Natural de Londres. \u201cSon especies que probablemente nunca ver\u00edas a menos que fueras a las islas Juan Fern\u00e1ndez, las islas Robinson Crusoe en medio del Pac\u00edfico, o si estuvieras en la selva tropical de Chile\u201d.<\/p>\n<p>Pero al trazar el linaje de las papas, los tomates y los etuberosums se revel\u00f3 un giro inesperado que parec\u00eda indicar que las papas estaban m\u00e1s estrechamente relacionadas con los tomates a nivel gen\u00e9tico, dijo Knapp.<\/p>\n<p>El equipo utiliz\u00f3 an\u00e1lisis filogen\u00e9ticos \u2014un proceso similar a determinar en los humanos una relaci\u00f3n padre-hija o hermana-hermana a nivel gen\u00e9tico\u2014 para determinar las relaciones entre las diferentes plantas, dijo Liu.<\/p>\n<p>El an\u00e1lisis mostr\u00f3 una contradicci\u00f3n: las papas podr\u00edan ser hermanas de los etuberosums o de los tomates, dependiendo de diferentes marcadores gen\u00e9ticos, dijo Liu.<\/p>\n<p>El ancestro com\u00fan de 14 millones de a\u00f1os de los tomates y los etuberosums, y las plantas que se derivaron de \u00e9l, ya no existen y se perdieron en la noche de los tiempos geol\u00f3gicos, afirm\u00f3 Knapp. En su lugar, los investigadores buscaron marcadores gen\u00e9ticos en las plantas para determinar su origen.<\/p>\n<p>\u201cLo que utilizamos es una se\u00f1al que viene del pasado, que todav\u00eda est\u00e1 en las plantas que tenemos hoy, para intentar reconstruir el pasado\u201d, dijo Knapp.<\/p>\n<p>Para rastrear esa se\u00f1al a trav\u00e9s del tiempo, los investigadores compilaron una base de datos gen\u00e9tica de papas, incluyendo el an\u00e1lisis de espec\u00edmenes de museos e, incluso, la recuperaci\u00f3n de datos de papas silvestres raras que son dif\u00edciles de encontrar, algunas de las cuales se encuentran en un solo valle en Los Andes, dijo Knapp.<\/p>\n<p>\u201cLas papas silvestres son muy dif\u00edciles de muestrear, por lo que este conjunto de datos representa la colecci\u00f3n m\u00e1s completa de datos gen\u00f3micos de papas silvestres jam\u00e1s analizada\u201d, dijo en un comunicado el coautor del estudio Zhiyang Zhang, investigador del Instituto de Gen\u00f3mica Agr\u00edcola de Shenzhen en la Academia China de Ciencias Agr\u00edcolas.<\/p>\n<p>La investigaci\u00f3n revel\u00f3 que la primera papa, y todas las especies de papa posteriores, inclu\u00edan una combinaci\u00f3n de material gen\u00e9tico derivado de etuberosums y tomates.<\/p>\n<p>Es probable que los cambios clim\u00e1ticos o geol\u00f3gicos hicieran que un antiguo etuberosum y un ancestro del tomate coexistieran en el mismo lugar, afirm\u00f3 Liu.<\/p>\n<p>Dado que ambas especies son polinizadas por abejas, lo m\u00e1s probable es que una abeja transportara el polen entre ambas plantas y diera origen a la papa, seg\u00fan Amy Charkowski, decana asociada de investigaci\u00f3n de la Facultad de Ciencias Agr\u00edcolas de la Universidad Estatal de Colorado. Charkowski no particip\u00f3 en la nueva investigaci\u00f3n.<\/p>\n<p>El lado del tomate proporcion\u00f3 un gen SP6A, un \u201cinterruptor maestro\u201d, que le indic\u00f3 a la planta de papa que comenzara a producir tub\u00e9rculos, mientras que un gen IT1 del lado del Etuberosum controlaba el crecimiento de los tallos subterr\u00e1neos que formaban los tub\u00e9rculos almidonados, explic\u00f3 Liu. Si alguno de estos genes hubiera faltado o no hubiera funcionado en conjunto, las papas nunca habr\u00edan formado tub\u00e9rculos, seg\u00fan los investigadores.<\/p>\n<p>\u201cUna de las cosas que ocurre en la hibridaci\u00f3n es que los genes se mezclan\u201d, dijo Knapp. \u201cEs como barajar una baraja de cartas de nuevo y encontrar diferentes cartas en diferentes combinaciones. Y afortunadamente para esta hibridaci\u00f3n en particular, se unieron dos tipos de genes, lo que cre\u00f3 la capacidad de tuberizar, y eso es un evento fortuito\u201d.<\/p>\n<p>La evoluci\u00f3n de las papas tuberosas coincidi\u00f3 con una \u00e9poca en la que la cordillera de Los Andes se elevaba r\u00e1pidamente debido a las interacciones entre las placas tect\u00f3nicas, lo que cre\u00f3 una enorme columna vertebral a lo largo del oeste de Sudam\u00e9rica, explic\u00f3 Knapp. Los Andes son una compleja cordillera con numerosos valles y una variedad de ecosistemas.<\/p>\n<p>Los tomates modernos prefieren ambientes secos y c\u00e1lidos, mientras que los etuberosums prefieren un espacio templado. Sin embargo, el ancestro de la papa evolucion\u00f3 para prosperar en los h\u00e1bitats secos, fr\u00edos y de gran altitud que surgieron en Los Andes, y el tub\u00e9rculo le permiti\u00f3 sobrevivir, explic\u00f3 Knapp. Las papas pod\u00edan reproducirse sin necesidad de semillas ni polinizaci\u00f3n. El crecimiento de nuevos tub\u00e9rculos dio lugar a nuevas plantas, que pod\u00edan prosperar en diversos ambientes.<\/p>\n<p>La papa cultivada que consumimos hoy es actualmente el tercer cultivo b\u00e1sico m\u00e1s importante del mundo y, junto con el trigo, el arroz y el ma\u00edz, es responsable del 80 % de la ingesta cal\u00f3rica humana, seg\u00fan el estudio.<\/p>\n<p>Entender la historia del origen de la papa podr\u00eda ser la clave para generar m\u00e1s innovaci\u00f3n en las papas del futuro; reintroducir genes clave del tomate podr\u00eda llevar a papas de reproducci\u00f3n r\u00e1pida reproducidas por semillas, algo con lo que Huang y su equipo en la Academia China de Ciencias Agr\u00edcolas est\u00e1n experimentando.<\/p>\n<p>Los cultivos modernos enfrentan presiones por el cambio ambiental, la crisis clim\u00e1tica y nuevas plagas y enfermedades, dijo Knapp.<\/p>\n<p>\u201cLas papas de semilla son interesantes porque pueden ser m\u00e1s diversas gen\u00e9ticamente y resistentes a enfermedades y otros riesgos agr\u00edcolas\u201d, afirm\u00f3 Knapp. La reproducci\u00f3n vegetativa de las papas (cortar una papa en trozos y plantarlos para crear un cultivo) da como resultado papas gen\u00e9ticamente id\u00e9nticas que pueden desaparecer si aparece una nueva enfermedad.<\/p>\n<p>Estudiar las especies silvestres que se han enfrentado a tales desaf\u00edos y han evolucionado en respuesta a ellos tambi\u00e9n podr\u00eda ser crucial, a\u00f1adi\u00f3.<\/p>\n<p>El laboratorio de Charkowski est\u00e1 interesado en c\u00f3mo las papas silvestres resisten las enfermedades y por qu\u00e9 algunas plagas y enfermedades de las plantas solo afectan a las papas o los tomates.<\/p>\n<p>\u201cAdem\u00e1s de ayudarnos a comprender la evoluci\u00f3n de la papa y el desarrollo del tub\u00e9rculo, los m\u00e9todos utilizados (en este estudio) tambi\u00e9n pueden ayudar a los investigadores a aprender sobre otras caracter\u00edsticas, como la resistencia a enfermedades e insectos, la nutrici\u00f3n, la tolerancia a la sequ\u00eda y muchas otras caracter\u00edsticas importantes de las plantas de papa y tomate\u201d, dijo Charkowski.<\/p>\n<p>Las papas siguen siendo un cultivo importante en regiones \u00e1ridas o \u00e1reas con veranos cortos y grandes altitudes, lugares donde no crecen otros cultivos importantes, dijo.<\/p>\n<p>Los hallazgos tambi\u00e9n muestran a las papas bajo una luz diferente: el resultado de un encuentro casual entre dos individuos muy diferentes, dijo la coautora del estudio, la Dra. Tiina S\u00e4rkinen, experta en solan\u00e1ceas del Real Jard\u00edn Bot\u00e1nico de Edimburgo.<\/p>\n<p>\u201cDe hecho, es bastante rom\u00e1ntico\u201d, dijo. \u201cEl origen de muchas de nuestras especies no es una historia sencilla, y es muy emocionante que ahora podamos descubrir estos or\u00edgenes intrincados y complejos gracias a la riqueza de los datos gen\u00f3micos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La humilde papa moderna, domesticada por primera vez hace unos 10.000 a\u00f1os, surgi\u00f3 en la cordillera de Los Andes antes de convertirse en un cultivo clave del que depende el mundo. Sin embargo, debido a que las plantas no se conservan bien en el registro f\u00f3sil, su linaje ha permanecido en gran medida en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465012","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La humilde papa moderna, domesticada por primera vez hace unos 10.000 a\u00f1os, surgi\u00f3 en la cordillera de Los Andes antes de convertirse en un cultivo clave del que depende el mundo. Sin embargo, debido a que las plantas no se conservan bien en el registro f\u00f3sil, su linaje ha permanecido en gran medida en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T20:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos\",\"datePublished\":\"2025-07-31T20:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/\"},\"wordCount\":1780,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/\",\"name\":\"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-31T20:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos - Noticias","og_description":"La humilde papa moderna, domesticada por primera vez hace unos 10.000 a\u00f1os, surgi\u00f3 en la cordillera de Los Andes antes de convertirse en un cultivo clave del que depende el mundo. Sin embargo, debido a que las plantas no se conservan bien en el registro f\u00f3sil, su linaje ha permanecido en gran medida en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-31T20:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/"},"author":{"name":"","@id":""},"headline":"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos","datePublished":"2025-07-31T20:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/"},"wordCount":1780,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/","name":"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-31T20:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La papa moderna evolucion\u00f3 a partir de un tomate silvestre hace 9 millones de a\u00f1os, dicen los cient\u00edficos","url":"http:\/\/noticiasya.com\/nacional\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/07\/31\/papa-evoluciono-tomate-silvestre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-31T20:03:43Z","datePublished":"2025-07-31T20:03:43Z","dateModified":"2025-07-31T20:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La papa moderna evolucion\\u00f3 a partir de un tomate silvestre hace 9 millones de a\\u00f1os, dicen los cient\\u00edficos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/31\\\/papa-evoluciono-tomate-silvestre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/07\\\/31\\\/papa-evoluciono-tomate-silvestre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-31T20:03:43Z\",\"datePublished\":\"2025-07-31T20:03:43Z\",\"dateModified\":\"2025-07-31T20:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1442885,"url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/30\/un-lagarto-sin-patas-avispas-que-controlan-plagas-y-mucho-mas-las-especies-descubiertas-en-2023\/","url_meta":{"origin":1465012,"position":0},"title":"Un lagarto sin patas, avispas que controlan plagas y mucho m\u00e1s: las especies descubiertas en 2023","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"(CNN) -- En 2023, cient\u00edficos del Museo de Historia Natural de Londres y la Academia de Ciencias de California descubrieron casi 1.000 nuevas especies, lo que demuestra que la Tierra todav\u00eda alberga muchas maravillas inexploradas.Los descubrimientos se realizaron durante un a\u00f1o que marca el 50 aniversario de la Ley de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458803,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/16\/papa-francisco-medicos-hospital-salud-trax\/","url_meta":{"origin":1465012,"position":1},"title":"El papa Francisco agradece a m\u00e9dicos y al personal sanitario por su segunda y &#171;tranquila&#187; noche en el hospital","author":"","date":"febrero 16, 2025","format":false,"excerpt":"El papa Francisco agradeci\u00f3 a los m\u00e9dicos y al personal sanitario del Hospital Gemelli de Roma sus cuidados en la oraci\u00f3n del \u00c1ngelus del domingo, mientras permanece hospitalizado recibiendo tratamiento para una bronquitis.\u201cQuisiera agradecer a los m\u00e9dicos y al personal sanitario de este hospital por sus cuidados: hacen un trabajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460266,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/22\/papa-francisco-reaparecera-domingo-trax\/","url_meta":{"origin":1465012,"position":2},"title":"El papa Francisco reaparecer\u00e1 p\u00fablicamente este domingo tras cinco semanas en el hospital","author":"","date":"marzo 22, 2025","format":false,"excerpt":"El papa Francisco planea hacer su primera aparici\u00f3n p\u00fablica desde que fue hospitalizado hace m\u00e1s de un mes el domingo. Se preve\u00e9 que salude al p\u00fablico desde el hospital donde est\u00e1 siendo tratado por neumon\u00eda doble.El pont\u00edfice de 88 a\u00f1os planea ofrecer una bendici\u00f3n y un saludo a los simpatizantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447189,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/21\/papa-exobispo-roger-vangheluwe-abuso-sexual-trax\/","url_meta":{"origin":1465012,"position":3},"title":"El papa Francisco destituye del sacerdocio al exobispo belga Roger Vangheluwe, quien admiti\u00f3 haber cometido abuso sexual hace a\u00f1os","author":"","date":"marzo 21, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El papa Francisco destituy\u00f3 del sacerdocio a Roger Vangheluwe, un exobispo belga que hace a\u00f1os admiti\u00f3 haber abusado sexualmente de dos de sus sobrinos.El Vaticano inform\u00f3 este jueves que Vangheluwe, de 87 a\u00f1os, hab\u00eda sido \u201cexpulsado del estado clerical\u201d despu\u00e9s de que salieran a la luz \u201celementos nuevos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473306,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/18\/papa-leon-disputa-trump-debate-viaje-africa-trax\/","url_meta":{"origin":1465012,"position":4},"title":"El papa Le\u00f3n XIV aborda su disputa con Trump y afirma que el &#171;debate&#187; no es el foco de su viaje a \u00c1frica","author":"","date":"abril 18, 2026","format":false,"excerpt":"El papa Le\u00f3n XIV dijo este s\u00e1bado que \u201cno me interesa\u201d debatir con el presidente de Estados Unidos, Donald Trump, e insisti\u00f3 en que su viaje a \u00c1frica est\u00e1 centrado en la construcci\u00f3n de la paz, m\u00e1s que en cualquier enfrentamiento personal.El primer papa estadounidense, dirigi\u00e9ndose a los periodistas a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447327,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/25\/papa-francisco-se-salta-homilia-en-la-misa-del-domingo-de-ramos-trax\/","url_meta":{"origin":1465012,"position":5},"title":"El papa Francisco se salta por sorpresa la homil\u00eda en la misa del Domingo de Ramos","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) --El papa Francisco inesperadamente se salt\u00f3 la homil\u00eda durante la misa de este domingo de ramos en el Vaticano.La homil\u00eda es un serm\u00f3n durante el cual el papa interpreta las escrituras y explica su significado en el mundo actual.El papa presidi\u00f3 el servicio que marca el comienzo de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1465012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1465012"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1465012\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1465012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1465012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1465012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}