{"id":1465034,"date":"2025-08-01T08:03:49","date_gmt":"2025-08-01T15:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/"},"modified":"2025-08-01T08:03:49","modified_gmt":"2025-08-01T15:03:49","slug":"paul-whelan-un-ano-liberacion-prision-rusia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","title":{"rendered":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &#171;La casa ya no est\u00e1. Los autos ya no est\u00e1n&#187;"},"content":{"rendered":"<p>Para Paul Whelan, regresar a la vida en Estados Unidos despu\u00e9s de m\u00e1s de medio decenio de encarcelamiento en Rusia ha sido \u201cinteresante\u201d, y no ha estado exento de desaf\u00edos.<\/p>\n<p>\u201cLiteralmente tuve que empezar de nuevo\u201d, dijo a CNN antes del primer aniversario del amplio acuerdo de intercambio de prisioneros entre Estados Unidos y Rusia que asegur\u00f3 su liberaci\u00f3n.<\/p>\n<p>\u201cPara personas como yo, que hemos regresado a casa despu\u00e9s de cinco a\u00f1os y medio, realmente no tenemos mucho. La casa ya no est\u00e1. Los autos ya no est\u00e1n. El empleo ya no est\u00e1. No hay seguro de salud\u201d, afirm\u00f3.<\/p>\n<p>Su trastorno de estr\u00e9s postraum\u00e1tico se activa en las habitaciones de hotel, despu\u00e9s de haber sido \u201carrestado violentamente\u201d en una de ellas en 2018 mientras estaba en Mosc\u00fa para asistir a la boda de un amigo. Fue ese arresto bajo cargos de espionaje el que inici\u00f3 su pesadilla de casi seis a\u00f1os de detenci\u00f3n en Rusia.<\/p>\n<p>Regresar a su hogar en Michigan fue una adaptaci\u00f3n, dijo, e incluso desarroll\u00f3 nuevas alergias estacionales por haber estado tanto tiempo fuera.<\/p>\n<p>\u201cMe tom\u00f3 un poco de tiempo sentirme c\u00f3modo conduciendo por las mismas calles de antes o ir a un parque o retomar cosas que hac\u00eda antes, especialmente con mi perra cuando estaba viva\u201d, cont\u00f3 Whelan a CNN. Su perra falleci\u00f3 mientras \u00e9l estaba en Rusia.<\/p>\n<p>\u201cHacer cosas rutinarias que no hab\u00eda hecho en cinco a\u00f1os y medio, seis a\u00f1os, y luego volver a hacerlas, s\u00ed me tom\u00f3 unos meses volver a acostumbrarme.\u201d<\/p>\n<p>Whelan no ha podido conseguir un nuevo trabajo. Algunas empresas no contratan a personas que han estado en prisi\u00f3n, sin importar si ese encarcelamiento fue injusto, explic\u00f3, y compite en el mercado laboral con personas que no tienen una brecha de casi seis a\u00f1os en su curr\u00edculum.<\/p>\n<p>\u201cLa mayor\u00eda de la gente entiende el tema de que se trat\u00f3 de una detenci\u00f3n injusta\u201d, dijo a CNN. \u201cNo saben qu\u00e9 hacer con eso. No necesariamente encaja en sus pol\u00edticas o procedimientos\u201d.<\/p>\n<p>Whelan ha estado trabajando con las representantes dem\u00f3cratas de Michigan Debbie Dingell y Haley Stevens, entre otros, para aprobar una ley \u201cque financie la atenci\u00f3n m\u00e9dica, dental y psicol\u00f3gica mencionada en la Ley Levinson, que nunca fue financiada, as\u00ed como para proporcionar compensaci\u00f3n y cosas similares para exrehenes que fueron detenidos injustamente\u201d, afirm\u00f3.<\/p>\n<p>La Ley Levinson codific\u00f3 partes clave de la pol\u00edtica de rehenes de Estados Unidos en la ley, incluyendo la creaci\u00f3n del puesto de Enviado Especial para Asuntos de Rehenes, y estableci\u00f3 criterios para determinar detenciones injustas. Enmiendas adicionales han buscado aumentar el apoyo a las familias de rehenes y detenidos injustamente de Estados Unidos.<\/p>\n<p>\u201cLa congresista Dingell ha trabajado de cerca con Paul Whelan para comprender y abordar los desaf\u00edos que enfrentan los presos pol\u00edticos cuando regresan a casa\u201d, dijo a CNN Michaela Johnson, subjefa de despacho de la legisladora. \u201cUno de estos es asegurar que tengan el tratamiento m\u00e9dico y los recursos de salud mental que necesitan para recuperarse de su experiencia traum\u00e1tica\u201d.<\/p>\n<p>\u201cElla est\u00e1 trabajando en una legislaci\u00f3n para abordar estos problemas que han surgido en su experiencia trabajando con Paul\u201d, a\u00f1adi\u00f3 Johnson.<\/p>\n<p>Whelan tambi\u00e9n quiere reunirse con el presidente Donald Trump y el secretario de Estado Marco Rubio para discutir el asunto.<\/p>\n<p>Whelan mantiene el contacto con compa\u00f1eros que estuvieron presos con \u00e9l en una colonia penal rusa en Mordovia.<\/p>\n<p>Esa instalaci\u00f3n, IK-17, ya ha cerrado y ahora albergar\u00e1 a prisioneros de guerra ucranianos, dijo Whelan. Sus amigos han quedado dispersados por todo el pa\u00eds, y afirman que la situaci\u00f3n es precaria.<\/p>\n<p>\u201cLa comida es peor que la que ten\u00edamos. Rusia est\u00e1 teniendo un problema tremendo con la econom\u00eda. Los guardias de la prisi\u00f3n no est\u00e1n contentos. No hay suficientes guardias para todos\u201d, relat\u00f3.<\/p>\n<p>A los prisioneros, especialmente a los extranjeros, les dicen que si quieren salir, tienen que ir a luchar a Ucrania, afirm\u00f3.<\/p>\n<p>Whelan tambi\u00e9n est\u00e1 en contacto con otros exdetenidos injustamente, dijo, incluyendo a Evan Gershkovich, quien fue liberado junto a \u00e9l en 2024. La periodista ruso-estadounidense Alsu Kurmasheva y el cr\u00edtico de Putin Vladimir Kara-Murza, quien es residente permanente de Estados Unidos, tambi\u00e9n fueron liberados como parte del amplio intercambio.<\/p>\n<p>Hay un sentido de camarader\u00eda entre los exdetenidos, dijo Whelan, compar\u00e1ndolo con \u201cla Isla de los Juguetes Inadaptados\u201d de la pel\u00edcula navide\u00f1a \u201cRodolfo el reno de la nariz roja\u201d.<\/p>\n<p>\u201cEs un club \u00fanico de personas de todos los or\u00edgenes que fuimos reunidas no por elecci\u00f3n propia, y que compartimos experiencias similares\u201d, dijo Whelan.<\/p>\n<p>De cara a c\u00f3mo conmemorar\u00e1 el primer aniversario de su liberaci\u00f3n, Whelan dijo: \u201cTengo una botella especial de whisky escoc\u00e9s que probablemente abrir\u00e9, y creo que tengo una caja de cigarros por ah\u00ed\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para Paul Whelan, regresar a la vida en Estados Unidos despu\u00e9s de m\u00e1s de medio decenio de encarcelamiento en Rusia ha sido \u201cinteresante\u201d, y no ha estado exento de desaf\u00edos. \u201cLiteralmente tuve que empezar de nuevo\u201d, dijo a CNN antes del primer aniversario del amplio acuerdo de intercambio de prisioneros entre Estados Unidos y Rusia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465034","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &quot;La casa ya no est\u00e1. Los autos ya no est\u00e1n&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &quot;La casa ya no est\u00e1. Los autos ya no est\u00e1n&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Para Paul Whelan, regresar a la vida en Estados Unidos despu\u00e9s de m\u00e1s de medio decenio de encarcelamiento en Rusia ha sido \u201cinteresante\u201d, y no ha estado exento de desaf\u00edos. \u201cLiteralmente tuve que empezar de nuevo\u201d, dijo a CNN antes del primer aniversario del amplio acuerdo de intercambio de prisioneros entre Estados Unidos y Rusia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-01T15:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &#171;La casa ya no est\u00e1. Los autos ya no est\u00e1n&#187;\",\"datePublished\":\"2025-08-01T15:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/\"},\"wordCount\":875,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/\",\"name\":\"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: \\\"La casa ya no est\u00e1. Los autos ya no est\u00e1n\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-01T15:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &#171;La casa ya no est\u00e1. Los autos ya no est\u00e1n&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: \"La casa ya no est\u00e1. Los autos ya no est\u00e1n\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: \"La casa ya no est\u00e1. Los autos ya no est\u00e1n\" - Noticias","og_description":"Para Paul Whelan, regresar a la vida en Estados Unidos despu\u00e9s de m\u00e1s de medio decenio de encarcelamiento en Rusia ha sido \u201cinteresante\u201d, y no ha estado exento de desaf\u00edos. \u201cLiteralmente tuve que empezar de nuevo\u201d, dijo a CNN antes del primer aniversario del amplio acuerdo de intercambio de prisioneros entre Estados Unidos y Rusia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-01T15:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/"},"author":{"name":"","@id":""},"headline":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &#171;La casa ya no est\u00e1. Los autos ya no est\u00e1n&#187;","datePublished":"2025-08-01T15:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/"},"wordCount":875,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","name":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: \"La casa ya no est\u00e1. Los autos ya no est\u00e1n\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-01T15:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &#171;La casa ya no est\u00e1. Los autos ya no est\u00e1n&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &#171;La casa ya no est\u00e1. Los autos ya no est\u00e1n&#187;","url":"http:\/\/noticiasya.com\/nacional\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-01T15:03:49Z","datePublished":"2025-08-01T15:03:49Z","dateModified":"2025-08-01T15:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Paul Whelan, un a\\u00f1o despu\\u00e9s de su liberaci\\u00f3n de una prisi\\u00f3n en Rusia: &#171;La casa ya no est\\u00e1. Los autos ya no est\\u00e1n&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/08\\\/01\\\/paul-whelan-un-ano-liberacion-prision-rusia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/08\\\/01\\\/paul-whelan-un-ano-liberacion-prision-rusia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-01T15:03:49Z\",\"datePublished\":\"2025-08-01T15:03:49Z\",\"dateModified\":\"2025-08-01T15:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451542,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/01\/quien-es-paul-whelan-detenido-rusia-orix\/","url_meta":{"origin":1465034,"position":0},"title":"Qui\u00e9n es Paul Whelan, el ex infante de Marina detenido por cinco a\u00f1os en Rusia y liberado en un intercambio de prisioneros","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Tras cinco a\u00f1os encarcelado en Rusia, el ex infante de Marina Paul Whelan fue liberado este jueves en un intercambio de prisioneros a gran escala que incluy\u00f3 tambi\u00e9n al periodista del Wall Street Journal Evan Gershkovich, seg\u00fan confirm\u00f3 Turqu\u00eda.El acuerdo entre Estados Unidos y Rusia puso fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451561,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/01\/biden-harris-intercambio-prisioneros-rusia-trax\/","url_meta":{"origin":1465034,"position":1},"title":"Biden celebra el intercambio de prisioneros y subraya la importancia de los aliados en un momento crucial para su legado","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN) -- El intercambio masivo de prisioneros entre varios pa\u00edses y Rusia, anunciado por Estados Unidos como el mayor desde el final de la Guerra Fr\u00eda, supuso este jueves un importante logro diplom\u00e1tico y un momento decisivo para el legado del presidente Joe Biden, a menos de seis meses de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446539,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","url_meta":{"origin":1465034,"position":2},"title":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &#171;extremadamente preocupante&#187; para \u00e9l","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN) -- Paul Whelan, estadounidense detenido en Rusia desde hace m\u00e1s de cinco a\u00f1os, dijo este martes a CNN que la muerte del opositor ruso Alexey Navalny en una prisi\u00f3n el mes pasado resulta \"extremadamente preocupante\" para \u00e9l.\"No puedo hablar demasiado por razones obvias, pero una cosa que s\u00ed dir\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451563,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/02\/3-estadounidenses-regresaron-casa-intercambio-prisioneros-trax\/","url_meta":{"origin":1465034,"position":3},"title":"Tres estadounidenses regresaron a casa como parte de un hist\u00f3rico intercambio de prisioneros. Esto es lo que hay que saber","author":"","date":"agosto 2, 2024","format":false,"excerpt":"(CNN) -- Unos 20 minutos antes de la medianoche de este jueves, un avi\u00f3n que transportaba a tres ciudadanos estadounidenses liberados de la detenci\u00f3n rusa aterriz\u00f3 en suelo norteamericano, en un momento hist\u00f3rico y emotivo despu\u00e9s de un esfuerzo de varios a\u00f1os en varios pa\u00edses que implic\u00f3 reuniones secretas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451539,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/01\/estados-unidos-rusia-intercambio-masivo-prisioneros-trax\/","url_meta":{"origin":1465034,"position":4},"title":"Estados Unidos y Rusia llevan a cabo un intercambio masivo de prisioneros que se espera que incluya a Evan Gershkovich y Paul Whelan","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN) --\u00a0Seg\u00fan una fuente familiarizada con el asunto, se espera se est\u00e1 llevando a cabo un intercambio masivo de prisioneros entre Estados Unidos y Rusia, que incluye a varios estadounidenses.Se espera que tanto el periodista de The Wall Street Journal Evan Gershkovich, como el exmarine estadounidense Paul Whelan est\u00e9n incluidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458614,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/12\/marc-fogel-detenido-regresa-rusia-intercambio-reunion-trump-trax\/","url_meta":{"origin":1465034,"position":5},"title":"Marc Fogel, profesor estadounidense detenido injustamente, se re\u00fane con Trump tras ser liberado de Rusia en un &#8216;intercambio&#8217;","author":"","date":"febrero 12, 2025","format":false,"excerpt":"Marc Fogel, un profesor estadounidense detenido durante m\u00e1s de tres a\u00f1os en Rusia, fue recibido nuevamente en Estados Unidos por el presidente Donald Trump este martes por la noche despu\u00e9s de que la Casa Blanca lograra su liberaci\u00f3n en un \u201cintercambio\u201d.Fogel lleg\u00f3 a la Casa Blanca este martes por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1465034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1465034"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1465034\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1465034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1465034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1465034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}