{"id":1466478,"date":"2025-09-15T11:03:50","date_gmt":"2025-09-15T18:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/"},"modified":"2025-09-15T11:03:50","modified_gmt":"2025-09-15T18:03:50","slug":"acciones-record-economia-deprimida-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/","title":{"rendered":"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos?"},"content":{"rendered":"<p>La contrataci\u00f3n est\u00e1 estancada. La inflaci\u00f3n est\u00e1 al alza de nuevo. La confianza del consumidor se acerca a m\u00ednimos hist\u00f3ricos. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/14\/eeuu\/indicador-mercado-financiero-temor-economia-ee-uu-trax\">Los estadounidenses est\u00e1n cada vez m\u00e1s hartos de la econom\u00eda<\/a>.<\/p>\n<p>Mientras tanto, el S&#038;P 500 ha alcanzado cuatro m\u00e1ximos hist\u00f3ricos este mes. El Dow Jones cerr\u00f3 por encima de los 46.000 puntos por primera vez en la historia el jueves. Entonces, si la econom\u00eda est\u00e1 en crisis, \u00bfpor qu\u00e9 est\u00e1 tan contenta la bolsa?<\/p>\n<p>En cierto modo, las acciones cotizan a m\u00e1ximos hist\u00f3ricos debido a la mala racha de la econom\u00eda estadounidense, no a pesar de ella.<\/p>\n<p>Un mercado laboral sorprendentemente d\u00e9bil ha aumentado significativamente las expectativas de los inversores de que la Reserva Federal se vea obligada a recortar los tipos de inter\u00e9s varias veces este a\u00f1o, seg\u00fan CME FedWatch, una herramienta que asigna las probabilidades de las decisiones de la Fed sobre los tipos a las maquinaciones del mercado. El mercado estima un 80 % de probabilidad de un recorte de tasas en diciembre, un 86 % de probabilidad de un recorte en octubre y un 100 % de probabilidad de que la Fed reduzca las tasas al concluir su reuni\u00f3n de dos d\u00edas el mi\u00e9rcoles.<\/p>\n<p>El mercado ha estado ansioso por menores costos de endeudamiento: la Fed no ha recortado las tasas en absoluto en 2025 despu\u00e9s de hacerlo dr\u00e1sticamente en un punto porcentual en tres reuniones a finales del a\u00f1o pasado. Sin embargo, el presidente de la Fed, Jerome Powell, ha declarado que la incertidumbre en torno a la pol\u00edtica arancelaria del presidente Donald Trump ha dado que pensar al comit\u00e9 de votaci\u00f3n. La inflaci\u00f3n ha aumentado gradualmente en los \u00faltimos meses, en parte porque los aranceles est\u00e1n, lentamente, comenzando a impulsar los precios. Los recortes de tasas podr\u00edan exacerbar la inflaci\u00f3n.<\/p>\n<p>A Wall Street le encantan los recortes de tasas, porque pueden ayudar a impulsar las ganancias de las empresas al reducir los costos de los pr\u00e9stamos. Esto otorga un mayor valor subyacente percibido a las acciones de las empresas y puede brindar a los empleadores fondos adicionales para contratar. Es por eso que los recortes de tasas tienden a impulsar la econom\u00eda con el tiempo.<\/p>\n<p>Los inversores burs\u00e1tiles tambi\u00e9n han celebrado la esperada fortaleza del mercado de bonos, que ha cobrado impulso repentinamente debido al creciente temor a una desaceleraci\u00f3n del crecimiento del empleo. El mercado de bonos del Tesoro estadounidense, considerado refugio seguro, ha estado en auge en los \u00faltimos d\u00edas mientras los operadores descuentan recortes de tasas, lo que suele hacer bajar los rendimientos y subir los precios (los precios y los rendimientos se mueven en direcciones opuestas). El rendimiento del bono a 2 a\u00f1os cotiza cerca de su nivel m\u00e1s bajo desde la crisis inflacionaria de 2022, y el bono a 10 a\u00f1os coquetea con el 4 % por primera vez desde el desplome de abril provocado por los aranceles.<\/p>\n<p>La reducci\u00f3n de los rendimientos de los bonos tambi\u00e9n ayuda a las empresas a reducir el gasto en deuda, lo que a\u00f1ade valor potencial a sus acciones.<\/p>\n<p>El S&#038;P 500, el \u00edndice de referencia del mercado burs\u00e1til, ha subido un 6 % desde que el impactante informe de empleo del 1 de agosto mostr\u00f3 que la contrataci\u00f3n se desaceler\u00f3 significativamente y que la econom\u00eda estadounidense hab\u00eda creado un cuarto de mill\u00f3n de empleos menos en los dos meses anteriores de lo que se cre\u00eda anteriormente. El mercado ha estado particularmente en racha en septiembre, previo a la reuni\u00f3n de la Fed, a medida que se publicaban m\u00e1s datos de empleo de baja rentabilidad: el S&#038;P 500 ha registrado ganancias en seis de las nueve sesiones de este mes.<\/p>\n<p>As\u00ed que las malas noticias sobre la econom\u00eda han sido, sin duda, buenas noticias para las acciones en los \u00faltimos meses.<\/p>\n<p>Pero esa no es la historia completa.<\/p>\n<p>Aunque la Fed sin duda ha impulsado el optimismo de que el mercado burs\u00e1til, ya hist\u00f3ricamente caro, a\u00fan tiene margen de crecimiento, la solidez de los beneficios empresariales tambi\u00e9n ha contribuido a la confianza de los operadores: las expectativas de crecimiento de beneficios y ventas de Wall Street se mantienen s\u00f3lidas.<\/p>\n<p>Y, despu\u00e9s de todo, el mercado burs\u00e1til es en realidad un conjunto de empresas individuales cuyos precios suben o bajan en funci\u00f3n de su valor percibido. Si los inversores no tuvieran fe en que las empresas con las que operan les generar\u00e1n beneficios, probablemente no valorar\u00edan tanto las acciones.<\/p>\n<p>El vertiginoso crecimiento de la industria de la inteligencia artificial tambi\u00e9n ha impulsado el alza del mercado. Nueve de las 10 acciones m\u00e1s valiosas del mercado est\u00e1n profundamente involucradas en la IA y, en conjunto, representan alrededor del 40 % del valor total del mercado burs\u00e1til.<\/p>\n<p>Para dar una idea del entusiasmo del mercado por la IA, las acciones de Oracle se dispararon un 36 % en un solo d\u00eda la semana pasada, tras un pron\u00f3stico estelar sobre la demanda de centros de datos impulsados \u200b\u200bpor la IA. Esto convirti\u00f3 brevemente al cofundador Larry Ellison en la persona m\u00e1s rica del mundo (aunque termin\u00f3 el mi\u00e9rcoles con US$ 1.000 millones menos que Elon Musk), e impuls\u00f3 a Oracle (ORCL) a la lista de las 10 empresas m\u00e1s valiosas del mercado.<\/p>\n<p>Y las acciones han ganado terreno tras la entrada en vigor de los aranceles de Trump a principios de agosto, lo que ha dado a las empresas cierta certidumbre tras meses de amenazas comerciales intermitentes que les impidieron tomar decisiones informadas sobre sus inversiones. Los beneficios fiscales otorgados por la emblem\u00e1tica ley \u201cOne Big Beautiful Bill Act\u201d de Trump tambi\u00e9n ayudaron a dar a las empresas un respaldo adicional a sus resultados finales, y les da confianza a los inversores de que las enormes fluctuaciones en las maniobras pol\u00edticas de la Casa Blanca se han calmado y, por lo tanto, pueden asumir m\u00e1s riesgo en sus carteras.<\/p>\n<p>Mientras tanto, los consumidores han seguido gastando, a pesar de los aranceles y la creciente preocupaci\u00f3n por la econom\u00eda. El gasto aument\u00f3 un 0,5 % en julio, seg\u00fan inform\u00f3 US$el Departamento de Comercio hace dos semanas. Esto es crucial: el gasto del consumidor representa m\u00e1s de dos tercios del producto interior bruto (PIB) de EE.UU., el indicador m\u00e1s amplio de la econom\u00eda estadounidense.<\/p>\n<p>\u201cNo se trata solo de la Reserva Federal\u201d, declar\u00f3 el analista de Citi Research, Scott Chronert, en una nota a los inversores el viernes. \u201cLas expectativas de beneficios siguen siendo s\u00f3lidas, mientras que la volatilidad y los niveles de las tasas de inter\u00e9s disminuyen. En conjunto, esta es una narrativa poderosa para los activos de riesgo\u201d.<\/p>\n<p>Pero a\u00fan hay motivos de preocupaci\u00f3n.<\/p>\n<p>Las acciones est\u00e1n hist\u00f3ricamente caras: el S&#038;P 500 cotiza a 3,3 veces el valor de las expectativas de ventas de sus accionistas, el m\u00e1s alto registrado. Tambi\u00e9n se encuentra en una relaci\u00f3n precio-beneficio hist\u00f3ricamente alta de 25 a 1; esto significa que para que una empresa obtenga US$ 1 en beneficios futuros, los inversores est\u00e1n dispuestos a pagar US$ 25 por el precio de las acciones. Eso significa que los inversores podr\u00edan estar adelant\u00e1ndose.<\/p>\n<p>El aumento de precios podr\u00eda empezar a afectar el gasto de los consumidores, socavando la posibilidad de un crecimiento de las ventas de las empresas. La inflaci\u00f3n de este a\u00f1o ha a\u00f1adido US$ 195 al mes en costes para un hogar estadounidense t\u00edpico, seg\u00fan Mark Zandi, economista jefe de Moody\u2019s.<\/p>\n<p>A medida que los costes empiezan a subir, los consumidores han ido incrementando su ya enorme carga de deuda, lo que podr\u00eda convertirse en un problema. La morosidad va en aumento, aceler\u00e1ndose debido a la reanudaci\u00f3n de los pagos de pr\u00e9stamos estudiantiles en octubre de 2024, seg\u00fan Dana Telsey, directora ejecutiva y directora de investigaci\u00f3n de Telsey Advisory Group. Los pagos de pr\u00e9stamos estudiantiles absorber\u00e1n US$ 80.000 millones de la econom\u00eda este a\u00f1o, seg\u00fan declar\u00f3 Brookings la semana pasada.<\/p>\n<p>La inflaci\u00f3n, aunque no en niveles descontrolados como en 2022, se est\u00e1 convirtiendo en una preocupaci\u00f3n tal que una cobertura tradicional contra la inflaci\u00f3n est\u00e1 batiendo nuevos r\u00e9cords: el oro. Cotizando a casi US$ 3.700, el oro ha ganado alrededor de un 40 % este a\u00f1o y recientemente eclips\u00f3 su m\u00e1ximo hist\u00f3rico ajustado a la inflaci\u00f3n establecido hace 45 a\u00f1os. Los operadores preocupados por la inflaci\u00f3n tienden a invertir en oro, que algunos creen que posee un valor intr\u00ednseco que lo protege contra el aumento de precios.<\/p>\n<p>Gary Friedman, director ejecutivo de RH (anteriormente Restoration Hardware), argument\u00f3 el jueves en una llamada con analistas de Wall Street que los aranceles y la inflaci\u00f3n representan una amenaza m\u00e1s significativa para las empresas de lo que la mayor\u00eda cree, por lo que no est\u00e1 muy entusiasmado con una rebaja de tipos por parte de la Reserva Federal.<\/p>\n<p>\u201c\u00bfQu\u00e9 es lo que m\u00e1s me preocupa? Simplemente acabar con la inflaci\u00f3n. Me motiva m\u00e1s acabar con la inflaci\u00f3n que conseguir una rebaja de tipos de inter\u00e9s ahora mismo, porque ya tuvimos una rebaja de tipos y los aranceles generan m\u00e1s inflaci\u00f3n de la que se cree\u201d, dijo Friedman. \u201cNo quiero ganar porque el 50 % de nuestros competidores, que son gente realmente buena y trabajadora, sean aniquilados\u201d.<\/p>\n<p>\u201cRealmente no creo que nadie est\u00e9 pensando en las matem\u00e1ticas\u201d, a\u00f1adi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La contrataci\u00f3n est\u00e1 estancada. La inflaci\u00f3n est\u00e1 al alza de nuevo. La confianza del consumidor se acerca a m\u00ednimos hist\u00f3ricos. Los estadounidenses est\u00e1n cada vez m\u00e1s hartos de la econom\u00eda. Mientras tanto, el S&#038;P 500 ha alcanzado cuatro m\u00e1ximos hist\u00f3ricos este mes. El Dow Jones cerr\u00f3 por encima de los 46.000 puntos por primera vez [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466478","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos? - Noticias\" \/>\n<meta property=\"og:description\" content=\"La contrataci\u00f3n est\u00e1 estancada. La inflaci\u00f3n est\u00e1 al alza de nuevo. La confianza del consumidor se acerca a m\u00ednimos hist\u00f3ricos. Los estadounidenses est\u00e1n cada vez m\u00e1s hartos de la econom\u00eda. Mientras tanto, el S&#038;P 500 ha alcanzado cuatro m\u00e1ximos hist\u00f3ricos este mes. El Dow Jones cerr\u00f3 por encima de los 46.000 puntos por primera vez [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T18:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos?\",\"datePublished\":\"2025-09-15T18:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/\"},\"wordCount\":1653,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/\",\"name\":\"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-15T18:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos? - Noticias","og_description":"La contrataci\u00f3n est\u00e1 estancada. La inflaci\u00f3n est\u00e1 al alza de nuevo. La confianza del consumidor se acerca a m\u00ednimos hist\u00f3ricos. Los estadounidenses est\u00e1n cada vez m\u00e1s hartos de la econom\u00eda. Mientras tanto, el S&#038;P 500 ha alcanzado cuatro m\u00e1ximos hist\u00f3ricos este mes. El Dow Jones cerr\u00f3 por encima de los 46.000 puntos por primera vez [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-15T18:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos?","datePublished":"2025-09-15T18:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/"},"wordCount":1653,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/","name":"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-15T18:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 las acciones est\u00e1n batiendo r\u00e9cords si la econom\u00eda parece estar por los suelos?","url":"http:\/\/noticiasya.com\/nacional\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/09\/15\/acciones-record-economia-deprimida-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-15T18:03:50Z","datePublished":"2025-09-15T18:03:50Z","dateModified":"2025-09-15T18:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 las acciones est\\u00e1n batiendo r\\u00e9cords si la econom\\u00eda parece estar por los suelos?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/15\\\/acciones-record-economia-deprimida-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/15\\\/acciones-record-economia-deprimida-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-15T18:03:50Z\",\"datePublished\":\"2025-09-15T18:03:50Z\",\"dateModified\":\"2025-09-15T18:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466945,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/29\/dinero-acciones-alerta-trax\/","url_meta":{"origin":1466478,"position":0},"title":"Los estadounidenses tienen m\u00e1s dinero en acciones que nunca. Los economistas dicen que esto es una clara se\u00f1al de alerta","author":"","date":"septiembre 29, 2025","format":false,"excerpt":"Los estadounidenses tienen m\u00e1s dinero invertido en acciones que nunca. Pero si bien el alza del mercado puede estar inflando sus cuentas, est\u00e1n m\u00e1s expuestos que nunca a una posible ca\u00edda del mercado.La tenencia directa e indirecta de acciones, incluyendo fondos mutuos o planes de jubilaci\u00f3n, represent\u00f3 un m\u00e1ximo hist\u00f3rico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470613,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/29\/trump-quiere-atencion-votantes-economia-trax\/","url_meta":{"origin":1466478,"position":1},"title":"Trump quiere volver a centrar la atenci\u00f3n de los votantes en la econom\u00eda. Quiz\u00e1s se arrepienta","author":"","date":"enero 29, 2026","format":false,"excerpt":"El presidente Donald Trump, que enfrenta una creciente reacci\u00f3n negativa por el comportamiento de sus agentes de inmigraci\u00f3n, viaj\u00f3 el martes a Iowa con la esperanza de cambiar el tema de la conversaci\u00f3n. Tal vez sus asesores concluyeron que la mejor estrategia es volver a lo b\u00e1sico y recordarles a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465532,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/15\/dow-jones-abre-territorio-record-tasas-trax\/","url_meta":{"origin":1466478,"position":2},"title":"El Dow Jones abre en territorio r\u00e9cord, en medio del entusiasmo de Wall Street por una posible bajada de las tasas de inter\u00e9s","author":"","date":"agosto 15, 2025","format":false,"excerpt":"El Dow Jones se encamina este viernes a registrar un m\u00e1ximo hist\u00f3rico del a\u00f1o, lo que refleja el optimismo sostenido en Wall Street a pesar de los signos de turbulencias subyacentes en la econom\u00eda.Las acciones estadounidenses abrieron mixtas el viernes por la ma\u00f1ana. El Dow Jones subi\u00f3 268 puntos, o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473677,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/30\/wall-street-mercados-guerra-iran-trax\/","url_meta":{"origin":1466478,"position":3},"title":"Todos estamos leyendo mal a los mercados","author":"","date":"abril 30, 2026","format":false,"excerpt":"Los precios de la gasolina est\u00e1n muy por encima de los US$ 4, las negociaciones de cese del fuego est\u00e1n congeladas y las aerol\u00edneas advierten que se est\u00e1n quedando sin combustible para aviones. Por eso parece extra\u00f1o que las acciones est\u00e9n en m\u00e1ximos hist\u00f3ricos.La culpa es de CNN. No, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470956,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/06\/acciones-hito-historico-dow-supera-50000-puntos-trax\/","url_meta":{"origin":1466478,"position":4},"title":"Las acciones alcanzan un hito hist\u00f3rico: el Dow super\u00f3 por primera vez los 50.000 puntos","author":"","date":"febrero 6, 2026","format":false,"excerpt":"El Dow acaba de alcanzar los 50.000 puntos por primera vez en la historia.El \u00edndice de primera l\u00ednea subi\u00f3 el viernes 1.097 puntos, o un 2,24 %, y super\u00f3 los 50.000 puntos durante la jornada. Es la primera vez que el \u00edndice, con 129 a\u00f1os de antig\u00fcedad, cruza el hist\u00f3rico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460252,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/21\/acciones-envidia-mundo-trump-podria-arriesgarlas-trax\/","url_meta":{"origin":1466478,"position":5},"title":"Las acciones estadounidenses han sido la envidia del mundo, pero Trump podr\u00eda ponerlas en riesgo","author":"","date":"marzo 21, 2025","format":false,"excerpt":"El mercado de valores de EE.UU. ha sido el est\u00e1ndar de oro durante d\u00e9cadas. Pero los inversionistas de todo el mundo est\u00e1n cada vez m\u00e1s nerviosos por las repercusiones de la agenda econ\u00f3mica del presidente Donald Trump. Eso ha llevado a los comerciantes a buscar acciones en Europa y Asia.Wall\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1466478"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466478\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1466478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1466478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1466478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}