{"id":1466483,"date":"2025-09-15T14:03:51","date_gmt":"2025-09-15T21:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/"},"modified":"2025-09-15T14:03:51","modified_gmt":"2025-09-15T21:03:51","slug":"bad-bunny-concierto-extra-puerto-rico-streaming-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/","title":{"rendered":"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros"},"content":{"rendered":"<p>Bad Bunny finalmente nos llevar\u00e1 a todos a Puerto Rico.<\/p>\n<p>La superestrella, cuya residencia de conciertos este verano en Puerto Rico ha tra\u00eddo orgullo, atenci\u00f3n y grandes cantidades de ingresos a la isla, anunci\u00f3 un concierto extra. Esta \u00faltima adici\u00f3n, programada para el 20 de septiembre, tambi\u00e9n ser\u00e1 transmitida en vivo por Amazon Prime, Twitch y la aplicaci\u00f3n Amazon Music.<\/p>\n<p>Al igual que los primeros nueve shows de su residencia, al concierto de Bad Bunny solo podr\u00e1n ingresar locales.<\/p>\n<p>La residencia de conciertos del artista, que comenz\u00f3 en julio, probablemente ha generado cientos de millones de d\u00f3lares en ingresos tur\u00edsticos para Puerto Rico. Bad Bunny declar\u00f3 recientemente que no estaba dispuesto a hacer una gira en Estados Unidos <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/11\/entretenimiento\/bad-bunny-conciertos-eeuu-redadas-ice-orix\">debido a las agresivas actividades de detenci\u00f3n del ICE<\/a>.<\/p>\n<p>El show del ganador del Grammy comenzar\u00e1 a las 8:30 p.m., hora de Miami, el s\u00e1bado 20 de septiembre. Amazon tambi\u00e9n anunci\u00f3 que se asociar\u00e1 con el artista en iniciativas en Puerto Rico que abarcan \u201ceducaci\u00f3n, ayuda en desastres y empoderamiento cultural\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bad Bunny finalmente nos llevar\u00e1 a todos a Puerto Rico. La superestrella, cuya residencia de conciertos este verano en Puerto Rico ha tra\u00eddo orgullo, atenci\u00f3n y grandes cantidades de ingresos a la isla, anunci\u00f3 un concierto extra. Esta \u00faltima adici\u00f3n, programada para el 20 de septiembre, tambi\u00e9n ser\u00e1 transmitida en vivo por Amazon Prime, Twitch [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466483","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros - Noticias\" \/>\n<meta property=\"og:description\" content=\"Bad Bunny finalmente nos llevar\u00e1 a todos a Puerto Rico. La superestrella, cuya residencia de conciertos este verano en Puerto Rico ha tra\u00eddo orgullo, atenci\u00f3n y grandes cantidades de ingresos a la isla, anunci\u00f3 un concierto extra. Esta \u00faltima adici\u00f3n, programada para el 20 de septiembre, tambi\u00e9n ser\u00e1 transmitida en vivo por Amazon Prime, Twitch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T21:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros\",\"datePublished\":\"2025-09-15T21:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/\"},\"wordCount\":208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/\",\"name\":\"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-15T21:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros - Noticias","og_description":"Bad Bunny finalmente nos llevar\u00e1 a todos a Puerto Rico. La superestrella, cuya residencia de conciertos este verano en Puerto Rico ha tra\u00eddo orgullo, atenci\u00f3n y grandes cantidades de ingresos a la isla, anunci\u00f3 un concierto extra. Esta \u00faltima adici\u00f3n, programada para el 20 de septiembre, tambi\u00e9n ser\u00e1 transmitida en vivo por Amazon Prime, Twitch [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-15T21:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/"},"author":{"name":"","@id":""},"headline":"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros","datePublished":"2025-09-15T21:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/"},"wordCount":208,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/","name":"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-15T21:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bad Bunny har\u00e1 un show m\u00e1s en Puerto Rico, para todos nosotros","url":"http:\/\/noticiasya.com\/nacional\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/09\/15\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-15T21:03:51Z","datePublished":"2025-09-15T21:03:51Z","dateModified":"2025-09-15T21:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bad Bunny har\\u00e1 un show m\\u00e1s en Puerto Rico, para todos nosotros\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/15\\\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/15\\\/bad-bunny-concierto-extra-puerto-rico-streaming-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-15T21:03:51Z\",\"datePublished\":\"2025-09-15T21:03:51Z\",\"dateModified\":\"2025-09-15T21:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466931,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/28\/bad-bunny-super-bowl-lx-show-medio-tiempo-trax\/","url_meta":{"origin":1466483,"position":0},"title":"Bad Bunny encabezar\u00e1 el espect\u00e1culo de medio tiempo del Super Bowl LX","author":"","date":"septiembre 28, 2025","format":false,"excerpt":"La superestrella puertorrique\u00f1a Bad Bunny se sube al escenario m\u00e1s grande del f\u00fatbol americano.El m\u00fasico, quien recientemente termin\u00f3 una residencia en Puerto Rico, fue anunciado el domingo como el artista del espect\u00e1culo de medio tiempo del Super Bowl LX.\u201cLo que siento va m\u00e1s all\u00e1 de m\u00ed mismo. Es por aquellos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465637,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/19\/famosos-conciertos-bad-bunny-puerto-rico-orix\/","url_meta":{"origin":1466483,"position":1},"title":"Todos los famosos que se han subido al escenario en los conciertos de Bad Bunny en Puerto Rico","author":"","date":"agosto 19, 2025","format":false,"excerpt":"No fue St. Barts, Mustique, Fiji o las Maldivas. La isla que fue un im\u00e1n para ricos y famosos este verano de 2025 fue Puerto Rico. La raz\u00f3n: la residencia del cantante Bad Bunny en la isla, una serie de 30 conciertos en el Coliseo de Puerto Rico con capacidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464441,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/11\/bad-bunny-declaracion-politica-residencia-puerto-rico-trax\/","url_meta":{"origin":1466483,"position":2},"title":"Bad Bunny hace una &#171;declaraci\u00f3n pol\u00edtica&#187; al iniciar su residencia en Puerto Rico","author":"","date":"julio 11, 2025","format":false,"excerpt":"Un ambiente de emoci\u00f3n se apoder\u00f3 de Puerto Rico mientras el artista local Bad Bunny, una de las mayores estrellas musicales del mundo, inicia este viernes su esperada residencia.Las tiendas agotan la mercanc\u00eda, los restaurantes crean men\u00fas tem\u00e1ticos y los noticieros locales dedican una cobertura especial a lo que los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466418,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/13\/bad-bunny-impulso-economia-puerto-rico-huracanes-trax\/","url_meta":{"origin":1466483,"position":3},"title":"C\u00f3mo Bad Bunny dio un impulso a la econom\u00eda de Puerto Rico durante la temporada de huracanes","author":"","date":"septiembre 13, 2025","format":false,"excerpt":"Fue una idea \u201calucinante\u201d, recuerda Jorge P\u00e9rez, dos a\u00f1os despu\u00e9s de escucharla por primera vez: Bad Bunny no iba a hacer una gira por Estados Unidos.En agosto de 2023, P\u00e9rez, funcionario de turismo que administra el Coliseo, la sala de conciertos m\u00e1s grande de la isla, recibi\u00f3 una llamada telef\u00f3nica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466396,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/12\/bad-bunny-conciertos-eeuu-redadas-ice-orix\/","url_meta":{"origin":1466483,"position":4},"title":"Bad Bunny dice que no incluy\u00f3 a EE.UU. en su gira de conciertos por temor a las redadas de ICE","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"El m\u00fasico puertorrique\u00f1o Bad Bunny dijo en una entrevista concedida a la revista i-D que no incluy\u00f3 a Estados Unidos en su gira de conciertos 2025-2026 por temor a que el Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos (ICE, por sus siglas en ingl\u00e9s) efectuara redadas entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464436,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/11\/bad-bunny-economia-puerto-rico-trax\/","url_meta":{"origin":1466483,"position":5},"title":"Se espera que la residencia de Bad Bunny implique un &#171;boom&#187; econ\u00f3mico para Puerto Rico","author":"","date":"julio 11, 2025","format":false,"excerpt":"La residencia de dos meses de Bad Bunny promete ser un buen negocio para Puerto Rico, que alguna vez estuvo en bancarrota.Este viernes, el m\u00fasico inicia una serie de 30 conciertos en una \u00e9poca que normalmente es lenta para el turismo en la isla. Sin embargo, el superastro puertorrique\u00f1o, cuyo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1466483"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466483\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1466483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1466483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1466483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}