{"id":1466500,"date":"2025-09-16T04:03:48","date_gmt":"2025-09-16T11:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/"},"modified":"2025-09-16T04:03:48","modified_gmt":"2025-09-16T11:03:48","slug":"analisis-trump-acceso-publico-datos-economicos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/","title":{"rendered":"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos"},"content":{"rendered":"<p>En un <a href=\"https:\/\/www.cnn.com\/2025\/09\/15\/economy\/trump-quarterly-reporting-sec-earnings\">d\u00eda ya de por s\u00ed agitado por las noticias<\/a> para <a href=\"https:\/\/www.cnn.com\/2025\/09\/15\/business\/musk-billion-dollar-tesla-share-purchase\">empresas e inversores<\/a>, el presidente agreg\u00f3 a la mezcla una publicaci\u00f3n en las redes sociales que casualmente suger\u00eda que los reguladores cambiaran por completo un elemento fijo de la vida corporativa estadounidense durante el \u00faltimo medio siglo.<\/p>\n<p><strong>Por si te lo perdiste:<\/strong> Este lunes por la ma\u00f1ana, el presidente Donald Trump <a href=\"https:\/\/www.cnn.com\/2025\/09\/15\/economy\/trump-quarterly-reporting-sec-earnings\">reaviv\u00f3<\/a> uno de sus proyectos favoritos de su primer mandato, afirmando que las empresas que cotizan en bolsa no deber\u00edan estar obligadas a informar sus resultados cada tres meses, sino cada seis. \u201cEsto ahorrar\u00e1 dinero y permitir\u00e1 a los directivos centrarse en la correcta gesti\u00f3n de sus empresas\u201d, escribi\u00f3.<\/p>\n<p>No se trata de una idea particularmente radical ni nueva: la mayor\u00eda de las empresas p\u00fablicas europeas y brit\u00e1nicas solo est\u00e1n obligadas a presentar informes cada seis meses. Sin embargo, la propuesta surge en un momento en que Trump tambi\u00e9n ha buscado rehacer la econom\u00eda estadounidense a su imagen y semejanza y <a href=\"https:\/\/www.cnn.com\/2025\/08\/01\/business\/trump-job-report-number-fire\">cuestionar<\/a> cualquier dato o instituci\u00f3n que pueda manchar su legado.<\/p>\n<p>Trump no es el \u00fanico que pide un calendario de divulgaci\u00f3n menos frecuente.<\/p>\n<p>Algunos acad\u00e9micos y l\u00edderes empresariales opinan que exigir a las empresas que divulguen sus finanzas trimestralmente, como se ha hecho en Estados Unidos desde 1970, exacerba la obsesi\u00f3n de las compa\u00f1\u00edas estadounidenses por complacer al mercado burs\u00e1til a corto plazo en lugar de centrarse en la creaci\u00f3n de valor a largo plazo.<\/p>\n<p>Trump impuls\u00f3 brevemente la idea en 2018, cuando <a href=\"https:\/\/x.com\/realDonaldTrump\/status\/1030416679069777921?dlbk\">tuite\u00f3<\/a> que hab\u00eda instado a la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) a \u201cestudiar\u201d la transici\u00f3n a un sistema de informes semestrales, aunque no est\u00e1 claro si se materializ\u00f3.<\/p>\n<p>Y, sin duda, el \u201ccapitalismo trimestral\u201d tiene cr\u00edticos en todo el espectro pol\u00edtico. Hillary Clinton abog\u00f3 en su campa\u00f1a presidencial por una <a href=\"https:\/\/medium.com\/hillary-for-america\/moving-beyond-quarterly-capitalism-7abec53733f6\">soluci\u00f3n multifac\u00e9tica<\/a> para impulsar a los CEO a priorizar el crecimiento a largo plazo y la estabilidad laboral sobre las ganancias a corto plazo.<\/p>\n<p>Los financieros Jamie Dimon y Warren Buffett <a href=\"https:\/\/www.wsj.com\/articles\/short-termism-is-harming-the-economy-1528336801\">argumentaron en 2018<\/a> que las empresas que cotizan en bolsa deber\u00edan reducir o eliminar la pr\u00e1ctica de <em>estimar<\/em> las ganancias trimestrales futuras, lo cual difiere ligeramente de lo que propone Trump.<\/p>\n<p>Dimon y Buffett dejaron claro que sus opiniones sobre las previsiones de ganancias \u201cno deben malinterpretarse como una oposici\u00f3n a la presentaci\u00f3n de informes trimestrales y anuales\u201d, que consideraban esenciales para la integridad de los mercados burs\u00e1tiles. (Las empresas no est\u00e1n obligadas a proporcionar proyecciones de ganancias, aunque muchas lo hacen voluntariamente para ayudar a gestionar las expectativas de Wall Street).<\/p>\n<p>El argumento a favor de los informes trimestrales es que unos mercados p\u00fablicos eficientes y justos requieren transparencia, por muy molesta que pueda resultar para los CEO, que tienen que pagar a personal para que se encargue del cumplimiento normativo, la contabilidad y las relaciones p\u00fablicas en torno a dicho informe cuatro veces al a\u00f1o.<\/p>\n<p>Incluso si solo se posee <em>una<\/em> acci\u00f3n de una empresa, esa peque\u00f1a participaci\u00f3n nos da derecho a estar al tanto de lo que ocurre entre bastidores con regularidad.<\/p>\n<p>Eliminar los informes trimestrales \u201caumentar\u00eda considerablemente la prima de riesgo del mercado de valores estadounidense en comparaci\u00f3n con sus pares internacionales\u201d, <a href=\"https:\/\/bsky.app\/profile\/peark.es\/post\/3lyur4nucik2h\">escribi\u00f3 George Pearkes<\/a>, estratega macro global de Bespoke Investment Group, en referencia a la propuesta de Trump, en una publicaci\u00f3n de Bluesky. \u201cEsta idea es terrible\u201d, subray\u00f3.<\/p>\n<p>Sin duda, cualquier cambio en el cronograma de informes necesitar\u00eda la <strong><\/strong>aprobaci\u00f3n de la SEC (algo que el presidente de la agencia designado por Trump, <strong><\/strong>Paul Atkins, <strong><\/strong>podr\u00eda proporcionar f\u00e1cilmente) y probablemente tomar\u00eda meses para implementarse.<\/p>\n<p>La Casa Blanca declin\u00f3 hacer comentarios m\u00e1s all\u00e1 de la publicaci\u00f3n de Trump en redes sociales.<\/p>\n<p>En un correo electr\u00f3nico, un portavoz de la SEC afirm\u00f3 que, a petici\u00f3n de Trump, Atkins y la SEC est\u00e1n priorizando esta propuesta para eliminar a\u00fan m\u00e1s las cargas regulatorias innecesarias para las empresas.<\/p>\n<p><strong>En resumen:<\/strong> No es ning\u00fan secreto que a Trump le importa mucho la imagen y no quiere rendir cuentas por \u201cmalos\u201d datos. En sus dos mandatos, el presidente ha mostrado un impulso a ignorar o manipular cifras que podr\u00edan manchar su legado.<\/p>\n<p>El mes pasado, cuando se enfrent\u00f3 a datos que suger\u00edan que sus aranceles estaban da\u00f1ando el mercado laboral estadounidense, <a href=\"https:\/\/www.cnn.com\/2025\/08\/04\/business\/trump\">Trump despidi\u00f3 a la directora de la Oficina de Estad\u00edsticas Laborales<\/a> y afirm\u00f3 que las cifras estaban manipuladas.<\/p>\n<p>\u00bfRecuerdan su obsesi\u00f3n con las multitudes que asistieron a la toma de posesi\u00f3n de 2016? \u00bfO en marzo de 2020, cuando defendi\u00f3 la idea de <a href=\"https:\/\/www.cnn.com\/2020\/07\/14\/politics\/donald-trump-coronavirus-testing\">mantener a los pasajeros en un crucero<\/a> en alta mar porque \u201cprefer\u00eda que el n\u00famero de pasajeros se mantuviera igual\u201d? \u00bfO la vez que fue <a href=\"https:\/\/www.cnn.com\/2023\/09\/26\/politics\/trump-organization-business-fraud\/index.html\">declarado responsable de inflar fraudulentamente<\/a> el valor de sus propiedades inmobiliarias?<\/p>\n<p>Por eso es importante considerar la propuesta de Trump de reducir la transparencia corporativa en el contexto de su intento de ocultar cualquier cifra negativa que pueda estar asociada a su administraci\u00f3n.<\/p>\n<p>Hasta ahora, las ganancias corporativas han resistido en gran medida la guerra comercial de Trump, lo que explica en parte la <a href=\"https:\/\/www.cnn.com\/2025\/09\/15\/business\/stock-market-dow-record-economy-jobs-inflation\" rel=\"noopener noreferrer\" target=\"_blank\">alta rentabilidad<\/a> del mercado burs\u00e1til a pesar de las dificultades econ\u00f3micas. Pero cuanto m\u00e1s tiempo se mantengan los aranceles, mayor ser\u00e1 su impacto en el resultado final.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un d\u00eda ya de por s\u00ed agitado por las noticias para empresas e inversores, el presidente agreg\u00f3 a la mezcla una publicaci\u00f3n en las redes sociales que casualmente suger\u00eda que los reguladores cambiaran por completo un elemento fijo de la vida corporativa estadounidense durante el \u00faltimo medio siglo. Por si te lo perdiste: Este [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466500","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos - Noticias\" \/>\n<meta property=\"og:description\" content=\"En un d\u00eda ya de por s\u00ed agitado por las noticias para empresas e inversores, el presidente agreg\u00f3 a la mezcla una publicaci\u00f3n en las redes sociales que casualmente suger\u00eda que los reguladores cambiaran por completo un elemento fijo de la vida corporativa estadounidense durante el \u00faltimo medio siglo. Por si te lo perdiste: Este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T11:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos\",\"datePublished\":\"2025-09-16T11:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/\"},\"wordCount\":960,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/\",\"name\":\"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-16T11:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos - Noticias","og_description":"En un d\u00eda ya de por s\u00ed agitado por las noticias para empresas e inversores, el presidente agreg\u00f3 a la mezcla una publicaci\u00f3n en las redes sociales que casualmente suger\u00eda que los reguladores cambiaran por completo un elemento fijo de la vida corporativa estadounidense durante el \u00faltimo medio siglo. Por si te lo perdiste: Este [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-16T11:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/"},"author":{"name":"","@id":""},"headline":"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos","datePublished":"2025-09-16T11:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/"},"wordCount":960,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/","name":"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-16T11:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump tiene una nueva propuesta para limitar el acceso del p\u00fablico a los datos econ\u00f3micos","url":"http:\/\/noticiasya.com\/nacional\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/09\/16\/analisis-trump-acceso-publico-datos-economicos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-16T11:03:48Z","datePublished":"2025-09-16T11:03:48Z","dateModified":"2025-09-16T11:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump tiene una nueva propuesta para limitar el acceso del p\\u00fablico a los datos econ\\u00f3micos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/16\\\/analisis-trump-acceso-publico-datos-economicos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/16\\\/analisis-trump-acceso-publico-datos-economicos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-16T11:03:48Z\",\"datePublished\":\"2025-09-16T11:03:48Z\",\"dateModified\":\"2025-09-16T11:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445585,"url":"https:\/\/noticiasya.com\/nacional\/2024\/02\/17\/que-pasara-con-las-empresas-de-trump-tras-su-sentencia-del-juicio-por-fraude-civil-en-nueva-york\/","url_meta":{"origin":1466500,"position":0},"title":"\u00bfQu\u00e9 pasar\u00e1 con las empresas de Trump tras su sentencia del juicio por fraude civil en Nueva York?","author":"","date":"febrero 17, 2024","format":false,"excerpt":"(CNN) --\u00a0Una enorme sentencia de US$ 355 millones y otras medidas punitivas en el juicio por fraude civil en Nueva York contra el expresidente Donald Trump, sus hijos y la Organizaci\u00f3n Trump supondr\u00e1n un golpe muy grande, aunque tal vez no fatal, a sus empresas con sede en el estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464943,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/29\/empresas-aranceles-trump-agosto-trax\/","url_meta":{"origin":1466500,"position":1},"title":"\u00bfC\u00f3mo se preparan las empresas para la entrada en vigor de los aranceles de Trump el 1 de agosto? No hay forma","author":"","date":"julio 29, 2025","format":false,"excerpt":"El 1 de agosto, cientos de pa\u00edses entrar\u00e1n en una nueva relaci\u00f3n comercial con Estados Unidos, luego de que finalice la pausa del presidente Donald Trump en los aranceles \u201crec\u00edprocos\u201d.Miles de empresas estadounidenses enfrentar\u00e1n tambi\u00e9n un nuevo futuro. Sin embargo, tras meses de una pol\u00edtica comercial irregular, planificar con certeza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461187,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/14\/empresas-demandan-gobierno-trump-autoridad-aranceles-trax\/","url_meta":{"origin":1466500,"position":2},"title":"Peque\u00f1as empresas demandan al Gobierno de Trump por la autoridad para imponer aranceles","author":"","date":"abril 14, 2025","format":false,"excerpt":"Un grupo de empresas estadounidenses present\u00f3 una demanda este lunes en la que argumentan que los aranceles del presidente Donald Trump son ilegales bajo la Ley de Poderes Econ\u00f3micos de Emergencia Internacional (IEEPA, por sus siglas en ingl\u00e9s).La demanda fue presentada en el Tribunal de Comercio Internacional de EE.UU. por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467611,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/21\/walmart-suspende-contrataciones-visa-h-1b-trax\/","url_meta":{"origin":1466500,"position":3},"title":"Walmart suspende contrataciones que requieran visa H-1B tras aumento a US$ 100.000 impuesto por Trump","author":"","date":"octubre 21, 2025","format":false,"excerpt":"Walmart, el mayor empleador del sector privado de Estados Unidos, est\u00e1 pausando las ofertas de trabajo a candidatos extranjeros que necesitan visas H-1B para trabajar en Estados Unidos, inform\u00f3 un portavoz de la empresa a CNN.Es un cambio significativo que muestra c\u00f3mo las grandes empresas est\u00e1n modificando sus pol\u00edticas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461543,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/23\/doce-estados-demandan-gobierno-trump-aumentos-aranceles-trax\/","url_meta":{"origin":1466500,"position":4},"title":"Doce estados demandan al Gobierno de Trump por &#171;aumentos de impuestos ilegales&#187; a trav\u00e9s de aranceles","author":"","date":"abril 23, 2025","format":false,"excerpt":"Doce estados demandaron al Gobierno de Trump este mi\u00e9rcoles por \u201cimponer ilegalmente\u201d aumentos de impuestos a los estadounidenses a trav\u00e9s de aranceles.Trump impuso los aranceles a trav\u00e9s de la Ley de Poderes Econ\u00f3micos de Emergencia Internacional (IEEPA, por sus siglas en ingl\u00e9s), que otorga al presidente la autoridad para ejercer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443158,"url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/04\/china-gasto-mas-de-us-55-millones-en-propiedades-de-trump-mientras-el-fue-presidente-segun-muestran-documentos\/","url_meta":{"origin":1466500,"position":5},"title":"China gast\u00f3 m\u00e1s de US$ 5,5 millones en propiedades de Trump mientras \u00e9l fue presidente, seg\u00fan muestran documentos","author":"","date":"enero 4, 2024","format":false,"excerpt":"(CNN) -- El gobierno chino y sus entidades controladas por el estado gastaron m\u00e1s de US$ 5,5 millones en propiedades de Donald Trump mientras \u00e9l estuvo en el cargo, el total de pagos m\u00e1s alto realizado por cualquier pa\u00eds extranjero conocido hasta la fecha, seg\u00fan documentos financieros citados en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1466500"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466500\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1466500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1466500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1466500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}