{"id":1466524,"date":"2025-09-16T14:03:45","date_gmt":"2025-09-16T21:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/"},"modified":"2025-09-16T14:03:45","modified_gmt":"2025-09-16T21:03:45","slug":"esquizofrenia-causas-sintomas-enfermedad-mental-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/","title":{"rendered":"Por qu\u00e9 la esquizofrenia podr\u00eda ser &#171;la m\u00e1s devastadora de las enfermedades mentales&#187;"},"content":{"rendered":"<p>Para Henry Cockburn, el inicio de la esquizofrenia se sinti\u00f3 como puro sentido com\u00fan.<\/p>\n<p>Era febrero de 2002, y el estudiante de arte de 20 a\u00f1os se hab\u00eda alejado de la Universidad de Brighton para satisfacer su deseo de una vida fuera de la ciudad. Tambi\u00e9n quer\u00eda emprender un viaje de 70 millas (unos 113 kil\u00f3metros) descalzo de regreso a su hogar de la infancia en Canterbury.<\/p>\n<p>A unas 15 millas (24 kil\u00f3metros) de su caminata, escuch\u00f3 aviones a lo lejos, y le dijo a CNN que cre\u00eda \u201cque de alguna manera una fuerza maligna sab\u00eda que me hab\u00eda ido\u201d.<br \/>Cockburn cre\u00eda con absoluta certeza que lo estaban siguiendo.<\/p>\n<p>La soluci\u00f3n, pens\u00f3, era sumergirse en las g\u00e9lidas aguas de la marea del estuario de Newhaven y nadar lejos de la presencia maligna. Pescadores lo encontraron y lo rescataron justo antes de que se desmayara por hipotermia.<\/p>\n<p>Despu\u00e9s de ser reanimado en un hospital general, fue trasladado a un hospital psiqui\u00e1trico, donde los m\u00e9dicos le diagnosticaron esquizofrenia. La instituci\u00f3n fue la primera de varias donde pasar\u00eda los siguientes ocho a\u00f1os.<\/p>\n<p>La esquizofrenia es simult\u00e1neamente una de las enfermedades mentales m\u00e1s famosas y una de las m\u00e1s incomprendidas. <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.who.int%2Fnews-room%2Ffact-sheets%2Fdetail%2Fschizophrenia&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571584505%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=KpvCnrRSI%2B7QDRdAjg7KgE7PmaVm1leGfUR%2FIZIQMz4%3D&#038;reserved=0\">Afecta al 0,32 % de la poblaci\u00f3n mundial<\/a>, o alrededor de 24 millones de personas, y es un trastorno cerebral cr\u00f3nico a menudo marcado por psicosis, delirios, alucinaciones, falta de motivaci\u00f3n y pensamiento y habla desorganizados, seg\u00fan la <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.psychiatry.org%2Fpatients-families%2Fschizophrenia%2Fwhat-is-schizophrenia&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571600929%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=WgJ56bMFUnfjusypugqW7SAmlCilCToWlK660XCZfi4%3D&#038;reserved=0\">American Psychiatric Association<\/a>. El caso de Cockburn refleja un patr\u00f3n t\u00edpico de inicio: en la edad adulta temprana, una ruptura psicol\u00f3gica en creencias falsas, alucinaciones y paranoia, todo lo cual escala con el tiempo.<\/p>\n<p>\u201cLo vi m\u00e1s como un despertar espiritual y no como esquizofrenia paranoide\u201d, record\u00f3 Cockburn. \u201cCasi sent\u00ed que estaba huyendo, y si eres parte del sistema y te sales del sistema, al sistema no le gusta eso.<\/p>\n<p>\u201cEstaba un poco molesto y enojado, como, \u2018\u00bfPor qu\u00e9 la gente no puede entenderme?\u2019\u201d, agreg\u00f3 Cockburn. \u201cAhora puedo ver un poco m\u00e1s su punto de vista\u201d.<\/p>\n<p>Parte de la confusi\u00f3n sobre la esquizofrenia puede originarse en el nombre del propio trastorno. Acu\u00f1ado por el psiquiatra suizo Dr. Paul Eugen Bleuler en 1908, \u201cesquizofrenia\u201d deriva de las palabras griegas \u201cschizo\u201d, que significa \u201cdividir\u201d, y \u201cphrene\u201d, o \u201cmente\u201d. Para describir el grave aislamiento social de algunos pacientes con esquizofrenia. Bleuler <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpmc.ncbi.nlm.nih.gov%2Farticles%2FPMC3757918%2F&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571633403%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=vWvd4%2BfTUPhlByN0FCoBtiI3OAr%2Fta%2FjPVRRKmotu48%3D&#038;reserved=0\">tambi\u00e9n ide\u00f3 el t\u00e9rmino \u201cautismo\u201d<\/a>.<\/p>\n<p>A principios del siglo XX, Bleuler propuso que el trastorno estaba marcado por una \u201cdivisi\u00f3n de las funciones psicol\u00f3gicas\u201d por la cual \u201cla personalidad pierde su unidad\u201d.<\/p>\n<p>La idea de que la esquizofrenia significa una mente dividida ha contribuido a la creencia generalizada en contextos m\u00e1s formales de que la condici\u00f3n es como el <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fmy.clevelandclinic.org%2Fhealth%2Fdiseases%2F9792-dissociative-identity-disorder-multiple-personality-disorder&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571651706%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=lOduwMGjdvmJ3YeelW8YC2tPcUqY0Rk%2Fde39LwsikEc%3D&#038;reserved=0\">trastorno de identidad disociativo<\/a>, anteriormente llamado trastorno de personalidad dividida o m\u00faltiple, dijo el Dr. Daniel Weinberger, director ejecutivo del Lieber Institute for Brain Development. El trastorno de identidad disociativo, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fmy.clevelandclinic.org%2Fhealth%2Fdiseases%2F9792-dissociative-identity-disorder-multiple-personality-disorder&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571670477%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=%2BjtrkyrqeyIreg40OenJw7bFM75hodlCQkwHmWLIPzY%3D&#038;reserved=0\">causado por un trauma<\/a>, ocurre cuando dos o m\u00e1s personalidades distintivas controlan el comportamiento de una persona, causando lagunas en la memoria cuando las personalidades cambian.<\/p>\n<p>M\u00e1s all\u00e1 de esas percepciones err\u00f3neas sobre su naturaleza subyacente, la esquizofrenia es uno de los trastornos de salud mental m\u00e1s estigmatizados, indic\u00f3 el Dr. Deepak D\u2019Souza, profesor de psiquiatr\u00eda Vikram Sodhi \u201992 y director del Grupo de Investigaci\u00f3n de Neurofarmacolog\u00eda de la Esquizofrenia en la Universidad de Yale.<\/p>\n<p>Existe un estereotipo generalizado de que las personas con esquizofrenia son una amenaza para los dem\u00e1s \u2014 \u201cla persona sin hogar caminando descalza en invierno gritando a nadie en particular (o el) asesino en masa impulsado por sus s\u00edntomas a matar extra\u00f1os\u201d, dijo el Dr. Jeffrey Lieberman, profesor de psiquiatr\u00eda Lawrence C.<br \/>Kolb en la Universidad de Columbia.<\/p>\n<p>Es la condici\u00f3n que la gente \u201casocia con la locura, la psicosis y la demencia\u201d, dijo Lieberman, quien es el autor de <a href=\"https:\/\/www.simonandschuster.com\/books\/Malady-of-the-Mind\/Jeffrey-A-Lieberman\/9781982136420\">\u201cMalady of the Mind<\/a>: Schizophrenia and the Path to Prevention\u201d. Si bien algunos de estos estereotipos se basan en s\u00edntomas reales que experimentan algunos pacientes, no reflejan la realidad de todos los pacientes y pueden impedir una visi\u00f3n hol\u00edstica y compasiva de la esquizofrenia como un trastorno tratable que suele ser m\u00e1s perjudicial para el paciente que para los dem\u00e1s.<\/p>\n<p>\u201cLa forma en que la sociedad lo ha abordado \u2014desde la antig\u00fcedad hasta la \u00e9poca medieval, incluso hasta el siglo XXI\u2014 es la de aislar o segregar a las personas con estos trastornos mentales graves\u201d, dijo Lieberman.<\/p>\n<p>Para empeorar las cosas, entre las personas que no tienen esquizofrenia, tambi\u00e9n existe el uso coloquial popular de \u201cesquizofr\u00e9nico\u201d o \u201cesquizo\u201d para describir el sentirse contradictorio o abrumado por tener m\u00faltiples factores estresantes o responsabilidades simult\u00e1neamente.<\/p>\n<p>Las percepciones err\u00f3neas y los miedos sobre la esquizofrenia pueden dificultar que las personas reconozcan sus signos y busquen ayuda para s\u00ed mismas o para otros, dicen los expertos. Esa ayuda es fundamental ya que el trastorno est\u00e1 asociado con problemas de salud mental concurrentes, una menor calidad y esperanza de vida, y tasas m\u00e1s altas de discapacidad, seg\u00fan el <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.nimh.nih.gov%2Fhealth%2Fstatistics%2Fschizophrenia&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571686990%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=v9XMvTZvvOYxdtxfK3G9YHwWYhLGOAMvLXqiESmGg7g%3D&#038;reserved=0\">Instituto Nacional de Salud Mental<\/a>.<\/p>\n<p>En consecuencia, entre algunos expertos existe un <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fdoi.org%2F10.1016%2Fj.schres.2021.08.034&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571703302%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=LlAVt2yAt1fuVBw%2BCaAkyicilSO%2BAdwy%2FGD3TO%2Fy4j4%3D&#038;reserved=0\">creciente inter\u00e9s<\/a> en cambiar el nombre de este trastorno cerebral cr\u00f3nico. S\u00edndrome de percepci\u00f3n alterada, s\u00edndrome del espectro psic\u00f3tico y trastorno de integraci\u00f3n neuroemocional fueron las alternativas m\u00e1s apoyadas en una <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpubmed.ncbi.nlm.nih.gov%2F34688117%2F&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571719610%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=A1n2u6XBtmuQf8tsgAW2Ps1ckL9E5aHPmV1r5lDL7cY%3D&#038;reserved=0\">encuesta de 2021<\/a> a casi 1.200 personas, incluyendo a aquellos que hab\u00edan experimentado enfermedades mentales, familiares, cl\u00ednicos, investigadores, funcionarios gubernamentales y el p\u00fablico en general.<\/p>\n<p>Los s\u00edntomas de la esquizofrenia suelen aparecer entre los 15 y los 25 a\u00f1os, seg\u00fan los expertos.<\/p>\n<p>A las personas les pod\u00eda ir bien o incluso muy bien en sus vidas, y de repente tienen lo que los expertos llaman un \u201cprimer brote\u201d en su capacidad para funcionar normalmente, dijo Weinberger, tambi\u00e9n profesor de psiquiatr\u00eda, neurolog\u00eda, neurociencia y medicina gen\u00e9tica en la Universidad Johns Hopkins.<\/p>\n<p>\u201cPara m\u00ed, (la esquizofrenia) es la m\u00e1s devastadora de las enfermedades mentales \u2014porque ataca antes de que una persona alcance su potencial\u201d, dijo D\u2019Souza.<\/p>\n<p>La investigaci\u00f3n sugiere que esta interrupci\u00f3n puede deberse a alteraciones en los <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpmc.ncbi.nlm.nih.gov%2Farticles%2FPMC3080672%2F&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571735713%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=PEZbs4WQhXgiX8XTRixOaion2YeqV4bQF3gLReQ8SAI%3D&#038;reserved=0\">procesos normales de neurodesarrollo<\/a> que ocurren a medida que los adolescentes maduran \u2014especialmente porque el extremo superior del rango de edad t\u00edpico de aparici\u00f3n es cuando el cerebro completa su maduraci\u00f3n, explic\u00f3 D\u2019Souza. Pero para algunas personas, el escenario para tales cambios puede establecerse tan temprano como en la infancia y requerir 20 a\u00f1os de maduraci\u00f3n cerebral para que los efectos se hagan evidentes, dijo Weinberger.<\/p>\n<p>Hay formas de esquizofrenia que pueden comenzar antes, pero es raro, dijo D\u2019Souza.<\/p>\n<p>La esquizofrenia ocurre predominantemente en hombres, a\u00f1adi\u00f3. Aun as\u00ed, \u201chay un segundo pico interesante en las tasas de esquizofrenia que ocurre a <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpmc.ncbi.nlm.nih.gov%2Farticles%2FPMC5688947%2F&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571752085%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=8jk8C7sqfFG%2BtPemeMQYktiNlHoc7Zvat6yRzNM4%2BCA%3D&#038;reserved=0\">principios de los 50<\/a>, y eso es predominantemente entre mujeres\u201d, afirm\u00f3 D\u2019Souza. \u201cSe cree que est\u00e1 relacionado con la menopausia\u201d.<\/p>\n<p>Lo que causa directamente la esquizofrenia no est\u00e1 claro, pero existen varios factores de riesgo conocidos, seg\u00fan Weinberger. Esos incluyen la qu\u00edmica cerebral y la gen\u00e9tica que aumentan la probabilidad de que, con suficientes factores de riesgo acumulados, alguien desarrolle el trastorno. Muchos estudios de neuroimagen tambi\u00e9n han mostrado anomal\u00edas estructurales en los cerebros de personas con esquizofrenia, pero nada lo suficientemente consistente en todas las poblaciones de pacientes como para convertirse en caracter\u00edsticas distintivas del trastorno.<\/p>\n<p>Un embarazo complicado por factores como la preeclampsia, el trabajo de parto prolongado o el bajo peso al nacer puede duplicar el riesgo de un ni\u00f1o, dijo Weinberger. El estr\u00e9s y el trauma tambi\u00e9n pueden <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.mayoclinic.org%2Fdiseases-conditions%2Fschizophrenia%2Fsymptoms-causes%2Fsyc-20354443&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571768194%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=uoysOQ8ur7WiN1nDYKvZ92VwBJGLFVB0pCmet1Ojm8A%3D&#038;reserved=0\">aumentar la probabilidad<\/a> de esquizofrenia.<\/p>\n<p>Tomar drogas que alteran la mente como adolescente o adulto joven es otro factor de riesgo, y los investigadores encuentran cada vez m\u00e1s <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2021%2F07%2F22%2Fhealth%2Fmarijuana-schizophrenia-study-wellness&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571784439%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=jeCN1eKgPZOtA4eoSb%2Fn8B284EK7rojYJ9IKRTT8QEs%3D&#038;reserved=0\">asociaciones entre el consumo de cannabis y la esquizofrenia<\/a>.<\/p>\n<p>Ese aumento puede deberse en parte a que hoy la <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2022%2F07%2F25%2Fhealth%2Fmarijuana-potency-addiction-study-wellness&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571800496%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=llF8e0JU8R8C1PX4oSoEvTgbTjZbXsVYCA2R0zr9fKo%3D&#038;reserved=0\">potencia del cannabis<\/a> var\u00eda de <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fonlinelibrary.wiley.com%2Fdoi%2Ffull%2F10.1111%2Fadd.15253&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571818980%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=bnQ%2FhECNnNecGt9RtVnNxVXIsQUulNXnzsjHGEktPgo%3D&#038;reserved=0\">cinco a 20 veces<\/a> lo que sol\u00eda ser en la d\u00e9cada de 1970, dijo D\u2019Souza. Adem\u00e1s, \u201clos j\u00f3venes la est\u00e1n usando en un momento en que el cerebro est\u00e1 experimentando una gran agitaci\u00f3n\u201d.<\/p>\n<p>Cuando Cockburn fue diagnosticado despu\u00e9s de su episodio de nataci\u00f3n a los 20 a\u00f1os, acababa de dejar de consumir marihuana unos cuatro d\u00edas a la semana y alcohol dos o tres d\u00edas a la semana desde que ten\u00eda 14 a\u00f1os, dijo. Cockburn no cree que el consumo de drogas haya causado su esquizofrenia, pero tambi\u00e9n hab\u00eda comenzado a comportarse de manera inusual \u2014caminando descalzo en invierno\u2014 antes de dejar las adicciones.<\/p>\n<p>Los qu\u00edmicos activos del cannabis imitan las mol\u00e9culas cerebrales naturales llamadas endocannabinoides, que estimulan los receptores cannabinoides; juntos, estos dos elementos representan el <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.health.harvard.edu%2Fblog%2Fthe-endocannabinoid-system-essential-and-mysterious-202108112569&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571835444%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=WOCDRWWDiFwpFfG9hRUMHvjN1Gqbw61Cl7hWJkfdC%2BM%3D&#038;reserved=0\">sistema endocannabinoide del cerebro<\/a>. El sistema no est\u00e1 ah\u00ed para facilitar el \u201ccoloc\u00f3n\u201d, dijo D\u2019Souza, sino para ayudar a regular los niveles y actividades de los neurotransmisores que afectan nuestro estado de \u00e1nimo, aprendizaje, temperatura corporal y m\u00e1s. Tambi\u00e9n tiene un papel clave en el neurodesarrollo, controlando d\u00f3nde migran algunas neuronas, cu\u00e1les se eliminan y si alguna se altera de manera poco saludable.<\/p>\n<p>\u201cImagina que este <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.health.harvard.edu%2Fblog%2Fthe-endocannabinoid-system-essential-and-mysterious-202108112569&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571852364%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=vwVvEqv3qXXkRApN1rZzpFb3afr3mdpZVfr8nXHI98s%3D&#038;reserved=0\">sistema endocannabinoide<\/a> funciona normalmente y luego es bombardeado con THC\u201d, coment\u00f3 D\u2019Souza. Ese es el compuesto delta-9-tetrahiDrocannabinol, el principal ingrediente activo del cannabis, que se cree que es responsable de los efectos psicoactivos de su uso.<\/p>\n<p>Weinberger cree que la investigaci\u00f3n sobre el cannabis y la esquizofrenia es controvertida, ya que la causa y el efecto no pueden inferirse de las asociaciones, dijo.<\/p>\n<p>Pero la idea no es nueva, seg\u00fan D\u2019Souza, y cit\u00f3 el trabajo del siglo XIX del psiquiatra franc\u00e9s Dr. Jacques Joseph Moreau, quien detall\u00f3 que los <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.sciencedirect.com%2Fscience%2Farticle%2Fabs%2Fpii%2FS0074774206780102&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571869359%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=bC0e5M068fKdsvOvCQWEvtvkMjej4zk4FByOCuLIGak%3D&#038;reserved=0\">usuarios de hach\u00eds<\/a> experimentaban delirios, alucinaciones y paranoia, todas cosas ahora asociadas con la esquizofrenia.<\/p>\n<p>Existen varias categor\u00edas de s\u00edntomas de esquizofrenia, y pueden afectar c\u00f3mo se sienten, piensan y act\u00faan las personas.<\/p>\n<p>Los delirios, o creer en cosas que no son verdaderas o reales, y actuar en consecuencia son comunes. Pueden ser \u201cextremadamente inquietantes, atormentadores y muy incapacitantes\u201d, dijo Weinberger.<\/p>\n<p>Alguien con delirios puede pensar que la Agencia Central de Inteligencia (CIA) ha infiltrado su tel\u00e9fono para espiarlos, dijo Weinberger, y por lo tanto, quitar la bater\u00eda del tel\u00e9fono. Cockburn dijo que la primavera pasada estaba leyendo la novela de C.S. Lewis \u201cThe Magician\u2019s Nephew\u201d y se fascin\u00f3 con la capacidad de Aslan, el le\u00f3n, para cantar el mundo de Narnia y crearlo a partir de un vac\u00edo oscuro.<\/p>\n<p>\u201cPens\u00e9 que as\u00ed hab\u00eda empezado el mundo\u201d, coment\u00f3 Cockburn. \u201cLeo libros de fantas\u00eda y luego busco la fantas\u00eda dentro de la realidad de este mundo\u201d.<\/p>\n<p>Cockburn tambi\u00e9n sinti\u00f3 que las plantas y los p\u00e1jaros pod\u00edan hablarle, y que pod\u00eda \u201cconversar con los esp\u00edritus\u201d, a\u00f1adi\u00f3. Una conversaci\u00f3n con un \u00e1rbol tuvo un gran impacto en \u00e9l: \u201cMe dijo que pod\u00eda rapear, y eso es lo que empec\u00e9 a hacer despu\u00e9s de eso\u201d.<\/p>\n<p>Durante algunas de las fugas de Cockburn de hospitales psiqui\u00e1tricos \u2014un h\u00e1bito que lo llev\u00f3 a ser admitido en cinco o seis hospitales mentales durante esos ocho a\u00f1os\u2014 se desnudaba y exploraba un bosque en un d\u00eda nevado.<\/p>\n<p>Muchas personas con esquizofrenia tambi\u00e9n tienen alucinaciones, como hablar con alguien que no est\u00e1 all\u00ed, dijo Weinberger. Cockburn a veces ve\u00eda francotiradores fuera de la ventana de su habitaci\u00f3n de hospital, indic\u00f3.<\/p>\n<p>Los delirios y las alucinaciones pueden llevar al miedo y la paranoia, se\u00f1al\u00f3 Weinberger. Esa paranoia puede hacer que los pacientes piensen que otros est\u00e1n hablando de ellos, conspirando contra ellos, o afectando o leyendo los pensamientos en sus propios cerebros, lo que \u201clos hace sentir muy inc\u00f3modos en entornos p\u00fablicos, porque sienten que no est\u00e1n seguros\u201d, a\u00f1adi\u00f3. \u201cLa mayor\u00eda de las personas con esquizofrenia son mucho m\u00e1s propensas a sentirse inseguras que a hacer que t\u00fa te sientas as\u00ed\u201d.<\/p>\n<p>Las alucinaciones tambi\u00e9n suelen tomar la forma de voces que a veces pueden empezar siendo benignas y oscurecerse con el tiempo, dijeron los expertos. Muchos pacientes a menudo escuchan varias voces que mantienen una conversaci\u00f3n sobre ellos.<\/p>\n<p>Cuando las voces le dec\u00edan a Cockburn que \u201cno hab\u00eda redenci\u00f3n para m\u00ed\u201d, recordaba: \u201cTen\u00eda d\u00edas realmente malos en los que sent\u00eda que me arrastraban a un mundo sin Dios, supongo, y mi estado de \u00e1nimo deca\u00eda\u201d.<\/p>\n<p>Las voces tambi\u00e9n pueden ordenar a alguien que realice acciones dif\u00edciles de resistir, incluso cuando son autodestructivas, dijo Weinberger. Probablemente <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpmc.ncbi.nlm.nih.gov%2Farticles%2FPMC1845151%2F&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571902845%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=XGNr5U%2Fzr5lOYKH0VmiOBY5kn4BvrapBnOHwL%2BF8gCs%3D&#038;reserved=0\">entre el 5 % y el 13 %<\/a> de los pacientes mueren por suicidio, y a veces eso se debe a seguir \u00f3rdenes alucinatorias para realizar acciones letales, agreg\u00f3 Weinberger.<\/p>\n<p>En estudios de neuroimagen de pacientes que escuchan voces, \u201clas \u00e1reas del cerebro responsables del lenguaje y la generaci\u00f3n del habla se iluminan\u201d, explic\u00f3 D\u2019Souza.<\/p>\n<p>Las personas con esquizofrenia pueden tener d\u00e9ficits cognitivos como dificultad para crear y seguir un plan, procesar informaci\u00f3n complicada o usar informaci\u00f3n para llegar a conclusiones apropiadas, dijo Weinberger. El habla desorganizada, los movimientos inusuales y la falta de motivaci\u00f3n son otros s\u00edntomas comunes, al igual que el aislamiento social, que Cockburn hab\u00eda comenzado a exhibir antes de su primera hospitalizaci\u00f3n.<\/p>\n<p>\u201cLa esquizofrenia es un problema muy incapacitante\u201d, dijo Weinberger.<\/p>\n<p>La esquizofrenia no se puede curar, dijo Lieberman, pero se puede aliviar sustancialmente con una combinaci\u00f3n de <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.mayoclinic.org%2Fdiseases-conditions%2Fschizophrenia%2Fdiagnosis-treatment%2Fdrc-20354449&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571918664%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=KMJWkIWl6NujfqBQwnhFHzl9LNqwHTo%2FdCnEOlycvOU%3D&#038;reserved=0\">medicamentos y terapias<\/a>, aunque acceder a atenci\u00f3n multidisciplinaria y conseguir que el seguro la cubra sigue siendo dif\u00edcil, incluso para los proveedores de atenci\u00f3n m\u00e9dica que desean ofrecer esos recursos a sus pacientes.<\/p>\n<p>Los medicamentos m\u00e1s efectivos para los pacientes son los antipsic\u00f3ticos, seg\u00fan Lieberman, ya que esos medicamentos <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fmy.clevelandclinic.org%2Fhealth%2Ftreatments%2F24692-antipsychotic-medications&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571934565%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=3H%2BoXTCAjLn9JW6U%2Fo4qZSBvPdWY%2FbmEbd8QnZAj8CQ%3D&#038;reserved=0\">controlan los elementos<\/a> de la psicosis que afectan los pensamientos y las percepciones. Las dificultades cognitivas son m\u00e1s dif\u00edciles de tratar, dijo Weinberger.<\/p>\n<p>Al mismo tiempo, a\u00f1adi\u00f3 Weinberger, el mayor obst\u00e1culo para el tratamiento es que los pacientes no tomen sus medicamentos, a veces debido a la anosognosia, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.nami.org%2Fabout-mental-illness%2Fcommon-with-mental-illness%2Fanosognosia%2F&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571950457%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=UBbhP1AzDrpTynnKRPOWUjDQRZ1HDFlDztAM5M2%2Bp1U%3D&#038;reserved=0\">la falta de conciencia de estar enfermo<\/a>, que afecta a entre el 50 % y el 98 % de las personas con esquizofrenia. Otras veces, la falta de adherencia se debe a los efectos secundarios inc\u00f3modos del medicamento. Pero ahora que los expertos comprenden mejor algunos factores causales de la esquizofrenia, otros medicamentos que <a href=\"https:\/\/info.thelancet.com\/e3t\/Ctc\/RF+113\/cs6tF04\/VWCXBV8mKV--W6svZxF4Jd0c9W2F3lfm5xBfCFN2dmMxz3qgyTW8wLKSR6lZ3psW7bcCBD1_xCl7W20wsmb2lm2LsW7MT-KL5DGNmxN6PyNNBQpdYnW8LB7ns30JNBhW1pHHmb7nb4GTW1Qyjrp5YMkCCW1ZcDn95TNNFqN675bf231m84W2_9C7k9kWWytW4L7BL75kV9nSW3Hk8Jb6_FtfgN1TFFq1fbrP9W4RpS0934t9n4W2N003_5k3jPNW1gM1lV4z6KyzW8S7ylF42-k44W17BztH4qjV7XW1q_ZK04G3jqqW4tnFW98xT6_HVJkz1h3x4XXNW3WNZVX5qpbHbW7M4VqG88JRLKW5B9Nxx2pX94nN6MDzLQFtT0qW5mwJKX4GhLPSW8trjhr4kw0ngW3vb4b76MvtH3f18-80C04\">se est\u00e1n estudiando<\/a> o desarrollando deber\u00edan ser mucho m\u00e1s efectivos y con menos efectos secundarios, dijo Weinberger.<\/p>\n<p>Las terapias efectivas incluyen la terapia conversacional, el entrenamiento en habilidades sociales y la <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.mountsinai.org%2Fcare%2Fpsychiatry%2Fservices%2Fschizophrenia%2Ftreatment%2Fcbtp&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571967416%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Lhk2mwc4BDGmyj6eilkRjvYmlonHZRyDhztiSJZgn5s%3D&#038;reserved=0\">terapia cognitivo-conductual<\/a> (TCC) para la psicosis, dijeron Weinberger y D\u2019Souza. Con un tratamiento integral, los pacientes pueden aprender a ignorar o responder a los impulsos o voces de formas m\u00e1s saludables.<\/p>\n<p>Desde que Cockburn fue dado de alta de su \u00faltimo hospital en 2011, ha logrado en gran medida justo esto, gracias a la TCC para la psicosis, los medicamentos y el asesoramiento. Justo antes de su entrevista con CNN, hab\u00eda salido a correr. Sinti\u00f3 algo m\u00e1s all\u00e1 de s\u00ed mismo que lo impulsaba a correr m\u00e1s de lo habitual, pero en lugar de obedecer, se dio la vuelta, dijo.<\/p>\n<p>\u201cMe sent\u00ed un poco culpable por ello\u201d, afirm\u00f3 Cockburn. \u201cPero luego, a medida que me acercaba al final de la carrera, me di cuenta de que no habr\u00eda podido terminarla si no hubiera regresado en ese momento. Supongo que el sentido com\u00fan me domin\u00f3\u201d.<\/p>\n<p>Las citas no existen para Cockburn, dijo, pero tiene amigos cercanos y familiares y vive con un compa\u00f1ero de piso en Inglaterra. Recibe beneficios por discapacidad del gobierno, pero a veces tambi\u00e9n se gana la vida con sus pinturas. Todav\u00eda sufre ataques de p\u00e1nico ocasionalmente, pero la reconfortante quietud de sentarse en una habitaci\u00f3n oscura y fresca los ayuda a pasar. Cockburn tambi\u00e9n ha terminado su licenciatura y trata de enfocarse m\u00e1s en lo bueno de la vida que en lo malo.<\/p>\n<p>En 2011, coescribi\u00f3 una memoria con su padre, el periodista Patrick Cockburn, titulada <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.amazon.com%2FHenrys-Demons-Father-Journey-Madness%2Fdp%2F1439154716&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432571985453%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=1mIJqQnER2W2RufpKnh5v60B6QImLKfDdX6t1h2h27g%3D&#038;reserved=0\">\u201cHenry\u2019s Demons:<\/a> A Father and Son\u2019s Journey Out of Madness\u201d. El libro fue preseleccionado para un premio por los ahora desaparecidos Costa Book Awards y dramatizado en una <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.bbc.co.uk%2Fprogrammes%2Fb0150mld&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432572002687%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=wTFFGnnik5svzz2sWGeQoSJl8m47EE%2FznuGsKvsSkhs%3D&#038;reserved=0\">obra de radio para BBC Radio 4<\/a>.<\/p>\n<p>\u201cSuena cursi, pero no se rindan\u201d, aconseja Cockburn a otras personas con esquizofrenia y a sus <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.nhs.uk%2Fmental-health%2Fconditions%2Fschizophrenia%2Fliving-with%2F&#038;data=05%7C02%7Ckristen.rogers%40cnn.com%7C4e9c75e6391e46e3f91b08dde4ede3db%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638918432572018882%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=tQMeDrw8%2F3rMhFhUadDwPPHwD1MUvWbVzuQ2%2FSsPav0%3D&#038;reserved=0\">seres queridos<\/a>. \u201cSiempre creo que incluso en tus momentos m\u00e1s oscuros, siempre hay alguien que te cuida en alg\u00fan lugar. No est\u00e1s solo\u201d.<\/p>\n<ul>\n<li><strong>C\u00f3mo obtener ayuda para alguien que podr\u00eda suicidarse: <\/strong>Llama al 1-800-273-8255 en EE.UU. para comunicarte con la L\u00ednea Nacional de Prevenci\u00f3n del Suicidio. Brinda asistencia gratuita y confidencial las 24 horas del d\u00eda, los siete d\u00edas de la semana, para personas en crisis suicidas o angustiadas. Puedes obtener m\u00e1s informaci\u00f3n sobre sus servicios <a href=\"https:\/\/suicidepreventionlifeline.org\/talk-to-someone-now\/\">aqu\u00ed<\/a>, incluida su gu\u00eda sobre <a href=\"https:\/\/suicidepreventionlifeline.org\/help-someone-else\/\">qu\u00e9 hacer si se identifican se\u00f1ales suicidas en las redes sociales<\/a>. Tambi\u00e9n puedes llamar al 1-800-273-8255 para hablar con alguien sobre c\u00f3mo puedes ayudar a una persona en crisis. Llama al 1-866-488-7386 para <a href=\"https:\/\/www.thetrevorproject.org\/#sm.0001gmc01nq5ses5x351cfukyu4ot\">TrevorLifeline<\/a>, un servicio de asesoramiento para la prevenci\u00f3n de suicidios para la comunidad LGBTQ. Para obtener asistencia fuera de EE.UU.,<a href=\"https:\/\/www.iasp.info\/resources\/Crisis_Centres\/\"> la Asociaci\u00f3n Internacional para la Prevenci\u00f3n del Suicidio<\/a> proporciona un directorio mundial de recursos y l\u00edneas directas internacionales. Tambi\u00e9n puedes recurrir a <a href=\"https:\/\/www.befrienders.org\/need-to-talk\">Befrienders Worldwide.<\/a> <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/01\/13\/depresion-donde-buscar-ayuda-argentina-mexico-colombia-peru-espana-ecuador\/\">Mira aqu\u00ed d\u00f3nde buscar ayuda en pa\u00edses de Am\u00e9rica Latina y Espa\u00f1a.<\/a><\/li>\n<li>Para obtener m\u00e1s informaci\u00f3n sobre las <strong>causas, los s\u00edntomas y los tratamientos<\/strong> de la esquizofrenia, <a href=\"https:\/\/mhanational.org\/conditions\/schizophrenia\/\">visite Mental Health America<\/a>.<\/li>\n<li>Para <strong>encontrar un profesional de la salud mental<\/strong>, visite Mental Health America <a href=\"https:\/\/mhanational.org\/resources\/finding-therapy\/\">si se encuentra en Estados Unidos<\/a> o Mind en el <a href=\"https:\/\/www.mind.org.uk\/information-support\/types-of-mental-health-problems\/schizophrenia\/useful-contacts\/\">Reino Unido<\/a>. La Alianza para la Acci\u00f3n contra la Esquizofrenia y la Psicosis ofrece <a href=\"https:\/\/sczaction.org\/treatment\/\">m\u00e1s consejos<\/a> para encontrar un tratamiento eficaz.<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para Henry Cockburn, el inicio de la esquizofrenia se sinti\u00f3 como puro sentido com\u00fan. Era febrero de 2002, y el estudiante de arte de 20 a\u00f1os se hab\u00eda alejado de la Universidad de Brighton para satisfacer su deseo de una vida fuera de la ciudad. Tambi\u00e9n quer\u00eda emprender un viaje de 70 millas (unos 113 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466524","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 la esquizofrenia podr\u00eda ser &quot;la m\u00e1s devastadora de las enfermedades mentales&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 la esquizofrenia podr\u00eda ser &quot;la m\u00e1s devastadora de las enfermedades mentales&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Para Henry Cockburn, el inicio de la esquizofrenia se sinti\u00f3 como puro sentido com\u00fan. Era febrero de 2002, y el estudiante de arte de 20 a\u00f1os se hab\u00eda alejado de la Universidad de Brighton para satisfacer su deseo de una vida fuera de la ciudad. Tambi\u00e9n quer\u00eda emprender un viaje de 70 millas (unos 113 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T21:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Por qu\u00e9 la esquizofrenia podr\u00eda ser &#171;la m\u00e1s devastadora de las enfermedades mentales&#187;\",\"datePublished\":\"2025-09-16T21:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/\"},\"wordCount\":3110,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/\",\"name\":\"Por qu\u00e9 la esquizofrenia podr\u00eda ser \\\"la m\u00e1s devastadora de las enfermedades mentales\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-16T21:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 la esquizofrenia podr\u00eda ser &#171;la m\u00e1s devastadora de las enfermedades mentales&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 la esquizofrenia podr\u00eda ser \"la m\u00e1s devastadora de las enfermedades mentales\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 la esquizofrenia podr\u00eda ser \"la m\u00e1s devastadora de las enfermedades mentales\" - Noticias","og_description":"Para Henry Cockburn, el inicio de la esquizofrenia se sinti\u00f3 como puro sentido com\u00fan. Era febrero de 2002, y el estudiante de arte de 20 a\u00f1os se hab\u00eda alejado de la Universidad de Brighton para satisfacer su deseo de una vida fuera de la ciudad. Tambi\u00e9n quer\u00eda emprender un viaje de 70 millas (unos 113 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-16T21:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/"},"author":{"name":"","@id":""},"headline":"Por qu\u00e9 la esquizofrenia podr\u00eda ser &#171;la m\u00e1s devastadora de las enfermedades mentales&#187;","datePublished":"2025-09-16T21:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/"},"wordCount":3110,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/","name":"Por qu\u00e9 la esquizofrenia podr\u00eda ser \"la m\u00e1s devastadora de las enfermedades mentales\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-16T21:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 la esquizofrenia podr\u00eda ser &#171;la m\u00e1s devastadora de las enfermedades mentales&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Por qu\u00e9 la esquizofrenia podr\u00eda ser &#171;la m\u00e1s devastadora de las enfermedades mentales&#187;","url":"http:\/\/noticiasya.com\/nacional\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/09\/16\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-16T21:03:45Z","datePublished":"2025-09-16T21:03:45Z","dateModified":"2025-09-16T21:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Por qu\\u00e9 la esquizofrenia podr\\u00eda ser &#171;la m\\u00e1s devastadora de las enfermedades mentales&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/16\\\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/16\\\/esquizofrenia-causas-sintomas-enfermedad-mental-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-16T21:03:45Z\",\"datePublished\":\"2025-09-16T21:03:45Z\",\"dateModified\":\"2025-09-16T21:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457092,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/31\/china-presenta-prototipo-tren-alta-velocidad-mas-rapido-mundo-trax\/","url_meta":{"origin":1466524,"position":0},"title":"China presenta prototipo de lo que podr\u00eda ser el tren de alta velocidad m\u00e1s r\u00e1pido del mundo","author":"","date":"diciembre 31, 2024","format":false,"excerpt":"China present\u00f3 un prototipo de su tren de alta velocidad de pr\u00f3xima generaci\u00f3n, un veh\u00edculo que, seg\u00fan afirma, est\u00e1 en camino de ser el m\u00e1s r\u00e1pido del mundo.El CR450, que se present\u00f3 en Beijing el 29 de diciembre, hab\u00eda alcanzado velocidades de prueba de hasta 450 kil\u00f3metros (281 millas) por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461137,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/13\/katy-perry-gayle-king-otras-cuatro-mujeres-espacio-trax\/","url_meta":{"origin":1466524,"position":1},"title":"Katy Perry, Gayle King y otras cuatro mujeres se dirigen al l\u00edmite del espacio. Esto significa","author":"","date":"abril 13, 2025","format":false,"excerpt":"Blue Origin llevar\u00e1 el lunes una tripulaci\u00f3n repleta de estrellas compuesta por seis pasajeras al borde del espacio en una de las misiones de turismo espacial suborbital m\u00e1s seguidas en a\u00f1os.El vuelo durar\u00e1 unos 10 minutos, llevar\u00e1 al grupo a m\u00e1s de 100 kil\u00f3metros (62 millas) de altura y les\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472510,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/24\/ioana-barbu-running-artico-selva-desierto-trax\/","url_meta":{"origin":1466524,"position":2},"title":"Esta corredora recorri\u00f3 m\u00e1s de 1.200 kil\u00f3metros a trav\u00e9s del \u00c1rtico, monta\u00f1as, desierto y hasta la selva en solo un a\u00f1o","author":"","date":"marzo 24, 2026","format":false,"excerpt":"Ioana Barbu participaba en una carrera de 200 kil\u00f3metros (143 millas) a trav\u00e9s de las imponentes y remotas monta\u00f1as Tian Shan, en Kirguist\u00e1n, cuando las cosas tomaron un giro inesperado y adverso.Una enorme tormenta se abati\u00f3 sobre la zona, castig\u00e1ndola con granizo y haciendo que las temperaturas se desplomaran desde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464237,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/04\/astronomos-detectan-objeto-interestelar-sistema-solar-trax\/","url_meta":{"origin":1466524,"position":3},"title":"Astr\u00f3nomos detectan un objeto interestelar atravesando nuestro sistema solar","author":"","date":"julio 4, 2025","format":false,"excerpt":"Un objeto reci\u00e9n descubierto que atraviesa r\u00e1pidamente nuestro sistema solar est\u00e1 generando entusiasmo entre los astr\u00f3nomos porque no es de aqu\u00ed. Se cree que es un cometa y es apenas el tercer cuerpo celeste proveniente de fuera de nuestro sistema solar que se ha observado en nuestra regi\u00f3n del universo.Este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446439,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/04\/arrestan-hombre-texas-tras-hallazgo-nina-desaparecida-trax-2\/","url_meta":{"origin":1466524,"position":4},"title":"Arrestan a hombre despu\u00e9s de que la polic\u00eda encontrara a ni\u00f1a desaparecida por 8 d\u00edas en Texas","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- Un hombre de Texas fue arrestado y acusado en relaci\u00f3n con la desaparici\u00f3n de una menor de 12 a\u00f1os del \u00e1rea de Houston que estuvo desaparecida durante ocho d\u00edas antes de ser encontrada sana y salva.La ni\u00f1a desapareci\u00f3 el 22 de febrero de su casa cerca de Houston.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467062,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/02\/venezuela-aviones-combate-eeuu-caribe-trax\/","url_meta":{"origin":1466524,"position":5},"title":"Venezuela dice que cinco aviones de combate de EE.UU. volaron cerca de su costa en el Caribe","author":"","date":"octubre 2, 2025","format":false,"excerpt":"Venezuela detect\u00f3 cinco aviones de combate de EE.UU. volando cerca de su costa sobre el Caribe, dijo este jueves el ministro de Defensa Vladimir Padrino L\u00f3pez, describiendo el incidente como una \u201cprovocaci\u00f3n\u201d de Washington.\u201cSon aviones de combate. Aviones de combate que el imperialismo estadounidense ha atrevido a acercarse a las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1466524"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466524\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1466524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1466524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1466524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}