{"id":1466567,"date":"2025-09-17T18:03:50","date_gmt":"2025-09-18T01:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/"},"modified":"2025-09-17T18:03:50","modified_gmt":"2025-09-18T01:03:50","slug":"ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/","title":{"rendered":"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &#038; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura"},"content":{"rendered":"<p>Horas despu\u00e9s de que Jerry Greenfield, cofundador de Ben &#038; Jerry\u2019s, renunciara a la compa\u00f1\u00eda de helados que fund\u00f3 hace casi cinco d\u00e9cadas, su exsocio Ben Cohen revel\u00f3 a CNN por qu\u00e9 Jerry sinti\u00f3 que deb\u00eda irse.<\/p>\n<p>\u201cJerry tiene un gran coraz\u00f3n, y este conflicto con Unilever realmente lo estaba destrozando. As\u00ed que sinti\u00f3 que no ten\u00eda otra opci\u00f3n que renunciar\u201d, dijo Cohen a Vanessa Yurkevich de CNN este mi\u00e9rcoles. \u201cJerry est\u00e1 un poco triste de haber llegado a esto, pero parte de \u00e9l siente alivio de ya no estar en este conflicto tan intenso\u201d.<\/p>\n<p>M\u00e1s temprano este mi\u00e9rcoles, Greenfield <a href=\"https:\/\/www.cnn.com\/2025\/09\/17\/business\/jerry-greenfield-quits-ice-cream-brand-intl-hnk\">comparti\u00f3 en redes sociales <\/a>que dejaba la compa\u00f1\u00eda de helados, acusando a la empresa matriz Unilever de limitar la capacidad de Ben &#038; Jerry\u2019s para pronunciarse sobre causas sociales y pol\u00edticas, algo que es sin\u00f3nimo de la identidad de la marca. El conflicto entre los cofundadores y Unilever sali\u00f3 a la luz p\u00fablica en los \u00faltimos a\u00f1os, resultando en <a href=\"https:\/\/www.cnn.com\/2025\/03\/19\/food\/ben-and-jerrys-ceo-lawsuit\">demandas <\/a>y <a href=\"https:\/\/www.cnn.com\/2025\/09\/09\/food\/ben-jerrys-open-letter-magnum-unilever\">cartas abiertamente p\u00fablicas.<\/a><\/p>\n<p>Unilever, con sede en el Reino Unido, compr\u00f3 Ben &#038; Jerry\u2019s por US$ 326 millones en el 2000, pero permiti\u00f3 que la compa\u00f1\u00eda operara de manera independiente y continuara con su misi\u00f3n social sin interferencia de la nueva empresa matriz. Cohen y Greenfield permanecieron en la compa\u00f1\u00eda, fundada en 1978, pero no en roles operativos. En cambio, se enfocaron en las misiones sociales de la empresa.<\/p>\n<p>Pero Cohen declar\u00f3 a CNN que, tras el cambio de direcci\u00f3n en Unilever, nadie de los que firmaron el acuerdo con Ben &#038; Jerry\u2019s permaneci\u00f3 en la empresa, y el conglomerado comenz\u00f3 a faltar a los t\u00e9rminos de su singular acuerdo con la helader\u00eda. La tensi\u00f3n se intensific\u00f3 en los \u00faltimos a\u00f1os cuando Ben &#038; Jerry\u2019s opt\u00f3 por retirar sus operaciones de Israel, decisi\u00f3n que fue revocada por Unilever.<\/p>\n<p>Desde entonces, la empresa y su matriz han tenido disputas, principalmente por publicaciones en redes sociales con tintes pol\u00edticos, a las que, seg\u00fan Cohen, Unilever se opuso y amenaz\u00f3 con despedir personal. Hablar abiertamente sobre temas pol\u00edticos, desde el presidente Donald Trump hasta Israel y Gaza, enfureci\u00f3 a Unilever, que despidi\u00f3 al CEO de la empresa a principios de este a\u00f1o.<\/p>\n<p>Finalmente, Greenfield se hart\u00f3. Pero Cohen dijo que eligi\u00f3 quedarse para seguir luchando por la independencia de la empresa.<\/p>\n<p>\u201cMe alegra que ambos defendamos los valores de Ben &#038; Jerry\u2019s\u201d, declar\u00f3 Cohen a CNN. \u201cCreo que puedo ser m\u00e1s \u00fatil desde dentro y Jerry intentar\u00e1 ser \u00fatil desde fuera\u201d.<\/p>\n<p>A pesar de la salida de Greenfield, Cohen dijo que est\u00e1 comprometido con la junta independiente que ayuda a controlar la marca y que trabajar\u00e1 para convencer a la empresa matriz de vender la marca a un grupo de inversionistas comprometidos con la misi\u00f3n social de Ben &#038; Jerry\u2019s. Actualmente, Ben &#038; Jerry\u2019s est\u00e1 siendo dividida de Unilever para formar una nueva empresa llamada The Magnum Ice Cream Company, que espera cotizar en la bolsa en noviembre.<\/p>\n<p>The Magnum Ice Cream Company dijo en un comunicado que no est\u00e1 de acuerdo con la perspectiva de Greenfield y Cohen, y afirm\u00f3 que ha intentado trabajar con los cofundadores de la marca.<\/p>\n<p>\u201cSeguimos comprometidos con la misi\u00f3n \u00fanica de tres partes de Ben &#038; Jerry\u2019s \u2014producto, econ\u00f3mica y social\u2014 y seguimos enfocados en mantener el legado de paz, amor y helado de esta marca ic\u00f3nica y muy querida\u201d, dijo un portavoz de Magnum en un comunicado.<\/p>\n<p>Un factor clave para que Cohen permanezca en la empresa es mantener intacta la misi\u00f3n de tres partes de Ben &#038; Jerry\u2019s: una misi\u00f3n social para apoyar la justicia y la igualdad, junto con una misi\u00f3n de producto y financiera. \u00c9l dice que las tres son fundamentales para la marca, y afirma que esto es bueno para el negocio.<\/p>\n<p>\u201cCuando creamos esa misi\u00f3n de tres partes, la escribimos deliberadamente de manera horizontal para dejar claro que todas son igual de importantes\u201d, dijo. \u201cA medida que la empresa act\u00faa seg\u00fan sus valores sociales y produce un gran helado, termina obteniendo buenas ganancias\u201d.<\/p>\n<p>Unilever, que no desglosa las ventas de Ben &#038; Jerry\u2019s por separado, inform\u00f3 en su reporte anual de ganancias de 2024 que su divisi\u00f3n de helados creci\u00f3 un 3.7 % respecto al a\u00f1o anterior.<\/p>\n<p>Cohen no se arrepiente de mantener sus posturas pol\u00edticas y sociales, y afirma que los productos de Ben &#038; Jerry\u2019s tienen una peque\u00f1a porci\u00f3n del mercado, as\u00ed que \u201cno tenemos que agradarle a todo el mundo\u201d.<\/p>\n<p>\u201cLa realidad es que las empresas son incre\u00edblemente pol\u00edticas\u201d, dijo. \u201cEl negocio promedio, (est\u00e1) usando su dinero para influir en las elecciones, y est\u00e1n usando su dinero y sus cabilderos para influir en la legislaci\u00f3n\u201d.<\/p>\n<p>Agreg\u00f3: \u201cLa \u00fanica diferencia es que los aspectos pol\u00edticos de Ben &#038; Jerry\u2019s son abiertos, donde dejamos a la gente saber lo que pensamos, mientras que otros negocios lo hacen de manera encubierta\u201d.<\/p>\n<p>Incluso con la salida de Greenfield de la empresa, \u201cel esp\u00edritu de Jerry siempre estar\u00e1 en Ben &#038; Jerry\u2019s\u201d, dijo Cohen. Y su amistad, que se remonta a la secundaria cuando eran \u201clos dos ni\u00f1os m\u00e1s lentos y gordos\u201d de la clase, perdurar\u00e1.<\/p>\n<p>\u201cYo fracas\u00e9 como alfarero. Nadie quer\u00eda comprar mi cer\u00e1mica. Jerry fue rechazado en la escuela de medicina, y nos juntamos cuando ten\u00edamos 26 a\u00f1os y dijimos: \u2018Intentemos iniciar un peque\u00f1o negocio. Tal vez eso funcione\u2019. Terminamos abriendo esta helader\u00eda casera en una vieja gasolinera en Burlington, Vermont, con una inversi\u00f3n de US$ 8.000 y no ten\u00edamos planes de ser nada m\u00e1s grande que eso\u201d, cont\u00f3 Cohen.<\/p>\n<p>\u201cHa sido un viaje incre\u00edble. Ha sido una aventura asombrosa, una odisea incre\u00edble. Ha habido buenos momentos, malos momentos, momentos desafiantes, y los hemos pasado todos juntos, Jerry y yo, y eso solo ha fortalecido nuestro v\u00ednculo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horas despu\u00e9s de que Jerry Greenfield, cofundador de Ben &#038; Jerry\u2019s, renunciara a la compa\u00f1\u00eda de helados que fund\u00f3 hace casi cinco d\u00e9cadas, su exsocio Ben Cohen revel\u00f3 a CNN por qu\u00e9 Jerry sinti\u00f3 que deb\u00eda irse. \u201cJerry tiene un gran coraz\u00f3n, y este conflicto con Unilever realmente lo estaba destrozando. As\u00ed que sinti\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466567","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &amp; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &amp; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura - Noticias\" \/>\n<meta property=\"og:description\" content=\"Horas despu\u00e9s de que Jerry Greenfield, cofundador de Ben &#038; Jerry\u2019s, renunciara a la compa\u00f1\u00eda de helados que fund\u00f3 hace casi cinco d\u00e9cadas, su exsocio Ben Cohen revel\u00f3 a CNN por qu\u00e9 Jerry sinti\u00f3 que deb\u00eda irse. \u201cJerry tiene un gran coraz\u00f3n, y este conflicto con Unilever realmente lo estaba destrozando. As\u00ed que sinti\u00f3 que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T01:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &#038; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura\",\"datePublished\":\"2025-09-18T01:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/\"},\"wordCount\":1040,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/\",\"name\":\"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben & Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-18T01:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &#038; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben & Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben & Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura - Noticias","og_description":"Horas despu\u00e9s de que Jerry Greenfield, cofundador de Ben &#038; Jerry\u2019s, renunciara a la compa\u00f1\u00eda de helados que fund\u00f3 hace casi cinco d\u00e9cadas, su exsocio Ben Cohen revel\u00f3 a CNN por qu\u00e9 Jerry sinti\u00f3 que deb\u00eda irse. \u201cJerry tiene un gran coraz\u00f3n, y este conflicto con Unilever realmente lo estaba destrozando. As\u00ed que sinti\u00f3 que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-18T01:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/"},"author":{"name":"","@id":""},"headline":"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &#038; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura","datePublished":"2025-09-18T01:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/"},"wordCount":1040,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/","name":"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben & Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-18T01:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &#038; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ben explica por qu\u00e9 Jerry dej\u00f3 Ben &#038; Jerry\u2019s y tiene que ver con una acusaci\u00f3n de censura","url":"http:\/\/noticiasya.com\/nacional\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/09\/17\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-18T01:03:50Z","datePublished":"2025-09-18T01:03:50Z","dateModified":"2025-09-18T01:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ben explica por qu\\u00e9 Jerry dej\\u00f3 Ben &#038; Jerry\\u2019s y tiene que ver con una acusaci\\u00f3n de censura\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/17\\\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/17\\\/ben-explica-por-que-jerry-dejo-ben-and-jerrys-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-18T01:03:50Z\",\"datePublished\":\"2025-09-18T01:03:50Z\",\"dateModified\":\"2025-09-18T01:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460139,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/19\/despiden-ceo-ben-and-jerrys-comentarios-politicos-unilever-trax\/","url_meta":{"origin":1466567,"position":0},"title":"Despiden al CEO de Ben &#038; Jerry&#8217;s por los comentarios pol\u00edticos de la compa\u00f1\u00eda","author":"","date":"marzo 19, 2025","format":false,"excerpt":"Ben & Jerry\u2019s acusa a su empresa matriz, Unilever, de incumplir su acuerdo de fusi\u00f3n al destituir al CEO de la helader\u00eda por sus reiterados comentarios p\u00fablicos sobre temas progresistas, tomando la decisi\u00f3n sin la aprobaci\u00f3n de la junta directiva.Esta es la escalada m\u00e1s reciente de una disputa cada vez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467185,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/07\/trayectoria-jerry-tormenta-tropical-trax\/","url_meta":{"origin":1466567,"position":1},"title":"Se form\u00f3 la tormenta tropical Jerry: d\u00f3nde est\u00e1 y hacia d\u00f3nde se dirige","author":"","date":"octubre 7, 2025","format":false,"excerpt":"La tormenta tropical Jerry se form\u00f3 sobre el Atl\u00e1ntico central este martes y se espera que se fortalezca hasta convertirse en hurac\u00e1n para el mi\u00e9rcoles.Jerry es la d\u00e9cima tormenta con nombre de una temporada tard\u00eda que ha generado tres huracanes en poco m\u00e1s de dos semanas.La tormenta tropical Jerry tiene\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462656,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/21\/ben-tasgal-la-intencion-de-israel-es-presionar-fisicamente-a-hamas-para-que-pida-otro-cese-de-fuego\/","url_meta":{"origin":1466567,"position":2},"title":"Ben-Tasgal: &#171;La intenci\u00f3n de Israel es presionar f\u00edsicamente a Hamas para que pida otro cese de fuego&#187;","author":"","date":"mayo 21, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Gabriel Ben-Tasgal, periodista especializado en Medio Oriente, dialog\u00f3 este mi\u00e9rcoles con Regreso CNN de Mariana Arias y Pepe Gil Vidal, donde analiz\u00f3 la situaci\u00f3n actual en Gaza y los objetivos del gobierno israel\u00ed en el conflicto con Hamas.\u201cAl menos 20 de los 58 rehenes est\u00e1n con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473239,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/the-white-lotus-cuarta-temporada-francia-orix\/","url_meta":{"origin":1466567,"position":3},"title":"&#171;The White Lotus&#187; comenz\u00f3 el rodaje de su cuarta temporada en Francia","author":"","date":"abril 16, 2026","format":false,"excerpt":"Hawai, Sicilia y Koh Samui en Tailandia. Cada temporada de la serie \u201cThe White Lotus\u201d transcurre en un destino paradis\u00edaco. Y ahora la acci\u00f3n se desplaz\u00f3 a la Costa Azul francesa, espec\u00edficamente al Festival de Cannes, donde el mi\u00e9rcoles comenz\u00f3 el rodaje de la cuarta temporada, seg\u00fan dio a conocer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455965,"url":"https:\/\/noticiasya.com\/nacional\/2024\/11\/20\/separacion-canales-cable-comcast-preguntas-futuro-televisivo-trax\/","url_meta":{"origin":1466567,"position":4},"title":"AN\u00c1LISIS | Comcast decidi\u00f3 separar sus canales de cable, lo que despierta dudas sobre el futuro del negocio de la TV","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) --\u00a0 Comcast acaba de iniciar una nueva temporada de cambios importantes en toda la industria televisiva. Y nadie sabe exactamente qu\u00e9 suceder\u00e1 despu\u00e9s.En la ma\u00f1ana de este mi\u00e9rcoles, el gigante de los medios confirm\u00f3 que escindir\u00e1 la mayor\u00eda de sus canales de cable, incluidos MSNBC y CNBC, en una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464014,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/27\/gabriel-ben-tasgal-desde-1980-israel-tiene-capacidad-nuclear-con-fines-militares\/","url_meta":{"origin":1466567,"position":5},"title":"Gabriel Ben-Tasgal: &#171;Desde 1980 Israel tiene capacidad nuclear con fines militares&#187;","author":"","date":"junio 27, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Gabriel Ben-Tasgal, especialista en seguridad internacional, habl\u00f3 este viernes con Regreso CNN de Mariana Arias y Pepe Gil Vidal sobre la situaci\u00f3n actual en Medio Oriente, el cese del fuego y el impacto geopol\u00edtico del conflicto.\u201cAhora en Medio Oriente se est\u00e1 averiguando cu\u00e1nta capacidad nuclear le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1466567"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466567\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1466567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1466567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1466567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}