{"id":1466592,"date":"2025-09-18T13:03:41","date_gmt":"2025-09-18T20:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/"},"modified":"2025-09-18T13:03:41","modified_gmt":"2025-09-18T20:03:41","slug":"base-militar-puerto-rico-ceiba-roosevelt-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","title":{"rendered":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela"},"content":{"rendered":"<p>La antigua base naval de Roosevelt Roads, en Ceiba, Puerto Rico, cerr\u00f3 en 2004 luego de m\u00e1s de seis d\u00e9cadas de operaciones militares de Estados Unidos. Durante a\u00f1os se intent\u00f3 transformarla en un polo de desarrollo tur\u00edstico y residencial, pero ninguno de esos planes prosper\u00f3. Ahora, el enorme complejo militar volvi\u00f3 a recibir aviones de combate en medio de la escalada de tensi\u00f3n entre Washington y Caracas.<\/p>\n<p>Varios <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/15\/eeuu\/f35-aviones-puerto-rico-tension-venezuela-orix\">cazas F-35<\/a> de EE.UU. aterrizaron la semana pasada en la pista del ahora llamado aeropuerto regional Jos\u00e9 Aponte de la Torre, que opera sobre la infraestructura de la antigua base.<\/p>\n<p>Seg\u00fan del<a href=\"https:\/\/x.com\/DeptofWar\/status\/1968689347235926383\"> Departamento de Defensa, <\/a>los cazas pertenecen al escuadr\u00f3n de ataque 225 y est\u00e1n \u201clistos para enfrentar a los c\u00e1rteles\u201d.<\/p>\n<p>La historia de Roosevelt Roads est\u00e1 marcada por sus idas y vueltas. Comisionada como base en 1943, se extiende sobre 3.500 hect\u00e1reas en la costa este de Puerto Rico, con carreteras internas, escuelas, hospitales y miles de viviendas para personal militar, seg\u00fan documentos de la Marina de Estados Unidos.<\/p>\n<p>La base lleg\u00f3 a ser \u201cuna de las instalaciones navales m\u00e1s grandes del mundo\u201d, <a href=\"https:\/\/www.navfac.navy.mil\/Divisions\/Environmental\/Products-and-Services\/Environmental-Restoration\/Southeast\/Puerto-Rico-NA\/\">seg\u00fan la Marina<\/a>, que destaca sus m\u00e1s de 160 kil\u00f3metros de caminos interiores pavimentados.<\/p>\n<p>Cuenta con una pista de m\u00e1s de 3 kil\u00f3metros de largo y un puerto de aguas profundas, la base tiene las condiciones para recibir a aviones y embarcaciones de gran envergadura.<\/p>\n<p>Con el paso de las d\u00e9cadas, fue cayendo en desuso para los militares estadounidenses.<\/p>\n<p>Su clausura en 2004 fue celebrada por sectores que rechazan la militarizaci\u00f3n de la isla, pero tambi\u00e9n fue lamentada por comunidades que se beneficiaban de la actividad econ\u00f3mica que la base motorizaba.<\/p>\n<p>Tras el traspaso de una parte de los terrenos al gobierno local, la Autoridad para el Redesarrollo Local (LRA) elabor\u00f3 un plan maestro en 2014 para el uso de 1.375 hect\u00e1reas que le fueron asignadas. La expectativa era atraer proyectos tur\u00edsticos \u2014como una marina ampliada y complejos hoteleros\u2014 e inversiones inmobiliarias.<\/p>\n<p>En 2023 el Gobierno de la isla firm\u00f3 <a href=\"https:\/\/senado.pr.gov\/document_vault\/legislative_measures\/2988\/document\/ps0895-22.pdf\">una ley<\/a> que cre\u00f3 un marco jur\u00eddico con incentivos especiales para la rehabilitaci\u00f3n de la zona, y en 2024 se abri\u00f3 una <a href=\"https:\/\/www.rooseveltroads.pr.gov\/rfp\">convocatoria internacional<\/a> para el desarrollo de la marina. Este a\u00f1o, la entidad anunci\u00f3 adem\u00e1s una inversi\u00f3n de US$ 79 millones en modernizaci\u00f3n el\u00e9ctrica con fondos federales.<\/p>\n<p>A pesar de esas iniciativas, la mayor parte de la antigua base permanece sin uso productivo desde hace 21 a\u00f1os.<\/p>\n<p>El panorama, hasta hace unas semanas, era de abandono casi total. Ahora, aunque no se trate de una reactivaci\u00f3n oficial de Roosevelt Roads como base permanente, la frase que se comenta es \u201cback in business\u201d, de vuelta al ruedo.<\/p>\n<p>De todas formas, no es la primera vez que EE.UU. vuelve a utilizarla desde su cierre, como en 2017, cuando las us\u00f3 como punto de entrada de la ayuda humanitaria tras la devastaci\u00f3n del hurac\u00e1n Mar\u00eda.<\/p>\n<p>La llegada de los F-35 a Puerto Rico se produce en paralelo a la decisi\u00f3n de Caracas de reforzar su despliegue militar en la frontera y en aguas del Caribe, incluso con<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/18\/venezuela\/venezuela-muestra-cazas-misiles-maniobras-orix\"> una serie de maniobras en la isla La Orchila<\/a>, 690 kil\u00f3metros al sur de Puerto Rico.<\/p>\n<p>D\u00edas atr\u00e1s, despu\u00e9s de una visita sorpresa del secretario de Defensa de EE.UU., Pete Hegseth, la gobernadora de Puerto Rico, Jenniffer Gonz\u00e1lez, asegur\u00f3 que su Gobierno \u201cest\u00e1 comprometido en esta lucha contra el narcotr\u00e1fico\u201d, y apoy\u00f3 el despliegue militar estadounidense, lo que fue <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/09\/venezuela\/maduro-apunta-gobernadora-puerto-rico-orix\">rechazado enf\u00e1ticamente<\/a> por el presidente de Venezuela, Nicol\u00e1s Maduro.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La antigua base naval de Roosevelt Roads, en Ceiba, Puerto Rico, cerr\u00f3 en 2004 luego de m\u00e1s de seis d\u00e9cadas de operaciones militares de Estados Unidos. Durante a\u00f1os se intent\u00f3 transformarla en un polo de desarrollo tur\u00edstico y residencial, pero ninguno de esos planes prosper\u00f3. Ahora, el enorme complejo militar volvi\u00f3 a recibir aviones de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466592","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"La antigua base naval de Roosevelt Roads, en Ceiba, Puerto Rico, cerr\u00f3 en 2004 luego de m\u00e1s de seis d\u00e9cadas de operaciones militares de Estados Unidos. Durante a\u00f1os se intent\u00f3 transformarla en un polo de desarrollo tur\u00edstico y residencial, pero ninguno de esos planes prosper\u00f3. Ahora, el enorme complejo militar volvi\u00f3 a recibir aviones de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T20:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela\",\"datePublished\":\"2025-09-18T20:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/\",\"name\":\"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-18T20:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela - Noticias","og_description":"La antigua base naval de Roosevelt Roads, en Ceiba, Puerto Rico, cerr\u00f3 en 2004 luego de m\u00e1s de seis d\u00e9cadas de operaciones militares de Estados Unidos. Durante a\u00f1os se intent\u00f3 transformarla en un polo de desarrollo tur\u00edstico y residencial, pero ninguno de esos planes prosper\u00f3. Ahora, el enorme complejo militar volvi\u00f3 a recibir aviones de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-18T20:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/"},"author":{"name":"","@id":""},"headline":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela","datePublished":"2025-09-18T20:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","name":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-18T20:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esta base militar no se us\u00f3 en d\u00e9cadas. Ahora EE.UU. la reactiv\u00f3 en plena tensi\u00f3n con Venezuela","url":"http:\/\/noticiasya.com\/nacional\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/09\/18\/base-militar-puerto-rico-ceiba-roosevelt-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-18T20:03:41Z","datePublished":"2025-09-18T20:03:41Z","dateModified":"2025-09-18T20:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esta base militar no se us\\u00f3 en d\\u00e9cadas. Ahora EE.UU. la reactiv\\u00f3 en plena tensi\\u00f3n con Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/18\\\/base-militar-puerto-rico-ceiba-roosevelt-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/09\\\/18\\\/base-militar-puerto-rico-ceiba-roosevelt-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-18T20:03:41Z\",\"datePublished\":\"2025-09-18T20:03:41Z\",\"dateModified\":\"2025-09-18T20:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466474,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/15\/f35-aviones-puerto-rico-tension-venezuela-orix\/","url_meta":{"origin":1466592,"position":0},"title":"Aviones F-35 de Estados Unidos llegan a Puerto Rico en medio de la tensi\u00f3n con Venezuela","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"Varios aviones de combate F-35 de Estados Unidos llegaron este fin de semana a Puerto Rico, en medio de la tensi\u00f3n entre Washington y Caracas y el despliegue militar estadounidense en el Caribe bajo el argumento de combatir al narcotr\u00e1fico.Al menos cinco cazas furtivos fueron vistos en el aeropuerto regional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467094,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/03\/f35-puerto-rico-bombas-caribe-orix\/","url_meta":{"origin":1466592,"position":1},"title":"EE.UU. muestra a sus F-35 en Puerto Rico armados con bombas horas antes de anunciar destrucci\u00f3n de otro bote en el Caribe","author":"","date":"octubre 3, 2025","format":false,"excerpt":"\u201cLetalidad y combate\u201d, comienza diciendo una publicaci\u00f3n en X hecha este viernes por el Comando Sur de Estados Unidos que muestra, por primera vez desde el inicio de la crisis con Venezuela en el Caribe, a sus avanzados cazas F-35 desplegados en Puerto Rico.La publicaci\u00f3n del video ocurri\u00f3 horas antes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469017,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/05\/f16-arribo-cordoba-dinamarca-orix\/","url_meta":{"origin":1466592,"position":2},"title":"Argentina entra al club de los F-16: llegan al pa\u00eds los primeros seis cazas comprados a Dinamarca","author":"","date":"diciembre 5, 2025","format":false,"excerpt":"Desde el retiro de los cazas Mirage III en 2015, Argentina, el octavo pa\u00eds del mundo en superficie y la 29\u00b0 econom\u00eda global, no ha contado con aviones de combate modernos en su arsenal, en un contexto de d\u00e9cadas de bajo gasto en Defensa y de fuertes p\u00e9rdidas durante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466460,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/14\/trump-no-descarta-accion-militar-contra-venezuela-trax\/","url_meta":{"origin":1466592,"position":3},"title":"Trump no descarta m\u00e1s acci\u00f3n militar contra Venezuela en medio de la escalada de tensiones","author":"","date":"septiembre 14, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump dej\u00f3 el domingo la puerta abierta a una posible escalada contra Venezuela, neg\u00e1ndose a descartar una acci\u00f3n militar en medio de las crecientes tensiones entre los dos pa\u00edses.Preguntado por los periodistas si ayudar a destituir al presidente de Venezuela Nicol\u00e1s Maduro estaba sobre la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466576,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/18\/venezuela-muestra-cazas-misiles-maniobras-orix\/","url_meta":{"origin":1466592,"position":4},"title":"Venezuela muestra sus cazas Sukhoi Su-30 armados con misiles antibuque y anuncia maniobras militares en el Caribe","author":"","date":"septiembre 18, 2025","format":false,"excerpt":"En medio de las crecientes tensiones entre Venezuela y Estados Unidos, en cuyo centro se encuentra el despliegue de al menos ocho buques de guerra estadounidenses en el Caribe, la Aviaci\u00f3n Militar Bolivariana (AMB) difundi\u00f3 el lunes im\u00e1genes de aviones de caza de fabricaci\u00f3n rusa Sukhoi Su-30 equipados con misiles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459175,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/25\/poder-aereo-america-latina-argentina-f16-orix\/","url_meta":{"origin":1466592,"position":5},"title":"Argentina present\u00f3 el primero de los F-16 comprados a Dinamarca. \u00bfC\u00f3mo se compara el poder a\u00e9reo en Am\u00e9rica Latina?","author":"","date":"febrero 25, 2025","format":false,"excerpt":"En un mundo donde las guerras, especialmente Ucrania, Gaza y el Congo, han vuelto ocupar la agenda global, el Gobierno de Argentina present\u00f3 formalmente el lunes su \u00faltima adquisici\u00f3n militar: el primero de los cazas F-16 comprados el a\u00f1o pasado a Dinamarca.\u201cUn d\u00eda hist\u00f3rico para la reconstrucci\u00f3n de nuestra Defensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1466592"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1466592\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1466592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1466592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1466592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}