{"id":1468334,"date":"2025-11-14T05:03:55","date_gmt":"2025-11-14T13:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/"},"modified":"2025-11-14T05:03:55","modified_gmt":"2025-11-14T13:03:55","slug":"rusia-complot-asesinato-ucrania-ataques-kyiv-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","title":{"rendered":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv"},"content":{"rendered":"<p>El servicio de seguridad ruso afirm\u00f3 haber frustrado un complot de Ucrania para asesinar a un alto funcionario del Kremlin dentro de Rusia, mientras el supuesto objetivo visitaba un cementerio.<\/p>\n<p>La afirmaci\u00f3n del Servicio Federal de Seguridad de Rusia (FSB, por sus siglas) se produjo mientras los residentes de Kyiv sufr\u00edan otra noche intensa de ataques a\u00e9reos rusos que, seg\u00fan funcionarios ucranianos, causaron la muerte de al menos cinco personas.<\/p>\n<p>Los servicios especiales ucranianos planeaban atentar contra el funcionario no identificado, descrito como \u201cuno de los funcionarios de m\u00e1s alto rango del Estado ruso\u201d, mientras visitaba las tumbas de sus familiares en un cementerio a las afueras de Mosc\u00fa, seg\u00fan un comunicado emitido el viernes por el FSB.<\/p>\n<p>El FSB tambi\u00e9n afirm\u00f3 en su comunicado que Ucrania est\u00e1 planeando otros ataques similares dentro de Rusia.<\/p>\n<p>CNN no pudo verificar de forma independiente las afirmaciones de Rusia. El Servicio de Seguridad de Ucrania neg\u00f3 el informe y declar\u00f3 a CNN: \u201cEst\u00e1n difundiendo noticias y declaraciones falsas sin parar. Nuestra postura es no comentar sus disparates\u201d.<\/p>\n<p>Ucrania <a href=\"https:\/\/www.cnn.com\/2025\/10\/29\/europe\/ukraine-car-bomb-veniamin-mazzherin-death-latam-intl\">se ha atribuido la responsabilidad de la muerte de funcionarios rusos en el pasado<\/a>, incluida la de un comandante, el mes pasado en Siberia.<\/p>\n<p>Tanto Ucrania como Rusia lanzaron ataques a\u00e9reos contra el territorio del otro durante la noche del viernes, seg\u00fan reportaron las autoridades de ambos pa\u00edses.<\/p>\n<p>En Kyiv, las autoridades locales informaron que al menos cinco personas murieron y decenas resultaron heridas en los \u00faltimos ataques. Entre los heridos se encontraban dos ni\u00f1os y una mujer embarazada, seg\u00fan la administraci\u00f3n militar de la ciudad.<\/p>\n<p>M\u00e1s de 15 edificios resultaron da\u00f1ados en la capital, entre ellos viviendas y un centro m\u00e9dico, a\u00f1adi\u00f3.<\/p>\n<p>Mientras tanto, un ataque con drones ucranianos tuvo como objetivo la ciudad portuaria rusa de Novorossiysk, dejando al menos cuatro heridos y da\u00f1os en un dep\u00f3sito de petr\u00f3leo, seg\u00fan el gobernador del krai de Krasnodar. Se ha declarado el estado de emergencia en la zona, informaron las autoridades.<\/p>\n<p>Seg\u00fan el gobernador, un hombre fue hospitalizado debido a los restos de drones ucranianos derribados, y agreg\u00f3 que al menos cuatro edificios de apartamentos y dos viviendas particulares resultaron da\u00f1ados.<\/p>\n<p>En total, el Ministerio de Defensa ruso afirm\u00f3 haber interceptado durante la noche un total de 216 drones ucranianos.<\/p>\n<p>Ucrania tambi\u00e9n lanz\u00f3 misiles de crucero Neptuno de largo alcance contra objetivos rusos la noche del jueves, seg\u00fan el presidente Volodymyr Zelensky. Los Neptuno son armas de fabricaci\u00f3n ucraniana.<\/p>\n<p>\u201cAnoche, nuestros soldados utilizaron con \u00e9xito misiles \u2018Neptuno de largo alcance\u2019 contra objetivos espec\u00edficos en territorio ruso, y esta es nuestra respuesta totalmente justificada al continuo terrorismo ruso\u201d, dijo Zelensky en una publicaci\u00f3n en redes sociales.<\/p>\n<p>Las muertes selectivas se han convertido en un sello distintivo de la guerra entre Rusia y Ucrania. Este tipo de atentados dentro de Rusia y las partes de Ucrania ocupadas por Rusia se han disparado desde 2022, <a href=\"https:\/\/acleddata.com\/report\/personal-payback-assassinations-escalate-ukraine-and-russias-shadow-war\">seg\u00fan el grupo de monitoreo Armed Conflict Location &#038; Event Data (ACLED)<\/a>.<\/p>\n<p>Seg\u00fan inform\u00f3 ACLED, en los tres primeros trimestres de 2025 se produjeron m\u00e1s intentos de asesinato dentro de Rusia que en la suma total anual de los tres a\u00f1os anteriores.<\/p>\n<p>El mes pasado, Ucrania <a href=\"https:\/\/www.cnn.com\/2025\/10\/29\/europe\/ukraine-car-bomb-veniamin-mazzherin-death-latam-intl\">anunci\u00f3 el asesinato del oficial ruso<\/a> Veniamin Mazzherin mediante un coche bomba. Mazzherin, subcomandante de una unidad de la polic\u00eda militar rusa en K\u00e9merovo, al suroeste de Siberia, presuntamente ayud\u00f3 a dirigir una unidad especial involucrada en cr\u00edmenes de guerra y genocidio contra el pueblo ucraniano, seg\u00fan la Inteligencia de Defensa ucraniana.<\/p>\n<p>En abril, el general ruso Yaroslav Moskalik muri\u00f3 en un atentado con coche bomba en las afueras de Mosc\u00fa. Las autoridades rusas afirmaron haber acusado de terrorismo a un agente de los servicios especiales ucranianos, aunque Ucrania no se atribuy\u00f3 ninguna responsabilidad en el incidente.<\/p>\n<p>Unos meses antes, un alto general ruso, acusado de usar armas qu\u00edmicas en Ucrania, fue asesinado por una bomba detonada a distancia colocada en un monopat\u00edn el\u00e9ctrico frente a un edificio de apartamentos en Mosc\u00fa. Una fuente con conocimiento de la operaci\u00f3n declar\u00f3 entonces a CNN que los servicios de seguridad ucranianos estaban detr\u00e1s del hecho.<\/p>\n<p>En noviembre de 2023, Ucrania se atribuy\u00f3 la responsabilidad de la muerte de Mikhail Filiponenko, diputado de una asamblea instaurada por el Kremlin en la ciudad ocupada de Luhansk, en el este de Ucrania. Filiponenko fue v\u00edctima de un atentado con coche bomba.<\/p>\n<p>Ucrania tambi\u00e9n ha sido escenario de muertes selectivas. En julio, un agente de los servicios de seguridad ucranianos fue <a href=\"https:\/\/www.cnn.com\/2025\/07\/13\/europe\/ukraine-russia-sbu-assassination-intl\">abatido a tiros a plena luz del d\u00eda<\/a> en Kyiv, y las autoridades responsabilizaron del crimen a los servicios de seguridad rusos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El servicio de seguridad ruso afirm\u00f3 haber frustrado un complot de Ucrania para asesinar a un alto funcionario del Kremlin dentro de Rusia, mientras el supuesto objetivo visitaba un cementerio. La afirmaci\u00f3n del Servicio Federal de Seguridad de Rusia (FSB, por sus siglas) se produjo mientras los residentes de Kyiv sufr\u00edan otra noche intensa de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468334","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv - Noticias\" \/>\n<meta property=\"og:description\" content=\"El servicio de seguridad ruso afirm\u00f3 haber frustrado un complot de Ucrania para asesinar a un alto funcionario del Kremlin dentro de Rusia, mientras el supuesto objetivo visitaba un cementerio. La afirmaci\u00f3n del Servicio Federal de Seguridad de Rusia (FSB, por sus siglas) se produjo mientras los residentes de Kyiv sufr\u00edan otra noche intensa de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-14T13:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv\",\"datePublished\":\"2025-11-14T13:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/\"},\"wordCount\":833,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/\",\"name\":\"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-14T13:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv - Noticias","og_description":"El servicio de seguridad ruso afirm\u00f3 haber frustrado un complot de Ucrania para asesinar a un alto funcionario del Kremlin dentro de Rusia, mientras el supuesto objetivo visitaba un cementerio. La afirmaci\u00f3n del Servicio Federal de Seguridad de Rusia (FSB, por sus siglas) se produjo mientras los residentes de Kyiv sufr\u00edan otra noche intensa de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-14T13:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/"},"author":{"name":"","@id":""},"headline":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv","datePublished":"2025-11-14T13:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/"},"wordCount":833,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","name":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-14T13:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Rusia afirm\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\u00edferos ataques nocturnos azotaban a Kyiv","url":"http:\/\/noticiasya.com\/nacional\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/11\/14\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-14T13:03:55Z","datePublished":"2025-11-14T13:03:55Z","dateModified":"2025-11-14T13:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Rusia afirm\\u00f3 haber frustrado un complot de asesinato de Ucrania mientras mort\\u00edferos ataques nocturnos azotaban a Kyiv\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/11\\\/14\\\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/11\\\/14\\\/rusia-complot-asesinato-ucrania-ataques-kyiv-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-14T13:03:55Z\",\"datePublished\":\"2025-11-14T13:03:55Z\",\"dateModified\":\"2025-11-14T13:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449397,"url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/10\/zelensky-despide-jefe-guardaespaldas-tras-complot-asesinato-trax\/","url_meta":{"origin":1468334,"position":0},"title":"Zelensky despide al jefe de sus guardaespaldas tras frustrado complot de asesinato","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN) -- El presidente de Ucrania, Volodymyr Zelensky, destituy\u00f3 al jefe de la agencia responsable de su protecci\u00f3n despu\u00e9s de que dos de sus funcionarios fueran detenidos por un presunto complot de asesinato en su contra.El despido del jefe del Servicio de la Guardia Estatal (UDO, por sus siglas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461659,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/26\/general-ruso-muerte-agente-ucraniano-trax\/","url_meta":{"origin":1468334,"position":1},"title":"El sospechoso de la muerte de general ruso es un &#171;agente de servicios especiales ucranianos&#187;, seg\u00fan medios estatales de Rusia","author":"","date":"abril 26, 2025","format":false,"excerpt":"Las autoridades rusas detuvieron a un hombre descrito como un \u201cagente de los servicios especiales ucranianos\u201d en relaci\u00f3n con la explosi\u00f3n de un coche en la que muri\u00f3 el general ruso Yaroslav Moskalik el viernes, seg\u00fan la agencia de noticias estatal rusa TASS.El Servicio Federal de Seguridad de Rusia (FSB)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468675,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/25\/conversaciones-paz-ucrania-rusia-abu-dhabi-trax\/","url_meta":{"origin":1468334,"position":2},"title":"Funcionarios estadounidenses y rusos mantienen conversaciones de paz sobre Ucrania, mientras Kyiv sufre un ataque mortal","author":"","date":"noviembre 25, 2025","format":false,"excerpt":"El secretario del Ej\u00e9rcito de Estados Unidos, Dan Driscoll, se reuni\u00f3 el lunes con funcionarios rusos en Abu Dhabi sobre un plan propuesto para poner fin a la guerra en Ucrania. Las conversaciones continuar\u00e1n el martes, dijo a CNN un funcionario estadounidense.Las reuniones, que se producen tras d\u00edas de intensos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464349,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/09\/rusia-ataque-ucrania-rusia-putin-trump-trax\/","url_meta":{"origin":1468334,"position":3},"title":"Rusia lanza un ataque r\u00e9cord con drones contra Ucrania tras las cr\u00edticas de Trump a Putin","author":"","date":"julio 9, 2025","format":false,"excerpt":"Rusia lanz\u00f3 su mayor ataque con drones contra Ucrania desde el comienzo de su invasi\u00f3n, dijeron el mi\u00e9rcoles funcionarios ucranianos, apenas horas despu\u00e9s de que el presidente de Estados Unidoss, Donald Trump, prometiera m\u00e1s apoyo militar a Kyiv y acusara a su hom\u00f3logo ruso, Vladimir Putin, de decir \u201ctonter\u00edas\u201d sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459755,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/11\/rusia-drones-ucranianos-conversaciones-estados-unidos-kyiv-trax\/","url_meta":{"origin":1468334,"position":4},"title":"Rusia dice haber derribado cientos de drones ucranianos antes de las cruciales conversaciones entre Estados Unidos y Kyiv","author":"","date":"marzo 11, 2025","format":false,"excerpt":"Rusia dijo que derrib\u00f3 cientos de drones ucranianos lanzados hacia su territorio durante la noche de este lunes, horas antes de conversaciones cr\u00edticas entre funcionarios de Washington y Kyiv.El Ministerio de Defensa de Mosc\u00fa dijo que hab\u00eda derribado 337 drones ucranianos disparados contra Rusia, de los cuales 91 ten\u00edan como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461544,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/23\/vance-ultimatum-ucrania-rubio-reunion-londres-trax\/","url_meta":{"origin":1468334,"position":5},"title":"Trump critica a Zelensky por negarse a reconocer el control ruso de Crimea","author":"","date":"abril 23, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, critic\u00f3 al presidente de Ucrania, Volodymyr Zelensky, este mi\u00e9rcoles por sus comentarios de que Ucrania no reconocer\u00e1 el control ruso sobre Crimea, calificando las declaraciones de \u201cmuy perjudiciales para las negociaciones de paz con Rusia\u201d.\u201cSon declaraciones incendiarias como las de Zelensky las que hacen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1468334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1468334"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1468334\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1468334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1468334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1468334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}