{"id":1468865,"date":"2025-12-01T15:03:48","date_gmt":"2025-12-01T23:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/"},"modified":"2025-12-01T15:03:48","modified_gmt":"2025-12-01T23:03:48","slug":"palabra-anio-2025-oxford-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/","title":{"rendered":"La palabra del a\u00f1o 2025 de Oxford es completamente irritante"},"content":{"rendered":"<p>\u00bfConoces esa sensaci\u00f3n cuando lees algo en l\u00ednea y te parece deliberadamente provocador, casi fabricado para indignar? Quiz\u00e1s te hayas topado con un <em>rage bait<\/em>: contenido dise\u00f1ado deliberadamente para causar ira y aumentar la interacci\u00f3n.<\/p>\n<p>Y se ha vuelto tan omnipresente en Internet que el Diccionario Oxford nombr\u00f3 el concepto <em>rage bait<\/em> como su Palabra del A\u00f1o este domingo.<\/p>\n<p>El uso del t\u00e9rmino se ha triplicado este a\u00f1o, lo que sugiere que las personas saben que \u201cest\u00e1n siendo arrastradas cada vez m\u00e1s r\u00e1pidamente a debates y argumentos polarizadores como respuesta a los algoritmos de las redes sociales y la naturaleza adictiva del contenido indignante\u201d, dijo el diccionario con sede en el Reino Unido en un comunicado.<\/p>\n<p>Casi todos los diccionarios importantes han nombrado una palabra relacionada con Internet como su palabra del a\u00f1o 2025, destacando la influencia de la tecnolog\u00eda en la vida cotidiana y el lenguaje que usamos para describirla.<\/p>\n<p>A veces, el <em>rage bait<\/em> puede ser relativamente inofensivo: una receta con combinaciones de alimentos repugnantes o alguien que molesta a su mascota, pareja o hermano. Pero tambi\u00e9n ha entrado en el discurso pol\u00edtico, donde la indignaci\u00f3n se utiliza para realzar el perfil de los pol\u00edticos y causar una cadena de reacciones y contrarreacciones.<\/p>\n<p>El Diccionario Collins eligi\u00f3 <em>vibe coding<\/em>, una forma de desarrollo de software que utiliza inteligencia artificial (IA) para convertir el lenguaje natural en c\u00f3digo inform\u00e1tico, y el Diccionario Cambridge se decidi\u00f3 por <em>parasocial<\/em>, en referencia a las relaciones que las personas forman en l\u00ednea con alguien que no conocen, como sus palabras del a\u00f1o.<\/p>\n<p>El a\u00f1o pasado Oxford hab\u00eda elegido <em>brain rot,<\/em> palabra que \u201ccaptura el agotamiento mental del desplazamiento interminable\u201d, dijo Casper Grathwohl, presidente de Oxford Languages, en un comunicado.<\/p>\n<p>En conjunto, el <em>rage bait<\/em> y el <em>brain rot<\/em> \u201cforman un ciclo poderoso donde la indignaci\u00f3n genera interacci\u00f3n, los algoritmos lo amplifican y la exposici\u00f3n constante nos deja mentalmente exhaustos\u201d, dijo Grathwohl.<\/p>\n<p>\u201cEstas palabras no solo definen tendencias; revelan c\u00f3mo las plataformas digitales est\u00e1n transformando nuestro pensamiento y comportamiento\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El Diccionario Oxford dej\u00f3 que el p\u00fablico eligiera su palabra del a\u00f1o de una lista corta que tambi\u00e9n inclu\u00eda <em>aura farming <\/em>y <em>biohack,<\/em> y public\u00f3 videos de parodia en su <a href=\"https:\/\/www.instagram.com\/oxunipress\/\">Instagram<\/a> para transmitir el esp\u00edritu de cada palabra.<\/p>\n<p>El <em>aura farming<\/em> o cultivo del aura hace referencia al \u201ccultivo de una personalidad impresionante, atractiva o carism\u00e1tica (\u2026) present\u00e1ndose de una manera que sutilmente intenta transmitir un aire de confianza, frescura o misticismo\u201d. Este t\u00e9rmino fue retratado como un hombre que vest\u00eda un c\u00e1rdigan y llevaba un bolso de mano, \u201csiempre a un matcha de terminar un guion experimental\u201d.<\/p>\n<p>Y el <em>biohack<\/em>, refiere a \u201cun intento (\u2026) de optimizar la propia (\u2026) salud, longevidad o bienestar alterando la dieta, rutina de ejercicios o estilo de vida, o mediante el uso de otros medios como medicamentos, suplementos o dispositivos tecnol\u00f3gicos\u201d. El concepto se represent\u00f3 como alguien conectado a un goteo intravenoso verde y con una m\u00e1scara facial LED, que hab\u00eda tomado \u201c27 plantas ricas en fitonutrientes\u201d a las 6:34 a.m.<\/p>\n<p>Por su parte, la caracterizaci\u00f3n de <em>rage bait<\/em> derram\u00f3 leche y az\u00facar por todas partes mientras preparaba una taza de t\u00e9, antes de arrancarse las u\u00f1as de los pies y verterse la leche encima.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfConoces esa sensaci\u00f3n cuando lees algo en l\u00ednea y te parece deliberadamente provocador, casi fabricado para indignar? Quiz\u00e1s te hayas topado con un rage bait: contenido dise\u00f1ado deliberadamente para causar ira y aumentar la interacci\u00f3n. Y se ha vuelto tan omnipresente en Internet que el Diccionario Oxford nombr\u00f3 el concepto rage bait como su Palabra [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468865","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La palabra del a\u00f1o 2025 de Oxford es completamente irritante - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La palabra del a\u00f1o 2025 de Oxford es completamente irritante - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u00bfConoces esa sensaci\u00f3n cuando lees algo en l\u00ednea y te parece deliberadamente provocador, casi fabricado para indignar? Quiz\u00e1s te hayas topado con un rage bait: contenido dise\u00f1ado deliberadamente para causar ira y aumentar la interacci\u00f3n. Y se ha vuelto tan omnipresente en Internet que el Diccionario Oxford nombr\u00f3 el concepto rage bait como su Palabra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T23:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La palabra del a\u00f1o 2025 de Oxford es completamente irritante\",\"datePublished\":\"2025-12-01T23:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/\"},\"wordCount\":604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/\",\"name\":\"La palabra del a\u00f1o 2025 de Oxford es completamente irritante - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-01T23:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La palabra del a\u00f1o 2025 de Oxford es completamente irritante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La palabra del a\u00f1o 2025 de Oxford es completamente irritante - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La palabra del a\u00f1o 2025 de Oxford es completamente irritante - Noticias","og_description":"\u00bfConoces esa sensaci\u00f3n cuando lees algo en l\u00ednea y te parece deliberadamente provocador, casi fabricado para indignar? Quiz\u00e1s te hayas topado con un rage bait: contenido dise\u00f1ado deliberadamente para causar ira y aumentar la interacci\u00f3n. Y se ha vuelto tan omnipresente en Internet que el Diccionario Oxford nombr\u00f3 el concepto rage bait como su Palabra [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-01T23:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/"},"author":{"name":"","@id":""},"headline":"La palabra del a\u00f1o 2025 de Oxford es completamente irritante","datePublished":"2025-12-01T23:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/"},"wordCount":604,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/","name":"La palabra del a\u00f1o 2025 de Oxford es completamente irritante - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-01T23:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La palabra del a\u00f1o 2025 de Oxford es completamente irritante"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La palabra del a\u00f1o 2025 de Oxford es completamente irritante","url":"http:\/\/noticiasya.com\/nacional\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/12\/01\/palabra-anio-2025-oxford-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-01T23:03:48Z","datePublished":"2025-12-01T23:03:48Z","dateModified":"2025-12-01T23:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La palabra del a\\u00f1o 2025 de Oxford es completamente irritante\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/01\\\/palabra-anio-2025-oxford-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/01\\\/palabra-anio-2025-oxford-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-01T23:03:48Z\",\"datePublished\":\"2025-12-01T23:03:48Z\",\"dateModified\":\"2025-12-01T23:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468451,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/18\/palabra-2025-diccionario-cambridge-parasaocial-trax\/","url_meta":{"origin":1468865,"position":0},"title":"La palabra del a\u00f1o 2025 del Diccionario de Cambridge es &#171;parasocial&#187; y captura un fen\u00f3meno moderno &#171;poco saludable&#187;","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"El diccionario de Cambridge ha elegido su palabra del a\u00f1o 2025: \u201c parasocial \u201d, que se utiliza para describir una conexi\u00f3n que las personas sienten con alguien que no conocen, o incluso con una inteligencia artificial.El t\u00e9rmino fue acu\u00f1ado en 1956 por los soci\u00f3logos Donald Horton y Richard Wohl, quienes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468875,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/02\/5-cosas-2-de-diciembre-orix\/","url_meta":{"origin":1468865,"position":1},"title":"Las 5 cosas que debes saber este 2 de diciembre: incertidumbre electoral en Honduras, aliados de Maduro y Nueva Orleans","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"Maduro perdi\u00f3 dos aliados, \u00bfqui\u00e9n le queda?. El hijo del Chapo Guzm\u00e1n se declara culpable de narcotr\u00e1fico en EE.UU. La curiosa coincidencia entre el Flamengo y la serie \u201cStranger Things\u201d. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455964,"url":"https:\/\/noticiasya.com\/nacional\/2024\/11\/20\/manifestar-palabra-2024-diccionario-cambridge-trax\/","url_meta":{"origin":1468865,"position":2},"title":"&#171;Manifestar&#187;: la palabra de este 2024 elegida por el Diccionario de Cambridge","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) -- El Diccionario de Cambridge lo puso en el universo, nombrando \"manifestar\" como su palabra del a\u00f1o para 2024.Popularizada por celebridades como la cantante Dua Lipa, \"manifestar\" se refiere a la pr\u00e1ctica de usar \"m\u00e9todos como la visualizaci\u00f3n y la afirmaci\u00f3n para ayudarte a imaginar lograr algo que deseas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465597,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/18\/diccionario-cambridge-nuevas-palabras-trax\/","url_meta":{"origin":1468865,"position":3},"title":"\u00bfQu\u00e9 significan &#171;skibidi&#187;, &#171;tradwife&#187; y &#171;delulu&#187;, las \u00faltimas incorporaciones del Diccionario Cambridge?","author":"","date":"agosto 18, 2025","format":false,"excerpt":"El creciente uso de las tendencias de TikTok y los t\u00e9rminos de redes sociales en las conversaciones cotidianas ha llevado al Diccionario Cambridge a incluir \u201cskibidi\u201d, \u201cdelulu\u201d y \u201ctradwife\u201d entre las 6.000 palabras nuevas que ha a\u00f1adido a su edici\u00f3n online durante el \u00faltimo a\u00f1o.Para quienes pasamos menos tiempo online,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456093,"url":"https:\/\/noticiasya.com\/nacional\/2024\/11\/26\/recatado-palabra-del-ano-2024-de-dictionary-com-trax\/","url_meta":{"origin":1468865,"position":4},"title":"&#171;Demure&#187; es la palabra del a\u00f1o 2024 de Dictionary.com","author":"","date":"noviembre 26, 2024","format":false,"excerpt":"(CNN) -- \"Recatado\" (Demure), una palabra que se hizo viral durante el verano, fue nombrada palabra del a\u00f1o 2024 por Dictionary.com, superando a otras candidatas como \"brainrot\" (decadencia mental), \"brat\" (maleducado) y \"weird\" (extra\u00f1o).En un comunicado publicado este lunes, el sitio web afirma que la palabra experiment\u00f3 un \"mete\u00f3rico aumento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463052,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/31\/palabra-con-r-normaliza-insulto-trax\/","url_meta":{"origin":1468865,"position":5},"title":"La &#171;palabra con r&#187; est\u00e1 de regreso: c\u00f3mo fue que un insulto volvi\u00f3 a normalizarse en el discurso p\u00fablico","author":"","date":"mayo 31, 2025","format":false,"excerpt":"En un episodio de abril de \u201cThe Joe Rogan Experience\u201d, el presentador utiliz\u00f3 un insulto en los primeros 45 segundos del programa.\u201cLa palabra \u2018retrasado\u2019 ha vuelto, y es una de las grandes victorias culturales\u201d, dijo Rogan entre risas en el episodio del 10 de abril de su popular podcast. \u201cProbablemente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1468865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1468865"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1468865\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1468865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1468865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1468865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}