{"id":1469205,"date":"2025-12-12T02:03:50","date_gmt":"2025-12-12T10:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/"},"modified":"2025-12-12T02:03:50","modified_gmt":"2025-12-12T10:03:50","slug":"sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/","title":{"rendered":"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero"},"content":{"rendered":"<p>Estados Unidos anunci\u00f3 nuevas sanciones a compa\u00f1\u00edas navieras y buques que, seg\u00fan dice, ayudan a transportar crudo venezolano, lo que pone m\u00e1s presi\u00f3n sobre un importante pilar del Gobierno del presidente Nicol\u00e1s Maduro un d\u00eda despu\u00e9s de que incautara un petrolero sancionado que probablemente transportaba combustible por valor de millones de d\u00f3lares frente a las costas del pa\u00eds.<\/p>\n<p>Tres sobrinos de la esposa de Maduro, Cilia Flores, as\u00ed como otro empresario af\u00edn a Maduro, tambi\u00e9n fueron incluidos en la lista de sanciones publicada el jueves por el Departamento del Tesoro de Estados Unidos.<\/p>\n<p>Dos de los sobrinos sancionados fueron <a href=\"https:\/\/www.justice.gov\/usao-sdny\/pr\/nephews-venezuela-first-lady-each-sentenced-18-years-prison-conspiring-import-cocaine\" rel=\"noopener noreferrer\" target=\"_blank\">condenados<\/a> previamente por narcotr\u00e1fico en Estados Unidos antes de ser liberados en un intercambio de prisioneros.<\/p>\n<p>El Tesoro afirm\u00f3 que los <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sb0332\">seis buques<\/a> incurrieron en pr\u00e1cticas de transporte mar\u00edtimo enga\u00f1osas e inseguras que proporcionaron recursos financieros al Gobierno de Maduro. Cuatro de los buques tienen bandera paname\u00f1a. Los otros dos tienen bandera de las Islas Cook y Hong Kong.<\/p>\n<p>La medida intensifica a\u00fan m\u00e1s la campa\u00f1a de presi\u00f3n que lleva meses llevando adelante la administraci\u00f3n Trump sobre Venezuela, que ha incluido el traslado de miles de tropas y un grupo de ataque de portaviones al Caribe, ataques a presuntos barcos cargados de drogas y reiteradas amenazas contra Maduro.<\/p>\n<p>El mi\u00e9rcoles, personal estadounidense armado <a href=\"https:\/\/www.cnn.com\/2025\/12\/10\/politics\/oil-tanker-seized-venezuela\">incaut\u00f3 un petrolero<\/a> en aguas internacionales frente a la costa venezolana que presuntamente hab\u00eda estado involucrado en una \u201cred de transporte il\u00edcito de petr\u00f3leo\u201d en apoyo a pa\u00edses como Venezuela e Ir\u00e1n, seg\u00fan la secretaria de Justicia, Pam Bondi.<\/p>\n<p>Venezuela alberga la <a href=\"https:\/\/www.cnn.com\/2025\/12\/02\/business\/venezuela-oil-trump\">mayor masa de crudo conocida del planeta<\/a>, pero las sanciones internacionales y una profunda crisis econ\u00f3mica han paralizado la industria petrolera del pa\u00eds.<\/p>\n<p>Sin embargo, la empresa estatal de petr\u00f3leo y gas natural PDVSA todav\u00eda representa la mayor fuente de ingresos para el Gobierno de Maduro, con problemas de liquidez, en parte gracias a una red de buques oscuros que introducen crudo venezolano de contrabando en las cadenas de suministro globales.<\/p>\n<p>La incautaci\u00f3n del combustible y las \u00faltimas sanciones a empresas y barcos acusados \u200b\u200bde ayudar a transportar petr\u00f3leo venezolano podr\u00edan inyectar incertidumbre en esas operaciones, dijo Muyu Xu, analista del sector s\u00e9nior de la firma de inteligencia comercial Kpler.<\/p>\n<p>\u201cLo que tenemos que tener en cuenta en los pr\u00f3ximos d\u00edas es si las cargas se retrasar\u00e1n, si ellos (Venezuela) ver\u00e1n menos buques petroleros yendo al Caribe\u201d, coment\u00f3 a CNN.<\/p>\n<p>\u201cPara atraer estos buques, probablemente Venezuela tenga que pagar fletes m\u00e1s altos a los armadores\u201d.<\/p>\n<p>Es posible que se produzcan m\u00e1s incautaciones en las pr\u00f3ximas semanas a medida que Estados Unidos aplica presi\u00f3n sobre Maduro, afirm\u00f3 anteriormente a CNN un alto funcionario estadounidense.<\/p>\n<p>Maduro ha afirmado que la creciente campa\u00f1a de Trump en su contra est\u00e1 motivada principalmente por el deseo de obtener petr\u00f3leo venezolano.<\/p>\n<p>Reuters inform\u00f3 que Maduro manifest\u00f3 que el barco, conocido como Skipper, transportaba casi dos millones de barriles de petr\u00f3leo \u201ca los mercados internacionales\u201d cuando fue incautado.<\/p>\n<p>Los precios del crudo se mantienen alrededor de los US$ 58 por barril en Estados Unidos.<\/p>\n<p>Si el petrolero transportaba alrededor de 1,8 millones de barriles de crudo Merey, Xu de Kpler dijo a CNN que el valor de la carga desembarcada ser\u00eda de alrededor de US$ 84 millones.<\/p>\n<p>Venezuela produce alrededor de un mill\u00f3n de barriles de petr\u00f3leo al d\u00eda, pero solo representa alrededor del 0,8 % de la producci\u00f3n mundial de crudo.<\/p>\n<p>Ese volumen es menos de la mitad de lo que produc\u00eda antes de que Maduro tomara el control del pa\u00eds en 2013 y menos de un tercio de los 3,5 millones de barriles que extra\u00eda antes de la llegada del Gobierno socialista al poder en 1999.<\/p>\n<p>CNN se ha comunicado con el Gobierno venezolano para solicitar comentarios sobre las \u00faltimas sanciones.<\/p>\n<p>El petrolero incautado se dirig\u00eda a Cuba y transportaba crudo venezolano cuando fue incautado por fuerzas estadounidenses.<\/p>\n<p>Sucedi\u00f3 casi al mismo tiempo que la l\u00edder de la oposici\u00f3n venezolana y premio Nobel de la Paz Mar\u00eda Corina Machado <a href=\"https:\/\/www.cnn.com\/2025\/12\/10\/europe\/nobel-prize-ceremony-machado-intl\">aterrizaba en Oslo<\/a>, despu\u00e9s de desafiar una prohibici\u00f3n de viajar y huir del pa\u00eds.<\/p>\n<p>El petrolero, anteriormente llamado Adisa, fue sancionado por Estados Unidos en 2022 por facilitar el comercio de crudo para Hezbollah y la Fuerza Quds del Cuerpo de la Guardia Revolucionaria Isl\u00e1mica de Ir\u00e1n.<\/p>\n<p>El Skipper hab\u00eda ocultado su verdadera ubicaci\u00f3n mientras estaba atracado en una terminal venezolana el mes pasado, seg\u00fan datos satelitales y de navegaci\u00f3n revisados \u200b\u200bpor CNN.<\/p>\n<p>El tanquero enarbolaba bandera guyanesa, a pesar de no estar registrado en Guyana, seg\u00fan inform\u00f3 el Departamento de Administraci\u00f3n Mar\u00edtima del pa\u00eds.<\/p>\n<p>Ninguno de los seis buques sancionados el jueves se encontraba en el Caribe a primera hora del viernes EST, seg\u00fan los datos de env\u00edo de AIS revisados \u200b\u200bpor CNN.<\/p>\n<p>A primera hora del viernes (hora del este), hab\u00eda al menos ocho petroleros bajo sanciones estadounidenses relacionadas con la guerra de Ir\u00e1n o Rusia contra Ucrania cerca de puertos venezolanos o frente a sus costas, de acuerdo con datos de transporte mar\u00edtimo de AIS revisados \u200b\u200bpor CNN y cotejados con informaci\u00f3n del Tesoro de EE.UU.<\/p>\n<p>Esto incluye tres petroleros que se encuentran cerca de la Terminal Petrolera de Puerto Jos\u00e9, la misma donde el buque recientemente incautado, Skipper, fue avistado en im\u00e1genes satelitales el mes pasado.<\/p>\n<p>La secretaria de prensa de la Casa Blanca, Karoline Leavitt, afirm\u00f3 que el Skipper ahora viajar\u00e1 a un puerto estadounidense, donde las autoridades estadounidenses pretenden tomar posesi\u00f3n de su cargamento de crudo.<\/p>\n<p>Mientras tanto, Maduro dijo que la incautaci\u00f3n marcaba \u201cuna nueva era de pirater\u00eda naval criminal en el Caribe\u201d y su Gobierno present\u00f3 una denuncia formal ante la Organizaci\u00f3n Mar\u00edtima Internacional.<\/p>\n<p>Xu, de Kpler, coment\u00f3 que si Estados Unidos comenzara a arrestar tripulaciones o a detener cargamentos con frecuencia, podr\u00eda ser un problema para la capacidad de Venezuela de exportar su petr\u00f3leo.<\/p>\n<p>\u201cPodr\u00eda ser realmente problem\u00e1tico, porque quiz\u00e1 en alg\u00fan momento los armadores se den cuenta de que el riesgo es demasiado alto y nadie querr\u00e1 ir\u201d, sostuvo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos anunci\u00f3 nuevas sanciones a compa\u00f1\u00edas navieras y buques que, seg\u00fan dice, ayudan a transportar crudo venezolano, lo que pone m\u00e1s presi\u00f3n sobre un importante pilar del Gobierno del presidente Nicol\u00e1s Maduro un d\u00eda despu\u00e9s de que incautara un petrolero sancionado que probablemente transportaba combustible por valor de millones de d\u00f3lares frente a las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469205","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero - Noticias\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos anunci\u00f3 nuevas sanciones a compa\u00f1\u00edas navieras y buques que, seg\u00fan dice, ayudan a transportar crudo venezolano, lo que pone m\u00e1s presi\u00f3n sobre un importante pilar del Gobierno del presidente Nicol\u00e1s Maduro un d\u00eda despu\u00e9s de que incautara un petrolero sancionado que probablemente transportaba combustible por valor de millones de d\u00f3lares frente a las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T10:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero\",\"datePublished\":\"2025-12-12T10:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/\"},\"wordCount\":1107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/\",\"name\":\"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-12T10:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero - Noticias","og_description":"Estados Unidos anunci\u00f3 nuevas sanciones a compa\u00f1\u00edas navieras y buques que, seg\u00fan dice, ayudan a transportar crudo venezolano, lo que pone m\u00e1s presi\u00f3n sobre un importante pilar del Gobierno del presidente Nicol\u00e1s Maduro un d\u00eda despu\u00e9s de que incautara un petrolero sancionado que probablemente transportaba combustible por valor de millones de d\u00f3lares frente a las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-12T10:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero","datePublished":"2025-12-12T10:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/"},"wordCount":1107,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/","name":"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-12T10:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. sanciona a navieras y buques que, seg\u00fan afirma, transportan crudo venezolano, un d\u00eda despu\u00e9s de incautar un petrolero","url":"http:\/\/noticiasya.com\/nacional\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/12\/12\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-12T10:03:50Z","datePublished":"2025-12-12T10:03:50Z","dateModified":"2025-12-12T10:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. sanciona a navieras y buques que, seg\\u00fan afirma, transportan crudo venezolano, un d\\u00eda despu\\u00e9s de incautar un petrolero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/12\\\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/12\\\/sanciones-sobrinos-maduro-empresas-navieras-petroleo-venezolano-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-12T10:03:50Z\",\"datePublished\":\"2025-12-12T10:03:50Z\",\"dateModified\":\"2025-12-12T10:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469245,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/13\/venezuela-trabajadores-alertas-seguridad-fisica-cibernetica-operaciones-petroleras-orix\/","url_meta":{"origin":1469205,"position":0},"title":"Venezuela pide a trabajadores estar alertas de la &#171;seguridad f\u00edsica&#187; y &#171;cibern\u00e9tica&#187; de las operaciones petroleras","author":"","date":"diciembre 13, 2025","format":false,"excerpt":"La vicepresidenta de Venezuela y ministra de Hidrocarburos del pa\u00eds, Delcy Rodr\u00edguez, pidi\u00f3 el viernes a trabajadores de la empresa estatal Petr\u00f3leos de Venezuela (PDVSA) que se mantengan alertas de la \u201cseguridad f\u00edsica\u201d y \u201ccibern\u00e9tica\u201d de las instalaciones y operaciones petroleras del pa\u00eds, en momentos en que crece la tensi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469431,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","url_meta":{"origin":1469205,"position":1},"title":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"Un petrolero y qu\u00edmico sancionado por Estados Unidos ha entrado en aguas venezolanas, seg\u00fan mostraron datos de rastreo de barcos, a pesar de que el presidente de EE.UU., Donald Trump, declar\u00f3 un \u201cbloqueo total y completo\u201d a dichos buques que transitan por el pa\u00eds.El barco con bandera de Gambia, llamado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469697,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/31\/estados-unidos-mas-sanciones-sector-petrolero-trax\/","url_meta":{"origin":1469205,"position":2},"title":"Estados Unidos anuncia m\u00e1s sanciones al sector petrolero de Venezuela","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"El Departamento del Tesoro de EE.UU. intent\u00f3 este mi\u00e9rcoles aumentar a\u00fan m\u00e1s la presi\u00f3n sobre el sector petrolero de Venezuela al sancionar a cuatro compa\u00f1\u00edas petroleras m\u00e1s y designar cuatro petroleros como \u201cpropiedad bloqueada\u201d.Los petroleros financian al Gobierno de Maduro, aleg\u00f3 el Tesoro. En un comunicado, el secretario del Tesoro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469233,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/13\/trump-ataques-venezuela-empezar-suceder-trax\/","url_meta":{"origin":1469205,"position":3},"title":"Trump dice que los ataques por tierra en Venezuela &#171;van a empezar a suceder&#187;","author":"","date":"diciembre 13, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, afirm\u00f3 este viernes que los ataques por tierra en Venezuela \u201cvan a empezar a suceder\u201d y que \u201cno vamos a permitir que destruyan a nuestra juventud\u201d.\u201cAhora estamos empezando por tierra, y por tierra es mucho m\u00e1s f\u00e1cil, y eso va a empezar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469545,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/24\/ee-uu-sanciones-venezuela-aplicadas-orix\/","url_meta":{"origin":1469205,"position":4},"title":"EE.UU. asegura que impondr\u00e1 sanciones &#171;al m\u00e1ximo&#187; sobre Venezuela: \u00e9stas son las que ya aplic\u00f3","author":"","date":"diciembre 24, 2025","format":false,"excerpt":"Estados Unidos profundiza la campa\u00f1a de presi\u00f3n sobre Venezuela y el presidente Nicol\u00e1s Maduro con la amenaza de nuevas sanciones \u201cal m\u00e1ximo\u201d sobre el pa\u00eds.El presidente de EE.UU., Donald Trump, tiene la intenci\u00f3n de usar \u201ctodo el poder y la fuerza\u201d con nuevas medidas, dijo este martes el embajador del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469221,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/12\/buques-petroleros-caribe-economia-venezuela-orix\/","url_meta":{"origin":1469205,"position":5},"title":"Hay decenas de buques petroleros en el Caribe que EE.UU. podr\u00eda incautar. \u00bfQu\u00e9 significar\u00eda para la econom\u00eda de Venezuela?","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"La econom\u00eda de Venezuela vive de un solo producto, el petr\u00f3leo, y ese producto ha sido blanco de sanciones de EE.UU. al menos desde 2019, que incluyen a la estatal PDVSA y por las cuales acaba de ser incautado un buque petrolero, el Skipper, posiblemente el primero de muchos. Solo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469205"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469205\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}