{"id":1469216,"date":"2025-12-12T10:03:51","date_gmt":"2025-12-12T18:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/"},"modified":"2025-12-12T10:03:51","modified_gmt":"2025-12-12T18:03:51","slug":"fotos-patrimonio-epstein-trump-clinton-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","title":{"rendered":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil"},"content":{"rendered":"<p>Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este viernes fotos del patrimonio de Jeffrey Epstein que muestran a numerosas figuras poderosas en la \u00f3rbita del difunto traficante sexual, incluyendo al presidente Donald Trump, al expresidente Bill Clinton, a Steve Bannon, Bill Gates, Richard Branson y otros.<\/p>\n<p>Muchos de los hombres han sido vinculados previamente con Epstein, aunque las fotos podr\u00edan arrojar nueva luz sobre el alcance de esas relaciones.<\/p>\n<p>En conjunto, las 19 im\u00e1genes \u2014que seg\u00fan la comisi\u00f3n provienen del patrimonio de Epstein\u2014 refuerzan que el financiero estuvo vinculado en el pasado con una amplia variedad de personas poderosas y de alto perfil, cuyos v\u00ednculos con \u00e9l ahora est\u00e1n bajo un escrutinio riguroso.<\/p>\n<p>Una imagen publicada este viernes muestra lo que parece ser un recipiente con condones con una caricatura del rostro de Trump. El recipiente tiene un letrero que dice \u201cCond\u00f3n Trump, US$ 4,50\u201d, y cada cond\u00f3n tiene una imagen del rostro de Trump con el texto \u201c\u00a1Soy ENORME!\u201d. Otra imagen muestra a Trump con seis mujeres con collares de flores, cuyos rostros fueron cubiertos por la comisi\u00f3n. Otras im\u00e1genes incluyen a Steve Bannon y Epstein tom\u00e1ndose una foto en un espejo; Bill Clinton con Epstein, Maxwell y otra pareja; y el multimillonario tecnol\u00f3gico Bill Gates con el expr\u00edncipe Andr\u00e9s. El expresidente de Harvard Larry Summers y el abogado Alan Dershowitz tambi\u00e9n aparecieron en fotos del patrimonio.<\/p>\n<p>Ninguna de las im\u00e1genes publicadas muestra conducta sexual inapropiada ni se cree que muestre a menores de edad. No se aclar\u00f3 de inmediato cu\u00e1ndo ni d\u00f3nde fueron tomadas, ni qui\u00e9n las tom\u00f3.<\/p>\n<p>La comisi\u00f3n, liderada por republicanos, obtuvo las im\u00e1genes del patrimonio de Epstein como parte de su investigaci\u00f3n en curso. Hasta la fecha, el panel ha publicado decenas de miles de documentos, correos electr\u00f3nicos y comunicaciones que recibi\u00f3 del patrimonio de Epstein, lo que contin\u00faa abriendo nuevas l\u00edneas de investigaci\u00f3n.<\/p>\n<p>El jueves, los abogados de los bienes escribieron una carta al comit\u00e9 indicando que pod\u00edan revisar los videos y fotograf\u00edas que hab\u00edan solicitado, \u201ctomados en cualquier propiedad propia, alquilada, operada o utilizada por Epstein entre el 1 de enero de 1990 y el 10 de agosto de 2019\u201d.<\/p>\n<p>\u201cAl igual que la presentaci\u00f3n de ayer, tambi\u00e9n incluye documentos que podr\u00edan no ser relevantes, pero que los abogados de los bienes no pudieron confirmar si fueron tomados en una propiedad propia, alquilada, operada o utilizada por Epstein. Los abogados han proporcionado una m\u00ednima edici\u00f3n de estas fotograf\u00edas; las ediciones se limitan a (tapar) la desnudez\u201d, escribieron.<\/p>\n<p>El representante Robert Garc\u00eda, el dem\u00f3crata de mayor rango en la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, declar\u00f3 que la \u00faltima presentaci\u00f3n del patrimonio conten\u00eda \u201cm\u00e1s de 95.000 fotos, incluyendo im\u00e1genes de los hombres ricos y poderosos que convivieron con Jeffrey Epstein\u201d y \u201cmiles de fotograf\u00edas de mujeres y de propiedades de Epstein\u201d.<\/p>\n<p>\u201cEs hora de poner fin a este encubrimiento de la Casa Blanca y hacer justicia a los sobrevivientes de Jeffrey Epstein y sus poderosos amigos\u201d, declar\u00f3 en un comunicado. \u201cEstas inquietantes fotos plantean a\u00fan m\u00e1s preguntas sobre Epstein y sus relaciones con algunos de los hombres m\u00e1s poderosos del mundo. No descansaremos hasta que el pueblo estadounidense conozca la verdad. El Departamento de Justicia debe publicar todos los archivos, \u00a1YA!\u201d.<\/p>\n<p>Un portavoz de la comisi\u00f3n acus\u00f3 a los dem\u00f3cratas del panel de \u201cseleccionar fotos a discreci\u00f3n y realizar ediciones selectivas para crear una narrativa falsa sobre el presidente Trump\u201d.<\/p>\n<p>\u201cRecibimos m\u00e1s de 95.000 fotos y los dem\u00f3cratas publicaron solo unas pocas. El enga\u00f1o de los dem\u00f3cratas contra el presidente Trump ha sido completamente desmentido. Nada en los documentos que hemos recibido demuestra ninguna irregularidad. Es vergonzoso que el representante Garc\u00eda y los dem\u00f3cratas sigan priorizando la pol\u00edtica sobre la justicia para los sobrevivientes\u201d, declar\u00f3 el portavoz.<\/p>\n<p>CNN se ha comunicado con la Casa Blanca y con los representantes de Bannon, Clinton, Gates, Allen, Branson, Summers, Dershowitz y Mountbatten-Windsor.<\/p>\n<p>Clinton nunca ha sido acusado por las fuerzas del orden de ning\u00fan delito relacionado con Epstein, y un portavoz ha afirmado repetidamente que cort\u00f3 v\u00ednculos con Epstein antes de su arresto por cargos federales en 2019 y que desconoc\u00eda sus delitos.<\/p>\n<p>Un portavoz de Gates ha negado repetidamente que Epstein haya trabajado para \u00e9l. Gates ya se arrepinti\u00f3 de haberse reunido con Epstein, y en 2021 declar\u00f3 a Anderson Cooper de CNN: \u201cFue un gran error pasar tiempo con \u00e9l, darle la credibilidad de estar all\u00ed\u201d.<\/p>\n<p>Los v\u00ednculos de Trump con Epstein son bien conocidos. Ambos formaban parte de los mismos c\u00edrculos sociales en Manhattan y Palm Beach. Pero Trump no ha sido acusado de ning\u00fan delito penal vinculado, y \u00e9l y su equipo han criticado anteriormente a Epstein, llam\u00e1ndolo \u201cpervertido\u201d y expuls\u00e1ndolo de su club.<\/p>\n<p>En una serie reciente de correos electr\u00f3nicos publicados por la comisi\u00f3n, Epstein afirm\u00f3 que Trump \u201cpas\u00f3 horas\u201d con una de sus acusadoras m\u00e1s destacadas, la difunta Virginia Giuffre. Epstein tambi\u00e9n escribi\u00f3 en un correo electr\u00f3nico que Trump \u201csab\u00eda de las chicas\u201d, una aparente referencia a la afirmaci\u00f3n de Trump de haber expulsado a Epstein de su club Mar-a-Lago por captar a las j\u00f3venes que trabajaban all\u00ed. Tras la publicaci\u00f3n de estos correos, Trump y la Casa Blanca calificaron el asunto de \u201cenga\u00f1o\u201d, y la secretaria de prensa, Karoline Leavitt, afirm\u00f3 que los correos \u201cno prueban absolutamente nada, salvo el hecho de que el presidente Trump no hizo nada malo\u201d.<\/p>\n<p>La revisi\u00f3n de CNN de miles de p\u00e1ginas de correos electr\u00f3nicos de Epstein muestra que, a lo largo de los a\u00f1os, Epstein invoc\u00f3 repetidamente a Trump, a veces para ofrecer un an\u00e1lisis de su comportamiento, a veces para chismear y a veces simplemente para presentarse como alguien con una visi\u00f3n excepcional del hombre que se hab\u00eda convertido en presidente.<\/p>\n<p>Otros que fueron asociados con Epstein han enfrentado consecuencias profesionales o de otro tipo por esa relaci\u00f3n, a pesar de que tampoco fueron acusados \u200b\u200bde ning\u00fan delito penal.<\/p>\n<p>Summers se tom\u00f3 una licencia en Harvard y renunci\u00f3 a su puesto en la junta directiva de OpenAI. Ha declarado sentirse \u201cprofundamente avergonzado\u201d de mantener v\u00ednculos con Epstein y, aunque se retira de cargos p\u00fablicos, dijo que trabajar\u00e1 para \u201creconstruir la confianza y reparar las relaciones con las personas m\u00e1s cercanas a \u00e9l\u201d. Andr\u00e9s Mountbatten-Windsor renunci\u00f3 al uso de sus t\u00edtulos reales a pesar de haber negado cualquier acusaci\u00f3n de mala conducta.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este viernes fotos del patrimonio de Jeffrey Epstein que muestran a numerosas figuras poderosas en la \u00f3rbita del difunto traficante sexual, incluyendo al presidente Donald Trump, al expresidente Bill Clinton, a Steve Bannon, Bill Gates, Richard Branson y otros. Muchos de los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469216","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este viernes fotos del patrimonio de Jeffrey Epstein que muestran a numerosas figuras poderosas en la \u00f3rbita del difunto traficante sexual, incluyendo al presidente Donald Trump, al expresidente Bill Clinton, a Steve Bannon, Bill Gates, Richard Branson y otros. Muchos de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T18:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil\",\"datePublished\":\"2025-12-12T18:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/\"},\"wordCount\":1180,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/\",\"name\":\"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-12T18:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil - Noticias","og_description":"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este viernes fotos del patrimonio de Jeffrey Epstein que muestran a numerosas figuras poderosas en la \u00f3rbita del difunto traficante sexual, incluyendo al presidente Donald Trump, al expresidente Bill Clinton, a Steve Bannon, Bill Gates, Richard Branson y otros. Muchos de los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-12T18:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/"},"author":{"name":"","@id":""},"headline":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil","datePublished":"2025-12-12T18:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/"},"wordCount":1180,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","name":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-12T18:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Publican m\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil","url":"http:\/\/noticiasya.com\/nacional\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/12\/12\/fotos-patrimonio-epstein-trump-clinton-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-12T18:03:51Z","datePublished":"2025-12-12T18:03:51Z","dateModified":"2025-12-12T18:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Publican m\\u00e1s fotos del archivo de Jeffrey Epstein que muestran a Trump, Bannon, Bill Clinton y otras figuras de alto perfil\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/12\\\/fotos-patrimonio-epstein-trump-clinton-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/12\\\/fotos-patrimonio-epstein-trump-clinton-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-12T18:03:51Z\",\"datePublished\":\"2025-12-12T18:03:51Z\",\"dateModified\":\"2025-12-12T18:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470049,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/13\/clinton-niegan-testificar-investigacion-epstein-trax\/","url_meta":{"origin":1469216,"position":0},"title":"Los Clinton se niegan a testificar en la investigaci\u00f3n del Congreso sobre Epstein pese a la amenaza de desacato","author":"","date":"enero 13, 2026","format":false,"excerpt":"Bill y Hillary Clinton se negaron a testificar este martes en el Capitolio ante la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes en el marco de la investigaci\u00f3n sobre Jeffrey Epstein, pese a la amenaza de legisladores de declararlos en desacato.\u201cUsted dir\u00e1 que no es nuestra decisi\u00f3n. Pero ya\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469395,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/18\/nuevas-fotos-patrimonio-epstein-trax\/","url_meta":{"origin":1469216,"position":1},"title":"Dem\u00f3cratas de la C\u00e1mara revelan m\u00e1s fotos de Epstein ante la fecha l\u00edmite de publicaci\u00f3n de los archivos","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes publicaron este jueves fotos del patrimonio de Jeffrey Epstein, la \u00faltima de una serie de revelaciones intermitentes que han impulsado una importante intriga pol\u00edtica en las \u00faltimas semanas sobre qui\u00e9n podr\u00eda haber estado asociado con el delincuente sexual\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468933,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/03\/divulgan-fotos-isla-epstein-trax\/","url_meta":{"origin":1469216,"position":2},"title":"Dem\u00f3cratas de la C\u00e1mara de Representantes revelan fotos y videos de la isla privada de Epstein","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes divulgaron este mi\u00e9rcoles nuevas fotos y videos de una isla privada en el Caribe que perteneci\u00f3 a Jeffrey Epstein, arrojando nueva luz sobre lo que fue el epicentro de las d\u00e9cadas de abuso de ni\u00f1as y mujeres por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464768,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/22\/fotos-videos-relacion-trump-jeffrey-epstein-trax\/","url_meta":{"origin":1469216,"position":3},"title":"Exclusivo: Fotos y videos reci\u00e9n descubiertos arrojan nueva luz sobre los lazos de Trump con Jeffrey Epstein","author":"","date":"julio 22, 2025","format":false,"excerpt":"Material de video archivado y fotos recientemente descubiertos revelan nuevos detalles sobre la relaci\u00f3n pasada de Donald Trump con Jeffrey Epstein.Fotos de 1993 confirman por primera vez que Epstein asisti\u00f3 a la boda de Trump con Marla Maples ese a\u00f1o. La asistencia de Epstein a la ceremonia en el Hotel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466274,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/08\/camara-representantes-patrimonio-epstein-trump-trax\/","url_meta":{"origin":1469216,"position":4},"title":"Comisi\u00f3n de la C\u00e1mara de Representantes publica &#171;libro de cumplea\u00f1os&#187; y otros registros del patrimonio de Epstein","author":"","date":"septiembre 8, 2025","format":false,"excerpt":"La Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes public\u00f3 este lunes por la noche registros del patrimonio de Jeffrey Epstein, incluida una colecci\u00f3n de cartas regaladas al fallecido delincuente sexual convicto por su 50\u00b0 cumplea\u00f1os que inclu\u00eda una nota con el nombre del presidente Donald Trump.Adem\u00e1s del \u201clibro de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469464,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/21\/que-contienen-archivos-epstein-publicados-trax\/","url_meta":{"origin":1469216,"position":5},"title":"\u00bfQu\u00e9 contienen los archivos de Epstein publicados por el Departamento de Justicia?","author":"","date":"diciembre 21, 2025","format":false,"excerpt":"El Departamento de Justicia public\u00f3 miles de archivos relacionados con el delincuente sexual y acusado de tr\u00e1fico sexual Jeffrey Epstein despu\u00e9s de que el Congreso aprobara una ley que oblig\u00f3 a la administraci\u00f3n Trump a hacerlo.La publicaci\u00f3n del viernes no incluy\u00f3 todos los archivos, ya que el Departamento de Justicia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469216"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469216\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}