{"id":1469640,"date":"2025-12-29T07:03:44","date_gmt":"2025-12-29T15:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/"},"modified":"2025-12-29T07:03:44","modified_gmt":"2025-12-29T15:03:44","slug":"inmigrantes-contribuyen-comunidad-arrestadas-ice","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/","title":{"rendered":"No son &#171;lo peor de lo peor&#187;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE"},"content":{"rendered":"<p>Detener y expulsar de Estados Unidos <a href=\"https:\/\/www.dhs.gov\/news\/2025\/11\/12\/secretary-noem-highlights-worst-worst-criminal-illegal-aliens-arrested-ice\">a \u201clo peor de lo peor\u201d<\/a>: bajo esa narrativa, la secretaria de Seguridad Nacional, Kristi Noem, defiende los arrestos de inmigrantes por parte del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) al argumentar que se trata de personas que cometieron delitos graves. Pero algunos datos y testimonios de los \u00faltimos meses parecen indicar lo contrario.<\/p>\n<p>Desde que el presidente Donald Trump asumi\u00f3 su segundo mandato hasta el 15 de octubre pasado, alrededor de 220.000 personas fueron arrestadas por ICE, seg\u00fan datos del Proyecto de Datos de Deportaci\u00f3n, un grupo de investigaci\u00f3n asociado con la facultad de derecho de UC Berkeley. Cerca de 75.000 personas que fueron detenidas en esos casi nueve meses no ten\u00edan <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/07\/eeuu\/personas-sin-antecedentes-penales-detenidas-ice-trax\">antecedentes penales<\/a>, agrega el reporte.<\/p>\n<p>En junio, CNN ya hab\u00eda reportado que <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/16\/eeuu\/menos-10-inmigrantes-detenidos-condenas-penales-graves-trax#:~:text=Y%20menos%20del%2010%20%25%20fueron%20condenadas%20por%20delitos%20graves%20como%20asesinato%2C%20agresi%C3%B3n%2C%20robo%20o%20violaci%C3%B3n.\">menos del 10 % de los inmigrantes detenidos<\/a> por ICE entre octubre de 2024 y mayo de 2025 fueron condenados por delitos graves como asesinato, agresi\u00f3n, robo o violaci\u00f3n.<\/p>\n<p>M\u00e1s all\u00e1 de los n\u00fameros, detr\u00e1s de estos casos hay historias de personas queridas y conocidas en su comunidad que pasaron semanas privadas de su libertad; de padres o madres que con sus detenciones vieron c\u00f3mo sus familias se fragmentaban mientras sus hijos quedaban sin saber c\u00f3mo seguir adelante econ\u00f3mica y emocionalmente.<\/p>\n<p>La ofensiva inmigratoria del Gobierno de Trump <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/19\/eeuu\/ice-huellas-comunidad-inmigrante-reorganiza-orix#:~:text=Los%20%C3%81ngeles%2C%20California,contener%20las%20manifestaciones.\">se intensific\u00f3 en junio con redadas en Los \u00c1ngeles, California<\/a>. Los operativos desencadenaron protestas, algunas de ellas violentas, y el despliegue de la Guardia Nacional para contener las manifestaciones.<\/p>\n<p>Sin tener antecedentes penales, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/28\/eeuu\/detenido-ice-liberado-regalo-paletas-celebrar-orix\">Ambrocio Lozano<\/a> pas\u00f3 m\u00e1s de cien d\u00edas en un centro de detenci\u00f3n de Los \u00c1ngeles luego de ser arrestado por agentes de inmigraci\u00f3n el 23 de junio.<\/p>\n<p>Vendedor de paletas desde hace m\u00e1s de 24 a\u00f1os, Lozano lleg\u00f3 a California en 1999 desde el estado de Guerrero, en M\u00e9xico. Desde entonces vende helados a la comunidad de Culver city, donde muchos vecinos y clientes esperaron durante meses su regreso.<\/p>\n<p>Acostumbrado durante d\u00e9cadas a trabajar todos los d\u00edas al aire libre con su carro, dice que estar encerrado entre cuatro paredes fue de las cosas m\u00e1s dif\u00edciles que tuvo que enfrentar. \u201cSent\u00eda que los d\u00edas se me hac\u00edan a\u00f1os\u201d.<\/p>\n<p>Pas\u00f3 en total 114 d\u00edas privado de su libertad. Finalmente, fue liberado y un juez de inmigraci\u00f3n aprob\u00f3 la petici\u00f3n de residencia permanente que su familia hab\u00eda presentado hace m\u00e1s de 20 a\u00f1os.<\/p>\n<p>Jorge Mario Cabrera, director de Comunicaciones de la Coalici\u00f3n por los Derechos Humanos de los Inmigrantes (CHIRLA, por sus siglas en ingl\u00e9s), dijo a CNN que  <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/19\/eeuu\/ice-huellas-comunidad-inmigrante-reorganiza-orix#:~:text=entre%205.000%20y%207.000%20personas%20que%20han%20sido%20detenidas%20o%20deportadas%20en%20el%20%C3%A1rea%20de%20Los%20%C3%81ngeles%20desde%20enero%20de%20este%20a%C3%B1o.\">entre 5.000 y 7.000 personas<\/a> han sido detenidas o deportadas en el \u00e1rea de Los \u00c1ngeles entre enero y diciembre de 2025. Seg\u00fan estimaciones de CHIRLA, \u201cel 60 % al 70 % de los detenidos en Los \u00c1ngeles no tiene ning\u00fan antecedente penal\u201d.<\/p>\n<p>Adem\u00e1s de ser el sustento econ\u00f3mico de su vida y la de su familia, Lozano afirma que es feliz como paletero. Se ve en sus gestos, en la alegr\u00eda al reencontrarse con sus clientes, en la actitud con la que empuja su carro de paletas y comparte esos sabores con ni\u00f1os y adultos.<\/p>\n<p>Tras su liberaci\u00f3n, el paletero organiz\u00f3 una tarde para reunirse con sus clientes y amigos de su comunidad en un parque p\u00fablico de Culver city. Para agradecerles les regal\u00f3 helados y comparti\u00f3 an\u00e9cdotas y abrazos. A cambio recibi\u00f3 carteles de bienvenida, aplausos y hasta una pintura de su carro de paletas.<\/p>\n<p>Esa alegr\u00eda lo ayud\u00f3 a seguir adelante. No fueron meses f\u00e1ciles y Lozano dice que la detenci\u00f3n dej\u00f3 secuelas en su salud f\u00edsica y mental, pero no quiere que eso lo detenga.<\/p>\n<p>En el centro de detenci\u00f3n migratorio Delaney Hall, ubicado en Newark, Nueva Jersey, la poblaci\u00f3n sin registros penales detenida era casi 10 veces mayor que la poblaci\u00f3n con antecedentes criminales, seg\u00fan <a href=\"https:\/\/www.ice.gov\/detain\/detention-management\">datos de ICE<\/a> hasta el 10 de noviembre.<\/p>\n<p>Una de esas personas fue e<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/11\/eeuu\/querido-chef-mexicano-detenido-ice-nueva-jersey-comunidad-apoyarlo-orix\">l chef Ruperto Vicens M\u00e1rquez<\/a>, de 38 a\u00f1os, originario del estado mexicano de Puebla. Fue arrestado por agentes de ICE el 19 de octubre mientras se dirig\u00eda al restaurante que fund\u00f3 con su hermano, Emilio\u2019s Kitchen.<\/p>\n<p>El Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/11\/eeuu\/querido-chef-mexicano-detenido-ice-nueva-jersey-comunidad-apoyarlo-orix\">dijo<\/a> a CNN que Ruperto es \u201cun extranjero ilegal de M\u00e9xico con una detenci\u00f3n previa por resistirse al arresto y una orden final de deportaci\u00f3n\u201d. Pero su abogado, Steven Lyons, rechaz\u00f3 esas afirmaciones y asegur\u00f3 que Ruperto ten\u00eda un permiso de trabajo v\u00e1lido hasta 2028 y una solicitud pendiente de alivio migratorio con cita ante la corte tambi\u00e9n prevista para ese a\u00f1o. El cargo citado por ICE fue desestimado en 2010, dijo Lyons, y agreg\u00f3 que no se trata de un delito, sino de una infracci\u00f3n civil.<\/p>\n<p>En Delaney Hall \u201chab\u00eda mucha gente que solamente la hab\u00edan agarrado saliendo de casa, en la calle, en el trabajo, de diferentes maneras, pero la mayor\u00eda no ten\u00eda r\u00e9cords criminales\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/24\/eeuu\/milagro-ayuda-comunidad-chef-ruperto-esperanza-detenido-inmigracion-orix#:~:text=Hab%C3%ADa%20mucha%20gente%20que%20solamente%20la%20hab%C3%ADan%20agarrado%20saliendo%20de%20casa%2C%20en%20la%20calle%2C%20en%20el%20trabajo%2C%20de%20diferentes%20maneras%2C%20pero%20la%20mayor%C3%ADa%20no%20ten%C3%ADa%20r%C3%A9cords%20criminales%E2%80%9D%2C%20afirma%20el%20chef%20de%2038%20a%C3%B1os.\">dijo el chef<\/a>.<\/p>\n<p>Adem\u00e1s de los datos y los testimonios, distintas organizaciones vinculadas a la defensa de casos de inmigrantes afirman que muchos de ellos distan de ser criminales o \u201clo peor de lo peor\u201d. Sui Chung, directora ejecutiva de Americans for Immigrant Justice, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/16\/eeuu\/menos-10-inmigrantes-detenidos-condenas-penales-graves-trax#:~:text=los%20inmigrantes%20han,comunidades%20durante%20a%C3%B1os.\">dijo a CNN<\/a> que la mayor\u00eda de los inmigrantes que representa su organizaci\u00f3n no tiene antecedentes penales.<\/p>\n<p>Los inmigrantes \u201chan sido retratados como un peligro para la comunidad, como una carga para la sociedad, como criminales, violadores, terroristas, y estas son afirmaciones incorrectas\u201d, dijo Chung. \u201cEs una narrativa muy peligrosa para promover en un pa\u00eds construido sobre la inmigraci\u00f3n\u201d.<\/p>\n<p>Muchos de los detenidos no han representado ning\u00fan peligro para la sociedad durante a\u00f1os, explic\u00f3.<\/p>\n<p>En Atlantic Highlands, una peque\u00f1a comunidad en la costa de Nueva Jersey, la detenci\u00f3n de Ruperto gener\u00f3 reacciones inmediatas.<\/p>\n<p>Decenas de vecinos le dieron<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/11\/eeuu\/querido-chef-mexicano-detenido-ice-nueva-jersey-comunidad-apoyarlo-orix\"> su apoyo<\/a>, tanto econ\u00f3mico como con protestas pac\u00edficas. La alcaldesa de Atlantic Highlands, Lori Hohenleitner, acompa\u00f1\u00f3 a la familia y organiz\u00f3 una <a href=\"https:\/\/www.gofundme.com\/f\/bring-ruperto-back-to-his-family-and-business\">campa\u00f1a<\/a> de GoFundMe que buscaba recaudar dinero para apoyar con los gastos legales.<\/p>\n<p>Un mes despu\u00e9s, Vicens Marquez qued\u00f3 en libertad tras el pago de una fianza que dispuso el juez. Al salir por la puerta de Delaney Hall, decenas de personas lo esperaban con aplausos y celebraciones.<\/p>\n<p>El chef de Emilio\u2019s Kitchen pudo regresar a la cocina a hacer lo que le apasiona. Para \u00e9l, la reacci\u00f3n de la comunidad fue \u201cun milagro\u201d.<\/p>\n<p>\u201cEstoy muy agradecido por lo que han ofrecido hacia mi persona y a mi familia, y les digo que han sido una esperanza muy grande, no solo para m\u00ed, sino para muchas personas que est\u00e1n pasando por las mismas situaciones\u201d, dijo.<\/p>\n<p>Para Leonel Ch\u00e1vez la realidad se parece mucho a una pesadilla.<\/p>\n<p>Este inmigrante mexicano de 42 a\u00f1os, que viv\u00eda en Estados Unidos desde hace d\u00e9cadas, fue separado de su familia al ser detenido a mediados de agosto junto a su hermano en Norwalk, Connecticut, y luego <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/26\/eeuu\/deportan-mexico-leonel-chavez-connecticut-orix\">deportado a Tamaulipas<\/a>, en M\u00e9xico.<\/p>\n<p>\u201cMe siento vac\u00edo, me siento devastado. A veces despierto y pienso que estoy all\u00e1. Es una pesadilla que a veces no me deja dormir\u201d, dijo Leonel Ch\u00e1vez en entrevista con CNN desde la ciudad de Puebla, su nuevo hogar.<\/p>\n<p>El video de su detenci\u00f3n <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/20\/eeuu\/inmigrantes-mexicanos-arrestados-norwalk-connecticut-orix\">gener\u00f3<\/a> cuestionamientos de las autoridades de Connecticut y tambi\u00e9n de la presidenta de M\u00e9xico, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/20\/eeuu\/inmigrantes-mexicanos-arrestados-norwalk-connecticut-orix\">Claudia Sheinbaum<\/a>, por considerar que se trataba de un operativo que se excedi\u00f3 en el uso de la fuerza y que constituye una \u201cviolaci\u00f3n de los derechos humanos\u201d.<\/p>\n<p>Ch\u00e1vez lleg\u00f3 a Estados Unidos a los 17 a\u00f1os. All\u00ed conoci\u00f3 a su esposa, ciudadana estadounidense, con quien se cas\u00f3 y tuvo tres hijos. Leonela es la mayor, de 21 a\u00f1os, y en mayo se gradu\u00f3 como psic\u00f3loga en la Universidad de Connecticut. Sus hermanos menores tienen 20 y 16. Todos ellos nacieron en Estados Unidos.<\/p>\n<p>Su hija <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/20\/eeuu\/inmigrantes-mexicanos-arrestados-norwalk-connecticut-orix\">cont\u00f3 a CNN<\/a> que su pap\u00e1 era el sost\u00e9n econ\u00f3mico de su familia y que si bien viv\u00eda como indocumentado en el pa\u00eds, ten\u00eda una peque\u00f1a compa\u00f1\u00eda con clientes que conf\u00edan en su trabajo, pagaba impuestos, y siempre estaba en b\u00fasqueda de hacer crecer su negocio.<\/p>\n<p>Adem\u00e1s, Ch\u00e1vez era un miembro activo de su comunidad en la iglesia, donde era habitual que ayudara con reparaciones y tambi\u00e9n en otras iglesias de la zona.<\/p>\n<p>Leonel Ch\u00e1vez tiene <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/20\/eeuu\/inmigrantes-mexicanos-arrestados-norwalk-connecticut-orix\">condenas por delitos menores, seg\u00fan documentos judiciales, <\/a>pero \u00e9l dice que fueron errores cometidos cuando era un adolescente y que siempre estuvo a disposici\u00f3n de la justicia.<\/p>\n<p>Desde entonces, dice, hizo todo lo que pudo para contribuir a su comunidad y al pa\u00eds con su trabajo. \u201c\u00bfPor qu\u00e9 no van a mi comunidad, o la iglesia donde yo trabajo y preguntan mis antecedentes?\u201d, cuestiona sobre el accionar de las autoridades.<\/p>\n<p>El Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/25\/eeuu\/politica-inmigratoria-trump-impacto-orix?iid=cnn_buildContentRecirc_end_recirc&#038;recs_exp=relacionado-article-end&#038;tenant_id=related.es#:~:text=El%20Departamento%20de%20Seguridad%20Nacional%20(DHS%2C%20por%20sus%20siglas%20en%20ingl%C3%A9s)%20afirma%20que%20ha%20deportado%20a%20m%C3%A1s%20de%20500.000%20inmigrantes%20indocumentados%20desde%20el%20inicio%20del%20segundo%20mandato%20de%20Trump.\">afirma que ha deportado<\/a> a m\u00e1s de <a href=\"https:\/\/www.dhs.gov\/news\/2025\/10\/27\/dhs-removes-more-half-million-illegal-aliens-us\">500.000 inmigrantes<\/a> indocumentados desde el inicio del segundo mandato de Trump. Pero la cifra a\u00fan es insuficiente para el Gobierno, que ten\u00eda el objetivo de llegar a <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/16\/latinoamerica\/deportados-latinoamericanos-trump-orix#:~:text=impuesto%20por%20la%20Casa%20Blanca%20de%20un%20mill%C3%B3n%20de%20deportaciones%20al%20a%C3%B1o.\">un mill\u00f3n de deportaciones al a\u00f1o.<\/a><\/p>\n<p>A principios de diciembre, el DHS inici\u00f3 operativos de inmigraci\u00f3n en Nueva Orleans para expulsar a \u201clo peor de lo peor\u201d bajo la denominada \u201cOperaci\u00f3n Catahoula Crunch\u201d, que buscaba lograr <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/03\/eeuu\/noem-operacion-inmigracion-nueva-orleans-expulsara-peor-trax#:~:text=la%20subsecretaria%20del%20Departamento%20de%20Seguridad%20Nacional%2C%20Tricia%20McLaughlin%2C%20dijo%20en%20entrevista%20con%20John%20Berman%20de%20CNN%20en%20CNN%20News%20Central%20que%20la%20denominada%20%E2%80%9COperaci%C3%B3n%20Catahoula%20Crunch%E2%80%9D%20buscar%C3%A1%205.000%20arrestos%20%E2%80%9Co%20m%C3%A1s%E2%80%9D.\">al menos 5.000 arrestos<\/a> de personas acusadas \u201cde delitos graves\u201d, seg\u00fan las autoridades.<\/p>\n<p>La concejala de la ciudad de Nueva Orleans, Lesli Harris, dijo que consideraba poco realista el objetivo si realmente solo estaban enfoc\u00e1ndose en los sospechosos m\u00e1s peligrosos, y autoridades de la ciudad plantearon su preocupaci\u00f3n por c\u00f3mo \u00e9stas operaciones podr\u00edan afectar a la poblaci\u00f3n indocumentada m\u00e1s vulnerable.<\/p>\n<p>CNN report\u00f3 <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/26\/eeuu\/dhs-inmigrantes-detenciones-liberacion-trax?iid=cnn_buildContentRecirc_end_recirc&#038;recs_exp=relacionado-article-end&#038;tenant_id=related.es\">al menos tres casos<\/a> de personas que fueron detenidas en las calles durante redadas en el \u00e1rea de Chicago, Charlotte y Nueva Orleans. Permanecieron en centros de detenci\u00f3n durante semanas hasta que la Justicia determin\u00f3 que sus arrestos eran ilegales: no ten\u00edan antecedentes penales y se les hab\u00eda permitido esperar sus pr\u00f3ximas audiencias judiciales de inmigraci\u00f3n en libertad.<\/p>\n<p>Mientras tanto, en Chicago, Los \u00c1ngeles y en otras ciudades estadounidenses, la comunidad inmigrante <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/19\/eeuu\/ice-huellas-comunidad-inmigrante-reorganiza-orix\">se organiza frente al temor<\/a> por las detenciones y busca dar apoyo emocional y ayuda legal a quienes lo necesitan. Patrullas escolares para acompa\u00f1ar a estudiantes y alumnos; actividades religiosas y culturales y distintas iniciativas han sido el punto de uni\u00f3n frente a los operativos de ICE que dejan miedo e incertidumbre en una comunidad que busca seguir adelante.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detener y expulsar de Estados Unidos a \u201clo peor de lo peor\u201d: bajo esa narrativa, la secretaria de Seguridad Nacional, Kristi Noem, defiende los arrestos de inmigrantes por parte del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) al argumentar que se trata de personas que cometieron delitos graves. Pero [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469640","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>No son &quot;lo peor de lo peor&quot;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No son &quot;lo peor de lo peor&quot;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE - Noticias\" \/>\n<meta property=\"og:description\" content=\"Detener y expulsar de Estados Unidos a \u201clo peor de lo peor\u201d: bajo esa narrativa, la secretaria de Seguridad Nacional, Kristi Noem, defiende los arrestos de inmigrantes por parte del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) al argumentar que se trata de personas que cometieron delitos graves. Pero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-29T15:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"No son &#171;lo peor de lo peor&#187;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE\",\"datePublished\":\"2025-12-29T15:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/\"},\"wordCount\":1853,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/\",\"name\":\"No son \\\"lo peor de lo peor\\\": estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-29T15:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No son &#171;lo peor de lo peor&#187;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No son \"lo peor de lo peor\": estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/","og_locale":"es_ES","og_type":"article","og_title":"No son \"lo peor de lo peor\": estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE - Noticias","og_description":"Detener y expulsar de Estados Unidos a \u201clo peor de lo peor\u201d: bajo esa narrativa, la secretaria de Seguridad Nacional, Kristi Noem, defiende los arrestos de inmigrantes por parte del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) al argumentar que se trata de personas que cometieron delitos graves. Pero [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/","og_site_name":"Noticias","article_published_time":"2025-12-29T15:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/"},"author":{"name":"","@id":""},"headline":"No son &#171;lo peor de lo peor&#187;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE","datePublished":"2025-12-29T15:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/"},"wordCount":1853,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/","url":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/","name":"No son \"lo peor de lo peor\": estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-29T15:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"No son &#171;lo peor de lo peor&#187;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"No son &#171;lo peor de lo peor&#187;: estos inmigrantes contribu\u00edan en sus comunidades y fueron arrestados por ICE","url":"http:\/\/noticiasya.com\/nacional\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/12\/29\/inmigrantes-contribuyen-comunidad-arrestadas-ice\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-29T15:03:44Z","datePublished":"2025-12-29T15:03:44Z","dateModified":"2025-12-29T15:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"No son &#171;lo peor de lo peor&#187;: estos inmigrantes contribu\\u00edan en sus comunidades y fueron arrestados por ICE\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/29\\\/inmigrantes-contribuyen-comunidad-arrestadas-ice\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/29\\\/inmigrantes-contribuyen-comunidad-arrestadas-ice\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-29T15:03:44Z\",\"datePublished\":\"2025-12-29T15:03:44Z\",\"dateModified\":\"2025-12-29T15:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463599,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/16\/menos-10-inmigrantes-detenidos-condenas-penales-graves-trax\/","url_meta":{"origin":1469640,"position":0},"title":"Menos del 10 % de los inmigrantes detenidos por el ICE desde octubre ten\u00edan condenas penales severas, seg\u00fan datos internos","author":"","date":"junio 16, 2025","format":false,"excerpt":"A medida que el Gobierno de Trump ha intensificado las redadas en Los \u00c1ngeles y otras partes del pa\u00eds, altos funcionarios han destacado la captura de inmigrantes condenados por delitos como asesinato, agresi\u00f3n y violaci\u00f3n, calific\u00e1ndolos de criminales \u201cb\u00e1rbaros\u201d que \u201csembraron el terror\u201d en comunidades estadounidenses.Pero documentos internos del Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464749,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/22\/hrw-condiciones-inhumanas-centros-detencion-florida-orix\/","url_meta":{"origin":1469640,"position":1},"title":"&#171;Tuvimos que comer como animales&#187;: HRW denuncia condiciones &#171;inhumanas&#187; en centros de detenci\u00f3n de inmigrantes en Florida","author":"","date":"julio 22, 2025","format":false,"excerpt":"Algunos de los inmigrantes que esperan su deportaci\u00f3n en el Centro Federal de Detenci\u00f3n en Miami fueron obligados a comer con las manos esposadas detr\u00e1s de la espalda, situaci\u00f3n que describieron como humillante y degradante, seg\u00fan un nuevo reporte de Human Rights Watch (HRW), Americans for Immigrant Justice y Sanctuary\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469059,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/07\/personas-sin-antecedentes-penales-detenidas-ice-trax\/","url_meta":{"origin":1469640,"position":2},"title":"Casi 75.000 personas sin antecedentes penales fueron detenidas por ICE, muestran nuevos datos","author":"","date":"diciembre 7, 2025","format":false,"excerpt":"Casi 75.000 personas sin antecedentes penales han sido detenidas por agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas de EE.UU. (ICE, por sus siglas en ingl\u00e9s) entre el 20 de enero y el 15 de octubre, seg\u00fan muestran nuevos datos.Desde que el presidente Donald Trump asumi\u00f3 el cargo, su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465695,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/20\/california-redadas-caida-empleo-inmigracion-orix\/","url_meta":{"origin":1469640,"position":3},"title":"Como en la pandemia o en la Gran Recesi\u00f3n: as\u00ed impacta el miedo a las redadas de ICE en la ca\u00edda de empleos en California","author":"","date":"agosto 20, 2025","format":false,"excerpt":"El endurecimiento de las medidas de control migratorio del Gobierno de Donald Trump ha tenido un \u201cefecto disruptivo\u201d en la econom\u00eda de California, la cuarta mayor del mundo, seg\u00fan un an\u00e1lisis del Centro Comunitario y Laboral de Universidad de California Merced. Trump pidi\u00f3, meses atr\u00e1s, \u201credoblar los esfuerzos\u201d para detener\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466136,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/03\/trump-camp-57-centro-detencion-ice-louisiana-trax\/","url_meta":{"origin":1469640,"position":4},"title":"Gobierno de Trump abrir\u00e1 &#171;Camp 57&#187;, un nuevo centro de detenci\u00f3n del ICE, en una prisi\u00f3n de Louisiana","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"El Gobierno de Trump abrir\u00e1 un nuevo campamento dentro de una conocida prisi\u00f3n estatal en Louisiana para albergar a inmigrantes indocumentados acusados de cometer delitos graves, anunciaron funcionarios este mi\u00e9rcoles.El nuevo centro de detenci\u00f3n, llamado \u201cCamp 57\u201d, estar\u00e1 ubicado en la prisi\u00f3n de m\u00e1xima seguridad m\u00e1s grande del pa\u00eds, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465135,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/05\/ice-arrestos-estados-republicanos-democratas-trax\/","url_meta":{"origin":1469640,"position":5},"title":"ICE utiliza t\u00e1cticas muy diferentes para arrestar inmigrantes en los estados republicanos y en los dem\u00f3cratas, seg\u00fan datos","author":"","date":"agosto 5, 2025","format":false,"excerpt":"El Gobierno de Trump est\u00e1 deteniendo a cientos de inmigrantes todos los d\u00edas en todo el pa\u00eds, pero hay una marcada divisi\u00f3n entre lo que hace el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) en los estados dem\u00f3cratas y en los republicanos.En los estados que votaron por el presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469640"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469640\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}