{"id":1469663,"date":"2025-12-30T10:03:50","date_gmt":"2025-12-30T18:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/"},"modified":"2025-12-30T10:03:50","modified_gmt":"2025-12-30T18:03:50","slug":"emiratos-arabes-unidos-retira-fuerzas-yemen-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/","title":{"rendered":"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria"},"content":{"rendered":"<p>Emiratos \u00c1rabes Unidos dijo este martes que retirar\u00e1 sus fuerzas restantes en Yemen despu\u00e9s de que Arabia Saudita bombardeara la ciudad portuaria de Mukalla, tras acusaciones de que dos barcos emirat\u00edes hab\u00edan entregado armas y veh\u00edculos de combate a fuerzas separatistas.<\/p>\n<p>Arabia Saudita acus\u00f3 a Emiratos \u00c1rabes Unidos, su estrecho aliado, de realizar acciones \u201caltamente peligrosas\u201d en Yemen que amenazaban su seguridad nacional. Se\u00f1al\u00f3 que lanz\u00f3 ataques a\u00e9reos \u201climitados\u201d contra Mukalla la ma\u00f1ana del martes y respald\u00f3 un llamado para que las fuerzas emirat\u00edes abandonen Yemen en un plazo de 24 horas.<\/p>\n<p>Emiratos \u00c1rabes Unidos rechaz\u00f3 inicialmente las acusaciones y expres\u00f3 sorpresa por los ataques, pero m\u00e1s tarde su Ministerio de Defensa anunci\u00f3 que, \u201ca la luz de los acontecimientos recientes\u201d, retirar\u00eda de manera voluntaria las unidades \u201cantiterroristas\u201d que a\u00fan manten\u00eda en Yemen.<\/p>\n<p>Las autoridades saud\u00edes no comentaron de inmediato la decisi\u00f3n emirat\u00ed, pero el episodio marca una escalada significativa entre Riad y Abu Dhabi, en momentos en que la relaci\u00f3n entre dos de los socios m\u00e1s estrechos de la regi\u00f3n muestra crecientes tensiones.<\/p>\n<p>El comunicado saud\u00ed que anunci\u00f3 la acci\u00f3n militar se emiti\u00f3 minutos despu\u00e9s de un discurso del jefe del Consejo Presidencial de Yemen, Rashad Al Olimi \u2014un \u00f3rgano respaldado por Arabia Saudita\u2014, quien acus\u00f3 a Emiratos \u00c1rabes Unidos de \u201cdirigir\u201d fuerzas para \u201crebelarse contra la autoridad del Estado\u201d y de \u201cescalar militarmente\u201d en el pa\u00eds.<\/p>\n<p>\u201cEl reino subraya que cualquier amenaza a su seguridad nacional es una l\u00ednea roja, y no dudar\u00e1 en tomar todas las medidas necesarias para enfrentar y neutralizar cualquier amenaza de ese tipo\u201d, se\u00f1al\u00f3 el Ministerio de Relaciones Exteriores de Arabia Saudita en el comunicado.<\/p>\n<p>Arabia Saudita afirm\u00f3 que Emiratos \u00c1rabes Unidos estaba \u201cpresionando\u201d al Consejo de Transici\u00f3n del Sur (STC, por sus siglas en ingl\u00e9s), una fuerza militar respaldada por los emirat\u00edes, para llevar a cabo operaciones en la frontera del reino, una acusaci\u00f3n que Abu Dhabi \u201ccondena\u201d.<\/p>\n<p>A principios de este mes, el STC respaldado por Emiratos \u00c1rabes Unidos lanz\u00f3 una ofensiva y tom\u00f3 el control de provincias clave en Yemen, una acci\u00f3n que enfureci\u00f3 al Gobierno respaldado por Arabia Saudita, que sostiene que la operaci\u00f3n fragment\u00f3 el frente de combate contra las fuerzas hut\u00edes apoyadas por Ir\u00e1n en el norte.<\/p>\n<p>Grupos aliados al STC avanzaron hacia la provincia rica en petr\u00f3leo de Hadramaut, afirmando controlar un total de ocho gobernaciones y renovando los llamados a que el sur de Yemen se separe como un Estado independiente.<\/p>\n<p>Previamente, grupos yemen\u00edes respaldados por Arabia Saudita exigieron que todas las fuerzas emirat\u00edes abandonaran el territorio yemen\u00ed en un plazo de 24 horas y pusieron fin a un pacto de defensa con Emiratos \u00c1rabes Unidos. Para la noche del martes, Emiratos \u00c1rabes Unidos anunci\u00f3 que retirar\u00eda sus tropas restantes en Yemen \u201cpor voluntad propia, de una manera que garantice la seguridad de su personal\u201d.<\/p>\n<p>Arabia Saudita y Emiratos \u00c1rabes Unidos \u2014ambos gigantes petroleros vecinos\u2014 son aliados cercanos y socios clave de Estados Unidos.<\/p>\n<p>Antes de la escalada, el secretario de Estado de EE.UU., Marco Rubio, llam\u00f3 la semana pasada a la diplomacia y la moderaci\u00f3n.<\/p>\n<p>\u201cEstados Unidos est\u00e1 preocupado por los acontecimientos recientes en el sureste de Yemen. Instamos a la moderaci\u00f3n y a la diplomacia continua, con miras a alcanzar una soluci\u00f3n duradera. Agradecemos el liderazgo diplom\u00e1tico de nuestros socios, el reino de Arabia Saudita y Emiratos \u00c1rabes Unidos, y seguimos apoyando todos los esfuerzos para avanzar nuestros intereses de seguridad compartidos\u201d, escribi\u00f3 en X.<\/p>\n<p>Ambos pa\u00edses se unieron anteriormente a Bahr\u00e9in y Egipto para imponer un bloqueo a Qatar que se extendi\u00f3 por m\u00e1s de tres a\u00f1os, marcando la crisis m\u00e1s grave reciente dentro del bloque \u00e1rabe. Emiratos \u00c1rabes Unidos tambi\u00e9n respald\u00f3 a Arabia Saudita en la guerra en Yemen, antes de retirarse en 2019.<\/p>\n<p>M\u00e1s de una d\u00e9cada de guerra en Yemen ha llevado al pa\u00eds a una de las peores crisis humanitarias del mundo. A\u00f1os de combates han profundizado la crisis econ\u00f3mica y destruido los servicios sociales.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emiratos \u00c1rabes Unidos dijo este martes que retirar\u00e1 sus fuerzas restantes en Yemen despu\u00e9s de que Arabia Saudita bombardeara la ciudad portuaria de Mukalla, tras acusaciones de que dos barcos emirat\u00edes hab\u00edan entregado armas y veh\u00edculos de combate a fuerzas separatistas. Arabia Saudita acus\u00f3 a Emiratos \u00c1rabes Unidos, su estrecho aliado, de realizar acciones \u201caltamente [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469663","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria - Noticias\" \/>\n<meta property=\"og:description\" content=\"Emiratos \u00c1rabes Unidos dijo este martes que retirar\u00e1 sus fuerzas restantes en Yemen despu\u00e9s de que Arabia Saudita bombardeara la ciudad portuaria de Mukalla, tras acusaciones de que dos barcos emirat\u00edes hab\u00edan entregado armas y veh\u00edculos de combate a fuerzas separatistas. Arabia Saudita acus\u00f3 a Emiratos \u00c1rabes Unidos, su estrecho aliado, de realizar acciones \u201caltamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-30T18:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria\",\"datePublished\":\"2025-12-30T18:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/\"},\"wordCount\":740,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/\",\"name\":\"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-30T18:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria - Noticias","og_description":"Emiratos \u00c1rabes Unidos dijo este martes que retirar\u00e1 sus fuerzas restantes en Yemen despu\u00e9s de que Arabia Saudita bombardeara la ciudad portuaria de Mukalla, tras acusaciones de que dos barcos emirat\u00edes hab\u00edan entregado armas y veh\u00edculos de combate a fuerzas separatistas. Arabia Saudita acus\u00f3 a Emiratos \u00c1rabes Unidos, su estrecho aliado, de realizar acciones \u201caltamente [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-30T18:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/"},"author":{"name":"","@id":""},"headline":"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria","datePublished":"2025-12-30T18:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/"},"wordCount":740,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/","name":"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-30T18:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Emiratos \u00c1rabes Unidos dice que retirar\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria","url":"http:\/\/noticiasya.com\/nacional\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/12\/30\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-30T18:03:50Z","datePublished":"2025-12-30T18:03:50Z","dateModified":"2025-12-30T18:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Emiratos \\u00c1rabes Unidos dice que retirar\\u00e1 sus fuerzas restantes en Yemen tras ataque de Arabia Saudita en una ciudad portuaria\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/30\\\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/30\\\/emiratos-arabes-unidos-retira-fuerzas-yemen-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-30T18:03:50Z\",\"datePublished\":\"2025-12-30T18:03:50Z\",\"dateModified\":\"2025-12-30T18:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473564,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/28\/emiratos-arabes-unidos-opep-arabia-saudita-trax\/","url_meta":{"origin":1469663,"position":0},"title":"Golpe para la OPEP y para Arabia Saudita: Emiratos \u00c1rabes Unidos se retirar\u00e1 de la organizaci\u00f3n","author":"","date":"abril 28, 2026","format":false,"excerpt":"Emiratos \u00c1rabes Unidos (EAU) se retirar\u00e1 de la Organizaci\u00f3n de Pa\u00edses Exportadores de Petr\u00f3leo (OPEP) el 1 de mayo, seg\u00fan inform\u00f3 la agencia estatal de noticias del pa\u00eds, WAM.\u201cEsta decisi\u00f3n se alinea con la visi\u00f3n estrat\u00e9gica y econ\u00f3mica a largo plazo de Emiratos \u00c1rabes Unidos y con el desarrollo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472636,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/28\/quienes-son-huties-yemen-iran-trax\/","url_meta":{"origin":1469663,"position":1},"title":"\u00bfQui\u00e9nes son los hut\u00edes, el grupo rebelde de Yemen respaldado por Ir\u00e1n?","author":"","date":"marzo 28, 2026","format":false,"excerpt":"Los hut\u00edes de Yemen, respaldados por Ir\u00e1n, anunciaron este s\u00e1bado que dispararon misiles contra Israel, sum\u00e1ndose as\u00ed al creciente conflicto en Medio Oriente. Las fuerzas de Israel hab\u00edan informado previamente que detectaron un misil procedente de Yemen.El movimiento hut\u00ed, tambi\u00e9n conocido como Ansar Allah (Partidarios de Dios), es uno de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472057,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/10\/ee-uu-israel-guerra-iran-efectos-emiratos-arabes-unidos-trax\/","url_meta":{"origin":1469663,"position":2},"title":"EE.UU. e Israel fueron a la guerra con Ir\u00e1n, pero Emiratos \u00c1rabes Unidos est\u00e1 pagando el precio. Esta es la raz\u00f3n","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Ir\u00e1n advirti\u00f3 que cualquier ataque contra el pa\u00eds desencadenar\u00eda un conflicto regional.Estados Unidos e Israel no le creyeron o consideraron que era un riesgo que val\u00eda la pena correr. Once d\u00edas despu\u00e9s del inicio de la guerra, son las naciones del golfo P\u00e9rsico las que est\u00e1n pagando el precio, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472093,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/11\/cuantos-muertos-iran-medio-oriente-guerra-trax\/","url_meta":{"origin":1469663,"position":3},"title":"\u00bfCu\u00e1ntas personas han muerto en Ir\u00e1n y otros pa\u00edses de Medio Oriente durante la guerra?","author":"","date":"marzo 11, 2026","format":false,"excerpt":"Estados Unidos, Israel e Ir\u00e1n contin\u00faan intercambiando ataques en Medio Oriente, donde la cifra de muertos por la guerra va en aumento.A continuaci\u00f3n, los n\u00fameros m\u00e1s recientes seg\u00fan un recuento de CNN basado en fuentes regionales.Ir\u00e1n: el embajador de Ir\u00e1n ante las Naciones Unidas declar\u00f3 el martes que m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462224,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/11\/trump-visita-emiratos-arabes-qatar-arabia-saudita-trax\/","url_meta":{"origin":1469663,"position":4},"title":"Trump visitar\u00e1 tres de las naciones m\u00e1s ricas del mundo. Aqu\u00ed est\u00e1 lo que est\u00e1 en su lista de deseos","author":"","date":"mayo 11, 2025","format":false,"excerpt":"Tres naciones \u00e1rabes del Golfo ricas en energ\u00eda compiten para convertir su influencia sobre Donald Trump en ganancias tangibles con la visita del presidente programada para la pr\u00f3xima semana.Han construido lazos personales con el presidente y han prometido colectivamente billones en inversiones en Estados Unidos mientras se presentan como intermediarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472165,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/13\/emiratos-arabes-unidos-ciberdelitos-trax\/","url_meta":{"origin":1469663,"position":5},"title":"Emiratos \u00c1rabes Unidos acusa a 21 personas de ciberdelitos por grabar y compartir videos de ataques con misiles, dice grupo","author":"","date":"marzo 13, 2026","format":false,"excerpt":"Veintiuna personas, entre ellas un turista brit\u00e1nico de 60 a\u00f1os, han sido acusadas en virtud de las leyes de ciberdelincuencia de los Emiratos \u00c1rabes Unidos por grabar y compartir videos de ataques con misiles y drones iran\u00edes, seg\u00fan una organizaci\u00f3n que presta asistencia legal a los detenidos en los EAU.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469663"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469663\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}