{"id":1469695,"date":"2025-12-31T12:03:48","date_gmt":"2025-12-31T20:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/"},"modified":"2025-12-31T12:03:48","modified_gmt":"2025-12-31T20:03:48","slug":"machado-2026-libertad-venezuela-maduro-resistencia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/","title":{"rendered":"Machado dice que en 2026 se &#171;consolidar\u00e1 la libertad&#187; en Venezuela, mientras el Gobierno de Maduro destaca su &#171;resistencia&#187;"},"content":{"rendered":"<p>Los l\u00edderes opositores de Venezuela Mar\u00eda Corina Machado y Edmundo Gonz\u00e1lez Urrutia dijeron este mi\u00e9rcoles que en 2026 se \u201cconsolidar\u00e1 la libertad\u201d de su pa\u00eds, mientras el canciller de Venezuela, Yv\u00e1n Gil, destac\u00f3 la capacidad de \u201cresistencia\u201d de<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/30\/venezuela\/chavismo-riquezas-aliados-tensiones-eeuu-orix\"> su pa\u00eds en medio de las crecientes tensiones con Estados Unidos.<\/a><\/p>\n<p>Machado y Gonz\u00e1lez Urrutia afirmaron que mantienen su compromiso con la \u201clucha\u201d iniciada tras denunciar fraude en las elecciones presidenciales de 2024, en las que las autoridades electorales declararon ganador a Nicol\u00e1s Maduro, aunque no han hecho p\u00fablicas las actas de votaci\u00f3n detalladas para verificar el resultado.<\/p>\n<p>\u201cEl 2026 ser\u00e1 el a\u00f1o de la consolidaci\u00f3n de la Libertad de nuestra naci\u00f3n\u201d, escribi\u00f3 Machado en la red social X, junto a un video en el que aparece Gonz\u00e1lez Urrutia, quien asegura ser el \u201cpresidente electo\u201d. En el mensaje, la opositora se\u00f1al\u00f3 que durante 2025 se dieron \u201cpasos decisivos\u201d y \u201clogros enormes\u201d, pese a los retos diarios.<\/p>\n<p>Gonz\u00e1lez Urrutia sostuvo que el pa\u00eds \u201ctiene un camino posible, realista y democr\u00e1tico\u201d que requiere \u201corden, constancia y compromiso colectivo\u201d, y afirm\u00f3 que \u201ccuando una naci\u00f3n decide avanzar no hay marcha atr\u00e1s\u201d.<\/p>\n<p>Ambos dirigentes se encuentran <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/19\/venezuela\/lideres-opositores-venezuela-apoyo-politico-exilio-orix\">fuera de Venezuela.<\/a> Machado sali\u00f3 del pa\u00eds a mediados de diciembre para recibir el Premio Nobel de la Paz 2025, tras permanecer once meses en la clandestinidad, mientras que Gonz\u00e1lez Urrutia se exili\u00f3 en Espa\u00f1a en septiembre pasado, al denunciar persecuci\u00f3n pol\u00edtica. Machado anunci\u00f3 el 24 de diciembre su intenci\u00f3n de regresar a Venezuela y prometi\u00f3 informar sobre \u201cnuevos pasos\u201d para concretar una \u201cvictoria\u201d.<\/p>\n<p>Mientras tanto, el Gobierno de Maduro destac\u00f3 este mi\u00e9rcoles la capacidad de resistencia de su pa\u00eds frente a lo que califica de presiones externas. El canciller Yv\u00e1n Gil afirm\u00f3 que Venezuela ha sabido sostener \u201cla unidad y la dignidad\u201d ante las adversidades y asegur\u00f3 que 2025 dej\u00f3 \u201cense\u00f1anzas y fortalezas\u201d que refuerzan la capacidad del pa\u00eds para resistir la presi\u00f3n internacional.<\/p>\n<p>\u201cEn este cierre de a\u00f1o, la Canciller\u00eda de Venezuela dirige un saludo de gratitud y esperanza a todo el pueblo, que con tenacidad y determinaci\u00f3n ha sabido sostener la unidad y la dignidad frente a las adversidades y las amenazas de todo tipo\u201d, dijo Gil en un mensaje en Telegram de fin de a\u00f1o.<\/p>\n<p>Gil augur\u00f3 un 2026 \u201ccargado de oportunidades\u201d, en un contexto de tensiones con Estados Unidos por el despliegue de activos militares estadounidenses en el mar Caribe. Los funcionarios estadounidenses insisten en que el objetivo es combatir al narcotr\u00e1fico, pero la jefa de gabinete de la Casa Blanca de Trump, Susie Wiles, afirm\u00f3 recientemente en una entrevista con Vanity Fair que los ataques a embarcaciones buscaban forzar a Maduro a \u201crendirse\u201d. Caracas, por su parte, denuncia que se trata de una amenaza.<\/p>\n<p>Las fricciones aumentaron tras el anuncio del presidente Donald Trump de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/16\/eeuu\/trump-ordena-bloqueo-petroleros-sancionados-venezuela-trax\">un bloqueo a petroleros sancionados <\/a>que transporten crudo venezolano y la confiscaci\u00f3n de dos buques en d\u00edas recientes. Trump tambi\u00e9n afirm\u00f3 que Estados Unidos atac\u00f3 una \u201cgran instalaci\u00f3n\u201d portuaria vinculada al narcotr\u00e1fico, sin precisar el lugar.<\/p>\n<p>CNN report\u00f3 que la CIA <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/29\/eeuu\/cia-ataque-drones-venezuela-trax\">ejecut\u00f3 un ataque con drones en diciembre <\/a> contra una instalaci\u00f3n portuaria en la costa venezolana, que el Gobierno de EE.UU. cre\u00eda que estaba siendo utilizado por la banda venezolana Tren de Aragua para almacenar drogas y trasladarlas a embarcaciones para su posterior env\u00edo, seg\u00fan las fuentes.<\/p>\n<p>Maduro <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/31\/venezuela\/maduro-eeuu-noticias-falsas-venezuela-orix\">acus\u00f3<\/a> este martes a Estados Unidos de difundir \u201cnoticias falsas\u201d sobre Venezuela, d\u00edas despu\u00e9s de las declaraciones del presidente Donald Trump sobre un ataque contra \u201cuna gran instalaci\u00f3n\u201d, pero el l\u00edder chavista evit\u00f3 aludir directamente a esas maniobras.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los l\u00edderes opositores de Venezuela Mar\u00eda Corina Machado y Edmundo Gonz\u00e1lez Urrutia dijeron este mi\u00e9rcoles que en 2026 se \u201cconsolidar\u00e1 la libertad\u201d de su pa\u00eds, mientras el canciller de Venezuela, Yv\u00e1n Gil, destac\u00f3 la capacidad de \u201cresistencia\u201d de su pa\u00eds en medio de las crecientes tensiones con Estados Unidos. Machado y Gonz\u00e1lez Urrutia afirmaron que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469695","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Machado dice que en 2026 se &quot;consolidar\u00e1 la libertad&quot; en Venezuela, mientras el Gobierno de Maduro destaca su &quot;resistencia&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Machado dice que en 2026 se &quot;consolidar\u00e1 la libertad&quot; en Venezuela, mientras el Gobierno de Maduro destaca su &quot;resistencia&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los l\u00edderes opositores de Venezuela Mar\u00eda Corina Machado y Edmundo Gonz\u00e1lez Urrutia dijeron este mi\u00e9rcoles que en 2026 se \u201cconsolidar\u00e1 la libertad\u201d de su pa\u00eds, mientras el canciller de Venezuela, Yv\u00e1n Gil, destac\u00f3 la capacidad de \u201cresistencia\u201d de su pa\u00eds en medio de las crecientes tensiones con Estados Unidos. Machado y Gonz\u00e1lez Urrutia afirmaron que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-31T20:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Machado dice que en 2026 se &#171;consolidar\u00e1 la libertad&#187; en Venezuela, mientras el Gobierno de Maduro destaca su &#171;resistencia&#187;\",\"datePublished\":\"2025-12-31T20:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/\"},\"wordCount\":665,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/\",\"name\":\"Machado dice que en 2026 se \\\"consolidar\u00e1 la libertad\\\" en Venezuela, mientras el Gobierno de Maduro destaca su \\\"resistencia\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-31T20:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Machado dice que en 2026 se &#171;consolidar\u00e1 la libertad&#187; en Venezuela, mientras el Gobierno de Maduro destaca su &#171;resistencia&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Machado dice que en 2026 se \"consolidar\u00e1 la libertad\" en Venezuela, mientras el Gobierno de Maduro destaca su \"resistencia\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Machado dice que en 2026 se \"consolidar\u00e1 la libertad\" en Venezuela, mientras el Gobierno de Maduro destaca su \"resistencia\" - Noticias","og_description":"Los l\u00edderes opositores de Venezuela Mar\u00eda Corina Machado y Edmundo Gonz\u00e1lez Urrutia dijeron este mi\u00e9rcoles que en 2026 se \u201cconsolidar\u00e1 la libertad\u201d de su pa\u00eds, mientras el canciller de Venezuela, Yv\u00e1n Gil, destac\u00f3 la capacidad de \u201cresistencia\u201d de su pa\u00eds en medio de las crecientes tensiones con Estados Unidos. Machado y Gonz\u00e1lez Urrutia afirmaron que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-31T20:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/"},"author":{"name":"","@id":""},"headline":"Machado dice que en 2026 se &#171;consolidar\u00e1 la libertad&#187; en Venezuela, mientras el Gobierno de Maduro destaca su &#171;resistencia&#187;","datePublished":"2025-12-31T20:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/"},"wordCount":665,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/","name":"Machado dice que en 2026 se \"consolidar\u00e1 la libertad\" en Venezuela, mientras el Gobierno de Maduro destaca su \"resistencia\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-31T20:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Machado dice que en 2026 se &#171;consolidar\u00e1 la libertad&#187; en Venezuela, mientras el Gobierno de Maduro destaca su &#171;resistencia&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Machado dice que en 2026 se &#171;consolidar\u00e1 la libertad&#187; en Venezuela, mientras el Gobierno de Maduro destaca su &#171;resistencia&#187;","url":"http:\/\/noticiasya.com\/nacional\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2025\/12\/31\/machado-2026-libertad-venezuela-maduro-resistencia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-31T20:03:48Z","datePublished":"2025-12-31T20:03:48Z","dateModified":"2025-12-31T20:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Machado dice que en 2026 se &#171;consolidar\\u00e1 la libertad&#187; en Venezuela, mientras el Gobierno de Maduro destaca su &#171;resistencia&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/31\\\/machado-2026-libertad-venezuela-maduro-resistencia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2025\\\/12\\\/31\\\/machado-2026-libertad-venezuela-maduro-resistencia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-31T20:03:48Z\",\"datePublished\":\"2025-12-31T20:03:48Z\",\"dateModified\":\"2025-12-31T20:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1453280,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/02\/maria-corina-machado-no-se-va-venezuela-orix\/","url_meta":{"origin":1469695,"position":0},"title":"Mar\u00eda Corina Machado asegura que no se va de Venezuela luego de que Maduro especulara con una supuesta salida","author":"","date":"octubre 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La l\u00edder opositora venezolana Mar\u00eda Corina Machado asegur\u00f3 que no tiene planes para salir del pa\u00eds, luego de que el s\u00e1bado el presidente Nicol\u00e1s Maduro dijera, sin pruebas, que la exdiputada \u201cest\u00e1 preparando maletas\u201d para dejar territorio venezolano.\u201cAqu\u00ed seguimos de frente con los venezolanos, cerca, a pesar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469779,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/04\/edmundo-gonzalez-presidente-mensaje-maduro-orix\/","url_meta":{"origin":1469695,"position":1},"title":"Edmundo Gonz\u00e1lez Urrutia hace un llamado a la serenidad &#171;como presidente de los venezolanos&#187;","author":"","date":"enero 4, 2026","format":false,"excerpt":"El l\u00edder opositor Edmundo Gonz\u00e1lez dijo este domingo que, \u201ccomo presidente de los venezolanos\u201d, las fuerzas armadas de Venezuela deben \u201chacer cumplir\u201d la victoria electoral que, seg\u00fan alegan \u00e9l y su movimiento pol\u00edtico, obtuvo en las elecciones presidenciales del 28 de julio de 2024.\u201cComo presidente de los venezolanos, hago un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470240,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/19\/henrique-capriles-transicion-libertades-orix\/","url_meta":{"origin":1469695,"position":2},"title":"Henrique Capriles dice que no habr\u00e1 transici\u00f3n en Venezuela si no se garantizan las libertades personales","author":"","date":"enero 19, 2026","format":false,"excerpt":"El excandidato presidencial y diputado opositor Henrique Capriles dijo este lunes que, desde su perspectiva, no podr\u00e1 haber una transici\u00f3n pol\u00edtica en Venezuela si antes no se garantizan las libertades personales de los ciudadanos.\u201cYo no creo que todav\u00eda podamos hablar de transici\u00f3n. M\u00e1s all\u00e1 de hablar de transici\u00f3n, yo hablar\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469760,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","url_meta":{"origin":1469695,"position":3},"title":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;","author":"","date":"enero 3, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, puso en duda este s\u00e1bado la capacidad de la l\u00edder opositora venezolana Mar\u00eda Corina Machado para gobernar el pa\u00eds tras la captura de Nicol\u00e1s Maduro, al afirmar que no cree que cuente con el respaldo necesario dentro de Venezuela.Consultado por periodistas sobre si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457438,"url":"https:\/\/noticiasya.com\/nacional\/2025\/01\/10\/gonzalez-urrutia-dice-prepara-regreso-venezuela-orix\/","url_meta":{"origin":1469695,"position":4},"title":"Gonz\u00e1lez Urrutia dice que prepara su regreso a Venezuela: &#171;Hagan lo que hagan, lograremos entrar&#187;","author":"","date":"enero 10, 2025","format":false,"excerpt":"El excandidato presidencial opositor venezolano Edmundo Gonz\u00e1lez Urrutia dijo este viernes que est\u00e1 preparando las condiciones para regresar a su pa\u00eds y poner fin al Gobierno de Nicol\u00e1s Maduro, al que calific\u00f3 de \u201ctragedia\u201d.\u201cPronto, muy pronto, aunque ellos hagan lo que hagan, lograremos entrar a Venezuela y le pondremos fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453181,"url":"https:\/\/noticiasya.com\/nacional\/2024\/09\/28\/maduro-venezuela-critica-edmundo-gonzalez-maria-corina-machado-orix\/","url_meta":{"origin":1469695,"position":5},"title":"Dos meses despu\u00e9s de las controversiales elecciones, Nicol\u00e1s Maduro critica la salida de Edmundo Gonz\u00e1lez y sugiere sin pruebas que Mar\u00eda Corina Machado abandonar\u00e1 Venezuela","author":"","date":"septiembre 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Venezuela, Nicol\u00e1s Maduro, critic\u00f3 este s\u00e1bado la salida a Espa\u00f1a del candidato presidencial opositor Edmundo Gonz\u00e1lez Urrutia y sugiri\u00f3, sin mayores explicaciones o pruebas, que Mar\u00eda Corina Machado podr\u00eda dejar el pa\u00eds.\"Y el cobarde de Edmundo Gonz\u00e1lez Urrutia huy\u00f3, se fue, claudic\u00f3, capitul\u00f3, abandon\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469695"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469695\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}