{"id":1469729,"date":"2026-01-02T09:03:47","date_gmt":"2026-01-02T17:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/"},"modified":"2026-01-02T09:03:47","modified_gmt":"2026-01-02T17:03:47","slug":"repatria-cuerpos-accidente-aeronave-medica-texas-efe","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/","title":{"rendered":"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas"},"content":{"rendered":"<p>La Secretar\u00eda de Marina (Semar) repatri\u00f3 este viernes los cuerpos de los seis mexicanos, entre ellos un ni\u00f1o de 2 a\u00f1os, que murieron en un <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/22\/eeuu\/muertos-accidente-avion-marina-mexico-texas-trax\">accidente<\/a> a\u00e9reo en Galveston, Texas, confirm\u00f3 la presidenta de M\u00e9xico, Claudia Sheinbaum.<\/p>\n<p>\u201cYa est\u00e1n aqu\u00ed (los restos). E incluso va a haber un homenaje a los marinos\u201d, dijo Sheinbaum durante su conferencia de prensa matutina.<\/p>\n<p>Al mediod\u00eda del jueves, el avi\u00f3n de la Marina aterriz\u00f3 en el Aeropuerto Internacional Scholes para iniciar los tr\u00e1mites de entrega de cuerpos e iniciar la investigaci\u00f3n de lo ocurrido.<\/p>\n<p>La ma\u00f1ana de este viernes los cuerpos de las seis v\u00edctimas fueron subidos al avi\u00f3n oficial para su regreso a M\u00e9xico y entrega a sus familiares.<\/p>\n<p>El pasado 22 de diciembre una aeronave de la Semar se desplom\u00f3 en la bah\u00eda de Galveston, Texas, en Estados Unidos, poco antes de llegar a su destino.<\/p>\n<p>El avi\u00f3n, un modelo bimotor de transporte ligero, llevaba a cuatro miembros de la Marina mexicana y a cuatro civiles, incluyendo a un menor que presentaba quemaduras graves, al que se estaba trasladando desde Campeche, estado en el sureste de M\u00e9xico, al hospital pedi\u00e1trico Shriner\u2019s de Galveston en colaboraci\u00f3n con la Fundaci\u00f3n Michou y Mau, dedicada a la asistencia de menores con quemaduras severas.<\/p>\n<p>El avi\u00f3n despeg\u00f3 de M\u00e9rida, en el estado mexicano de Yucat\u00e1n, y se dirig\u00eda al Aeropuerto Internacional Galveston Scholes, a unos 80 kil\u00f3metros al sureste de Houston, seg\u00fan la web de seguimiento a\u00e9reo FlightRadar24.<\/p>\n<p>Otros testigos aseguraron que, en el momento del siniestro, en la zona hab\u00eda muy poca visibilidad debido a la niebla, motivo por el que se cree que pudo ocurrir el accidente.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Marina (Semar) repatri\u00f3 este viernes los cuerpos de los seis mexicanos, entre ellos un ni\u00f1o de 2 a\u00f1os, que murieron en un accidente a\u00e9reo en Galveston, Texas, confirm\u00f3 la presidenta de M\u00e9xico, Claudia Sheinbaum. \u201cYa est\u00e1n aqu\u00ed (los restos). E incluso va a haber un homenaje a los marinos\u201d, dijo Sheinbaum durante [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469729","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Secretar\u00eda de Marina (Semar) repatri\u00f3 este viernes los cuerpos de los seis mexicanos, entre ellos un ni\u00f1o de 2 a\u00f1os, que murieron en un accidente a\u00e9reo en Galveston, Texas, confirm\u00f3 la presidenta de M\u00e9xico, Claudia Sheinbaum. \u201cYa est\u00e1n aqu\u00ed (los restos). E incluso va a haber un homenaje a los marinos\u201d, dijo Sheinbaum durante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-02T17:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas\",\"datePublished\":\"2026-01-02T17:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/\",\"name\":\"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-02T17:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas - Noticias","og_description":"La Secretar\u00eda de Marina (Semar) repatri\u00f3 este viernes los cuerpos de los seis mexicanos, entre ellos un ni\u00f1o de 2 a\u00f1os, que murieron en un accidente a\u00e9reo en Galveston, Texas, confirm\u00f3 la presidenta de M\u00e9xico, Claudia Sheinbaum. \u201cYa est\u00e1n aqu\u00ed (los restos). E incluso va a haber un homenaje a los marinos\u201d, dijo Sheinbaum durante [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/","og_site_name":"Noticias","article_published_time":"2026-01-02T17:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/"},"author":{"name":"","@id":""},"headline":"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas","datePublished":"2026-01-02T17:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/","url":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/","name":"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-02T17:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9xico repatr\u00eda cuerpos de personas fallecidas en accidente de aeronave m\u00e9dica en Texas","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/02\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-02T17:03:47Z","datePublished":"2026-01-02T17:03:47Z","dateModified":"2026-01-02T17:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e9xico repatr\\u00eda cuerpos de personas fallecidas en accidente de aeronave m\\u00e9dica en Texas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/02\\\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/02\\\/repatria-cuerpos-accidente-aeronave-medica-texas-efe\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-02T17:03:47Z\",\"datePublished\":\"2026-01-02T17:03:47Z\",\"dateModified\":\"2026-01-02T17:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469503,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/22\/muertos-accidente-avion-marina-mexico-texas-trax\/","url_meta":{"origin":1469729,"position":0},"title":"Al menos 4 muertos tras accidente de avi\u00f3n de la Marina de M\u00e9xico en misi\u00f3n m\u00e9dica en Texas","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"Al menos cuatro personas murieron despu\u00e9s de que un avi\u00f3n de la Marina de M\u00e9xico que transportaba pacientes con quemaduras se estrell\u00f3 en la bah\u00eda de Galveston, Texas, este lunes, informaron funcionarios del sheriff a la filial de CNN KPRC.Ocho personas iban a bordo de la aeronave, incluidos dos pilotos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469650,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/29\/tren-interoceanico-accidente-oaxaca-orix\/","url_meta":{"origin":1469729,"position":1},"title":"Descarrilamiento del Tren Interoce\u00e1nico en M\u00e9xico: \u00bfqu\u00e9 se sabe hasta ahora sobre las v\u00edctimas y las causas?","author":"","date":"diciembre 29, 2025","format":false,"excerpt":"El Tren Interoce\u00e1nico, un proyecto ferroviario clave del Gobierno de M\u00e9xico que recorre el Istmo de Tehuantepec en el sur del pa\u00eds, descarril\u00f3 este domingo en el centro del estado de Oaxaca, dejando al menos 13 muertos y m\u00e1s de un centenar de heridos, seg\u00fan la Secretar\u00eda de Marina (Semar).Tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450373,"url":"https:\/\/noticiasya.com\/nacional\/2024\/06\/14\/sheinbaum-ofrece-recuperacion-cuerpos-mineros-pasta-de-conchos-orix\/","url_meta":{"origin":1469729,"position":2},"title":"Sheinbaum ofrece terminar recuperaci\u00f3n de cuerpos de mineros de Pasta de Conchos","author":"","date":"junio 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Claudia Sheinbaum, ganadora de las elecciones presidenciales de M\u00e9xico, ofreci\u00f3 este viernes continuar los trabajos de recuperaci\u00f3n de cuerpos de los 63 trabajadores que hace 18 a\u00f1os quedaron atrapados tras un colapso en la mina de carb\u00f3n Pasta de Conchos, en el estado de Coahuila, fronterizo con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472638,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/28\/veleros-desaparecidos-cuba-localizadostripulantes-salvo-orix\/","url_meta":{"origin":1469729,"position":3},"title":"Los veleros desaparecidos rumbo a Cuba fueron localizados y los tripulantes est\u00e1n a salvo, informan autoridades de M\u00e9xico","author":"","date":"marzo 28, 2026","format":false,"excerpt":"La Secretar\u00eda de Marina de M\u00e9xico (Semar) inform\u00f3 este s\u00e1bado que los dos veleros del Convoy Nuestra Am\u00e9rica que desaparecieron cuando se dirig\u00edan a Cuba para entregar ayuda humanitaria fueron localizados \u201c80 millas n\u00e1uticas al noroeste de La Habana\u201d.Se localiz\u00f3 a los veleros a trav\u00e9s de una aeronave de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462530,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/19\/quienes-son-victimas-accidente-buque-mexico-brooklyn-orix\/","url_meta":{"origin":1469729,"position":4},"title":"\u00bfQui\u00e9nes son y qu\u00e9 sabemos de las v\u00edctimas fatales del accidente de un buque mexicano en Nueva York?","author":"","date":"mayo 19, 2025","format":false,"excerpt":"El 17 de mayo por la noche un buque perteneciente a la Armada de M\u00e9xico colision\u00f3 con la base del puente de Brooklyn, en Nueva York, mientras realizaba una gira de buena voluntad. De acuerdo con la Secretar\u00eda de Marina (Semar), la embarcaci\u00f3n contaba con 277 personas a bordo, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467906,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/31\/barco-menores-sinaloa-investigan-explotacion-infantil-laboral-orix\/","url_meta":{"origin":1469729,"position":5},"title":"Rescatan barco con 28 menores de edad en Sinaloa. Sheinbaum dice que investigan si se trata de explotaci\u00f3n laboral infantil","author":"","date":"octubre 31, 2025","format":false,"excerpt":"La Fiscal\u00eda General del Estado de Sinaloa report\u00f3 el jueves un rescate de 28 menores en altamar en el municipio de Ahome. La presidenta de M\u00e9xico, Claudia Sheinbaum, inform\u00f3 este viernes que detuvieron al adulto que los acompa\u00f1aba y que investigan los hechos para determinar \u201csi hay un modelo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469729"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469729\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}