{"id":1469760,"date":"2026-01-03T12:03:50","date_gmt":"2026-01-03T20:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/"},"modified":"2026-01-03T12:03:50","modified_gmt":"2026-01-03T20:03:50","slug":"trump-maria-corina-machado-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","title":{"rendered":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;"},"content":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, puso en duda este s\u00e1bado la capacidad de <a href=\"https:\/\/cnnespanol.cnn.com\/venezuela\/live-news\/explosiones-caracas-venezuela-en-vivo-orix?post-id=cmjymej95000r356nxbnlozch\">la l\u00edder opositora venezolana Mar\u00eda Corina Machado<\/a> para gobernar el pa\u00eds tras la captura de Nicol\u00e1s Maduro, al afirmar que no cree que cuente con el respaldo necesario dentro de Venezuela.<\/p>\n<p>Consultado por periodistas sobre si ha mantenido contacto con Machado desde la detenci\u00f3n de Maduro, Trump respondi\u00f3 de forma tajante: \u201cNo\u201d.<\/p>\n<p>\u201cCreo que ser\u00eda muy dif\u00edcil para ella ser la l\u00edder. No tiene el apoyo ni el respeto del pa\u00eds\u201d, dijo. \u201cEs una mujer muy agradable, pero no tiene el respeto necesario para ser l\u00edder\u201d, a\u00f1adi\u00f3 el mandatario estadounidense.<\/p>\n<p>Las declaraciones de Trump se produjeron poco despu\u00e9s de que Machado publicara un <a href=\"https:\/\/x.com\/MariaCorinaYA\/status\/2007473689583829046\">mensaje en sus redes sociales<\/a>, en el que se pronunci\u00f3 tras conocerse la captura de Maduro por parte de Estados Unidos y llam\u00f3 a una movilizaci\u00f3n ciudadana. En su mensaje, la l\u00edder opositora afirm\u00f3 que Edmundo Gonz\u00e1lez Urrutia es quien debe asumir como el \u201cleg\u00edtimo presidente de Venezuela\u201d.<\/p>\n<p>\u201cEsta es la hora de los ciudadanos. Los que arriesgamos todo por la democracia el 28 de julio. Los que elegimos a Edmundo Gonz\u00e1lez Urrutia como leg\u00edtimo presidente de Venezuela, quien debe asumir de inmediato su mandato constitucional y ser reconocido como comandante en jefe de la Fuerza Armada Nacional\u201d, escribi\u00f3 Machado.<\/p>\n<p>En su mensaje, Machado asegur\u00f3 que la oposici\u00f3n est\u00e1 preparada para avanzar hacia una transici\u00f3n democr\u00e1tica. \u201cHoy estamos preparados para hacer valer nuestro mandato y tomar el poder. Permanezcamos vigilantes, activos y organizados hasta que se concrete la transici\u00f3n democr\u00e1tica. Una transici\u00f3n que nos necesita a TODOS\u201d, escribi\u00f3. Tambi\u00e9n llam\u00f3 a los venezolanos dentro del pa\u00eds a estar \u201clistos\u201d para futuras instrucciones y exhort\u00f3 a la di\u00e1spora a mantenerse movilizada y a presionar a gobiernos y ciudadanos del mundo para respaldar la reconstrucci\u00f3n de Venezuela.<\/p>\n<p>\u201cEn estas horas decisivas, reciban todos mi fuerza, mi confianza y mi cari\u00f1o. Seguimos todos alerta y en contacto\u201d, concluy\u00f3 Machado en el mensaje publicado en su cuenta de X.<\/p>\n<p>Gonz\u00e1lez Urrutia replic\u00f3 el mensaje desde su propia cuenta en la misma red social, acompa\u00f1ado de una breve declaraci\u00f3n: \u201cVenezolanos, son horas decisivas. Sepan que estamos listos para la gran operaci\u00f3n de la reconstrucci\u00f3n de nuestra naci\u00f3n\u201d. Machado es una de las figuras m\u00e1s visibles de la oposici\u00f3n venezolana y fue inhabilitada para competir en las elecciones presidenciales del 28 de julio de 2024, en las que Gonz\u00e1lez Urrutia fue el candidato opositor. Otros dirigentes opositores de alto perfil, como Juan Guaid\u00f3, Edmundo Gonz\u00e1lez Urrutia y Leopoldo L\u00f3pez, permanecen actualmente en el exilio.<\/p>\n<p>Hasta el momento, la Casa Blanca no ha detallado c\u00f3mo se estructurar\u00eda <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/03\/venezuela\/reacciones-lideres-ataque-eeuu-maduro-orix\">una eventual transici\u00f3n pol\u00edtica en Venezuela<\/a> ni ha precisado qu\u00e9 actores considera clave para ese proceso, en medio de un escenario marcado por la incertidumbre institucional y reacciones divididas dentro y fuera del pa\u00eds.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, puso en duda este s\u00e1bado la capacidad de la l\u00edder opositora venezolana Mar\u00eda Corina Machado para gobernar el pa\u00eds tras la captura de Nicol\u00e1s Maduro, al afirmar que no cree que cuente con el respaldo necesario dentro de Venezuela. Consultado por periodistas sobre si ha mantenido contacto con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469760","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &quot;No tiene el apoyo&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &quot;No tiene el apoyo&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos, Donald Trump, puso en duda este s\u00e1bado la capacidad de la l\u00edder opositora venezolana Mar\u00eda Corina Machado para gobernar el pa\u00eds tras la captura de Nicol\u00e1s Maduro, al afirmar que no cree que cuente con el respaldo necesario dentro de Venezuela. Consultado por periodistas sobre si ha mantenido contacto con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-03T20:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;\",\"datePublished\":\"2026-01-03T20:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/\"},\"wordCount\":547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/\",\"name\":\"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: \\\"No tiene el apoyo\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-03T20:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: \"No tiene el apoyo\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: \"No tiene el apoyo\" - Noticias","og_description":"El presidente de Estados Unidos, Donald Trump, puso en duda este s\u00e1bado la capacidad de la l\u00edder opositora venezolana Mar\u00eda Corina Machado para gobernar el pa\u00eds tras la captura de Nicol\u00e1s Maduro, al afirmar que no cree que cuente con el respaldo necesario dentro de Venezuela. Consultado por periodistas sobre si ha mantenido contacto con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-03T20:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;","datePublished":"2026-01-03T20:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/"},"wordCount":547,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","name":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: \"No tiene el apoyo\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-03T20:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-03T20:03:50Z","datePublished":"2026-01-03T20:03:50Z","dateModified":"2026-01-03T20:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump cuestiona la capacidad de Mar\\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/03\\\/trump-maria-corina-machado-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/03\\\/trump-maria-corina-machado-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-03T20:03:50Z\",\"datePublished\":\"2026-01-03T20:03:50Z\",\"dateModified\":\"2026-01-03T20:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469758,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/03\/trump-transicion-oposicion-machado-orix\/","url_meta":{"origin":1469760,"position":0},"title":"Trump cuestiona el liderazgo de Machado y la oposici\u00f3n venezolana, por ahora, mantiene el silencio","author":"","date":"enero 3, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, dijo que Washington se encargar\u00e1 de gobernar Venezuela tras la captura del mandatario Nicol\u00e1s Maduro, descartando tanto la continuaci\u00f3n de la administraci\u00f3n chavista como el manejo de la oposici\u00f3n venezolana, que esperaba asumir el poder.Trump dijo en una conferencia de prensa que no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470399,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/22\/trump-hablo-jueves-maria-corina-machado-trax\/","url_meta":{"origin":1469760,"position":1},"title":"Trump dice que habl\u00f3 este jueves con la l\u00edder opositora venezolana Mar\u00eda Corina Machado","author":"","date":"enero 22, 2026","format":false,"excerpt":"El presidente Donald Trump dijo que habl\u00f3 hoy con la l\u00edder opositora venezolana Mar\u00eda Corina Machado, aunque continu\u00f3 expresando su apoyo a la presidenta encargada del pa\u00eds, quien asumi\u00f3 despu\u00e9s de que Estados Unidos capturara a Nicol\u00e1s Maduro.\u201cTambi\u00e9n habl\u00e9 con Mar\u00eda hoy, y saben, me cae muy bien\u201d, dijo Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470732,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","url_meta":{"origin":1469760,"position":2},"title":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;","author":"","date":"febrero 1, 2026","format":false,"excerpt":"Mar\u00eda Corina Machado, l\u00edder opositora venezolana, dijo que ser\u00e1 presidenta de Venezuela cuando llegue el momento, cuando las condiciones en el pa\u00eds permitan elecciones democr\u00e1ticas.\u201cSer\u00e9 presidenta cuando llegue el momento. Pero eso no importa. Eso debe decidirse en elecciones por el pueblo venezolano\u201d, dijo Machado durante una entrevista transmitida el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469767,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/03\/oposicion-venezuela-captura-trump-trabajar-trax\/","url_meta":{"origin":1469760,"position":3},"title":"La oposici\u00f3n de Venezuela celebr\u00f3 la captura de Maduro, pero Trump no parece interesado en trabajar con ellos","author":"","date":"enero 3, 2026","format":false,"excerpt":"En las horas inmediatas tras los ataques a\u00e9reos en Caracas por Estados Unidos y la captura del presidente de Venezuela, Nicol\u00e1s Maduro, y su esposa, la acosada oposici\u00f3n venezolana estaba euf\u00f3rica.\u201cVenezolanos, la hora de la libertad ha llegado\u201d, declar\u00f3 Mar\u00eda Corina Machado, l\u00edder del movimiento de oposici\u00f3n venezolano y ganadora\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453280,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/02\/maria-corina-machado-no-se-va-venezuela-orix\/","url_meta":{"origin":1469760,"position":4},"title":"Mar\u00eda Corina Machado asegura que no se va de Venezuela luego de que Maduro especulara con una supuesta salida","author":"","date":"octubre 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La l\u00edder opositora venezolana Mar\u00eda Corina Machado asegur\u00f3 que no tiene planes para salir del pa\u00eds, luego de que el s\u00e1bado el presidente Nicol\u00e1s Maduro dijera, sin pruebas, que la exdiputada \u201cest\u00e1 preparando maletas\u201d para dejar territorio venezolano.\u201cAqu\u00ed seguimos de frente con los venezolanos, cerca, a pesar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470114,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/15\/maria-corina-machado-venezuela-oposicion-perfil-trax\/","url_meta":{"origin":1469760,"position":5},"title":"Mar\u00eda Corina Machado, la &#171;Dama de Hierro&#187; que gan\u00f3 el Nobel y a\u00fan lucha por su lugar en Venezuela","author":"","date":"enero 15, 2026","format":false,"excerpt":"En las primeras horas de la madrugada del 11 de diciembre, una multitud se congregaba frente al Grand Hotel de Oslo, Noruega. Realizaban una vigilia, iluminando el lugar con las linternas de sus tel\u00e9fonos en lugar de velas y cantaban en voz alta en espa\u00f1ol. Una figura sali\u00f3 del balc\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469760"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469760\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}