{"id":1469783,"date":"2026-01-04T18:03:50","date_gmt":"2026-01-05T02:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/"},"modified":"2026-01-04T18:03:50","modified_gmt":"2026-01-05T02:03:50","slug":"delcy-rodriguez-trump-invitacion-mensaje-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/","title":{"rendered":"Delcy Rodr\u00edguez invita a Trump &#171;a trabajar conjuntamente&#187; en su primer mensaje como presidenta encargada de Venezuela"},"content":{"rendered":"<p>En su primer mensaje como presidenta encargada de Venezuela tras la captura del presidente Nicol\u00e1s Maduro, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/03\/venezuela\/delcy-rodriguez-vicepresidenta-perfil-orix\">Delcy Rodr\u00edguez<\/a> se dirigi\u00f3 al presidente de Estados Unidos, Donald Trump, a quien invit\u00f3 \u201ca trabajar conjuntamente\u201d y llam\u00f3 a que ambos pa\u00edses tengan una relaci\u00f3n respetuosa y que entre ellos exista \u201cla paz y el di\u00e1logo, no la guerra\u201d.<\/p>\n<p>Rodr\u00edguez hizo este llamado tras <a href=\"https:\/\/prensapresidencialvenezuela.gob.ve\/index.php\/2026\/01\/04\/presidenta-encargada-delcy-rodriguez-lidera-consejo-de-ministros-757-para-garantizar-la-paz-y-soberania-nacional\/\">asumir como presidenta encargada del pa\u00eds<\/a> y encabezar su primera sesi\u00f3n del Consejo de Ministros, un d\u00eda despu\u00e9s de que el Tribunal Supremo de Justicia de Venezuela (TSJ) le ordenara que, en su condici\u00f3n de vicepresidenta ejecutiva, <a href=\"https:\/\/cnnespanol.cnn.com\/venezuela\/live-news\/explosiones-caracas-venezuela-en-vivo-orix?post-id=cmjz3d94y000d3j6q95yslpns\">tomara las funciones presidenciales<\/a> de forma provisional ante la imposibilidad material de que el presidente Maduro est\u00e9 en el cargo.<\/p>\n<p>El s\u00e1bado, Maduro y su esposa, Cilia Flores, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/03\/venezuela\/trump-anuncia-captura-nicolas-maduro-orix\">fueron capturados<\/a> en un operativo estadounidense en Caracas.<\/p>\n<p>\u201cPresidente Donald Trump: nuestros pueblos y nuestra regi\u00f3n merecen la paz y el di\u00e1logo, no la guerra. Ese ha sido siempre el predicamento del Presidente Nicol\u00e1s Maduro y es el de toda Venezuela en este momento\u201d, dijo Rodr\u00edguez en su mensaje, difundido a trav\u00e9s de su canal oficial de Telegram.<\/p>\n<p>\u201cNuestro pa\u00eds aspira a vivir sin amenazas externas, en un entorno de respeto y cooperaci\u00f3n internacional. Creemos que la paz global se construye garantizando primero la paz de cada naci\u00f3n (\u2026) Extendemos la invitaci\u00f3n al gobierno de los EE.UU. a trabajar conjuntamente en una agenda de cooperaci\u00f3n, orientada al desarrollo compartido, en el marco de la legalidad internacional y fortalezca una convivencia comunitaria duradera\u201d, se\u00f1al\u00f3 la presidenta encargada.<\/p>\n<p>CNN contact\u00f3 a la Casa Blanca para pedir comentarios y espera respuesta.<\/p>\n<p>El mensaje de Rodr\u00edguez se produce tras el operativo que condujo a la captura de Maduro y su esposa, a quienes Estados Unidos acusa de delitos de narcoterrorismo, narcotr\u00e1fico y armas, cargos que Venezuela rechaza.<\/p>\n<p>Tanto Rodr\u00edguez como otros altos funcionarios cercanos a Maduro han reprobado la operaci\u00f3n militar y calificado de \u201csecuestro\u201d las acciones contra la pareja. Incluso, durante una sesi\u00f3n del Consejo de Ministros el s\u00e1bado, Rodr\u00edguez exigi\u00f3 a Estados Unidos <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/03\/venezuela\/delcy-rodriguez-vicepresidenta-exige-liberacion-maduro-esposa-venezuela-orix\">su \u201cinmediata liberaci\u00f3n\u201d<\/a>.<\/p>\n<p>El operativo de Estados Unidos <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/03\/venezuela\/reacciones-lideres-ataque-eeuu-maduro-orix\">ha generado opiniones divididas<\/a> dentro y fuera de Venezuela. Fuera, pa\u00edses como Brasil, Cuba, Colombia y M\u00e9xico han reprobado el despliegue de Washington, que consideran violatorio de la soberan\u00eda venezolana, mientras que otros como Argentina y Ecuador lo han respaldado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su primer mensaje como presidenta encargada de Venezuela tras la captura del presidente Nicol\u00e1s Maduro, Delcy Rodr\u00edguez se dirigi\u00f3 al presidente de Estados Unidos, Donald Trump, a quien invit\u00f3 \u201ca trabajar conjuntamente\u201d y llam\u00f3 a que ambos pa\u00edses tengan una relaci\u00f3n respetuosa y que entre ellos exista \u201cla paz y el di\u00e1logo, no la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469783","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Delcy Rodr\u00edguez invita a Trump &quot;a trabajar conjuntamente&quot; en su primer mensaje como presidenta encargada de Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delcy Rodr\u00edguez invita a Trump &quot;a trabajar conjuntamente&quot; en su primer mensaje como presidenta encargada de Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"En su primer mensaje como presidenta encargada de Venezuela tras la captura del presidente Nicol\u00e1s Maduro, Delcy Rodr\u00edguez se dirigi\u00f3 al presidente de Estados Unidos, Donald Trump, a quien invit\u00f3 \u201ca trabajar conjuntamente\u201d y llam\u00f3 a que ambos pa\u00edses tengan una relaci\u00f3n respetuosa y que entre ellos exista \u201cla paz y el di\u00e1logo, no la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-05T02:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Delcy Rodr\u00edguez invita a Trump &#171;a trabajar conjuntamente&#187; en su primer mensaje como presidenta encargada de Venezuela\",\"datePublished\":\"2026-01-05T02:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/\"},\"wordCount\":453,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/\",\"name\":\"Delcy Rodr\u00edguez invita a Trump \\\"a trabajar conjuntamente\\\" en su primer mensaje como presidenta encargada de Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-05T02:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delcy Rodr\u00edguez invita a Trump &#171;a trabajar conjuntamente&#187; en su primer mensaje como presidenta encargada de Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delcy Rodr\u00edguez invita a Trump \"a trabajar conjuntamente\" en su primer mensaje como presidenta encargada de Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Delcy Rodr\u00edguez invita a Trump \"a trabajar conjuntamente\" en su primer mensaje como presidenta encargada de Venezuela - Noticias","og_description":"En su primer mensaje como presidenta encargada de Venezuela tras la captura del presidente Nicol\u00e1s Maduro, Delcy Rodr\u00edguez se dirigi\u00f3 al presidente de Estados Unidos, Donald Trump, a quien invit\u00f3 \u201ca trabajar conjuntamente\u201d y llam\u00f3 a que ambos pa\u00edses tengan una relaci\u00f3n respetuosa y que entre ellos exista \u201cla paz y el di\u00e1logo, no la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-05T02:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/"},"author":{"name":"","@id":""},"headline":"Delcy Rodr\u00edguez invita a Trump &#171;a trabajar conjuntamente&#187; en su primer mensaje como presidenta encargada de Venezuela","datePublished":"2026-01-05T02:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/"},"wordCount":453,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/","name":"Delcy Rodr\u00edguez invita a Trump \"a trabajar conjuntamente\" en su primer mensaje como presidenta encargada de Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-05T02:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Delcy Rodr\u00edguez invita a Trump &#171;a trabajar conjuntamente&#187; en su primer mensaje como presidenta encargada de Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Delcy Rodr\u00edguez invita a Trump &#171;a trabajar conjuntamente&#187; en su primer mensaje como presidenta encargada de Venezuela","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/04\/delcy-rodriguez-trump-invitacion-mensaje-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-05T02:03:50Z","datePublished":"2026-01-05T02:03:50Z","dateModified":"2026-01-05T02:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Delcy Rodr\\u00edguez invita a Trump &#171;a trabajar conjuntamente&#187; en su primer mensaje como presidenta encargada de Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/04\\\/delcy-rodriguez-trump-invitacion-mensaje-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/04\\\/delcy-rodriguez-trump-invitacion-mensaje-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-05T02:03:50Z\",\"datePublished\":\"2026-01-05T02:03:50Z\",\"dateModified\":\"2026-01-05T02:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469807,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/05\/delcy-rodriguez-jura-presidenta-encargada-orix\/","url_meta":{"origin":1469783,"position":0},"title":"Delcy Rodr\u00edguez asume formalmente como presidenta encargada y rechaza &#171;agresi\u00f3n militar ileg\u00edtima&#187; contra Venezuela","author":"","date":"enero 5, 2026","format":false,"excerpt":"La vicepresidenta Delcy Rodr\u00edguez asumi\u00f3 este lunes formalmente como presidenta encargada de Venezuela, luego de la captura del presidente Nicol\u00e1s Maduro en un operativo militar de Estados Unidos.La juramentaci\u00f3n se dio en una ceremonia en la Asamblea Nacional, encabezada por el diputado Jorge Rodr\u00edguez, hermano de la presidenta encargada y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470577,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/28\/delcy-rodriguez-dialogo-comandante-fanb-orix\/","url_meta":{"origin":1469783,"position":1},"title":"Delcy Rodr\u00edguez pide que quienes &#171;pretendan perpetrar da\u00f1o y agresi\u00f3n contra Venezuela&#187; se queden en Washington","author":"","date":"enero 28, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, afirm\u00f3 este mi\u00e9rcoles que su Gobierno ha abierto un \u201cespacio para el di\u00e1logo pol\u00edtico\u201d, pero advirti\u00f3 que quienes \u201cpretendan perpetrar el da\u00f1o y la agresi\u00f3n\u201d contra Venezuela deben permanecer en Washington.\u201cLe tengo un mensaje muy claro al extremismo de Venezuela y a sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469776,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/04\/padrino-lopez-apoyo-delcy-rodriguez-fuerza-armada-orix\/","url_meta":{"origin":1469783,"position":2},"title":"Padrino L\u00f3pez respalda a Delcy Rodr\u00edguez como &#171;presidenta encargada&#187; de Venezuela y pide a poblaci\u00f3n retomar sus actividades","author":"","date":"enero 4, 2026","format":false,"excerpt":"El ministro de Defensa de Venezuela, Vladimir Padrino L\u00f3pez, respald\u00f3 este domingo a la vicepresidenta Delcy Rodr\u00edguez como la \u201cpresidenta encargada\u201d del pa\u00eds luego de que Nicol\u00e1s Maduro y la primera dama Cilia Flores fueran capturados por Estados Unidos en una operaci\u00f3n militar que incluy\u00f3 ataques en Caracas.El Tribunal Supremo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469789,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/05\/5-cosas-5-enero-orix\/","url_meta":{"origin":1469783,"position":3},"title":"Las 5 cosas que debes saber este 5 de enero: Delcy Rodr\u00edguez asume en Venezuela, Maduro ante un tribunal de EE.UU.","author":"","date":"enero 5, 2026","format":false,"excerpt":"Trump lanza advertencias a otros pa\u00edses de Am\u00e9rica Latina. Maduro har\u00e1 su primera aparici\u00f3n ante un tribunal en Nueva York. La oposici\u00f3n venezolana pide que se respeten los resultados de las elecciones de 2024. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470783,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/02\/delcy-rodriguez-reunion-encargada-negocios-eeuu-laura-dogu-orix\/","url_meta":{"origin":1469783,"position":4},"title":"Delcy Rodr\u00edguez se re\u00fane por primera vez con la nueva encargada de negocios de EE.UU. desde su llegada a Caracas","author":"","date":"febrero 2, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, se reuni\u00f3 este lunes con Laura Dogu, la nueva encargada de negocios de Estados Unidos, en su primer encuentro oficial desde la llegada de Dogu a Caracas este s\u00e1bado para reabrir la misi\u00f3n diplom\u00e1tica estadounidense, cerrada tras la ruptura de relaciones entre ambos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470140,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/16\/director-cia-venezuela-delcy-rodriguez-trax\/","url_meta":{"origin":1469783,"position":5},"title":"El director de la CIA viaj\u00f3 a Venezuela para reunirse con la presidenta encargada, Delcy Rodr\u00edguez","author":"","date":"enero 16, 2026","format":false,"excerpt":"El director de la CIA, John Ratcliffe, se reuni\u00f3 con la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, en Caracas el jueves, seg\u00fan un funcionario estadounidense.\u201cDurante la reuni\u00f3n en Caracas, el director Ratcliffe abord\u00f3 posibles oportunidades de colaboraci\u00f3n econ\u00f3mica y recalc\u00f3 que Venezuela ya no puede ser un refugio seguro para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469783"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469783\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}