{"id":1469784,"date":"2026-01-04T19:03:50","date_gmt":"2026-01-05T03:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/"},"modified":"2026-01-04T19:03:50","modified_gmt":"2026-01-05T03:03:50","slug":"petro-responde-amenazas-trump-operacion-captura-maduro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/","title":{"rendered":"&#171;Su castigo es tratarme falsamente de narcotraficante&#187;: Petro responde a las amenazas de Trump"},"content":{"rendered":"<p>El presidente de Colombia, Gustavo Petro, rechaz\u00f3 este domingo las acusaciones del presidente de Estados Unidos, Donald Trump, quien lo vincul\u00f3 con el narcotr\u00e1fico y advirti\u00f3 que tendr\u00eda que \u201ccuidar su trasero\u201d tras la operaci\u00f3n militar estadounidense en la que fue capturado Nicol\u00e1s Maduro.<\/p>\n<p>\u201cSu castigo es tratarme falsamente de narcotraficante y de tener f\u00e1bricas de coca\u00edna\u201d, <a href=\"https:\/\/x.com\/petrogustavo\/status\/2007968550418362866\">escribi\u00f3 Petro en su cuenta de X<\/a>, en un mensaje en el que defendi\u00f3 su historial y asegur\u00f3 que nunca ha sido mencionado en investigaciones judiciales relacionadas con el tr\u00e1fico de drogas.<\/p>\n<p>Trump<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/03\/latinoamerica\/tump-advierte-petro-trax\"> lanz\u00f3 la advertencia<\/a> horas despu\u00e9s de la captura de Maduro y al ser consultado sobre las declaraciones de Petro, quien aseguraba no temer las consecuencias de la operaci\u00f3n.<\/p>\n<p>\u201cTiene f\u00e1bricas donde hace coca\u00edna\u201d, respondi\u00f3 Trump en una conferencia de prensa en Mar-a-Lago. \u201cEst\u00e1 haciendo coca\u00edna y la est\u00e1n enviando a Estados Unidos\u201d, y agreg\u00f3: \u201cAs\u00ed que tiene que cuidar su trasero\u201d.<\/p>\n<p>Un d\u00eda despu\u00e9s, Trump volvi\u00f3 a referirse al tema y sus comentarios dejaron entrever que su advertencia podr\u00eda extenderse a una operaci\u00f3n en Colombia. \u201cColombia tambi\u00e9n est\u00e1 muy enferma, gobernada por un hombre que le gusta producir coca\u00edna y venderla a Estados Unidos, y no lo va a hacer por mucho tiempo\u201d, dijo a los periodistas a bordo del Air Force One.<\/p>\n<p>\u201cEstamos en el negocio de tener pa\u00edses viables y exitosos a nuestro alrededor, donde se permita la libre explotaci\u00f3n del petr\u00f3leo. Eso es bueno, baja los precios y beneficia a nuestro pa\u00eds\u201d, agreg\u00f3.<\/p>\n<p>Al ser preguntado si eso significaba que podr\u00eda haber una operaci\u00f3n similar contra Colombia, Trump respondi\u00f3 de manera escueta: \u201cMe parecer\u00eda bien\u201d.<\/p>\n<p>Semanas atr\u00e1s, Trump ya hab\u00eda lanzado advertencias similares contra Colombia. Al ser consultado en la Casa Blanca sobre si ten\u00eda intenci\u00f3n de hablar con Petro, el republicano lo descart\u00f3, argumentando que el mandatario sudamericano \u201cha sido bastante hostil con Estados Unidos\u201d.<\/p>\n<p>Por su parte, Petro fue uno de los primeros l\u00edderes de la regi\u00f3n en pronunciarse tras la operaci\u00f3n en Caracas. El presidente colombiano <a href=\"https:\/\/x.com\/petrogustavo\/status\/2007387712454562220\">expres\u00f3 <\/a>que su Gobierno \u201crechaza la agresi\u00f3n a la soberan\u00eda de Venezuela y de Am\u00e9rica Latina\u201d y pidi\u00f3 paz y di\u00e1logo. \u201cLos conflictos internos entre los pueblos los resuelven los mismos pueblos en paz\u201d, agreg\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Colombia, Gustavo Petro, rechaz\u00f3 este domingo las acusaciones del presidente de Estados Unidos, Donald Trump, quien lo vincul\u00f3 con el narcotr\u00e1fico y advirti\u00f3 que tendr\u00eda que \u201ccuidar su trasero\u201d tras la operaci\u00f3n militar estadounidense en la que fue capturado Nicol\u00e1s Maduro. \u201cSu castigo es tratarme falsamente de narcotraficante y de tener f\u00e1bricas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469784","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Su castigo es tratarme falsamente de narcotraficante&quot;: Petro responde a las amenazas de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Su castigo es tratarme falsamente de narcotraficante&quot;: Petro responde a las amenazas de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Colombia, Gustavo Petro, rechaz\u00f3 este domingo las acusaciones del presidente de Estados Unidos, Donald Trump, quien lo vincul\u00f3 con el narcotr\u00e1fico y advirti\u00f3 que tendr\u00eda que \u201ccuidar su trasero\u201d tras la operaci\u00f3n militar estadounidense en la que fue capturado Nicol\u00e1s Maduro. \u201cSu castigo es tratarme falsamente de narcotraficante y de tener f\u00e1bricas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-05T03:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Su castigo es tratarme falsamente de narcotraficante&#187;: Petro responde a las amenazas de Trump\",\"datePublished\":\"2026-01-05T03:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/\"},\"wordCount\":434,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/\",\"name\":\"\\\"Su castigo es tratarme falsamente de narcotraficante\\\": Petro responde a las amenazas de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-05T03:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Su castigo es tratarme falsamente de narcotraficante&#187;: Petro responde a las amenazas de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Su castigo es tratarme falsamente de narcotraficante\": Petro responde a las amenazas de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\"Su castigo es tratarme falsamente de narcotraficante\": Petro responde a las amenazas de Trump - Noticias","og_description":"El presidente de Colombia, Gustavo Petro, rechaz\u00f3 este domingo las acusaciones del presidente de Estados Unidos, Donald Trump, quien lo vincul\u00f3 con el narcotr\u00e1fico y advirti\u00f3 que tendr\u00eda que \u201ccuidar su trasero\u201d tras la operaci\u00f3n militar estadounidense en la que fue capturado Nicol\u00e1s Maduro. \u201cSu castigo es tratarme falsamente de narcotraficante y de tener f\u00e1bricas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-05T03:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/"},"author":{"name":"","@id":""},"headline":"&#171;Su castigo es tratarme falsamente de narcotraficante&#187;: Petro responde a las amenazas de Trump","datePublished":"2026-01-05T03:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/"},"wordCount":434,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/","name":"\"Su castigo es tratarme falsamente de narcotraficante\": Petro responde a las amenazas de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-05T03:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Su castigo es tratarme falsamente de narcotraficante&#187;: Petro responde a las amenazas de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Su castigo es tratarme falsamente de narcotraficante&#187;: Petro responde a las amenazas de Trump","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/04\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-05T03:03:50Z","datePublished":"2026-01-05T03:03:50Z","dateModified":"2026-01-05T03:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Su castigo es tratarme falsamente de narcotraficante&#187;: Petro responde a las amenazas de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/04\\\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/04\\\/petro-responde-amenazas-trump-operacion-captura-maduro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-05T03:03:50Z\",\"datePublished\":\"2026-01-05T03:03:50Z\",\"dateModified\":\"2026-01-05T03:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469789,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/05\/5-cosas-5-enero-orix\/","url_meta":{"origin":1469784,"position":0},"title":"Las 5 cosas que debes saber este 5 de enero: Delcy Rodr\u00edguez asume en Venezuela, Maduro ante un tribunal de EE.UU.","author":"","date":"enero 5, 2026","format":false,"excerpt":"Trump lanza advertencias a otros pa\u00edses de Am\u00e9rica Latina. Maduro har\u00e1 su primera aparici\u00f3n ante un tribunal en Nueva York. La oposici\u00f3n venezolana pide que se respeten los resultados de las elecciones de 2024. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470755,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/02\/petro-reunion-trump-washington-orix\/","url_meta":{"origin":1469784,"position":1},"title":"Petro lleg\u00f3 a Washington para su reuni\u00f3n con Trump tras un a\u00f1o de fuertes tensiones","author":"","date":"febrero 2, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, lleg\u00f3 este lunes a Washington para reunirse con el mandatario estadounidense, Donald Trump, quien lo recibir\u00e1 el martes en la Casa Blanca tras un a\u00f1o de varios ataques verbales y tensiones que se aliviaron en las \u00faltimas semanas.\u201cEmpiezo mi jornada de comunicaci\u00f3n intensa con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469927,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/09\/trump-petro-amenazas-tension-llamada-orix\/","url_meta":{"origin":1469784,"position":2},"title":"Un a\u00f1o de relaciones entre Trump y Petro: de las amenazas y el odio a una llamada de tel\u00e9fono y la distensi\u00f3n","author":"","date":"enero 9, 2026","format":false,"excerpt":"En medio de la tormenta pol\u00edtica, lleg\u00f3 la calma para Colombia\u2026 al menos por ahora. Este mi\u00e9rcoles, luego de una andanada de declaraciones entre los presidentes Gustavo Petro y Donald Trump despu\u00e9s del ataque militar estadounidense en Venezuela, ambos mandatarios mantuvieron una llamada telef\u00f3nica donde el tono amenazante de sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469756,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/03\/tump-advierte-petro-trax\/","url_meta":{"origin":1469784,"position":3},"title":"Tras la captura de Maduro, Tump advierte a Petro, presidente de Colombia: &#171;Tiene que tener cuidado&#187;","author":"","date":"enero 3, 2026","format":false,"excerpt":"El presidente Donald Trump lanz\u00f3 este s\u00e1bado una dura advertencia al presidente de Colombia, Gustavo Petro, al citar la preocupaci\u00f3n por el narcotr\u00e1fico tras la captura de Nicol\u00e1s Maduro por parte de Estados Unidos en una operaci\u00f3n militar a gran escala.Cuando se le pregunt\u00f3 sobre las recientes declaraciones de Petro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467730,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/25\/razones-sanciones-petro-orix\/","url_meta":{"origin":1469784,"position":4},"title":"Las razones por las que el Departamento del Tesoro de EE.UU. sancion\u00f3 a Petro y a su familia en Colombia","author":"","date":"octubre 25, 2025","format":false,"excerpt":"La Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s) del Departamento del Tesoro de Estados Unidos sancion\u00f3 este viernes al presidente de Colombia Gustavo Petro por su presunto rol en el tr\u00e1fico il\u00edcito global de drogas, junto a su esposa, su hijo y el ministro del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467712,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/24\/estados-unidos-sanciona-gustavo-petro-trax\/","url_meta":{"origin":1469784,"position":5},"title":"Estados Unidos sanciona al presidente de Colombia, Gustavo Petro","author":"","date":"octubre 24, 2025","format":false,"excerpt":"El Departamento del Tesoro de EE.UU. anunci\u00f3 este viernes que est\u00e1 sancionando al presidente de Colombia, Gustavo Petro, \u201cpor su papel en el comercio mundial il\u00edcito de drogas\u201d. Tambi\u00e9n han sido sancionados la esposa y el hijo de Petro, as\u00ed como el ministro del Interior de Colombia.\u201cDesde que el presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469784"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469784\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}