{"id":1469827,"date":"2026-01-06T08:03:51","date_gmt":"2026-01-06T16:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/"},"modified":"2026-01-06T08:03:51","modified_gmt":"2026-01-06T16:03:51","slug":"trump-congela-fondos-sociales-estados-democratas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","title":{"rendered":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas"},"content":{"rendered":"<p>El Gobierno de Trump decidi\u00f3 recortar US$ 10.000 millones en fondos para servicios sociales y cuidado infantil en cinco estados gobernados por dem\u00f3cratas, confirm\u00f3 a CNN un funcionario del Departamento de Salud y Servicios Humanos (HHS). La agencia insinu\u00f3, sin pruebas, que los fondos se han utilizado de forma fraudulenta.<\/p>\n<p>La congelaci\u00f3n, reportada inicialmente por el New York Post, afectar\u00e1 a California, Colorado, Illinois, Minnesota y Nueva York, seg\u00fan informes de prensa confirmados por el HHS.<\/p>\n<p>El HHS recortar\u00e1 m\u00e1s de US$ 7.000 millones en fondos para el programa de Asistencia Temporal para Familias Necesitadas, que proporciona asistencia econ\u00f3mica a hogares, junto con m\u00e1s de US$ 2.000 millones para el Fondo de Cuidado y Desarrollo Infantil. El departamento tambi\u00e9n retendr\u00e1 alrededor de US$ 870 millones de la Subvenci\u00f3n Global para Servicios Sociales.<\/p>\n<p>\u201cDurante demasiado tiempo, los estados y gobernadores dem\u00f3cratas han sido c\u00f3mplices de permitir que se produzcan fraudes masivos bajo su supervisi\u00f3n\u201d, declar\u00f3 a CNN el portavoz del HHS, Andrew Nixon. \u201cBajo la administraci\u00f3n Trump, nos aseguramos de que el dinero de los contribuyentes federales se utilice para fines leg\u00edtimos. Nos aseguraremos de que estos estados cumplan con la ley y protejan el dinero que los contribuyentes ganaron con tanto esfuerzo\u201d.<\/p>\n<p>CNN se ha comunicado con la Oficina de Administraci\u00f3n y Presupuesto (OMB) y con los departamentos de salud y las oficinas de los gobernadores de los cinco estados para obtener m\u00e1s informaci\u00f3n sobre los recortes.<\/p>\n<p>La noticia llega pocos d\u00edas despu\u00e9s de que el Gobierno de Trump suspendiera la financiaci\u00f3n federal de los programas de cuidado infantil en Minnesota, en medio de una investigaci\u00f3n federal cada vez m\u00e1s profunda sobre acusaciones de fraude relacionadas con los servicios sociales. Las acusaciones fueron presentadas en un video de YouTube por el creador de contenido de 23 a\u00f1os Nick Shirley, quien afirm\u00f3, con escasas pruebas, que centros de cuidado infantil administrados por somal\u00edes en Minnesota estaban obteniendo fraudulentamente fondos destinados a brindar cuidado infantil a familias de bajos ingresos.<\/p>\n<p>Tras el video viral, el Departamento de Seguridad Nacional y el FBI intensificaron su presencia en el estado, se congelaron los fondos federales para el cuidado infantil y la administraci\u00f3n Trump anunci\u00f3 el despliegue de 2.000 agentes federales como parte de una ofensiva contra la inmigraci\u00f3n. Las investigaciones federales y estatales sobre presuntas irregularidades contin\u00faan. No ha habido evidencia que sugiera que los otros cuatro estados dem\u00f3cratas hayan sufrido un fraude generalizado.<\/p>\n<p>La senadora Kirsten Gillibrand, dem\u00f3crata por Nueva York, conden\u00f3 la congelaci\u00f3n de fondos y acus\u00f3 al Gobierno de \u201crepresalia pol\u00edtica\u201d.<\/p>\n<p>\u201cUsar el poder del Gobierno para perjudicar a los estadounidenses m\u00e1s necesitados es inmoral e indefendible\u201d, declar\u00f3 la senadora en un comunicado publicado en X. \u201cEsto no tiene nada que ver con fraude, sino con represalias pol\u00edticas que castigan a ni\u00f1os pobres que necesitan ayuda\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Trump decidi\u00f3 recortar US$ 10.000 millones en fondos para servicios sociales y cuidado infantil en cinco estados gobernados por dem\u00f3cratas, confirm\u00f3 a CNN un funcionario del Departamento de Salud y Servicios Humanos (HHS). La agencia insinu\u00f3, sin pruebas, que los fondos se han utilizado de forma fraudulenta. La congelaci\u00f3n, reportada inicialmente por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469827","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Trump decidi\u00f3 recortar US$ 10.000 millones en fondos para servicios sociales y cuidado infantil en cinco estados gobernados por dem\u00f3cratas, confirm\u00f3 a CNN un funcionario del Departamento de Salud y Servicios Humanos (HHS). La agencia insinu\u00f3, sin pruebas, que los fondos se han utilizado de forma fraudulenta. La congelaci\u00f3n, reportada inicialmente por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T16:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas\",\"datePublished\":\"2026-01-06T16:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/\"},\"wordCount\":529,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/\",\"name\":\"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-06T16:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas - Noticias","og_description":"El Gobierno de Trump decidi\u00f3 recortar US$ 10.000 millones en fondos para servicios sociales y cuidado infantil en cinco estados gobernados por dem\u00f3cratas, confirm\u00f3 a CNN un funcionario del Departamento de Salud y Servicios Humanos (HHS). La agencia insinu\u00f3, sin pruebas, que los fondos se han utilizado de forma fraudulenta. La congelaci\u00f3n, reportada inicialmente por [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-06T16:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas","datePublished":"2026-01-06T16:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/"},"wordCount":529,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","name":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-06T16:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-06T16:03:51Z","datePublished":"2026-01-06T16:03:51Z","dateModified":"2026-01-06T16:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Trump congela miles de millones de d\\u00f3lares en fondos para servicios sociales en cinco estados dem\\u00f3cratas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/06\\\/trump-congela-fondos-sociales-estados-democratas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/06\\\/trump-congela-fondos-sociales-estados-democratas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-06T16:03:51Z\",\"datePublished\":\"2026-01-06T16:03:51Z\",\"dateModified\":\"2026-01-06T16:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469953,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/10\/juez-detiene-recorte-fondos-trump-estados-democratas-trax\/","url_meta":{"origin":1469827,"position":0},"title":"Juez detiene recorte de fondos sociales y cuidado infantil que orden\u00f3 Trump contra cinco estados liderados por dem\u00f3cratas","author":"","date":"enero 10, 2026","format":false,"excerpt":"Un juez federal suspendi\u00f3 temporalmente este viernes la congelaci\u00f3n de US$ 10.000 millones en fondos de asistencia social y cuidado infantil por parte de la administraci\u00f3n Trump en cinco estados liderados por dem\u00f3cratas a ra\u00edz de una amplia investigaci\u00f3n sobre un presunto fraude en la financiaci\u00f3n federal en Minnesota.El juez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469741,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/02\/centros-cuidado-infantil-minnesota-acusados-irregularidades-informe-trax\/","url_meta":{"origin":1469827,"position":1},"title":"Centros de cuidado infantil de Minnesota acusados de irregularidades operaban seg\u00fan lo esperado, dice un informe","author":"","date":"enero 2, 2026","format":false,"excerpt":"Los centros de cuidado infantil de Minnesota en el centro de amplias acusaciones de fraude alimentadas por un video viral estaban operando seg\u00fan lo esperado cuando fueron visitados por investigadores, dijo el Departamento de Ni\u00f1os, J\u00f3venes y Familias (DCYF, por sus siglas en ingl\u00e9s) del estado en un comunicado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470407,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/22\/administracion-trump-estados-democratas-revision-financiacion-trax\/","url_meta":{"origin":1469827,"position":2},"title":"La administraci\u00f3n Trump somete a 14 estados dem\u00f3cratas a una revisi\u00f3n radical de la financiaci\u00f3n federal","author":"","date":"enero 22, 2026","format":false,"excerpt":"La administraci\u00f3n Trump ha ordenado una revisi\u00f3n de los fondos federales enviados a m\u00e1s de una docena de estados liderados por dem\u00f3cratas, seg\u00fan m\u00faltiples fuentes familiarizadas con el asunto.La amplia escala de la revisi\u00f3n se describe en una solicitud de datos presupuestarios que se envi\u00f3 el martes a todos los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460698,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/01\/washington-23-estados-demandan-trump-salud-publica-trax\/","url_meta":{"origin":1469827,"position":3},"title":"23 estados y la ciudad de Washington demandan al Gobierno de Trump por el recorte de fondos en Salud p\u00fablica","author":"","date":"abril 1, 2025","format":false,"excerpt":"Fiscales generales dem\u00f3cratas de 23 estados y de la ciudad de Washington presentaron una demanda contra el Departamento de Salud y Servicios Humanos de EE.UU. (HHS, por sus siglas en ingl\u00e9s) y contra su secretario, Robert F. Kennedy Jr., por la repentina reducci\u00f3n de US$ 12.000 millones en fondos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467911,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/31\/jueces-exigen-trump-fondos-emergencia-snap-trax\/","url_meta":{"origin":1469827,"position":4},"title":"Dos jueces exigen al Gobierno de Trump recurrir a fondos de emergencia para cubrir parcialmente los cupones de alimentos SNAP","author":"","date":"octubre 31, 2025","format":false,"excerpt":"Dos jueces federales dijeron este viernes que el Gobierno de Donald Trump debe recurrir a miles de millones de d\u00f3lares en fondos de emergencia para cubrir al menos parcialmente los beneficios de cupones de alimentos para decenas de millones de estadounidenses en noviembre.Los fallos de los jueces en Massachusetts y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469821,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","url_meta":{"origin":1469827,"position":5},"title":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo","author":"","date":"enero 6, 2026","format":false,"excerpt":"La administraci\u00f3n Trump ha comenzado a desplegar a alrededor de 2.000 agentes federales en Minneapolis como parte del \u00faltimo esfuerzo del presidente de acabar con la inmigraci\u00f3n irregular, afirmaron a CNN dos funcionarios policiales.Mientras, la ciudad y sus autoridades lidian con un esc\u00e1ndalo de fraude de asistencia social que ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469827"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469827\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}