{"id":1469850,"date":"2026-01-06T18:03:49","date_gmt":"2026-01-07T02:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/"},"modified":"2026-01-06T18:03:49","modified_gmt":"2026-01-07T02:03:49","slug":"entregar-30-50-millones-barriles-petroleo-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/","title":{"rendered":"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU."},"content":{"rendered":"<p>El presidente Donald Trump afirm\u00f3 este martes por la noche que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a Estados Unidos, que se vender\u00e1n a precio de mercado y cuyos ingresos ser\u00e1n controlados por EE.UU.<\/p>\n<p>\u201cMe complace anunciar que las autoridades interinas de Venezuela entregar\u00e1n entre 30 y 50 MILLONES de barriles de petr\u00f3leo sancionado de alta calidad a los Estados Unidos de Am\u00e9rica\u201d,<a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Ftruthsocial.com%2F%40realDonaldTrump%2Fposts%2F115850817778602689&#038;data=05%7C02%7Cluciana2.lopez%40cnn.com%7Cf97033206c4b47c655f708de4d7f613c%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639033406653275999%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=j%2B1aqena9ppcgdLU%2Bdc7N5QvlXkYzj5mPSF%2FO8T1A%2Bk%3D&#038;reserved=0\"> dijo Trump en Truth Social<\/a>.<\/p>\n<p>\u201cEste petr\u00f3leo se vender\u00e1 a su precio de mercado, y ese dinero ser\u00e1 controlado por m\u00ed, como presidente de los Estados Unidos de Am\u00e9rica, para garantizar que se utilice en beneficio del pueblo de Venezuela y de Estados Unidos\u201d.<\/p>\n<p>Trump afirm\u00f3 que orden\u00f3 al secretario del Departamento de Energ\u00eda, Chris Wright, que \u201cejecute este plan de inmediato\u201d y que los barriles \u201cser\u00e1n transportados por buques de almacenamiento y llevados directamente a los muelles de descarga de Estados Unidos\u201d.<\/p>\n<p>CNN se ha puesto en contacto con la Casa Blanca para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>Un alto funcionario del Gobierno, que habl\u00f3 bajo condici\u00f3n de anonimato, dijo a CNN que el petr\u00f3leo ya se ha producido y se ha almacenado en barriles. La mayor parte se encuentra actualmente en barcos y ahora se trasladar\u00e1 a instalaciones estadounidenses en el golfo para su refinaci\u00f3n.<\/p>\n<p>Aunque entre 30 y 50 millones de barriles de petr\u00f3leo parece una cantidad considerable, Estados Unidos consumi\u00f3 poco m\u00e1s de 20 millones de barriles diarios durante el \u00faltimo mes.<\/p>\n<p>Esa cantidad de petr\u00f3leo puede bajar un poco los precios, pero probablemente no reducir\u00e1 tanto los precios de la gasolina para los estadounidenses: el expresidente Joe Biden liber\u00f3 entre cuatro y seis veces m\u00e1s \u2014180 millones de barriles de petr\u00f3leo\u2014 de la Reserva Estrat\u00e9gica de Petr\u00f3leo de Estados Unidos en 2022, lo que redujo los precios de la gasolina entre 13 y 31 centavos por gal\u00f3n en el transcurso de cuatro meses, seg\u00fan un<a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fhome.treasury.gov%2Fnews%2Fpress-releases%2Fjy0887&#038;data=05%7C02%7Cluciana2.lopez%40cnn.com%7Cb368d9bcdc744112921c08de4d8572ef%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639033432747329661%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=XnF2uHwQDO5lrLjge1uGy6oWsjm3K8bWut6MPURwj0A%3D&#038;reserved=0\"> an\u00e1lisis del Departamento del Tesoro<\/a>.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/markets#commodities\">El petr\u00f3leo estadounidense cay\u00f3 alrededor de US$ 1 por barril<\/a>, o algo menos del 2 %, hasta los US$ 56, inmediatamente despu\u00e9s de que Trump hiciera su anuncio en Truth Social.<\/p>\n<p>La venta de hasta 50 millones de barriles podr\u00eda generar ingresos considerables: el petr\u00f3leo venezolano se cotiza actualmente a US$ 55 por barril, por lo que, si Estados Unidos logra encontrar compradores dispuestos a pagar el precio de mercado, la operaci\u00f3n podr\u00eda recaudar entre US$ 1.650 millones y US$ 2.750 millones.<\/p>\n<p>Venezuela ha acumulado importantes reservas de crudo desde que Estados Unidos impuso un embargo petrolero a finales del a\u00f1o pasado. Sin embargo, entregar tal cantidad de petr\u00f3leo a Estados Unidos podr\u00eda agotar las propias reservas petroleras de Venezuela.<\/p>\n<p>Es casi seguro que el petr\u00f3leo proviene tanto de sus almacenes en tierra como de algunos de los petroleros incautados que transportaban petr\u00f3leo: el pa\u00eds tiene una capacidad de almacenamiento de unos 48 millones de barriles y estaba casi lleno, seg\u00fan Phil Flynn, analista senior de mercado de Price Futures Group. Los petroleros transportaban entre 15 y 22 millones de barriles de petr\u00f3leo, de acuerdo con estimaciones de la industria.<\/p>\n<p>No est\u00e1 claro en qu\u00e9 plazo Venezuela entregar\u00e1 el petr\u00f3leo a Estados Unidos.<\/p>\n<p>El alto funcionario del Gobierno se\u00f1al\u00f3 que la transferencia ocurrir\u00e1 r\u00e1pidamente porque el crudo de Venezuela es muy pesado, lo que significa que no se puede almacenar durante mucho tiempo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump afirm\u00f3 este martes por la noche que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a Estados Unidos, que se vender\u00e1n a precio de mercado y cuyos ingresos ser\u00e1n controlados por EE.UU. \u201cMe complace anunciar que las autoridades interinas de Venezuela entregar\u00e1n entre 30 y 50 MILLONES de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469850","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump afirm\u00f3 este martes por la noche que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a Estados Unidos, que se vender\u00e1n a precio de mercado y cuyos ingresos ser\u00e1n controlados por EE.UU. \u201cMe complace anunciar que las autoridades interinas de Venezuela entregar\u00e1n entre 30 y 50 MILLONES de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-07T02:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU.\",\"datePublished\":\"2026-01-07T02:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/\"},\"wordCount\":607,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/\",\"name\":\"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-07T02:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU. - Noticias","og_description":"El presidente Donald Trump afirm\u00f3 este martes por la noche que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a Estados Unidos, que se vender\u00e1n a precio de mercado y cuyos ingresos ser\u00e1n controlados por EE.UU. \u201cMe complace anunciar que las autoridades interinas de Venezuela entregar\u00e1n entre 30 y 50 MILLONES de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-07T02:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU.","datePublished":"2026-01-07T02:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/"},"wordCount":607,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/","name":"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-07T02:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump afirma que Venezuela entregar\u00e1 entre 30 y 50 millones de barriles de petr\u00f3leo a EE.UU.","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/06\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-07T02:03:49Z","datePublished":"2026-01-07T02:03:49Z","dateModified":"2026-01-07T02:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump afirma que Venezuela entregar\\u00e1 entre 30 y 50 millones de barriles de petr\\u00f3leo a EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/06\\\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/06\\\/entregar-30-50-millones-barriles-petroleo-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-07T02:03:49Z\",\"datePublished\":\"2026-01-07T02:03:49Z\",\"dateModified\":\"2026-01-07T02:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470045,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/13\/sudamerica-petroleo-venezuela-trump-precio-orix\/","url_meta":{"origin":1469850,"position":0},"title":"Varios pa\u00edses de Sudam\u00e9rica producen petr\u00f3leo: \u00bfqu\u00e9 les pasar\u00eda si Venezuela vuelve a ser una potencia exportadora?","author":"","date":"enero 13, 2026","format":false,"excerpt":"La intervenci\u00f3n de Estados Unidos contra Venezuela y la captura de Nicol\u00e1s Maduro trajo incertidumbre en la geopol\u00edtica mundial pero, hasta el momento, en t\u00e9rminos econ\u00f3micos y sobre los precios globales del petr\u00f3leo el efecto ha sido marginal, sostienen distintos analistas consultados por CNN. Sin embargo, el interrogante que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457757,"url":"https:\/\/noticiasya.com\/nacional\/2025\/01\/22\/trump-venezuela-petroleo-orix\/","url_meta":{"origin":1469850,"position":1},"title":"Trump dice que EE.UU. &#171;probablemente&#187; dejar\u00e1 de comprar petr\u00f3leo a Venezuela: \u00bfcu\u00e1n importante es este proveedor?","author":"","date":"enero 22, 2025","format":false,"excerpt":"Puede parecer una contradicci\u00f3n, dado el constante enfrentamiento, pero Estados Unidos sigue siendo uno de los principales compradores de petr\u00f3leo de Venezuela.Y no solo eso: una empresa estadounidense, Chevron, es una de las principales petroleras extrayendo el crudo pesado de Venezuela, en acuerdo con PDVSA, y mediante licencias concedidas para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469988,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/11\/trump-cuba-acuerdo-ameneza-trax\/","url_meta":{"origin":1469850,"position":2},"title":"Trump le dice a Cuba que &#171;haga un trato antes de que sea demasiado tarde&#187;","author":"","date":"enero 11, 2026","format":false,"excerpt":"El presidente de EE.UU. Donald Trump, en una publicaci\u00f3n en Truth Social el domingo, aument\u00f3 la presi\u00f3n sobre Cuba. Dijo que \u201csugiere firmemente\u201d que la naci\u00f3n haga un trato con Washington y que no recibir\u00e1 m\u00e1s dinero de la industria petrolera de Venezuela.\u201cCuba vivi\u00f3, durante muchos a\u00f1os, de grandes cantidades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459580,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/06\/chevron-petroleo-venezuela-que-significa-orix\/","url_meta":{"origin":1469850,"position":3},"title":"EE.UU. pone fin a licencia de Chevron para exportar petr\u00f3leo venezolano: \u00bfQu\u00e9 significa para Venezuela?","author":"","date":"marzo 6, 2025","format":false,"excerpt":"Apenas una semana despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, anunciara sus intenciones de revertir las \u201cconcesiones\u201d para la exportaci\u00f3n de petr\u00f3leo de Venezuela, la Casa Blanca puso fin el martes a la licencia que permit\u00eda a la petrolera Chevron operar en el pa\u00eds sudamericano y le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470158,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/16\/murillo-ortega-rompen-silencio-venezuela-maduro-cuba-orix\/","url_meta":{"origin":1469850,"position":4},"title":"La pareja Murillo-Ortega rompe el silencio sobre Venezuela: pide el regreso de Maduro y alto a las amenazas de EE.UU. a Cuba","author":"","date":"enero 16, 2026","format":false,"excerpt":"Daniel Ortega, presidente de Nicaragua, y Rosario Murillo, copresidenta del pa\u00eds y esposa de Ortega, rompieron el silencio este viernes sobre el ataque militar de Estados Unidos contra Venezuela del s\u00e1bado 3 de enero, que deriv\u00f3 en la captura del presidente derrocado Nicol\u00e1s Maduro y de la primera dama Cilia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469752,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/03\/petroleo-precios-eeuu-venezuela-trax\/","url_meta":{"origin":1469850,"position":5},"title":"Qu\u00e9 implica el ataque de EE.UU. a Venezuela para el precio de la gasolina y para la mayor reserva de petr\u00f3leo del mundo","author":"","date":"enero 3, 2026","format":false,"excerpt":"El presidente de Venezuela Nicol\u00e1s Maduro fue capturado y trasladado fuera del pa\u00eds tras un ataque a gran escala de Estados Unidos contra Caracas, lo que ha abierto un escenario de incertidumbre para el pa\u00eds y para sus enormes reservas de petr\u00f3leo.El Gobierno del presidente Donald Trump acaba de atacar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469850"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469850\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}