{"id":1469911,"date":"2026-01-08T16:03:47","date_gmt":"2026-01-09T00:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/"},"modified":"2026-01-08T16:03:47","modified_gmt":"2026-01-09T00:03:47","slug":"tenista-abdelkader-kenya-jugo-mal-viral-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/","title":{"rendered":"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta"},"content":{"rendered":"<p>Podr\u00eda haber sido un partido de tenis que pasara desapercibido. En cambio, se hizo viral instant\u00e1neamente en internet.<\/p>\n<p>La primera ronda del torneo W35 de la Federaci\u00f3n Internacional de Tenis, disputada en una cancha de tierra batida en Nairobi, Kenya, normalmente no causar\u00eda gran revuelo en el mundo del tenis, pero millones de personas han visto lo que sucedi\u00f3 durante 37 minutos en la capital.<\/p>\n<p>El marcador del partido no fue inusual, una victoria por 6-0 y 6-0 para la alemana Lorena Schaedel; lo que s\u00ed llam\u00f3 la atenci\u00f3n fue <a href=\"https:\/\/www.youtube.com\/watch?v=Sq7VML683u8\">la actuaci\u00f3n<\/a> de su oponente, la egipcia Hajar Abdelkader, de 21 a\u00f1os, en lo que parece haber sido su debut profesional. Pero, como han se\u00f1alado algunos observadores en las redes sociales, parec\u00eda que era la primera vez que pisaba una cancha de tenis.<\/p>\n<p>Ahora est\u00e1n surgiendo nuevos detalles sobre c\u00f3mo Abdelkader se encontr\u00f3 completamente superada en un torneo profesional y a merced de los comentaristas de tenis de todo el mundo. En un comunicado a CNN Sports, Tennis Kenya declar\u00f3 que Abdelkader hab\u00eda sido admitida en el torneo mediante una invitaci\u00f3n especial (wild card), que b\u00e1sicamente es una invitaci\u00f3n al torneo que evita la necesidad de clasificarse para el cuadro principal o de obtener un puesto a trav\u00e9s del sistema de clasificaci\u00f3n.<\/p>\n<p>La organizaci\u00f3n dijo que ella present\u00f3 una solicitud formal para la invitaci\u00f3n especial y que hab\u00eda llegado a Nairobi el martes por la ma\u00f1ana. Se abri\u00f3 una plaza en el torneo cuando otra jugadora se retir\u00f3 con poca antelaci\u00f3n y opt\u00f3 por participar en la fase de clasificaci\u00f3n.<\/p>\n<p>\u201cEn ese momento, la Sra. Abdelkader era la \u00fanica otra jugadora que hab\u00eda solicitado una invitaci\u00f3n especial\u201d, explicaba el comunicado.<\/p>\n<p>Seg\u00fan los pocos detalles disponibles en su perfil de jugadora de la ITF, Abdelkader lleva jugando al tenis siete a\u00f1os, desde los 14, pero a muchos les result\u00f3 dif\u00edcil de creer, ya que parec\u00eda completamente fuera de lugar en la cancha. En un deporte tan t\u00e9cnico, se nota si apenas sabes c\u00f3mo sujetar una raqueta, y Abdelkader a menudo ten\u00eda dificultades para pasar la pelota por encima de la red.<\/p>\n<p>Cometi\u00f3 20 dobles faltas y solo gan\u00f3 tres puntos, todos ellos por errores de su oponente. En ocasiones, parec\u00eda que Abdelkader ni siquiera sab\u00eda d\u00f3nde colocarse para sacar.<\/p>\n<p>La Federaci\u00f3n Egipcia de Tenis inform\u00f3 a CNN Sports que Abdelkader no est\u00e1 registrada con ellos ni forma parte de sus listas oficiales de jugadoras. \u201cSeg\u00fan la informaci\u00f3n de la que disponemos, la jugadora reside actualmente en Kenya\u201d, dec\u00eda su comunicado. \u201cLa Federaci\u00f3n Egipcia de Tenis no tuvo ninguna participaci\u00f3n, ni directa ni indirecta, en la nominaci\u00f3n, aprobaci\u00f3n o concesi\u00f3n de esta invitaci\u00f3n, y no estuvimos involucrados en la participaci\u00f3n de la jugadora en el torneo de ninguna manera\u201d.<\/p>\n<p>La reacci\u00f3n de los comentaristas en l\u00ednea ante su actuaci\u00f3n vari\u00f3 desde la perplejidad hasta el rid\u00edculo, y algunos observadores afirmaron que su oportunidad se habr\u00eda producido a expensas de una jugadora verdaderamente profesional. Los torneos de la ITF son la categor\u00eda m\u00e1s baja del tenis profesional (la ganadora, Schaedel, ocupa el puesto n\u00famero 1.026 del mundo), pero son eventos profesionales con importantes puntos para el ranking en juego, y la campeona del torneo en Nairobi se embolsar\u00e1 25.000 d\u00f3lares.<\/p>\n<p>Tennis Kenya declar\u00f3 que la decisi\u00f3n de incluir a Abdelkader en el cuadro principal se tom\u00f3 \u201cen base a la informaci\u00f3n proporcionada y con el fin de mantener un cuadro completo y equilibrado, al tiempo que se apoya el desarrollo del tenis en \u00c1frica\u201d.<\/p>\n<p>Sin embargo, admiten que preferir\u00edan evitar un partido tan rid\u00edculo en el futuro.<\/p>\n<p>\u201cEn retrospectiva\u201d, dijeron, \u201cTennis Kenya reconoce que esta invitaci\u00f3n no deber\u00eda haberse concedido dado el nivel de la jugadora. La federaci\u00f3n ha tomado nota de esta experiencia y se asegurar\u00e1 de que un incidente tan excepcional no vuelva a ocurrir. Tennis Kenya mantiene su compromiso con la equidad, la transparencia y la integridad de la competici\u00f3n, as\u00ed como con el desarrollo continuo del tenis en Kenia, \u00c1frica Oriental y en todo el continente africano\u201d.<\/p>\n<p>El partido estaba disponible para verse completo en el sitio web de la ITF, pero desde entonces ha sido retirado sin explicaci\u00f3n. Tennis Kenya tambi\u00e9n reconoci\u00f3 el impacto personal que la posterior exposici\u00f3n medi\u00e1tica podr\u00eda tener en una joven, y se\u00f1al\u00f3 que tanto ellos como la ITF se hab\u00edan puesto en contacto con Abdelkader y Schaedel para ofrecerles apoyo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podr\u00eda haber sido un partido de tenis que pasara desapercibido. En cambio, se hizo viral instant\u00e1neamente en internet. La primera ronda del torneo W35 de la Federaci\u00f3n Internacional de Tenis, disputada en una cancha de tierra batida en Nairobi, Kenya, normalmente no causar\u00eda gran revuelo en el mundo del tenis, pero millones de personas han [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469911","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta - Noticias\" \/>\n<meta property=\"og:description\" content=\"Podr\u00eda haber sido un partido de tenis que pasara desapercibido. En cambio, se hizo viral instant\u00e1neamente en internet. La primera ronda del torneo W35 de la Federaci\u00f3n Internacional de Tenis, disputada en una cancha de tierra batida en Nairobi, Kenya, normalmente no causar\u00eda gran revuelo en el mundo del tenis, pero millones de personas han [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-09T00:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta\",\"datePublished\":\"2026-01-09T00:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/\"},\"wordCount\":827,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/\",\"name\":\"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-09T00:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta - Noticias","og_description":"Podr\u00eda haber sido un partido de tenis que pasara desapercibido. En cambio, se hizo viral instant\u00e1neamente en internet. La primera ronda del torneo W35 de la Federaci\u00f3n Internacional de Tenis, disputada en una cancha de tierra batida en Nairobi, Kenya, normalmente no causar\u00eda gran revuelo en el mundo del tenis, pero millones de personas han [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-09T00:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/"},"author":{"name":"","@id":""},"headline":"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta","datePublished":"2026-01-09T00:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/"},"wordCount":827,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/","name":"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-09T00:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una tenista jug\u00f3 tan mal que se hizo viral: parec\u00eda que era la primera vez que agarraba una raqueta","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/08\/tenista-abdelkader-kenya-jugo-mal-viral-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-09T00:03:47Z","datePublished":"2026-01-09T00:03:47Z","dateModified":"2026-01-09T00:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una tenista jug\\u00f3 tan mal que se hizo viral: parec\\u00eda que era la primera vez que agarraba una raqueta\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/08\\\/tenista-abdelkader-kenya-jugo-mal-viral-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/08\\\/tenista-abdelkader-kenya-jugo-mal-viral-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-09T00:03:47Z\",\"datePublished\":\"2026-01-09T00:03:47Z\",\"dateModified\":\"2026-01-09T00:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466011,"url":"https:\/\/noticiasya.com\/nacional\/2025\/08\/30\/jelena-ostapenko-disculpa-us-open-taylor-townsend-trax\/","url_meta":{"origin":1469911,"position":0},"title":"Jelena Ostapenko se disculpa por sus comentarios durante el partido del US Open contra Taylor Townsend","author":"","date":"agosto 30, 2025","format":false,"excerpt":"Jelena Ostapenko se disculp\u00f3 por algunos de los comentarios que hizo durante un tenso intercambio con Taylor Townsend en su partido de segunda ronda del US Open, disputado el mi\u00e9rcoles.Tras la victoria de Townsend en dos sets, ambas jugadoras intercambiaron palabras junto a la cancha. La letona le dijo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451090,"url":"https:\/\/noticiasya.com\/nacional\/2024\/07\/13\/por-que-tenistas-visten-blanco-trax\/","url_meta":{"origin":1469911,"position":1},"title":"C\u00f3digo de vestimenta: \u00bfPor qu\u00e9 los tenistas visten de blanco?","author":"","date":"julio 13, 2024","format":false,"excerpt":"(CNN) -- Pr\u00edstinos, n\u00edtidos y totalmente blancos: los blancos en el tenis han sido una tradici\u00f3n que se remonta a siglos atr\u00e1s. Su aspecto distintivo no s\u00f3lo ha hecho que el deporte de la raqueta se destaque, sino que tambi\u00e9n se ha convertido en un pilar de la vestimenta fuera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462760,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/24\/novak-djokovic-gana-100-titulos-atp-tenis-trax\/","url_meta":{"origin":1469911,"position":2},"title":"Novak Djokovic se convierte en el tercer hombre en la historia en ganar 100 t\u00edtulos ATP tras vencer a Hubert Hurkacz","author":"","date":"mayo 24, 2025","format":false,"excerpt":"Novak Djokovic se convirti\u00f3 este s\u00e1bado en apenas el tercer hombre en la Era Abierta en ganar 100 t\u00edtulos individuales de la ATP, al derrotar a Hubert Hurkacz 5-7, 7-6 (7-2), 7-6 (7-2) en la final del Abierto de Ginebra.El ganador de 24 t\u00edtulos Grand Slam se une a Jimmy\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466232,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/07\/us-open-emisoras-reacciones-trump-trax\/","url_meta":{"origin":1469911,"position":3},"title":"El US Open pide a las emisoras evitar las reacciones del p\u00fablico ante Trump durante la final masculina","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"La \u00faltima vez que el presidente Donald Trump asisti\u00f3 a un partido del Abierto de Estados Unidos, cuando todav\u00eda era candidato presidencial en 2015, los abucheos fueron tan fuertes que varios medios de comunicaci\u00f3n publicaron art\u00edculos sobre la cr\u00edtica reacci\u00f3n del p\u00fablico. La transmisi\u00f3n en vivo de ESPN se detuvo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451089,"url":"https:\/\/noticiasya.com\/nacional\/2024\/07\/13\/wimbledon-2024-jasmine-paolini-barbora-krejcikova-final-femenina-trax\/","url_meta":{"origin":1469911,"position":4},"title":"Wimbledon 2024: Jasmine Paolini se enfrenta a Barbora Krej\u010d\u00edkov\u00e1 en la final femenina y ya hacen historia","author":"","date":"julio 13, 2024","format":false,"excerpt":"(CNN) -- La final individual femenina de Wimbledon 2024 lleg\u00f3: Jasmine Paolini se enfrentar\u00e1 contra Barbora Krej\u010d\u00edkov\u00e1 por el derecho a levantar el ic\u00f3nico Venus Rosewater Dish (el Plato de Agua de Rosas de Venus, en espa\u00f1ol) por primera vez en cualquiera de sus carreras.Ambas competidoras han aprovechado un empate\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470098,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/14\/abierto-australia-favoritos-tenis-sinner-alcaraz-sabalenka-orix\/","url_meta":{"origin":1469911,"position":5},"title":"Abierto de Australia: grandes favoritos y el &#171;bromance&#187; de Alcaraz y Sinner antes de entablar sus &#171;batallas&#187; en la cancha","author":"","date":"enero 14, 2026","format":false,"excerpt":"El Abierto de Australia est\u00e1 en marcha en Melbourne con los partidos clasificatorios. Sin embargo, la pr\u00f3xima semana ser\u00e1 cuando Jannik Sinner y Carlos Alcaraz reanuden su rivalidad en el primer Grand Slam del a\u00f1o, cuando comience la acci\u00f3n del cuadro principal y pensando en que hipot\u00e9ticamente el n\u00famero uno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469911"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469911\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}