{"id":1469960,"date":"2026-01-10T09:03:42","date_gmt":"2026-01-10T17:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/"},"modified":"2026-01-10T09:03:42","modified_gmt":"2026-01-10T17:03:42","slug":"confirman-excarcelados-presos-politicos-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","title":{"rendered":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela"},"content":{"rendered":"<p>El director presidente de la organizaci\u00f3n sin fines de lucro Foro Penal, Alfredo Romero, dijo este s\u00e1bado que hasta ahora han confirmado la excarcelaci\u00f3n de doce presos pol\u00edticos desde el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/venezuela\/liberara-numero-importante-presos-politicos-venezolanos-extranjeros-asamblea-nacional-orix\">anuncio del jueves<\/a> por parte del presidente de la Asamblea Nacional, Jorge Rodr\u00edguez, quien asegur\u00f3 que Venezuela liberar\u00eda \u201cun n\u00famero importante\u201d de detenidos.<\/p>\n<p>Los \u00faltimos tres excarcelados son Didelis Raquel Corredor y Virgilio Valverde, dijo Romero <a href=\"https:\/\/x.com\/alfredoromero\/status\/2009998787541176499\">en X<\/a>. Gonzalo Himiob Santom\u00e9, director vicepresidente de Foro Penal, <a href=\"https:\/\/x.com\/HimiobSantome\/status\/2010010462361170301\">confirm\u00f3 tambi\u00e9n<\/a> la excarcelaci\u00f3n de Antonio Gerardo (Nino) Buzzetta Pacheco, un ciudadano \u00edtalo-venezolano detenido desde el 30 de septiembre de 2024.<\/p>\n<p>Virgilio Valverde es coordinador juvenil de Vente Venezuela, dijo el presidente de Foro Penal. El Comit\u00e9 de Derechos Humanos del movimiento pol\u00edtico tambi\u00e9n inform\u00f3 la noticia: \u201cConfirmamos la excarcelaci\u00f3n de Virgilio Laverde, coordinador juvenil de Vente Venezuela en el estado Bol\u00edvar\u201d, dijo la organizaci\u00f3n <a href=\"https:\/\/x.com\/venteddhh\/status\/2009986971226067078?s=48&#038;t=SswpdBSqpGMAc2E7h34yeg\">en X<\/a>, y agreg\u00f3 que estuvo privado de su libertad desde el 15 de agosto del 2024.<\/p>\n<p>Corredor, por su parte, estaba en prisi\u00f3n desde el 13 julio de 2023, agreg\u00f3 Romero e inform\u00f3 que a\u00fan quedan 809 presos pol\u00edticos, de acuerdo con sus reportes.<\/p>\n<p>Las once personas que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/venezuela\/quien-son-presos-politicos-liberados-venezuela-orix\">salieron de prisi\u00f3n<\/a> desde que se anunciaron las excarcelaciones son Jos\u00e9 Mar\u00eda Basoa (de nacionalidad espa\u00f1ola), al igual que Andr\u00e9s Mart\u00ednez Adasme, Ernesto Gorbe y Miguel Moreno Dapena; Roc\u00edo San Miguel (espa\u00f1ola-venezolana), Biagio Pillieri, Enrique M\u00e1rquez, Larry Osorio, Aracelis Balza, Virgilio Valverde y Didelis Raquel Corredor.<\/p>\n<p>Foro Penal <a href=\"https:\/\/x.com\/alfredoromero\/status\/2009720504895025294\">dijo<\/a> que entre los 87 presos pol\u00edticos de nacionalidad extranjera en Venezuela \u201cse mantienen 2 ciudadanos estadounidenses\u201d y que tambi\u00e9n hay un ciudadano cubano con residencia estadounidense, de acuerdo con sus registros.<\/p>\n<p>CNN consult\u00f3 al Ministerio P\u00fablico de Venezuela y respondieron que \u201cpor ahora\u201d no hay una lista oficial sobre qui\u00e9nes salieron de prisi\u00f3n.<\/p>\n<p>Mientras tanto, en la ma\u00f1ana de este s\u00e1bado persist\u00edan los reclamos por m\u00e1s excarcelaciones en Venezuela.<\/p>\n<p>Si bien el presidente de la Asamblea Nacional de Venezuela anunci\u00f3 que el Gobierno liberar\u00eda a un \u201cn\u00famero importante\u201d de presos pol\u00edticos con el fin de \u201ccolaborar en el esfuerzo de la uni\u00f3n nacional\u201d, hasta el momento ese proceso se dio de forma m\u00e1s lenta de la esperada y representa poco m\u00e1s del 1 % del total de los detenidos que registra Foro Penal.<\/p>\n<p>Organizaciones no gubernamentales y familiares de detenidos reclaman que se lleven a cabo todas las excarcelaciones, y organizaron vigilias a las afueras de distintos centros de detenci\u00f3n en Venezuela en la noche del viernes, la segunda tras el anuncio de las autoridades del pa\u00eds.<\/p>\n<p>En las inmediaciones de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/venezuela\/centro-comercial-prision-torturas-denuncias-el-helicoide-orix\">El Helicoide<\/a>, una de las prisiones m\u00e1s temidas de Venezuela, familiares y activistas ped\u00edan respuestas al Gobierno. \u201cNo tenemos ning\u00fan tipo de informaci\u00f3n. Todas las ONGs est\u00e1n igual, confiando en las palabras que les dan los familiares, esperando que los familiares avisen de que sus familiares fueron excarcelados y pendientes de la noticia pr\u00e1cticamente las 24 horas\u201d, dijo el viernes a CNN Lizbeth A\u00f1ez, defensora de Derechos Humanos.<\/p>\n<p>Mayra Morales, hermana de uno de los detenidos, cuestion\u00f3 que el Gobierno de Venezuela anunci\u00f3 \u201cuna liberaci\u00f3n masiva\u201d y que \u201cno han cumplido\u201d con lo que dijeron. \u201cNosotros como familiares exigimos nuestros derechos. Exigimos que liberen a mi hermano. Exigimos que liberen a todos los presos pol\u00edticos por pensar diferente\u201d, pidi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director presidente de la organizaci\u00f3n sin fines de lucro Foro Penal, Alfredo Romero, dijo este s\u00e1bado que hasta ahora han confirmado la excarcelaci\u00f3n de doce presos pol\u00edticos desde el anuncio del jueves por parte del presidente de la Asamblea Nacional, Jorge Rodr\u00edguez, quien asegur\u00f3 que Venezuela liberar\u00eda \u201cun n\u00famero importante\u201d de detenidos. Los \u00faltimos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469960","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"El director presidente de la organizaci\u00f3n sin fines de lucro Foro Penal, Alfredo Romero, dijo este s\u00e1bado que hasta ahora han confirmado la excarcelaci\u00f3n de doce presos pol\u00edticos desde el anuncio del jueves por parte del presidente de la Asamblea Nacional, Jorge Rodr\u00edguez, quien asegur\u00f3 que Venezuela liberar\u00eda \u201cun n\u00famero importante\u201d de detenidos. Los \u00faltimos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-10T17:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela\",\"datePublished\":\"2026-01-10T17:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/\"},\"wordCount\":613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/\",\"name\":\"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-10T17:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela - Noticias","og_description":"El director presidente de la organizaci\u00f3n sin fines de lucro Foro Penal, Alfredo Romero, dijo este s\u00e1bado que hasta ahora han confirmado la excarcelaci\u00f3n de doce presos pol\u00edticos desde el anuncio del jueves por parte del presidente de la Asamblea Nacional, Jorge Rodr\u00edguez, quien asegur\u00f3 que Venezuela liberar\u00eda \u201cun n\u00famero importante\u201d de detenidos. Los \u00faltimos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-10T17:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela","datePublished":"2026-01-10T17:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/"},"wordCount":613,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","name":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-10T17:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-10T17:03:42Z","datePublished":"2026-01-10T17:03:42Z","dateModified":"2026-01-10T17:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Confirman otros tres excarcelados y ya son doce los detenidos pol\\u00edticos que dejaron la prisi\\u00f3n en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/10\\\/confirman-excarcelados-presos-politicos-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/10\\\/confirman-excarcelados-presos-politicos-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-10T17:03:42Z\",\"datePublished\":\"2026-01-10T17:03:42Z\",\"dateModified\":\"2026-01-10T17:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470463,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","url_meta":{"origin":1469960,"position":0},"title":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela","author":"","date":"enero 25, 2026","format":false,"excerpt":"La organizaci\u00f3n no gubernamental Foro Penal dijo que al menos 80 presos pol\u00edticos fueron liberados este domingo en Venezuela, mientras trabaja por confirmar las identidades de los involucrados.\u201cAl menos 80 presos pol\u00edticos que estamos verificando han sido excarcelados el d\u00eda de hoy en todo el pa\u00eds. Probablemente se producen m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470086,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/14\/foro-penal-numeros-presos-politicos-excarcelados-orix\/","url_meta":{"origin":1469960,"position":1},"title":"Las divergencias entre las cifras de excarcelados reportadas por el Gobierno y por Foro Penal en Venezuela: qu\u00e9 dice cada uno","author":"","date":"enero 14, 2026","format":false,"excerpt":"Casi una semana despu\u00e9s de que el presidente de la Asamblea Nacional de Venezuela, Jorge Rodr\u00edguez, anunci\u00f3 que saldr\u00edan de prisi\u00f3n un gran n\u00famero de presos pol\u00edticos, la informaci\u00f3n oficial es escasa y hay marcadas diferencias entre los datos que anunci\u00f3 el Gobierno venezolano y los que reportan organizaciones no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452328,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/31\/excarcelacion-16-adolescentes-detenidos-protestas-venezuela-orix\/","url_meta":{"origin":1469960,"position":2},"title":"Reportan excarcelaci\u00f3n de 16 adolescentes detenidos durante las protestas poselectorales en Venezuela","author":"","date":"agosto 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 16 adolescentes que hab\u00edan sido detenidos durante las protestas poselectorales en Venezuela fueron excarcelados este jueves, inform\u00f3 Alfredo Romero, director presidente de la organizaci\u00f3n no gubernamental Foro Penal, que ha documentado posibles violaciones a los derechos humanos durante las manifestaciones tras las elecciones presidenciales del 28 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456965,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/25\/excarcelan-adolescentes-protestas-poselectorales-orix\/","url_meta":{"origin":1469960,"position":3},"title":"Excarcelan a todos los adolescentes detenidos en las protestas poselectorales en Venezuela, dice ONG Foro Penal","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Todos los adolescentes que fueron detenidos durante las protestas registradas despu\u00e9s de las controvertidas elecciones presidenciales de Venezuela quedaron excarcelados en los \u00faltimos d\u00edas, dijo Alfredo Romero, director presidente de Foro Penal, organizaci\u00f3n no gubernamental de derechos humanos que ha dado seguimiento a estos casos.\u201cEso es una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469713,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/01\/excarcelacion-personas-detenidas-tocoron-orix\/","url_meta":{"origin":1469960,"position":4},"title":"Gobierno de Venezuela anuncia excarcelaci\u00f3n de 88 personas detenidas durante las protestas de 2024","author":"","date":"enero 1, 2026","format":false,"excerpt":"El Gobierno de Venezuela anunci\u00f3 este jueves la excarcelaci\u00f3n de 88 personas detenidas en medio de la crisis poselectoral tras la votaci\u00f3n presidencial de 2024, apenas una semana despu\u00e9s de la liberaci\u00f3n de otras 99 personas en Navidad.El Ministerio del Poder Popular para el Servicio Penitenciario dijo en redes sociales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469576,"url":"https:\/\/noticiasya.com\/nacional\/2025\/12\/25\/reportan-excarcelacion-detenidos-orix\/","url_meta":{"origin":1469960,"position":5},"title":"Reportan la excarcelaci\u00f3n de al menos 26 personas detenidas en Venezuela","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"Al menos 26 personas que estaban detenidas en Venezuela presuntamente por motivos pol\u00edticos fueron excarceladas este jueves, dijo Alfredo Romero, director presidente de la organizaci\u00f3n no gubernamental de derechos humanos Foro Penal, en su cuenta de X.Tres de esas personas son adolescentes, agreg\u00f3 Romero, cuyo equipo da seguimiento a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469960"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469960\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}