{"id":1469962,"date":"2026-01-10T10:03:58","date_gmt":"2026-01-10T18:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/"},"modified":"2026-01-10T10:03:58","modified_gmt":"2026-01-10T18:03:58","slug":"protestas-ice-renee-good-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/10\/protestas-ice-renee-good-orix\/","title":{"rendered":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good"},"content":{"rendered":"<p>Est\u00e1 previsto que m\u00e1s de<a href=\"https:\/\/www.cnn.com\/us\/live-news\/minneapolis-ice-shooting-immigration-crackdown-01-10-26?post-id=cmk878y7100003b609t2xvrjf\"> 1.000 manifestaciones <\/a>que exigen que el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) abandone las comunidades locales se desarrollen este fin de semana en todo EE.UU., despu\u00e9s de la convocatoria por parte de una coalici\u00f3n nacional de grupos de defensa de los inmigrantes y los derechos civiles.<\/p>\n<p>Los eventos coordinados bajo el lema de \u201cICE Out For Good\u201d est\u00e1n planeados para este s\u00e1bado y para domingo en respuesta a \u201cla escalada de violencia de ICE en nuestras comunidades\u201d, el tiroteo mortal de ICE contra Renee Good, as\u00ed como \u201cel patr\u00f3n de meses de violencia y abuso sin control en comunidades marginadas de todo Estados Unidos\u201d, dice el comunicado de la coalici\u00f3n. La indignaci\u00f3n por la muerte de Good sigue creciendo, tanto en la ciudad como a nivel nacional.<\/p>\n<p>Todos los eventos organizados por la coalici\u00f3n reunir\u00e1n a personas que se congregar\u00e1n en acciones \u201cno violentas, legales y dirigidas por la comunidad\u201d para honrar a las personas que han muerto en enfrentamientos con ICE y exigir rendici\u00f3n de cuentas, dijo la coalici\u00f3n, que incluye a la Uni\u00f3n Estadounidense por las Libertades Civiles y el movimiento de protesta 50501.<\/p>\n<p>Las protestas<a href=\"https:\/\/www.cnn.com\/us\/live-news\/minneapolis-ice-shooting-immigration-crackdown-01-10-26?post-id=cmk7iup0l001527p44u3ibhrd\"> estallaron en el centro de Minneapolis <\/a>desde la noche del viernes y continuaron este s\u00e1bado, cuando cientos de manifestantes llenaron las calles para alzar la voz contra la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/07\/eeuu\/quien-mujer-murio-disparos-ice-minneapolis-trax\">muerte de Renee Good<\/a>, una madre de tres hijos que muri\u00f3 baleada por un agente de ICE involucrado en la ofensiva inmigratoria del presidente Donald Trump.<\/p>\n<p>Al menos 30 personas han sido detenidas y luego liberadas despu\u00e9s de que la polic\u00eda de Minneapolis declarara ilegal una agrupaci\u00f3n cuando cientos de manifestantes se congregaron en un hotel del centro el viernes, dijeron las autoridades.<\/p>\n<p>El hotel se convirti\u00f3 en el objetivo de manifestantes contra ICE, quienes, bajo la creencia de que agentes federales se alojaban all\u00ed, golpearon tambores, silbaron y alumbraron con luces las ventanas, inform\u00f3 Omar Jimenez de CNN desde el lugar.<\/p>\n<p>Alrededor de las 10:15 p.m. hora local, la polic\u00eda de Minneapolis \u201cdeclar\u00f3 una asamblea ilegal y emiti\u00f3 m\u00faltiples \u00f3rdenes de dispersi\u00f3n\u201d, dijo un vocero de la Polic\u00eda a CNN en un comunicado.<\/p>\n<p>La Polic\u00eda dijo que la medida sigui\u00f3 a enfrentamientos crecientes, incluyendo reportes de que \u201calgunas personas forzaron la entrada al hotel por una entrada lateral\u201d poco antes de la declaraci\u00f3n.<\/p>\n<p>Durante el transcurso de la noche, personas \u201clanzaron nieve, hielo y piedras a los agentes, veh\u00edculos policiales y otros veh\u00edculos en la v\u00eda p\u00fablica\u201d, agreg\u00f3 el vocero. Varias centenas de personas se hab\u00edan reunido m\u00e1s temprano en la noche, a las 8:00 p.m., cerca del hotel y se desplazaron por el centro hasta un segundo hotel, donde la polic\u00eda report\u00f3 da\u00f1os a la propiedad. Un agente sufri\u00f3 heridas leves que no requirieron atenci\u00f3n m\u00e9dica, dijo la Polic\u00eda.<\/p>\n<p>\u201cCon la ayuda de la (Patrulla Estatal de Minnesota) y el (Departamento de Recursos Naturales de Minnesota), al menos 30 personas fueron detenidas, citadas y luego puestas en libertad\u201d, dijo el portavoz.<\/p>\n<p>Renee Nicole Good, ciudadana estadounidense de 37 a\u00f1os, muri\u00f3 cuando un agente del ICE <a href=\"https:\/\/www.cnn.com\/2026\/01\/07\/us\/minneapolis-shooting-ice-video-analysis-vis\">dispar\u00f3 contra su veh\u00edculo<\/a> durante un enfrentamiento en la ma\u00f1ana del mi\u00e9rcoles.<\/p>\n<p>El Departamento de Seguridad Nacional asegur\u00f3 el tiroteo donde falleci\u00f3 Good se trat\u00f3 de una acci\u00f3n de \u201cdefensa propia\u201d, pues, de acuerdo con la secretaria Kristi Noem, la mujer atac\u00f3 a los agentes de ICE con su autom\u00f3vil.<\/p>\n<p>Sin embargo, los funcionarios estatales y locales han cuestionado en\u00e9rgicamente las afirmaciones de que los disparos, <a href=\"https:\/\/www.cnn.com\/2026\/01\/07\/us\/video\/mn-minnesota-shooting-timeline-digvid\">capturados en video<\/a>, hayan sido en defensa propia, ya que las tensiones explotaron en medio del despliegue esta semana de unos <a href=\"https:\/\/www.cnn.com\/2026\/01\/05\/us\/ice-minnesota-immigration-federal-agents-somali\">2.000 agentes federales<\/a> como parte de la \u00faltima ofensiva <a href=\"https:\/\/www.cnn.com\/2026\/01\/06\/us\/minneapolis-ice-crackdown-what-we-know\">migratoria<\/a> del Gobierno de Trump.<\/p>\n<p>El presidente de EE.UU., Donald Trump, reforz\u00f3 la explicaci\u00f3n del Departamento de Seguridad Nacional sobre los acontecimientos en Minneapolis <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/07\/eeuu\/tiroteo-minneapolis-ice-trax\">el mi\u00e9rcoles.<\/a> El presidente culp\u00f3 a la \u201cizquierda radical\u201d por \u201camenazar, agredir y atacar a nuestros agentes de la ley y del ICE diariamente\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 previsto que m\u00e1s de 1.000 manifestaciones que exigen que el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) abandone las comunidades locales se desarrollen este fin de semana en todo EE.UU., despu\u00e9s de la convocatoria por parte de una coalici\u00f3n nacional de grupos de defensa de los inmigrantes y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469962","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good - Noticias\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 previsto que m\u00e1s de 1.000 manifestaciones que exigen que el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) abandone las comunidades locales se desarrollen este fin de semana en todo EE.UU., despu\u00e9s de la convocatoria por parte de una coalici\u00f3n nacional de grupos de defensa de los inmigrantes y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-10T18:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good\",\"datePublished\":\"2026-01-10T18:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/\"},\"wordCount\":738,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/\",\"name\":\"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-10T18:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good - Noticias","og_description":"Est\u00e1 previsto que m\u00e1s de 1.000 manifestaciones que exigen que el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) abandone las comunidades locales se desarrollen este fin de semana en todo EE.UU., despu\u00e9s de la convocatoria por parte de una coalici\u00f3n nacional de grupos de defensa de los inmigrantes y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-10T18:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/"},"author":{"name":"","@id":""},"headline":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good","datePublished":"2026-01-10T18:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/"},"wordCount":738,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/","name":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-10T18:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/10\/protestas-ice-renee-good-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/10\/protestas-ice-renee-good-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/10\/protestas-ice-renee-good-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/10\/protestas-ice-renee-good-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-10T18:03:58Z","datePublished":"2026-01-10T18:03:58Z","dateModified":"2026-01-10T18:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/10\\\/protestas-ice-renee-good-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/10\\\/protestas-ice-renee-good-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-10T18:03:58Z\",\"datePublished\":\"2026-01-10T18:03:58Z\",\"dateModified\":\"2026-01-10T18:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469982,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/11\/protestas-contra-ice-muerte-mujer-minneapolis-trax\/","url_meta":{"origin":1469962,"position":0},"title":"Protestas contra ICE en todo Estados Unidos tras la muerte a tiros de una mujer en Minneapolis por parte de un agente","author":"","date":"enero 11, 2026","format":false,"excerpt":"La indignaci\u00f3n nacional por la muerte a tiros de una mujer de Minneapolis a manos de un agente de ICE se traslad\u00f3 el s\u00e1bado a las calles de ciudades en todo Estados Unidos, con manifestantes que exig\u00edan la salida de las autoridades federales de inmigraci\u00f3n de sus comunidades y justicia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469986,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/11\/noem-refuerza-ice-minneapolis-tiroteo-trax\/","url_meta":{"origin":1469962,"position":1},"title":"Kristi Noem anunci\u00f3 mayor presencia de ICE en Minneapolis. Acus\u00f3 a autoridades locales de &#171;politizar&#187; la muerte de Renee Good","author":"","date":"enero 11, 2026","format":false,"excerpt":"La secretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, anunci\u00f3 este domingo el env\u00edo de \u201ccientos m\u00e1s\u201d de agentes federales a Minneapolis para reforzar la seguridad de ICE tras la muerte de Renee Good durante un operativo de control inmigratorio, y arremeti\u00f3 contra las autoridades locales por, seg\u00fan dijo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466878,"url":"https:\/\/noticiasya.com\/nacional\/2025\/09\/26\/rechazo-comunidad-latina-violencia-ice-mujer-ecuatoriana-orix\/","url_meta":{"origin":1469962,"position":2},"title":"&#171;Crueldad indefendible&#187;: el rechazo de la comunidad latina a la violencia del ICE contra una mujer ecuatoriana","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"El Gobierno de Ecuador y organizaciones defensoras de derechos humanos en Am\u00e9rica Latina rechazaron con firmeza el accionar del Servicio de Inmigraci\u00f3n y Control de Aduanas de los Estados Unidos (ICE, por sus siglas en ingl\u00e9s) en el caso de M\u00f3nica Moreta Galarza, la mujer ecuatoriana violentamente empujada y arrojada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470005,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","url_meta":{"origin":1469962,"position":3},"title":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE","author":"","date":"enero 12, 2026","format":false,"excerpt":"Cientos de agentes de la Patrulla Fronteriza se est\u00e1n movilizando para reforzar la ofensiva del presidente Donald Trump contra la inmigraci\u00f3n en la nevada Minneapolis, dijo el domingo la secretaria de Seguridad Nacional, Kristi Noem, mientras aumentan las tensiones entre las autoridades federales y las locales tras un tiroteo ocurrido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470144,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/16\/renee-good-911-detalles-muerte-trax\/","url_meta":{"origin":1469962,"position":4},"title":"Transcripciones del 911 y un informe revelan detalles de la muerte de Renee Good y la reacci\u00f3n de su comunidad en tiempo real","author":"","date":"enero 16, 2026","format":false,"excerpt":"Despu\u00e9s de que Renee Good fuera baleada la semana pasada por un agente federal de inmigraci\u00f3n en Minneapolis, la madre de tres hijos estaba \u201cinconsciente, sin respirar, con pulso d\u00e9bil, irregular e intermitente\u201d, seg\u00fan un informe del Departamento de Bomberos de la ciudad.\u201cVi\u2026 a un agente de ICE disparar dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470364,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/22\/autoridades-federales-terroristas-domesticos-vigilan-ice-trax\/","url_meta":{"origin":1469962,"position":5},"title":"Las autoridades federales han calificado de &#171;terroristas dom\u00e9sticos&#187; a quienes vigilan a ICE","author":"","date":"enero 22, 2026","format":false,"excerpt":"Un d\u00eda despu\u00e9s del tiroteo fatal de Renee Good por parte de un agente de Inmigraci\u00f3n y Control de Aduanas en Minneapolis a principios de este mes, un grupo de defensa de los inmigrantes de Minnesota inform\u00f3 que aumento tres veces el n\u00famero de personas que se inscribieron para convertirse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469962"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469962\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}