{"id":1469984,"date":"2026-01-11T10:03:46","date_gmt":"2026-01-11T18:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/"},"modified":"2026-01-11T10:03:46","modified_gmt":"2026-01-11T18:03:46","slug":"trump-posible-intervencion-militar-iran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/","title":{"rendered":"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n"},"content":{"rendered":"<p>El presidente Donald Trump eval\u00faa una serie de posibles opciones militares en Ir\u00e1n tras las protestas mortales en el pa\u00eds, dijeron a CNN dos funcionarios estadounidenses, mientras considera cumplir sus recientes amenazas de atacar al r\u00e9gimen iran\u00ed si utiliza fuerza letal contra civiles.<\/p>\n<p>Trump recibi\u00f3 en los \u00faltimos d\u00edas informes sobre distintos planes de intervenci\u00f3n, dijeron los funcionarios a CNN, en medio de una escalada de violencia que ha dejado decenas de muertos y detenidos.<\/p>\n<p>Varias de las opciones presentadas al presidente se han centrado en atacar a los servicios de seguridad de Teher\u00e1n que est\u00e1n siendo utilizados para sofocar las protestas, se\u00f1alaron los funcionarios.<\/p>\n<p>Sin embargo, dentro del Gobierno existen preocupaciones de que los ataques militares puedan resultar contraproducentes y socavar las protestas. Los funcionarios advirtieron que estas acciones podr\u00edan tener el efecto no deseado de unir a la poblaci\u00f3n iran\u00ed en apoyo al Gobierno, o provocar una represalia militar por parte de Ir\u00e1n.<\/p>\n<p>Trump tambi\u00e9n est\u00e1 considerando otras opciones dirigidas al r\u00e9gimen iran\u00ed que no implican ataques militares, dijeron los funcionarios, mientras busca cumplir su promesa de ayudar a los manifestantes en el pa\u00eds.<\/p>\n<p>Entre las alternativas figuran operaciones cibern\u00e9ticas contra objetivos del Ej\u00e9rcito iran\u00ed o del r\u00e9gimen, una medida que podr\u00eda interrumpir los esfuerzos por reprimir las protestas, indic\u00f3 un funcionario.<\/p>\n<p>Las opciones tambi\u00e9n incluyen nuevas sanciones contra figuras del r\u00e9gimen o contra sectores de la econom\u00eda iran\u00ed, como el energ\u00e9tico o el bancario.<\/p>\n<p>El Gobierno tambi\u00e9n ha explorado la posibilidad de proporcionar tecnolog\u00eda como Starlink para reforzar la conectividad a internet en Ir\u00e1n y ayudar a los manifestantes a eludir un apag\u00f3n informativo. El entonces presidente Joe Biden ofreci\u00f3 asistencia similar durante el \u00faltimo estallido de protestas callejeras en 2022.<\/p>\n<p>Varias agencias distintas han participado en la preparaci\u00f3n de opciones para el presidente, dijeron los funcionarios. Se esperan sesiones informativas m\u00e1s formales en la pr\u00f3xima semana, incluido el martes, cuando se prev\u00e9 que Trump convoque a altos funcionarios de seguridad nacional para discutir c\u00f3mo proceder.<\/p>\n<p>Teher\u00e1n tratar\u00e1 como objetivos de represalia a las bases militares y comerciales de Estados Unidos si Washington interviene militarmente en el Ir\u00e1n sacudido por disturbios, advirti\u00f3 el presidente del Parlamento iran\u00ed, de l\u00ednea dura.<\/p>\n<p>\u201cSi Estados Unidos toma una acci\u00f3n militar contra Ir\u00e1n o los territorios ocupados, los centros militares y navales de Estados Unidos ser\u00e1n considerados objetivos leg\u00edtimos\u201d, dijo Mohammad Baqer Qalibaf.<\/p>\n<p>\u201cNo nos limitamos a reaccionar solo despu\u00e9s de que se haya tomado una acci\u00f3n\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El presidente a\u00fan no ha tomado una decisi\u00f3n final sobre una intervenci\u00f3n, dijeron los funcionarios, pero est\u00e1 considerando seriamente actuar mientras el n\u00famero de muertos en Ir\u00e1n sigue en aumento. Las opciones que eval\u00faa el mandatario no implican desplegar tropas sobre el terreno en Ir\u00e1n, dijo a CNN un alto funcionario de la Casa Blanca.<\/p>\n<p>Al menos 10.675 personas han sido arrestadas, entre ellas 169 menores, en los \u00faltimos 15 d\u00edas durante las manifestaciones contra el r\u00e9gimen en Ir\u00e1n, seg\u00fan un recuento detallado entregado a CNN por Skylar Thompson, subdirector de <em>Human Rights Activists in Iran<\/em> (HRA).<\/p>\n<p>El brazo informativo de HRA se llama <em>Human Rights Activists News Agency<\/em> (HRANA).<\/p>\n<p>Al menos 490 manifestantes han muerto en el mismo per\u00edodo, de acuerdo con el \u00faltimo balance del grupo, actualizado el domingo. CNN no puede verificar de forma independiente las cifras de v\u00edctimas ni de arrestos de HRANA.<\/p>\n<p>\u201cIr\u00e1n est\u00e1 mirando a la LIBERTAD, quiz\u00e1 como nunca antes\u201d, escribi\u00f3 Trump en redes sociales el s\u00e1bado. \u201c\u00a1Estados Unidos est\u00e1 listo para ayudar!\u201d.<\/p>\n<p>El viernes, Trump dijo a periodistas que si Teher\u00e1n recurre a la violencia letal contra los manifestantes, Estados Unidos \u201cse involucrar\u00e1\u201d.<\/p>\n<p>\u201cHe sido muy claro al decir que, si empiezan a matar gente como lo han hecho en el pasado, nos involucraremos\u201d, dijo Trump durante una reuni\u00f3n con ejecutivos petroleros. \u201cY eso no significa tropas sobre el terreno, pero s\u00ed significa golpearlos muy, muy fuerte donde les duele\u201d.<\/p>\n<p>El secretario de Estado, Marco Rubio, y el primer ministro de Israel, Benjamin Netanyahu, hablaron el s\u00e1bado sobre las protestas en curso, dijeron dos fuentes familiarizadas con la llamada. Los l\u00edderes tambi\u00e9n abordaron la situaci\u00f3n en Siria y en Gaza.<\/p>\n<p>Las Fuerzas de Defensa de Israel (FDI) dijeron el domingo que est\u00e1n \u201cmonitoreando los acontecimientos\u201d en Ir\u00e1n, mientras el pa\u00eds entra en su tercera semana de protestas contra el Gobierno.<\/p>\n<p>\u201cLas protestas son un asunto interno de Ir\u00e1n. No obstante, las FDI est\u00e1n preparadas en el plano defensivo y contin\u00faan mejorando sus capacidades y su preparaci\u00f3n operativa\u201d, dijo un portavoz en un comunicado.<\/p>\n<p>Entretanto, Netanyahu tiene previsto convocar la noche del domingo una consulta de seguridad limitada, con los acontecimientos en Ir\u00e1n y en L\u00edbano como temas centrales, seg\u00fan una fuente israel\u00ed.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump eval\u00faa una serie de posibles opciones militares en Ir\u00e1n tras las protestas mortales en el pa\u00eds, dijeron a CNN dos funcionarios estadounidenses, mientras considera cumplir sus recientes amenazas de atacar al r\u00e9gimen iran\u00ed si utiliza fuerza letal contra civiles. Trump recibi\u00f3 en los \u00faltimos d\u00edas informes sobre distintos planes de intervenci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469984","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump eval\u00faa una serie de posibles opciones militares en Ir\u00e1n tras las protestas mortales en el pa\u00eds, dijeron a CNN dos funcionarios estadounidenses, mientras considera cumplir sus recientes amenazas de atacar al r\u00e9gimen iran\u00ed si utiliza fuerza letal contra civiles. Trump recibi\u00f3 en los \u00faltimos d\u00edas informes sobre distintos planes de intervenci\u00f3n, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-11T18:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n\",\"datePublished\":\"2026-01-11T18:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/\"},\"wordCount\":870,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/\",\"name\":\"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-11T18:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n - Noticias","og_description":"El presidente Donald Trump eval\u00faa una serie de posibles opciones militares en Ir\u00e1n tras las protestas mortales en el pa\u00eds, dijeron a CNN dos funcionarios estadounidenses, mientras considera cumplir sus recientes amenazas de atacar al r\u00e9gimen iran\u00ed si utiliza fuerza letal contra civiles. Trump recibi\u00f3 en los \u00faltimos d\u00edas informes sobre distintos planes de intervenci\u00f3n, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-11T18:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/"},"author":{"name":"","@id":""},"headline":"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n","datePublished":"2026-01-11T18:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/"},"wordCount":870,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/","name":"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-11T18:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump considera una posible intervenci\u00f3n militar en Ir\u00e1n","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/11\/trump-posible-intervencion-militar-iran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-11T18:03:46Z","datePublished":"2026-01-11T18:03:46Z","dateModified":"2026-01-11T18:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump considera una posible intervenci\\u00f3n militar en Ir\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/11\\\/trump-posible-intervencion-militar-iran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/11\\\/trump-posible-intervencion-militar-iran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-11T18:03:46Z\",\"datePublished\":\"2026-01-11T18:03:46Z\",\"dateModified\":\"2026-01-11T18:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470131,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/15\/ataques-contra-iran-detuvieron-que-sigue-trax\/","url_meta":{"origin":1469984,"position":0},"title":"Al borde de ataques contra Ir\u00e1n, Estados Unidos se contuvo. Lo que ocurra ahora depende de Trump","author":"","date":"enero 15, 2026","format":false,"excerpt":"Al salir el martes de una reuni\u00f3n nocturna en la Sala de Situaci\u00f3n para analizar opciones ante un posible ataque contra Ir\u00e1n, varios de los principales asesores de seguridad nacional del presidente Donald Trump estaban relativamente convencidos de que una decisi\u00f3n sobre una acci\u00f3n militar era inminente.El presidente, seg\u00fan relataron,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463718,"url":"https:\/\/noticiasya.com\/nacional\/2025\/06\/18\/trump-conflicto-amplio-ataques-iran-israel-trax\/","url_meta":{"origin":1469984,"position":1},"title":"Trump busca evitar un conflicto m\u00e1s amplio mientras se decide sobre posibles ataques de EE.UU. en Ir\u00e1n, seg\u00fan fuentes","author":"","date":"junio 18, 2025","format":false,"excerpt":"Mientras el presidente Donald Trump sopesa si unirse a los ataques de Israel contra Ir\u00e1n (incluyendo el uso de bombas rompe-b\u00fankeres para atacar instalaciones nucleares profundamente subterr\u00e1neas), se est\u00e1 llevando a cabo una discusi\u00f3n entre sus altos funcionarios sobre c\u00f3mo Estados Unidos puede atacar esos objetivos sin verse envuelto en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469998,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/12\/analisis-regimen-iran-represion-trump-presion-trax\/","url_meta":{"origin":1469984,"position":2},"title":"Ir\u00e1n recrudece la represi\u00f3n mientras Trump aumenta la presi\u00f3n","author":"","date":"enero 12, 2026","format":false,"excerpt":"Mientras las furiosas protestas entran en su tercera semana y llevan a Ir\u00e1n al borde del cambio, el gobierno teocr\u00e1tico del pa\u00eds est\u00e1 tratando de sobrevivir reprimiendo duramente las crecientes manifestaciones.El clero gobernante de Ir\u00e1n ha resistido multitudinarias protestas en numerosas ocasiones. Pero el control del poder por parte del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470001,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/12\/5-cosas-12-enero-2026-orix\/","url_meta":{"origin":1469984,"position":3},"title":"Las 5 cosas que debes saber este 12 de enero","author":"","date":"enero 12, 2026","format":false,"excerpt":"Reportan la excarcelaci\u00f3n de otros 24 presos pol\u00edticos en Venezuela. Trump eval\u00faa una posible intervenci\u00f3n militar en Ir\u00e1n. \u00bfQui\u00e9nes fueron los ganadores de los premios Globo de Oro? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470058,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/13\/iran-disturbios-israel-espera-trump-trax\/","url_meta":{"origin":1469984,"position":4},"title":"Mientras Ir\u00e1n enfrenta disturbios, Israel espera en silencio el pr\u00f3ximo movimiento de Trump","author":"","date":"enero 13, 2026","format":false,"excerpt":"Mientras oleadas de protestas ponen a prueba la capacidad del r\u00e9gimen iran\u00ed para gestionar la disidencia, el pa\u00eds que probablemente tiene m\u00e1s que ganar ha estado esperando entre bastidores, reacio a intervenir incluso cuando su adversario regional se encuentra en su punto m\u00e1s vulnerable en a\u00f1os.Tras meses de amenazas p\u00fablicas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471455,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/19\/trump-enfrenta-decision-iran-ataques-trax\/","url_meta":{"origin":1469984,"position":5},"title":"Trump se enfrenta a la decisi\u00f3n que tomar\u00e1 sobre Ir\u00e1n: desde ataques selectivos hasta potencialmente derrocar al r\u00e9gimen","author":"","date":"febrero 19, 2026","format":false,"excerpt":"El presidente Donald Trump enfrenta una de las decisiones m\u00e1s trascendentales de su segundo mandato mientras ordena el mayor despliegue militar en Medio Oriente en 22 a\u00f1os.Si decide seguir adelante con un ataque contra Ir\u00e1n, sus opciones ahora van desde ataques m\u00e1s espec\u00edficos hasta operaciones sostenidas que podr\u00edan durar potencialmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1469984"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1469984\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1469984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1469984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1469984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}