{"id":1470005,"date":"2026-01-12T07:03:53","date_gmt":"2026-01-12T15:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/"},"modified":"2026-01-12T07:03:53","modified_gmt":"2026-01-12T15:03:53","slug":"cientos-agentes-ice-llegaran-minneapolis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","title":{"rendered":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE"},"content":{"rendered":"<p>Cientos de agentes de la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/11\/eeuu\/noem-refuerza-ice-minneapolis-tiroteo-trax\">Patrulla Fronteriza se est\u00e1n movilizando<\/a> para reforzar la ofensiva del presidente Donald Trump contra la inmigraci\u00f3n en la nevada Minneapolis, dijo el domingo la secretaria de Seguridad Nacional, Kristi Noem, mientras aumentan las tensiones entre las autoridades federales y las locales tras un tiroteo ocurrido la semana pasada durante una operaci\u00f3n de ICE, que dej\u00f3 muerta a una madre de tres hijos.<\/p>\n<p>Siguen apareciendo videos del incidente y a\u00fan hay mucho por esclarecer, pero el despliegue es el desarrollo m\u00e1s reciente en la disputa que lleva meses entre la ciudad gobernada por dem\u00f3cratas y el Gobierno federal, despu\u00e9s de que el presidente Donald Trump intensificara en diciembre las operaciones contra la comunidad somal\u00ed de Minnesota.<\/p>\n<p>Funcionarios del estado de la Estrella del Norte han reiterado sus llamados para que los agentes de inmigraci\u00f3n cooperen con las fuerzas policiales locales y se retiren, lo que ha provocado una dura respuesta verbal por parte de funcionarios federales.<\/p>\n<p>Tras un fin de semana marcado por cruces de alto nivel, la difusi\u00f3n de nuevos videos del tiroteo y protestas generalizadas, esto es lo m\u00e1s reciente.<\/p>\n<p>El s\u00e1bado, el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) <a href=\"https:\/\/x.com\/DHSgov\/status\/2010074554258075966\">public\u00f3 en X un nuevo video<\/a> que muestra los tres minutos y 30 segundos previos a los disparos de un agente de ICE que alcanzaron y mataron a Renee Good, de 37 a\u00f1os, en Minneapolis, el mi\u00e9rcoles.<\/p>\n<p>El nuevo video muestra el veh\u00edculo de Good \u2014una Honda Pilot color vino tinto\u2014 parcialmente bloqueando la calle. Varios veh\u00edculos que se detienen detr\u00e1s de ella parecen pertenecer a agentes federales, seg\u00fan la actividad observada en otros videos.<\/p>\n<p>En su publicaci\u00f3n, el DHS afirm\u00f3, sin presentar pruebas, que Good estaba \u201cacosando e interfiriendo en una operaci\u00f3n de las fuerzas del orden a lo largo de la ma\u00f1ana\u201d.<\/p>\n<p>Durante el video, varios veh\u00edculos pasan junto al autom\u00f3vil de Good. Unos 40 segundos despu\u00e9s de iniciado el clip, la c\u00e1mara se enfoca en Good movi\u00e9ndose dentro de su veh\u00edculo mientras se escucha el sonido de bocinas, aunque no est\u00e1 claro de d\u00f3nde provienen.<\/p>\n<p>Tres minutos despu\u00e9s, se activan sirenas de las fuerzas del orden y se oyen m\u00e1s bocinas. En el segundo 3:11, dos veh\u00edculos pasan junto a la camioneta de Good. Una camioneta que parece pertenecer a un agente federal se detiene de forma perpendicular a su veh\u00edculo y varios agentes descienden. Good parece hacerles se\u00f1as con las manos.<\/p>\n<p>Los agentes entonces salen del veh\u00edculo y el video se corta justo antes del tiroteo mortal.<\/p>\n<p>La publicaci\u00f3n del DHS se produjo un d\u00eda despu\u00e9s de que CNN obtuviera un video de tel\u00e9fono celular de la interacci\u00f3n, captado por el propio agente que dispar\u00f3 contra Good, Jonathan Ross.<\/p>\n<p>El video de Ross no muestra si la SUV hizo contacto con \u00e9l, ya que el \u00e1ngulo de la c\u00e1mara se sacude hacia el cielo. Un video previo grabado por un testigo muestra que la SUV pudo haber hecho contacto cuando avanza bruscamente y \u00e9l se mueve hacia un costado.<\/p>\n<p>La vice<\/p>\n<p>secretaria del DHS, Tricia McLaughlin, dijo que el video de Ross respalda lo que ha sostenido la agencia: que el agente de ICE actu\u00f3 en defensa propia.<\/p>\n<p>El momento exacto del disparo no es visible, pero se escuchan tres detonaciones mientras el tel\u00e9fono que Ross sostiene se sacude a\u00fan m\u00e1s y luego queda apuntando hacia la casa que est\u00e1 detr\u00e1s de \u00e9l.<\/p>\n<p>Las tensiones llegaron al escenario nacional la ma\u00f1ana del domingo, cuando Noem inst\u00f3 a los funcionarios de Minnesota a \u201cmadurar\u201d, tras sus quejas de que las agencias federales no est\u00e1n cooperando con las autoridades estatales y locales que investigan la muerte de Good.<\/p>\n<p>Noem apunt\u00f3 directamente contra el gobernador de Minnesota, Tim Walz, y el alcalde de Minneapolis, Jacob Frey, a quienes acus\u00f3 de politizar el tiroteo y de alentar la \u201cdestrucci\u00f3n\u201d y la \u201cviolencia\u201d en la ciudad.<\/p>\n<p>\u201cHan politizado de forma extrema e inapropiada lo que ocurre sobre el terreno en su ciudad. Han inflamado al p\u00fablico. Han alentado el tipo de destrucci\u00f3n y violencia que hemos visto en Minneapolis en los \u00faltimos d\u00edas\u201d, dijo Noem el domingo en \u201cState of the Union\u201d, de CNN.<\/p>\n<p>\u201cLes recomendar\u00eda que maduren, que tengan un poco de madurez, que act\u00faen como personas responsables, que quieren que la gente est\u00e9 a salvo y que se haga lo correcto\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Momentos despu\u00e9s, Frey conden\u00f3 en\u00e9rgicamente el hecho ante Jake Tapper, de CNN, e inst\u00f3 a los agentes de ICE a salir de Minneapolis.<\/p>\n<p>\u201cElla est\u00e1 llamando a Minneapolis este agujero infernal dist\u00f3pico. \u00bfSabe cu\u00e1ntos tiroteos hemos tenido en lo que va del a\u00f1o? Dos, y uno de ellos fue de ICE\u201d, dijo Frey a Tapper.<\/p>\n<p>Frey reiter\u00f3 su afirmaci\u00f3n de que el agente que dispar\u00f3 contra Good fue \u201cun agente federal que us\u00f3 el poder de forma imprudente y eso termin\u00f3 con la muerte de una persona\u201d.<\/p>\n<p>\u201c\u00bfEstoy sesgado en esto? Claro. Estoy sesgado porque tengo dos ojos. Cualquiera puede ver estos videos, cualquiera puede ver que esta v\u00edctima no es una terrorista dom\u00e9stica\u201d, afirm\u00f3.<\/p>\n<p>El alcalde pidi\u00f3 una investigaci\u00f3n independiente del tiroteo. El Departamento de Justicia ha impedido que investigadores estatales participen en la pesquisa.<\/p>\n<p>En Washington, la congresista dem\u00f3crata por Minnesota, Ilhan Omar, dijo que el Gobierno federal est\u00e1 alimentando el \u201ccaos\u201d con sus esfuerzos de aplicaci\u00f3n de leyes inmigratorias de mano dura tras la muerte por disparos de una ciudadana estadounidense la semana pasada.<\/p>\n<p>\u201cLo que hemos visto en Minneapolis es que los agentes de ICE a menudo saltan de sus autos. Son veh\u00edculos sin identificaci\u00f3n. A menudo llevan mascarillas\u201d, dijo Omar el domingo en \u201cFace the Nation\u201d, de CBS. \u201cLo que est\u00e1n haciendo es crear confusi\u00f3n, caos, tratando de intimidar a las personas para que no puedan ejercer sus actividades normales y cotidianas\u201d.<\/p>\n<p>Omar, acompa\u00f1ada por otros congresistas dem\u00f3cratas de Minnesota, dijo que el s\u00e1bado por la ma\u00f1ana se le neg\u00f3 el acceso a un centro de ICE en su estado, despu\u00e9s de haber estado brevemente en su interior.<\/p>\n<p>Noem emiti\u00f3 el jueves una directiva que proh\u00edbe a los legisladores visitar centros de detenci\u00f3n sin dar aviso con una semana de anticipaci\u00f3n, dijo McLaughlin en un comunicado, debido a \u201cdisturbios en aumento y violencia pol\u00edtica dirigida contra edificios e instalaciones utilizados por ICE\u201d.<\/p>\n<p>La secretaria del DHS actu\u00f3 para \u201cgarantizar una protecci\u00f3n adecuada tanto para los miembros del Congreso y su personal como para los detenidos y los empleados de ICE\u201d, se\u00f1al\u00f3 McLaughlin en su declaraci\u00f3n del domingo.<\/p>\n<p>A medida que crec\u00eda la indignaci\u00f3n tras la muerte de Good, m\u00e1s de 1.000 manifestaciones fueron convocadas en todo Estados Unidos durante el fin de semana en protesta por el aumento de las acciones de control inmigratorio del Gobierno de Trump en Minneapolis y en otros lugares.<\/p>\n<p>La protesta masiva del s\u00e1bado en las llamadas Ciudades Gemelas tom\u00f3 m\u00faltiples formas a lo largo del d\u00eda. Comenz\u00f3 en Powderhorn Park, un sitio hist\u00f3rico para manifestaciones, conocido como uno de los principales puntos de reuni\u00f3n durante las protestas por George Floyd, en 2020. Tras marchar por un vecindario de Minneapolis, la multitud, compuesta por miles de personas, se concentr\u00f3 en la calle donde Good muri\u00f3 tras recibir disparos.<\/p>\n<p>Noem dijo el domingo que el DHS est\u00e1 enviando \u201ccientos m\u00e1s\u201d de agentes a Minneapolis, adem\u00e1s de los cerca de 2.000 agentes federales que ya han sido desplegados en la zona.<\/p>\n<p>\u201cEstamos enviando m\u00e1s agentes hoy y ma\u00f1ana, y llegar\u00e1n. Habr\u00e1 cientos m\u00e1s para permitir que nuestro personal de ICE y de la Patrulla Fronteriza que trabaja en Minneapolis pueda hacerlo de manera segura\u201d, dijo Noem en el programa \u201cSunday Morning Futures\u201d, de Fox News.<\/p>\n<p>Mientras tanto, miles de personas protestaron en otras partes del pa\u00eds en manifestaciones contra las pol\u00edticas inmigratorias.<\/p>\n<p>En Los \u00c1ngeles, el reflector de un helic\u00f3ptero policial ilumin\u00f3 a manifestantes en la calle Alameda, que portaban banderas estadounidenses invertidas y carteles hechos a mano contra ICE.<\/p>\n<p>Esa calle tambi\u00e9n fue escenario de enfrentamientos entre manifestantes y agentes en junio del a\u00f1o pasado, cuando multitudes se reunieron para protestar contra redadas inmigratorias y el despliegue de la Guardia Nacional por parte de Trump.<\/p>\n<p>Con pancartas que dec\u00edan \u201cEl r\u00e9gimen fascista de Trump DEBE IRSE YA\u201d y \u201cDESPIERTA, EE.UU.\u201d, los manifestantes marcharon frente a la Casa Blanca pese a la lluvia constante en la capital.<\/p>\n<p>Una de las manifestantes, Claudia Schur, se uni\u00f3 a la marcha para expresar su rechazo a varias acciones del Gobierno de Trump.<\/p>\n<p>\u201cYa no hay reglas, no hay verg\u00fcenza, no hay integridad\u201d, dijo Schur mientras sosten\u00eda un cartel que dec\u00eda \u201cICE Out\u201d. \u201cEs simplemente un pa\u00eds que ya no reconozco\u201d.<\/p>\n<p>Julia Doherty \u2014quien marchaba junto a Schur\u2014 dijo que le preocupa la polarizaci\u00f3n entre los estadounidenses.<\/p>\n<p>\u201cNo hay sentido de comunidad. Estamos tan polarizados que es aterrador\u201d, afirm\u00f3 Doherty. \u201cY tenemos que levantarnos y hacer todo lo que podamos para provocar un cambio\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cientos de agentes de la Patrulla Fronteriza se est\u00e1n movilizando para reforzar la ofensiva del presidente Donald Trump contra la inmigraci\u00f3n en la nevada Minneapolis, dijo el domingo la secretaria de Seguridad Nacional, Kristi Noem, mientras aumentan las tensiones entre las autoridades federales y las locales tras un tiroteo ocurrido la semana pasada durante una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470005","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cientos de agentes de la Patrulla Fronteriza se est\u00e1n movilizando para reforzar la ofensiva del presidente Donald Trump contra la inmigraci\u00f3n en la nevada Minneapolis, dijo el domingo la secretaria de Seguridad Nacional, Kristi Noem, mientras aumentan las tensiones entre las autoridades federales y las locales tras un tiroteo ocurrido la semana pasada durante una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T15:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE\",\"datePublished\":\"2026-01-12T15:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/\"},\"wordCount\":1605,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/\",\"name\":\"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-12T15:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE - Noticias","og_description":"Cientos de agentes de la Patrulla Fronteriza se est\u00e1n movilizando para reforzar la ofensiva del presidente Donald Trump contra la inmigraci\u00f3n en la nevada Minneapolis, dijo el domingo la secretaria de Seguridad Nacional, Kristi Noem, mientras aumentan las tensiones entre las autoridades federales y las locales tras un tiroteo ocurrido la semana pasada durante una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-12T15:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/"},"author":{"name":"","@id":""},"headline":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE","datePublished":"2026-01-12T15:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/"},"wordCount":1605,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","name":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-12T15:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cientos de agentes de inmigraci\u00f3n m\u00e1s llegar\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/12\/cientos-agentes-ice-llegaran-minneapolis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-12T15:03:53Z","datePublished":"2026-01-12T15:03:53Z","dateModified":"2026-01-12T15:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cientos de agentes de inmigraci\\u00f3n m\\u00e1s llegar\\u00e1n a Minneapolis, dice Noem, tras muerte vinculada a ICE\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/12\\\/cientos-agentes-ice-llegaran-minneapolis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/12\\\/cientos-agentes-ice-llegaran-minneapolis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-12T15:03:53Z\",\"datePublished\":\"2026-01-12T15:03:53Z\",\"dateModified\":\"2026-01-12T15:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469986,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/11\/noem-refuerza-ice-minneapolis-tiroteo-trax\/","url_meta":{"origin":1470005,"position":0},"title":"Kristi Noem anunci\u00f3 mayor presencia de ICE en Minneapolis. Acus\u00f3 a autoridades locales de &#171;politizar&#187; la muerte de Renee Good","author":"","date":"enero 11, 2026","format":false,"excerpt":"La secretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, anunci\u00f3 este domingo el env\u00edo de \u201ccientos m\u00e1s\u201d de agentes federales a Minneapolis para reforzar la seguridad de ICE tras la muerte de Renee Good durante un operativo de control inmigratorio, y arremeti\u00f3 contra las autoridades locales por, seg\u00fan dijo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470848,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/04\/retiraran-700-agentes-minneapolis-inmigracion-ice-trax\/","url_meta":{"origin":1470005,"position":1},"title":"El Departamento de Seguridad Nacional retirar\u00e1 a 700 agentes de Minnesota &#171;inmediatamente&#187;, dice Homan","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Tom Homan, zar de la frontera del presidente Trump, anunci\u00f3 este mi\u00e9rcoles que el Departamento de Seguridad Nacional retirar\u00e1 700 agentes de Minneapolis de manera inmediata.Aproximadamente 3.000 agentes del Departamento de Seguridad Nacional hab\u00edan sido desplegados en Minneapolis como parte de la Operaci\u00f3n Metro Surge que comenz\u00f3 a principios de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469962,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/10\/protestas-ice-renee-good-orix\/","url_meta":{"origin":1470005,"position":2},"title":"Miles de personas en EE.UU. participan en protestas contra ICE este fin de semana tras la muerte de Renee Good","author":"","date":"enero 10, 2026","format":false,"excerpt":"Est\u00e1 previsto que m\u00e1s de 1.000 manifestaciones que exigen que el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) abandone las comunidades locales se desarrollen este fin de semana en todo EE.UU., despu\u00e9s de la convocatoria por parte de una coalici\u00f3n nacional de grupos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471477,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/20\/trump-aplicar-todo-pais-manual-inmigracion-homan-trax\/","url_meta":{"origin":1470005,"position":3},"title":"La administraci\u00f3n Trump planea aplicar en todo el pa\u00eds el manual de inmigraci\u00f3n de Homan en Minneapolis","author":"","date":"febrero 20, 2026","format":false,"excerpt":"La administraci\u00f3n Trump planea redoblar los esfuerzos en la aplicaci\u00f3n de leyes inmigratorias espec\u00edficas, tomando el ejemplo de Tom Homan en Minneapolis y aplic\u00e1ndolo a varias ciudades del pa\u00eds, seg\u00fan funcionarios actuales y anteriores de Seguridad Nacional.Esto representa un cambio radical con respecto a las t\u00e1cticas, muy visibles y agresivas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470784,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/02\/agentes-seguridad-nacional-camaras-corporales-trax\/","url_meta":{"origin":1470005,"position":4},"title":"Agentes de Seguridad Nacional en Minneapolis portar\u00e1n c\u00e1maras corporales, dice Noem","author":"","date":"febrero 2, 2026","format":false,"excerpt":"Todos los agentes de Seguridad Nacional en el terreno en Minneapolis recibir\u00e1n c\u00e1maras corporales, anunci\u00f3 el lunes la secretaria Kristi Noem.\u201cCon efecto inmediato estamos desplegando c\u00e1maras corporales a cada agente en el terreno en Minneapolis\u201d, escribi\u00f3 Noem en una publicaci\u00f3n en redes sociales. \u201cA medida que haya fondos disponibles, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470495,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/26\/quien-es-tom-homan-zar-fronterizo-trump-minnesota-trax\/","url_meta":{"origin":1470005,"position":5},"title":"\u00bfQui\u00e9n es Tom Homan? El zar fronterizo de Trump llegar\u00e1 a Minnesota en medio de una crisis sin precedentes","author":"","date":"enero 26, 2026","format":false,"excerpt":"El zar fronterizo de la Casa Blanca que el presidente Donald Trump enviar\u00e1 a Minneapolis tras el tiroteo fatal de dos estadounidenses es un veterano funcionario de las fuerzas del orden que ha impulsado algunas de las controvertidas pol\u00edticas del Gobierno de Trump relacionadas con la inmigraci\u00f3n.Trump dijo este lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1470005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1470005"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1470005\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1470005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1470005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1470005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}