{"id":1470077,"date":"2026-01-14T10:03:40","date_gmt":"2026-01-14T18:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/"},"modified":"2026-01-14T10:03:40","modified_gmt":"2026-01-14T18:03:40","slug":"nasa-astronautas-crew-11-estacion-espacial-internacional-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","title":{"rendered":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo"},"content":{"rendered":"<p>Cuatro astronautas est\u00e1n a punto de abandonar la Estaci\u00f3n Espacial Internacional (EEI) debido a un problema de salud, y su partida anticipada, sin precedentes, dejar\u00e1 una tripulaci\u00f3n m\u00ednima a cargo del puesto orbital.<\/p>\n<p>Cuando la tripulaci\u00f3n aborde la c\u00e1psula SpaceX que los llevar\u00e1 de regreso a la Tierra, solo tres personas permanecer\u00e1n en el laboratorio espacial: los cosmonautas de Roscosmos Sergey Kud-Sverchkov y Sergei Mikaev de Rusia, y el astronauta de la NASA Chris Williams.<\/p>\n<p>La agencia espacial estadounidense transmitir\u00e1 en directo la partida de la c\u00e1psula SpaceX Crew en <a href=\"https:\/\/plus.nasa.gov\/scheduled-video\/nasas-spacex-crew-11-re-entry-and-splashdown\/\">NASA+<\/a> a partir de las 4:45 p.m. (hora de Miami) de este mi\u00e9rcoles, y se prev\u00e9 que la c\u00e1psula se desacople de la estaci\u00f3n espacial alrededor de las 5 p.m. (hora de Miami).<\/p>\n<p>Es una situaci\u00f3n poco ideal. La NASA ha se\u00f1alado repetidamente que mantener la EEI con la tripulaci\u00f3n completa es una prioridad m\u00e1xima, debido a que la agencia busca maximizar la cantidad de investigaci\u00f3n cient\u00edfica que puede realizar en la estaci\u00f3n, que ya tiene sus a\u00f1os, antes de que sea retirada definitivamente a principios de la pr\u00f3xima d\u00e9cada.<\/p>\n<p>El nuevo administrador de la NASA, Jared Isaacman, tom\u00f3 la decisi\u00f3n la semana pasada de traer de regreso a la tripulaci\u00f3n de cuatro personas cuando la agencia cancel\u00f3 una caminata espacial programada para el 8 de enero, que iba a ser realizada por los astronautas estadounidenses Mike Fincke y Zena Cardman.<\/p>\n<p>\u201cDurante m\u00e1s de 60 a\u00f1os, la NASA ha establecido el est\u00e1ndar de seguridad en los vuelos espaciales tripulados\u201d, dijo Isaacman durante una conferencia de prensa la semana pasada. \u201cEn estas iniciativas, incluidos los 25 a\u00f1os de presencia humana continua a bordo de la Estaci\u00f3n Espacial Internacional, la salud y el bienestar de nuestros astronautas son y ser\u00e1n siempre nuestra m\u00e1xima prioridad\u201d.<\/p>\n<p>Fincke y Cardman, junto con el astronauta Kimiya Yui de la Agencia Japonesa de Exploraci\u00f3n Aeroespacial (JAXA) y el cosmonauta de Roscosmos Oleg Platonov, forman parte de la misi\u00f3n Crew-11 que abandona la estaci\u00f3n espacial. <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/ciencia\/regreso-astronautas-nasa-crew11-trax\">La NASA no especific\u00f3 qu\u00e9 miembro de la tripulaci\u00f3n presenta el problema de salud<\/a>, ni proporcion\u00f3 detalles sobre la naturaleza de la afecci\u00f3n, citando motivos de privacidad. Sin embargo, la NASA ha dicho que el astronauta afectado se encuentra en condici\u00f3n estable.<\/p>\n<p>\u201cTodos a bordo est\u00e1n estables, seguros y bien atendidos\u201d, confirm\u00f3 Fincke en un comunicado publicado en <a href=\"https:\/\/www.linkedin.com\/feed\/update\/urn:li:activity:7416022070469378048\/\">LinkedIn<\/a>. \u201cEsta fue una decisi\u00f3n deliberada para permitir que se realizaran las evaluaciones m\u00e9dicas adecuadas en tierra, donde se dispone de toda la capacidad de diagn\u00f3stico. Es la decisi\u00f3n correcta, aunque sea un poco agridulce\u201d.<\/p>\n<p>Est\u00e1 previsto que la tripulaci\u00f3n de la misi\u00f3n Crew-11 americe en el oc\u00e9ano Pac\u00edfico a bordo de la c\u00e1psula Crew Dragon alrededor de las 3:40 a.m. (hora de Miami) del jueves.<\/p>\n<p>Mientras tanto, la NASA trabaja para acelerar el lanzamiento de una tripulaci\u00f3n de reemplazo, denominada Crew-12, que originalmente estaba programada para mediados de febrero.<\/p>\n<p>La estaci\u00f3n espacial no hab\u00eda tenido una tripulaci\u00f3n tan peque\u00f1a a bordo en a\u00f1os. Sin embargo, durante una conferencia de prensa la semana pasada, Amit Kshatriya, administrador asociado de la NASA, se\u00f1al\u00f3 que no es algo sin precedentes.<\/p>\n<p>Antes de que SpaceX comenzara a operar regularmente su c\u00e1psula Crew Dragon en misiones de rotaci\u00f3n de personal a la estaci\u00f3n espacial en 2020, la NASA tuvo que comprar asientos en la c\u00e1psula Soyuz rusa para los viajes a la estaci\u00f3n durante casi una d\u00e9cada, despu\u00e9s de que el transbordador espacial fuera retirado en 2011.<\/p>\n<p>\u201cLa tripulaci\u00f3n a bordo, tanto rusa como estadounidense, est\u00e1 bien entrenada para operar en el entorno en el que se encuentra y puede operar los sistemas y la investigaci\u00f3n de forma normal, seg\u00fan lo previsto, hasta que lleguen sus compa\u00f1eros\u201d, dijo Kshatriya, utilizando el t\u00e9rmino de vuelos espaciales \u201cnominal\u201d para referirse a las operaciones normales.<\/p>\n<p>Aun as\u00ed, es probable que los miembros restantes de la tripulaci\u00f3n tengan que dejar algunas tareas sin atender. Por ejemplo, Kshatriya reconoci\u00f3 que el tr\u00edo no podr\u00e1 realizar la caminata espacial que Fincke y Cardman ten\u00edan previsto realizar.<\/p>\n<p>El d\u00fao estadounidense ten\u00eda la tarea de salir de la estaci\u00f3n espacial para preparar su exterior para la instalaci\u00f3n de nuevos paneles solares, que proporcionan energ\u00eda a la estaci\u00f3n.<\/p>\n<p>No se espera que los retrasos en la instalaci\u00f3n de los paneles solares causen problemas urgentes, ya que el nuevo equipo estaba destinado a proporcionar a la estaci\u00f3n espacial un aumento de energ\u00eda para la expansi\u00f3n de las actividades a bordo, dijo Kshatriya.<\/p>\n<p>Tal como est\u00e1n las cosas, el puesto de avanzada no necesita energ\u00eda adicional para las operaciones b\u00e1sicas, y hay \u201cmucho margen\u201d, se\u00f1al\u00f3 Kshatriya.<\/p>\n<p>Sin embargo, intentar mantener la estaci\u00f3n espacial con solo tres tripulantes a bordo presenta desaf\u00edos y riesgos, seg\u00fan Garret Reisman, exastronauta de la NASA que form\u00f3 parte de una tripulaci\u00f3n de tres personas junto con dos rusos en el puesto orbital hace m\u00e1s de una d\u00e9cada.<\/p>\n<p>\u201cSi tuviera que se\u00f1alar algo que aumenta significativamente el riesgo, ser\u00eda si algo se averiara en el exterior\u201d, dijo Reisman a CNN en una entrevista telef\u00f3nica el martes.<\/p>\n<p>Por ejemplo, si surgiera un problema en el exterior del lado estadounidense de la estaci\u00f3n espacial, como la aver\u00eda repentina de una unidad de conmutaci\u00f3n el\u00e9ctrica, Williams no podr\u00eda realizar una caminata espacial para solucionar el problema por s\u00ed solo.<\/p>\n<p>Probablemente, uno de sus colegas rusos tendr\u00eda que usar un traje estadounidense e intentar ayudarlo en dicha excursi\u00f3n, posiblemente con poca capacitaci\u00f3n.<\/p>\n<p>Este escenario de emergencia es muy improbable, se\u00f1al\u00f3 Reisman, pero destaca por qu\u00e9 a la NASA no le gusta que la tripulaci\u00f3n de la EEI regrese a casa hasta que ya haya una tripulaci\u00f3n de reemplazo en su lugar.<\/p>\n<p>La agencia estadounidense ha indicado desde hace tiempo que quiere evitar que la estaci\u00f3n espacial se quede con poco personal por diversas razones.<\/p>\n<p>Isaacman, multimillonario y astronauta privado, ha se\u00f1alado que considera que la investigaci\u00f3n innovadora en el laboratorio orbital es una prioridad urgente. Este trabajo, seg\u00fan Isaacman, puede ayudar a allanar el camino para nuevas estaciones espaciales comerciales que puedan reemplazar a la actual.<\/p>\n<p>\u201cYo, como muchos entusiastas del espacio, sue\u00f1o con el d\u00eda en que tengamos m\u00faltiples estaciones espaciales comerciales en la \u00f3rbita terrestre baja\u201d, dijo Isaacman durante una audiencia de confirmaci\u00f3n en diciembre. \u201cPero creo que para que sea un modelo financieramente viable, tenemos que maximizar absolutamente la vida \u00fatil restante de la Estaci\u00f3n Espacial Internacional: obtener la mayor cantidad posible de ciencia e investigaci\u00f3n en el espacio\u201d.<\/p>\n<p>La NASA ha esperado durante mucho tiempo que las empresas del sector privado construyan estaciones espaciales en la \u00f3rbita terrestre baja para que la agencia espacial pueda enfocarse en sus esfuerzos de exploraci\u00f3n en las profundidades del sistema solar.<\/p>\n<p>La NASA afirma que una presencia robusta de la tripulaci\u00f3n es crucial para obtener el m\u00e1ximo valor y productividad a bordo del laboratorio orbital, cuyo funcionamiento cuesta alrededor de US$ 3.000 millones al a\u00f1o. La agencia federal se ha esforzado mucho en a\u00f1os anteriores para garantizar que la estaci\u00f3n espacial cuente con al menos siete astronautas a bordo en todo momento.<\/p>\n<p>Por ejemplo, en 2024, dos astronautas de la NASA ten\u00edan previsto pasar solo una semana en la estaci\u00f3n espacial. Pero cuando la NASA descubri\u00f3 que su c\u00e1psula presentaba un fallo y no ser\u00eda segura para el viaje de regreso, la agencia espacial opt\u00f3 por dejar a los dos astronautas \u2014Butch Wilmore y Suni Williams\u2014 en la estaci\u00f3n durante nueve meses para mantener el n\u00famero de tripulantes.<\/p>\n<p>\u201cOperar la EEI es una tarea complicada y lo ha sido durante los \u00faltimos 25 a\u00f1os\u201d, dijo Kshatriya durante la conferencia de prensa de la semana pasada. \u201cLo que recordamos a diario es la naturaleza implacable de los vuelos espaciales tripulados\u201d.<\/p>\n<p>En cuanto a Chris Williams, es posible que pase un tiempo m\u00e1s solitario al tener toda la secci\u00f3n estadounidense de la estaci\u00f3n espacial para \u00e9l solo.<\/p>\n<p>\u201cEs bueno tener a otro estadounidense, pero Chris pas\u00f3 mucho tiempo con sus compa\u00f1eros de tripulaci\u00f3n rusos durante el entrenamiento, y estoy seguro de que tienen una buena relaci\u00f3n\u201d, dijo Reisman.<\/p>\n<p>Las relaciones entre Estados Unidos y Rusia se han vuelto notablemente m\u00e1s tensas en la d\u00e9cada transcurrida desde que Reisman pas\u00f3 meses solo con sus compa\u00f1eros de tripulaci\u00f3n rusos, se\u00f1al\u00f3.<\/p>\n<p>\u201cPero, en general, est\u00e1n ignorando la situaci\u00f3n geopol\u00edtica. Es como la cena de Acci\u00f3n de Gracias: simplemente no se habla de pol\u00edtica ni de religi\u00f3n\u201d, dijo Reisman riendo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro astronautas est\u00e1n a punto de abandonar la Estaci\u00f3n Espacial Internacional (EEI) debido a un problema de salud, y su partida anticipada, sin precedentes, dejar\u00e1 una tripulaci\u00f3n m\u00ednima a cargo del puesto orbital. Cuando la tripulaci\u00f3n aborde la c\u00e1psula SpaceX que los llevar\u00e1 de regreso a la Tierra, solo tres personas permanecer\u00e1n en el laboratorio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470077","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuatro astronautas est\u00e1n a punto de abandonar la Estaci\u00f3n Espacial Internacional (EEI) debido a un problema de salud, y su partida anticipada, sin precedentes, dejar\u00e1 una tripulaci\u00f3n m\u00ednima a cargo del puesto orbital. Cuando la tripulaci\u00f3n aborde la c\u00e1psula SpaceX que los llevar\u00e1 de regreso a la Tierra, solo tres personas permanecer\u00e1n en el laboratorio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-14T18:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo\",\"datePublished\":\"2026-01-14T18:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/\"},\"wordCount\":1550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/\",\"name\":\"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-14T18:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo - Noticias","og_description":"Cuatro astronautas est\u00e1n a punto de abandonar la Estaci\u00f3n Espacial Internacional (EEI) debido a un problema de salud, y su partida anticipada, sin precedentes, dejar\u00e1 una tripulaci\u00f3n m\u00ednima a cargo del puesto orbital. Cuando la tripulaci\u00f3n aborde la c\u00e1psula SpaceX que los llevar\u00e1 de regreso a la Tierra, solo tres personas permanecer\u00e1n en el laboratorio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-14T18:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/"},"author":{"name":"","@id":""},"headline":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo","datePublished":"2026-01-14T18:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/"},"wordCount":1550,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","name":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-14T18:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-14T18:03:40Z","datePublished":"2026-01-14T18:03:40Z","dateModified":"2026-01-14T18:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cuatro astronautas abandonar\\u00e1n la Estaci\\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/14\\\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/14\\\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-14T18:03:40Z\",\"datePublished\":\"2026-01-14T18:03:40Z\",\"dateModified\":\"2026-01-14T18:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470104,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/15\/astronautas-regresan-tierra-problema-medico-trax\/","url_meta":{"origin":1470077,"position":0},"title":"Cuatro astronautas regresan a la Tierra por un problema m\u00e9dico que los oblig\u00f3 a salir de la Estaci\u00f3n Espacial Internacional","author":"","date":"enero 15, 2026","format":false,"excerpt":"Cuatro astronautas a bordo de una c\u00e1psula SpaceX Crew Dragon aterrizaron la madrugada del jueves en el oc\u00e9ano Pac\u00edfico, poniendo fin a un esfuerzo de una semana para llevar a casa a un miembro de la tripulaci\u00f3n an\u00f3nimo para evaluar un problema m\u00e9dico.La tripulaci\u00f3n abandon\u00f3 la Estaci\u00f3n Espacial Internacional a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459947,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/14\/spacex-crew-10-butch-wilmore-suni-williams-nasa-regreso-trax\/","url_meta":{"origin":1470077,"position":1},"title":"El lanzamiento de SpaceX Crew-10 allanar\u00e1 el camino para que Butch Wilmore y Suni Williams de la NASA regresen a casa","author":"","date":"marzo 14, 2025","format":false,"excerpt":"SpaceX est\u00e1 una vez m\u00e1s en camino de intentar lanzar una tripulaci\u00f3n de astronautas en una misi\u00f3n para relevar a Sunni Williams y Butch Wilmore de la NASA, permiti\u00e9ndoles regresar a casa desde la Estaci\u00f3n Espacial Internacional despu\u00e9s de un viaje de varios d\u00edas que se convirti\u00f3 en un viaje\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471186,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/13\/spacex-nasa-envio-astronautas-estacion-espacial-trax\/","url_meta":{"origin":1470077,"position":2},"title":"SpaceX y NASA preparan env\u00edo de astronautas a la Estaci\u00f3n Espacial Internacional y reforzar su tripulaci\u00f3n de tres personas","author":"","date":"febrero 13, 2026","format":false,"excerpt":"Una c\u00e1psula de SpaceX pronto transportar\u00e1 a cuatro astronautas a la Estaci\u00f3n Espacial Internacional, lo que permitir\u00e1 que el laboratorio en \u00f3rbita vuelva a contar con su personal completo despu\u00e9s de un mes de operar con una tripulaci\u00f3n m\u00ednima.La misi\u00f3n, denominada Crew-12, despegar\u00e1 no antes de las 5:15 a.m., hora\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459987,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/16\/spacex-wilmore-williams-nasa-regresen-trax\/","url_meta":{"origin":1470077,"position":3},"title":"Crew-10 de SpaceX llega a la ISS, allanando el camino para que Wilmore y Williams de la NASA regresen a casa","author":"","date":"marzo 16, 2025","format":false,"excerpt":"Una tripulaci\u00f3n de astronautas de la NASA arrib\u00f3 a la Estaci\u00f3n Espacial Internacional para reemplazar a Suni Williams y Butch Wilmore, permiti\u00e9ndole al d\u00fao regresar a casa despu\u00e9s de un viaje de varios d\u00edas que se convirti\u00f3 en nueve meses pol\u00edticamente cargados.La misi\u00f3n Crew-10, parte de una rotaci\u00f3n rutinaria de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460092,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/18\/suni-williams-butch-wilmore-astronautas-nasa-regresan-tierra-trax\/","url_meta":{"origin":1470077,"position":4},"title":"Suni Williams y Butch Wilmore, los astronautas &#171;varados&#187; en el espacio, regresan a la Tierra","author":"","date":"marzo 18, 2025","format":false,"excerpt":"Suni Williams y Butch Wilmore, de la NASA, quienes acapararon la atenci\u00f3n internacional cuando su breve estancia prevista en el espacio se prolong\u00f3 hasta convertirse en una misi\u00f3n pol\u00edticamente conflictiva de m\u00e1s de nueve meses, finalmente est\u00e1n en casa.Williams y Wilmore, junto con Nick Hague, de la NASA, y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453167,"url":"https:\/\/noticiasya.com\/nacional\/2024\/09\/28\/spacex-lanzamiento-starliner-crew-9-astronautas-trax\/","url_meta":{"origin":1470077,"position":5},"title":"SpaceX se dispone a lanzar una misi\u00f3n para devolver a los astronautas del Starliner, retrasada desde hace tiempo","author":"","date":"septiembre 28, 2024","format":false,"excerpt":"(CNN) -- Una misi\u00f3n de SpaceX que despegar\u00e1 este s\u00e1bado pretende reunir a los astronautas del Boeing Starliner con la nave espacial que los traer\u00e1 de vuelta a casa. Suni Williams y Butch Wilmore, de la NASA, llevan ya en la Estaci\u00f3n Espacial Internacional m\u00e1s de 100 d\u00edas m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1470077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1470077"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1470077\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1470077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1470077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1470077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}