{"id":1470078,"date":"2026-01-14T10:03:40","date_gmt":"2026-01-14T18:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/"},"modified":"2026-01-14T10:03:40","modified_gmt":"2026-01-14T18:03:40","slug":"china-superavit-comercial-america-latina-importaciones-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/","title":{"rendered":"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones"},"content":{"rendered":"<p>El r\u00e9cord alcanzado por China en su <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/14\/economia\/china-alcanza-superavit-comercial-record-trax\">super\u00e1vit comercial<\/a> de 2025, que dio un salto de 20 % con respecto a 2024, tuvo un importante impulso de Am\u00e9rica Latina, con compras al gigante asi\u00e1tico que aumentaron en el \u00faltimo a\u00f1o en medio de las tensiones con Estados Unidos por los aranceles instaurados por el presidente Donald Trump.<\/p>\n<p>Las exportaciones de China a los pa\u00edses de la regi\u00f3n crecieron 9,3 % entre enero y noviembre de 2025, en comparaci\u00f3n el mismo per\u00edodo de 2024, y alcanzaron los US$ 271.680 millones, seg\u00fan <a href=\"http:\/\/english.customs.gov.cn\/Statics\/26eb5b5d-1d18-4181-ac02-a7585e93424a.html\">datos<\/a> de la Administraci\u00f3n General de Aduanas de China.<\/p>\n<p>M\u00e9xico, el principal destino de las exportaciones chinas en Am\u00e9rica Latina, mostr\u00f3 un crecimiento moderado. Los \u00faltimos datos disponibles del Banco de M\u00e9xico muestran que entre enero y octubre de 2025 el pa\u00eds adquiri\u00f3 bienes por un total de US$ 109.394 millones, un crecimiento de 1,4 % sobre dichos meses del a\u00f1o previo.<\/p>\n<p>El comercio entre estos dos pa\u00edses se ver\u00e1 afectado en 2026 por los <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/11\/mexico\/mexico-aranceles-china-asia-eeuu-ap\">aranceles que aprob\u00f3<\/a> M\u00e9xico para m\u00e1s de 1.400 productos de China y otras naciones con las que no tiene un acuerdo de libre comercio.<\/p>\n<p>El panorama no fue el mismo en Brasil, que arroj\u00f3 una ca\u00edda de 2 % entre enero y noviembre, seg\u00fan <a href=\"http:\/\/english.customs.gov.cn\/Statics\/26eb5b5d-1d18-4181-ac02-a7585e93424a.html\">datos<\/a> de la Aduana china. Se trata de dos socios en el bloque BRICS que anunciaron a mediados de 2025, en medio de una crisis diplom\u00e1tica entre Brasilia y Washington, que profundizar\u00edan sus lazos.<\/p>\n<p>El alza fue notoria en el caso de Chile, que en 2025 import\u00f3 bienes por US$ 26.435, casi un 25 % m\u00e1s que en 2024, seg\u00fan el <a href=\"https:\/\/www.bcentral.cl\/web\/banco-central\/areas\/estadisticas\/comercio-exterior-de-bienes\/monitor-comercio-exterior\">reporte<\/a> del Banco Central chileno.<\/p>\n<p>Por su parte, Argentina fue un verdadero trampol\u00edn para el super\u00e1vit chino. Entre enero y noviembre, el pa\u00eds sudamericano compr\u00f3 bienes a China por US$ 16.432 millones, un aumento interanual del 57,1 %, seg\u00fan el Instituto Nacional de Estad\u00edstica y Censos (<a href=\"https:\/\/www.indec.gob.ar\/uploads\/informesdeprensa\/ica_12_25FDC51E164D.pdf\">Indec<\/a>). El mayor incremento porcentual estuvo en el rubro de veh\u00edculos automotores, con un 337 %.<\/p>\n<p>Per\u00fa, donde el presidente Xi Jinping inaugur\u00f3 a finales de 2024 un <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/14\/dina-boluarte-xi-hinping-inauguran-megapuerto-chancay-peru-orix\">megapuerto<\/a> con mayor\u00eda de capitales chinos, tambi\u00e9n mostr\u00f3 un aumento sustancial. Entre enero y noviembre de 2025, las importaciones chinas llegaron hasta los US$ 14.900 millones, un salto de 21 % sobre el mismo per\u00edodo del a\u00f1o anterior, seg\u00fan <a href=\"https:\/\/www.gob.pe\/institucion\/inei\/colecciones\/6049-exportaciones-e-importaciones\">report\u00f3<\/a> el Instituto Nacional de Estad\u00edstica e Inform\u00e1tica peruano.<\/p>\n<p>\u201cChina responde con su fortaleza\u201d a los aranceles de EE.UU., dijo a CNN el economista Hern\u00e1n Letcher, director del Centro de Econom\u00eda Pol\u00edtica Argentina. Para el analista, Washington intent\u00f3 con esa pol\u00edtica resolver el desbalance comercial, pero China \u201cha sido eficiente en su estrategia de construirse como el pa\u00eds hegem\u00f3nico, sustentado no desde lo militar\u201d.<\/p>\n<p>\u201cEl caso de Argentina es llamativo. El Gobierno (del presidente Javier Milei) se comprometi\u00f3 y hace eco del pedido recurrente de (el secretario del Tesoro, Scott) Bessent y Trump, en lo discursivo, de desplazar a China. Pero la verdad es que el proceso es inverso\u201d, coment\u00f3.<\/p>\n<p>En cambio, el Gobierno de Lula da Silva, cercano a Xi, arroj\u00f3 un retroceso en sus compras. Para Letcher, el dinamismo de las importaciones \u201cest\u00e1 m\u00e1s relacionado con el desarrollo de la propia actividad que otra cosa\u201d, y con los acuerdos que se puedan implementar. \u201cTal vez no es tanto en clave geopol\u00edtica: si la econom\u00eda crece, se espera m\u00e1s importaciones, de lo contrario, no\u201d, apunt\u00f3.<\/p>\n<p>En sus perspectivas para 2026, el analista dice que \u201cla pregunta del mill\u00f3n\u201d es c\u00f3mo va a actuar Estados Unidos, que se ha mostrado m\u00e1s asertivo en la regi\u00f3n y busca contener la presencia de Beijing. \u201cImagino que China va a intentar sostener lo que ha sucedido en el transcurso del a\u00f1o pasado: mantener el incremento constante de sus exportaciones. Va a tratar de ganar tiempo sin entrar en conflicto, porque su negocio es imponerse en temas comerciales. Deber\u00eda haber una reacci\u00f3n de EE.UU. en ese aspecto, va a intentar truncarlo, hay que mirarlo de cerca\u201d, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El r\u00e9cord alcanzado por China en su super\u00e1vit comercial de 2025, que dio un salto de 20 % con respecto a 2024, tuvo un importante impulso de Am\u00e9rica Latina, con compras al gigante asi\u00e1tico que aumentaron en el \u00faltimo a\u00f1o en medio de las tensiones con Estados Unidos por los aranceles instaurados por el presidente [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470078","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"El r\u00e9cord alcanzado por China en su super\u00e1vit comercial de 2025, que dio un salto de 20 % con respecto a 2024, tuvo un importante impulso de Am\u00e9rica Latina, con compras al gigante asi\u00e1tico que aumentaron en el \u00faltimo a\u00f1o en medio de las tensiones con Estados Unidos por los aranceles instaurados por el presidente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-14T18:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones\",\"datePublished\":\"2026-01-14T18:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/\"},\"wordCount\":715,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/\",\"name\":\"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-14T18:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/","og_locale":"es_ES","og_type":"article","og_title":"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones - Noticias","og_description":"El r\u00e9cord alcanzado por China en su super\u00e1vit comercial de 2025, que dio un salto de 20 % con respecto a 2024, tuvo un importante impulso de Am\u00e9rica Latina, con compras al gigante asi\u00e1tico que aumentaron en el \u00faltimo a\u00f1o en medio de las tensiones con Estados Unidos por los aranceles instaurados por el presidente [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-14T18:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/"},"author":{"name":"","@id":""},"headline":"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones","datePublished":"2026-01-14T18:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/"},"wordCount":715,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/","name":"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-14T18:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"China aument\u00f3 su super\u00e1vit comercial a niveles nunca registrados: estos pa\u00edses de Am\u00e9rica Latina subieron sus importaciones","url":"http:\/\/noticiasya.com\/nacional\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/01\/14\/china-superavit-comercial-america-latina-importaciones-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-14T18:03:40Z","datePublished":"2026-01-14T18:03:40Z","dateModified":"2026-01-14T18:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"China aument\\u00f3 su super\\u00e1vit comercial a niveles nunca registrados: estos pa\\u00edses de Am\\u00e9rica Latina subieron sus importaciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/14\\\/china-superavit-comercial-america-latina-importaciones-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/01\\\/14\\\/china-superavit-comercial-america-latina-importaciones-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-14T18:03:40Z\",\"datePublished\":\"2026-01-14T18:03:40Z\",\"dateModified\":\"2026-01-14T18:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470060,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/14\/china-alcanza-superavit-comercial-record-trax\/","url_meta":{"origin":1470078,"position":0},"title":"China alcanza un super\u00e1vit comercial r\u00e9cord de US$ 1,2 billones en 2025, un 20 % m\u00e1s pese a los aranceles de Trump","author":"","date":"enero 14, 2026","format":false,"excerpt":"China registr\u00f3 el mayor super\u00e1vit comercial de su historia en 2025, un salto del 20 % respecto de 2024, culminando un a\u00f1o en el que la f\u00e1brica m\u00e1s grande del mundo desafi\u00f3 la presi\u00f3n comercial de EE.UU. e increment\u00f3 las exportaciones a otros mercados mundiales.En conjunto, el comercio exterior de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471960,"url":"https:\/\/noticiasya.com\/nacional\/2026\/03\/06\/trump-reune-aliados-latinoamerica-miami-derecha-orix\/","url_meta":{"origin":1470078,"position":1},"title":"Trump reunir\u00e1 a sus aliados latinoamericanos en Miami en una &#171;coalici\u00f3n hist\u00f3rica&#187; de gobiernos de derecha","author":"","date":"marzo 6, 2026","format":false,"excerpt":"Trump recibir\u00e1 este s\u00e1bado en Florida a los l\u00edderes de m\u00e1s de una decena de pa\u00edses de Am\u00e9rica Latina, un encuentro que la Casa Blanca llam\u00f3 \u201cShield of the Americas Summit\u201d (Cumbre del Escudo de las Am\u00e9ricas). La convocatoria del presidente de Estados Unidos fue dirigida exclusivamente a los mandatarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456668,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/16\/china-america-latina-historia-comercio-inversiones-orix\/","url_meta":{"origin":1470078,"position":2},"title":"China y Am\u00e9rica Latina: una historia de comercio, inversiones y suspicacias","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"Pas\u00f3 r\u00e1pido y a la sombra de grandes acontecimientos en Ucrania, Gaza y el L\u00edbano: a mediados de noviembre la presidenta de Per\u00fa, Dina Boluarte, y el presidente de China, Xi Jinping, inauguraron en Chancay un gigantesco puerto sobre el oc\u00e9ano Pac\u00edfico, dise\u00f1ado \u2013seg\u00fan ambos Gobiernos\u2013 para potenciar el intercambio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462247,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/12\/petro-china-ruta-seda-colombia-orix\/","url_meta":{"origin":1470078,"position":3},"title":"Gustavo Petro en China: &#171;Vamos a firmar la Ruta de la Seda&#187;","author":"","date":"mayo 12, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, lleg\u00f3 este lunes a Beijing para asistir a la IV Reuni\u00f3n Ministerial del Foro China-Comunidad de Estados Latinoamericanos y Caribe\u00f1os, Celac, y desde all\u00ed anunci\u00f3 que firmar\u00e1n la adhesi\u00f3n a la Ruta de la Seda.\u201cVamos a firmar la Ruta de la Seda. Tanto Am\u00e9rica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468533,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/20\/china-socio-comercial-argentina-eeuu-orix\/","url_meta":{"origin":1470078,"position":4},"title":"Pese a la presi\u00f3n de EE.UU. sobre Milei, China sobrepasa a Brasil como principal socio comercial de Argentina","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Corr\u00edan las horas m\u00e1s febriles del gobierno del presidente de Argentina, Javier Milei. Estados Unidos acababa de anunciar un plan de rescate financiero, en medio de una presi\u00f3n sobre el valor del d\u00f3lar que no encontraba sosiego. Se acercaban las elecciones de mitad de mandato del 26 de octubre, tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468369,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/14\/china-poderio-comercial-aranceles-eeuu-trax\/","url_meta":{"origin":1470078,"position":5},"title":"China utiliz\u00f3 su poder\u00edo comercial para resistir los aranceles de EE.UU. \u00bfPodr\u00e1 mantener su ventaja?","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"A principios de este a\u00f1o, cuando los aranceles de EE.UU. a las importaciones chinas fueron aumentando cada vez m\u00e1s, Derek Wang se prepar\u00f3 para una importante perturbaci\u00f3n.Ante la paralizaci\u00f3n de los pedidos estadounidenses, Wang, de 36 a\u00f1os, que vende utensilios de cocina inteligentes desde la provincia de Guangdong, en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1470078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1470078"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1470078\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1470078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1470078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1470078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}