{"id":1473234,"date":"2026-04-16T07:03:49","date_gmt":"2026-04-16T14:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/"},"modified":"2026-04-16T07:03:49","modified_gmt":"2026-04-16T14:03:49","slug":"sheinbaum-fracking-4t-mexico-analisis-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/","title":{"rendered":"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T?"},"content":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, enfrenta un inesperado debate al interior de su movimiento: mantener los postulados econ\u00f3micos de la llamada Cuarta Transformaci\u00f3n, que fund\u00f3 su antecesor Andr\u00e9s Manuel L\u00f3pez Obrador, o trazar un camino pragm\u00e1tico que ayude a solucionar la estrechez presupuestal de su Gobierno -tambi\u00e9n heredada de la administraci\u00f3n anterior- y la dependencia energ\u00e9tica con Estados Unidos, que se ha complicado con el actual contexto de guerra en el Oriente Medio y sus repercusiones econ\u00f3micas globales. Hoy, el 75 por ciento del gas licuado que consume M\u00e9xico y 50 por ciento de las gasolinas lo importa de EE.UU.<\/p>\n<p>Son pol\u00edticas de cambio que la presidenta ha delineado y que comienzan a generar fricci\u00f3n entre los distintos grupos de izquierda del movimiento. Los m\u00e1s radicales no han dudado en se\u00f1alar una \u201ctraici\u00f3n\u201d a los principios rectores de la izquierda mexicana. Ven en esas propuestas una amenaza contra la \u201csoberan\u00eda nacional\u201d que, seg\u00fan estos basamentos, radica en el sector energ\u00e9tico y en otros temas que se han considerado intocables a lo largo del siglo XX y lo que va del XXI.  En s\u00edntesis, las propuestas de Sheinbaum son consideradas un retorno al \u201cneoliberalismo\u201d que, se supone, hab\u00eda sido desterrado.<\/p>\n<p>El pasado domingo 12 de abril, de gira de trabajo por el estado de Tlaxcala, en el centro de M\u00e9xico, la presidenta dijo que \u201cel Estado no puede hacerlo todo, requiere necesariamente de la coordinaci\u00f3n con la iniciativa privada y por eso buscamos un modelo integral donde el pueblo viva mejor y al mismo tiempo haya m\u00e1s inversiones para genera mejores empleos, con mejores salarios\u201d.<\/p>\n<p>Sheinbaum se refer\u00eda a su proyecto de 15 \u201cpolos de desarrollo\u201d, uno de los cuales se instalar\u00e1 precisamente en Tlaxcala, con el objetivo de generar parques industriales para atraer a empresas nacionales e internacionales, con facilidades fiscales e infraestructura y as\u00ed generar empleo y riqueza para esas regiones. El Estado mexicano se compromete a establecer las condiciones necesarias para que la inversi\u00f3n llegue y las empresas, a echar ra\u00edces y generar empleo, con proyectos que pueden ir desde el sector automotriz hasta el agr\u00edcola.<\/p>\n<p>Se trata de una postura que parecer\u00eda normal para cualquier pa\u00eds, pero que hoy en M\u00e9xico rompe con lo que se ha planteado en los \u00faltimos siete a\u00f1os, en los que ha habido un alejamiento radical entre gobierno y sectores empresariales que son vistos, al menos hasta hace poco, como enemigos del pueblo. Esta postura llev\u00f3 a que los grandes proyectos de infraestructura del pa\u00eds, en \u00e1reas tan amplias como la construcci\u00f3n de aeropuertos, puertos mar\u00edtimos, aduanas, carreteras, trenes, refiner\u00edas e incluso hoteles, fueran delegados a las Fuerzas Armadas, algunos a la Marina Armada y otros al Ej\u00e9rcito.<\/p>\n<p>Otro componente de la estrategia y que genera m\u00e1s resistencias tiene que ver con el sector energ\u00e9tico: la mandataria propone abrir contratos a empresas privadas, nacionales y extranjeras, para la explotaci\u00f3n de yacimientos no convencionales, que por diversos motivos no han podido ponerse a producir y que representan una enorme riqueza enterrada en el subsuelo. Para ello Sheinbaum design\u00f3 un comit\u00e9 de especialistas para que analice todos los escenarios para acceder a esos recursos, incluida la t\u00e9cnica de fracking o fractura hidr\u00e1ulica de rocas, que permitir\u00eda explotar los yacimientos de gas de la Cuenca de Burgos, de los m\u00e1s ricos de todo el pa\u00eds.<\/p>\n<p>El problema es que el fracking cuenta con un enorme rechazo dentro de la Cuarta Transformaci\u00f3n y grupos ambientalistas. Este rechazo lleg\u00f3 incluso a ser un postulado del expresidente L\u00f3pez Obrador, quien lo prohibi\u00f3 en el pa\u00eds, aunque no de manera legal sino enunciativa.<\/p>\n<p>La presidenta argumenta que, si bien el fracking representaba una amenaza al medio ambiente por el uso intensivo de agua dulce que requer\u00eda, la tecnolog\u00eda ha avanzado enormemente y los riesgos ambientales han disminuido. Pero sus detractores argumentan que el fracking ha mejorado en cuanto a producci\u00f3n, pero no en cuanto a los da\u00f1os ambientales y que la famosa Cuenca de Burgos tiene una hist\u00f3rica problem\u00e1tica de acceso al agua que al final terminar\u00eda afectando a las comunidades de esta regi\u00f3n del norte de M\u00e9xico.<\/p>\n<p>En todo caso, Sheinbaum, como soluci\u00f3n, propone analizar el tema con especialistas y ver el costo beneficio para el pa\u00eds, es decir, intentar apartarse de la ideolog\u00eda para tener un acercamiento m\u00e1s t\u00e9cnico y cient\u00edfico al problema.<\/p>\n<p>Parece sencillo, pero ese ser\u00e1 un enorme reto para la presidenta porque el tema energ\u00e9tico est\u00e1 profundamente anclado en los conceptos doctrinarios de naci\u00f3n, patria, soberan\u00eda y libre determinaci\u00f3n que ha acu\u00f1ado la izquierda a lo largo de su historia. Y m\u00e1s complicado cuando esas cr\u00edticas de sectores de la izquierda y del propio movimiento, viene acompa\u00f1ada de movilizaci\u00f3n social y de acusaciones hacia la presidenta y parte de su equipo por haber sucumbido \u201ca los intereses de los grandes capitales\u201d.<\/p>\n<p>La disyuntiva para la presidenta viene de algo tan sencillo como analizar el presupuesto y de hacer un an\u00e1lisis del resultado, hasta el momento, de las pol\u00edticas por la Cuarta Transformaci\u00f3n. Simplemente no dan las cuentas entre mantener u aumentar las pol\u00edticas de apoyo social y el nivel de recaudaci\u00f3n que mantiene el pa\u00eds. Se ha apretado el cintur\u00f3n a los contribuyentes, pero ya no se puede m\u00e1s sin un crecimiento de la econom\u00eda. El contexto global marca un cambio de rumbo o a al menos una rectificaci\u00f3n. Me parece que eso es lo que busca la presidenta al acercarse al sector empresarial: compartir los costos de los grandes proyectos de infraestructura que necesita el pa\u00eds y compartir tambi\u00e9n los riesgos de esas inversiones multimillonarias.<\/p>\n<p>El modelo del Estado constructor y administrador de aeropuertos, hoteles, trenes y otras tantas cosas, fue demasiado costoso por su falta de pericia, por su opacidad y por su poco cuidado en los detalles y por la enorme corrupci\u00f3n que desat\u00f3, y que ha quedado exhibida en casos como la rede de robo y contrabando de combustible.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, enfrenta un inesperado debate al interior de su movimiento: mantener los postulados econ\u00f3micos de la llamada Cuarta Transformaci\u00f3n, que fund\u00f3 su antecesor Andr\u00e9s Manuel L\u00f3pez Obrador, o trazar un camino pragm\u00e1tico que ayude a solucionar la estrechez presupuestal de su Gobierno -tambi\u00e9n heredada de la administraci\u00f3n anterior- y la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473234","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T? - Noticias\" \/>\n<meta property=\"og:description\" content=\"La presidenta de M\u00e9xico, Claudia Sheinbaum, enfrenta un inesperado debate al interior de su movimiento: mantener los postulados econ\u00f3micos de la llamada Cuarta Transformaci\u00f3n, que fund\u00f3 su antecesor Andr\u00e9s Manuel L\u00f3pez Obrador, o trazar un camino pragm\u00e1tico que ayude a solucionar la estrechez presupuestal de su Gobierno -tambi\u00e9n heredada de la administraci\u00f3n anterior- y la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T14:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T?\",\"datePublished\":\"2026-04-16T14:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/\"},\"wordCount\":1089,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/\",\"name\":\"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-16T14:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T? - Noticias","og_description":"La presidenta de M\u00e9xico, Claudia Sheinbaum, enfrenta un inesperado debate al interior de su movimiento: mantener los postulados econ\u00f3micos de la llamada Cuarta Transformaci\u00f3n, que fund\u00f3 su antecesor Andr\u00e9s Manuel L\u00f3pez Obrador, o trazar un camino pragm\u00e1tico que ayude a solucionar la estrechez presupuestal de su Gobierno -tambi\u00e9n heredada de la administraci\u00f3n anterior- y la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-16T14:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/"},"author":{"name":"","@id":""},"headline":"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T?","datePublished":"2026-04-16T14:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/"},"wordCount":1089,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/","name":"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-16T14:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Sheinbaum ahora apuesta por el fracking y \u00bftraiciona a la 4T?","url":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/sheinbaum-fracking-4t-mexico-analisis-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-16T14:03:49Z","datePublished":"2026-04-16T14:03:49Z","dateModified":"2026-04-16T14:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Sheinbaum ahora apuesta por el fracking y \\u00bftraiciona a la 4T?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/sheinbaum-fracking-4t-mexico-analisis-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/sheinbaum-fracking-4t-mexico-analisis-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-16T14:03:49Z\",\"datePublished\":\"2026-04-16T14:03:49Z\",\"dateModified\":\"2026-04-16T14:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462684,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/22\/sheinbaum-negociaciones-ee-uu-remesas-orix\/","url_meta":{"origin":1473234,"position":0},"title":"Sheinbaum habla de las negociaciones con EE.UU. y sobre impuestos a las remesas","author":"","date":"mayo 22, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este jueves que tendr\u00e1 futuras llamadas con el presidente Donald Trump para \u201cseguir\u201d abordando el tema de los aranceles y el impuesto a las remesas.\u201cLa tasa del impuesto de las remesas tuvo una disminuci\u00f3n del cinco al 3,5 por ciento. De todas maneras,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470154,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/16\/mexico-eeuu-trump-sheinbaum-reclamo-analisis-orix\/","url_meta":{"origin":1473234,"position":1},"title":"\u00bfQu\u00e9 le pide realmente Trump a Sheinbaum cuando reclama \u2018m\u00e1s colaboraci\u00f3n\u2019? La respuesta implica riesgos para la presidenta","author":"","date":"enero 16, 2026","format":false,"excerpt":"Muchos nos hacemos hoy en M\u00e9xico una pregunta que genera acalorados debates: \u00bfordenar\u00e1 Trump ataques contra c\u00e1rteles de la droga en territorio mexicano?. La pregunta deja de ser una especulaci\u00f3n si tomamos en cuenta las constantes menciones directas del presidente de Estados Unidos, Donald Trump, sobre el tema. La m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471494,"url":"https:\/\/noticiasya.com\/nacional\/2026\/02\/20\/poder-sombra-sheinbaum-morena-orix\/","url_meta":{"origin":1473234,"position":2},"title":"El poder en la sombra: Sheinbaum y la lucha por el control de su presidencia y de Morena","author":"","date":"febrero 20, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, libra una lucha por el control de su propio mandato. Son muchos frentes de batalla al interior de su gobierno y su movimiento \u2014el de la autollamada \u201ccuarta transformaci\u00f3n\u201d\u2014, que van desde dominio territorial del partido Morena y los poderes f\u00e1cticos a las posiciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472769,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/01\/mexico-deja-atras-ee-uu-presidenta-mujer-meryl-streep-claudia-sheinbaum-orix\/","url_meta":{"origin":1473234,"position":3},"title":"Meryl Streep elogi\u00f3 a Sheinbaum y la presidenta de M\u00e9xico respondi\u00f3: &#171;Es la mejor actriz del mundo&#187;","author":"","date":"abril 1, 2026","format":false,"excerpt":"La actriz estadounidense Meryl Streep reconoci\u00f3 el rol de la presidenta de M\u00e9xico, Claudia Sheinbaum, y consider\u00f3 que el pa\u00eds \u201cha dejado atr\u00e1s\u201d a Estados Unidos al tener una presidenta mujer, la primera en m\u00e1s de 200 a\u00f1os de historia.\u201cClaro que M\u00e9xico ha dejado atr\u00e1s a los Estados Unidos teniendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449951,"url":"https:\/\/noticiasya.com\/nacional\/2024\/06\/03\/amlo-celebra-victoria-claudia-sheinbaum-orix\/","url_meta":{"origin":1473234,"position":4},"title":"L\u00f3pez Obrador celebra la victoria de Sheinbaum: &#171;El pueblo de M\u00e9xico decidi\u00f3 libre y democr\u00e1ticamente&#187;","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, celebr\u00f3 que la candidata oficialista Claudia Sheinbaum resultara ganadora de la Presidencia de M\u00e9xico en los resultados preliminares reportados este domingo por el Instituto Nacional Electoral (INE).\"Hoy es un d\u00eda de gloria porque el pueblo de M\u00e9xico decidi\u00f3 libre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469902,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/08\/mexico-sheinbaum-analisis-desafios-2026-trump-orix\/","url_meta":{"origin":1473234,"position":5},"title":"Desde el Mundial hasta la violencia y una econom\u00eda estancada, Sheinbaum enfrenta varios desaf\u00edos, todos atravesados por Trump","author":"","date":"enero 8, 2026","format":false,"excerpt":"El Mundial de F\u00fatbol y la revisi\u00f3n del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC) son dos acontecimientos que marcar\u00e1n la agenda de 2026 en M\u00e9xico. Ambos representan retos distintos, pero igualmente relevantes para el pa\u00eds y para la presidenta Claudia Sheinbaum en su segundo a\u00f1o de gobierno.Sin embargo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1473234"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473234\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1473234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1473234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1473234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}