{"id":1473236,"date":"2026-04-16T08:03:42","date_gmt":"2026-04-16T15:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/"},"modified":"2026-04-16T08:03:42","modified_gmt":"2026-04-16T15:03:42","slug":"justin-fairfax-esposa-suicidio-virginia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/","title":{"rendered":"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda"},"content":{"rendered":"<p>El ex vicegobernador de Virginia Justin Fairfax, cuyo mandato estuvo marcado por denuncias de agresi\u00f3n sexual, mat\u00f3 a tiros a su esposa, Cerina Fairfax, dentro de su casa y luego se suicid\u00f3, inform\u00f3 la polic\u00eda.<\/p>\n<p>Los dos hijos adolescentes de la pareja estaban dentro de la vivienda cuando ocurrieron los disparos, dijo Kevin Davis, jefe de la polic\u00eda del condado de Fairfax. Seg\u00fan explic\u00f3, uno de los hijos fue quien llam\u00f3 al 911.<\/p>\n<p>La polic\u00eda del condado de Fairfax acudi\u00f3 a la casa de la pareja en Annandale, Virginia, en la madrugada de este jueves. All\u00ed encontr\u00f3 muertos a un hombre y una mujer, informaron antes las autoridades. El mismo arma de fuego parece haber sido usada en ambos disparos, dijo Davis.<\/p>\n<p>El tiroteo se origin\u00f3 en medio de una disputa dom\u00e9stica relacionada con \u201clo que parece ser un divorcio complicado o conflictivo\u201d, dijo Davis. Seg\u00fan explic\u00f3, Fairfax hab\u00eda recibido recientemente documentos judiciales en los que se le notificaba la pr\u00f3xima audiencia del proceso de divorcio.<\/p>\n<p>Los detectives revisaron el caso con ayuda de \u201cmuchas c\u00e1maras\u201d instaladas dentro de la vivienda como parte del proceso de divorcio, dijo Davis. Tambi\u00e9n se\u00f1al\u00f3 que una llamada que hizo Justin Fairfax a la polic\u00eda en enero, en la que denunciaba una supuesta agresi\u00f3n por parte de su esposa, no pudo ser corroborada.<\/p>\n<p>\u201cEs muy tr\u00e1gico para los hijos perder a ambos padres, y a\u00fan m\u00e1s tr\u00e1gico que estuvieran dentro de la casa cuando ocurri\u00f3\u201d, dijo Davis. \u201cSin duda es un derrumbe estrepitoso para una familia relativamente conocida que aparentemente ten\u00eda muchas cosas a su favor\u201d.<\/p>\n<p>Los hijos est\u00e1n bajo el cuidado de sus abuelos y otros familiares, con apoyo de la divisi\u00f3n de servicios a v\u00edctimas del Departamento de Polic\u00eda del condado de Fairfax, dijo Davis.<\/p>\n<p>\u201cLa mitad de Estados Unidos probablemente pasa por un proceso de divorcio en alg\u00fan momento, y muy rara vez, afortunadamente, termina as\u00ed\u201d, dijo Davis. \u201cEs muy triste para esta comunidad\u2026 mucha gente que conoce a la familia Fairfax est\u00e1 en shock. Nosotros tambi\u00e9n\u201d.<\/p>\n<p>Fairfax, dem\u00f3crata, fue vicegobernador de Virginia durante la gesti\u00f3n del gobernador Ralph Northam entre 2018 y 2022. Tambi\u00e9n se postul\u00f3 a gobernador de Virginia en 2021. Despu\u00e9s de dejar el cargo, volvi\u00f3 a ejercer como abogado, mientras que su esposa trabajaba como dentista, seg\u00fan Davis.<\/p>\n<p>Fairfax enfrent\u00f3 llamados a renunciar tras las denuncias de agresi\u00f3n sexual en su contra en 2019.<\/p>\n<p>El banco Capital One present\u00f3 en octubre de 2024 una demanda civil por deudas contra Fairfax por un monto principal de US$ 5.922,58, seg\u00fan registros del Tribunal General de Distrito del condado de Fairfax. En mayo de 2025, Discover Bank present\u00f3 otra demanda por deudas contra Fairfax por US$ 23.871,31, seg\u00fan los registros.<\/p>\n<p>Ambos casos terminaron en fallos en rebeld\u00eda a favor de los bancos, seg\u00fan los registros. Un fallo en rebeld\u00eda ocurre cuando el demandado no responde a la citaci\u00f3n judicial o no comparece ante el tribunal.<\/p>\n<p>Glasser and Glasser, un bufete de abogados con sede en Norfolk que represent\u00f3 a los bancos en ambos casos, no respondi\u00f3 de inmediato a una solicitud de comentarios de CNN.<\/p>\n<p><em>Esta es una noticia en desarrollo y ser\u00e1 actualizada.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ex vicegobernador de Virginia Justin Fairfax, cuyo mandato estuvo marcado por denuncias de agresi\u00f3n sexual, mat\u00f3 a tiros a su esposa, Cerina Fairfax, dentro de su casa y luego se suicid\u00f3, inform\u00f3 la polic\u00eda. Los dos hijos adolescentes de la pareja estaban dentro de la vivienda cuando ocurrieron los disparos, dijo Kevin Davis, jefe [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473236","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ex vicegobernador de Virginia Justin Fairfax, cuyo mandato estuvo marcado por denuncias de agresi\u00f3n sexual, mat\u00f3 a tiros a su esposa, Cerina Fairfax, dentro de su casa y luego se suicid\u00f3, inform\u00f3 la polic\u00eda. Los dos hijos adolescentes de la pareja estaban dentro de la vivienda cuando ocurrieron los disparos, dijo Kevin Davis, jefe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T15:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda\",\"datePublished\":\"2026-04-16T15:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/\"},\"wordCount\":587,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/\",\"name\":\"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-16T15:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda - Noticias","og_description":"El ex vicegobernador de Virginia Justin Fairfax, cuyo mandato estuvo marcado por denuncias de agresi\u00f3n sexual, mat\u00f3 a tiros a su esposa, Cerina Fairfax, dentro de su casa y luego se suicid\u00f3, inform\u00f3 la polic\u00eda. Los dos hijos adolescentes de la pareja estaban dentro de la vivienda cuando ocurrieron los disparos, dijo Kevin Davis, jefe [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-16T15:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/"},"author":{"name":"","@id":""},"headline":"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda","datePublished":"2026-04-16T15:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/"},"wordCount":587,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/","name":"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-16T15:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ex vicegobernador de Virginia Justin Fairfax mat\u00f3 a su esposa y luego se suicid\u00f3, seg\u00fan la polic\u00eda","url":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/justin-fairfax-esposa-suicidio-virginia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-16T15:03:42Z","datePublished":"2026-04-16T15:03:42Z","dateModified":"2026-04-16T15:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ex vicegobernador de Virginia Justin Fairfax mat\\u00f3 a su esposa y luego se suicid\\u00f3, seg\\u00fan la polic\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/justin-fairfax-esposa-suicidio-virginia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/justin-fairfax-esposa-suicidio-virginia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-16T15:03:42Z\",\"datePublished\":\"2026-04-16T15:03:42Z\",\"dateModified\":\"2026-04-16T15:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462677,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/22\/seguridad-cia-disparo-mujer-frente-puertas-sede-agencia-trax\/","url_meta":{"origin":1473236,"position":0},"title":"La seguridad de la CIA le dispar\u00f3 a una mujer frente a las puertas de la sede de la agencia","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Agentes de seguridad de la CIA dispararon e hirieron a una mujer que se acerc\u00f3 a las puertas principales de la agencia en un autom\u00f3vil alrededor de las 4 a.m. hora de Miami del jueves, seg\u00fan una fuente policial y otra persona familiarizada con el asunto.Esa persona ahora est\u00e1 bajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452121,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/24\/cronologia-madre-desaparecida-virginia-esposo-acusado-matarla-trax\/","url_meta":{"origin":1473236,"position":1},"title":"Cronolog\u00eda de la investigaci\u00f3n sobre la madre desaparecida en Virginia cuyo esposo est\u00e1 acusado de matarla en su casa","author":"","date":"agosto 24, 2024","format":false,"excerpt":"Nota del editor: Esta historia incluye descripciones gr\u00e1ficas que algunos lectores pueden encontrar perturbadoras.(CNN) -- Naresh Bhatt dijo a los periodistas que estaba \"sufriendo\" mientras las autoridades buscaban a su esposa desaparecida en Virginia. Una semana despu\u00e9s, en la ma\u00f1ana de este viernes, sin embargo, se present\u00f3 ante un juez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464685,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/20\/inundaciones-rescates-acuaticos-virginia-maryland-trax\/","url_meta":{"origin":1473236,"position":2},"title":"Inundaciones repentinas obligan a realizar rescates en Virginia y Maryland","author":"","date":"julio 20, 2025","format":false,"excerpt":"Decenas de personas fueron rescatadas este s\u00e1bado por la noche debido a inundaciones repentinas producidas por fuertes lluvias que azotaran partes de Virginia, Maryland y la ciudad de Washington.Seg\u00fan el Departamento de Bomberos y Rescate del Condado de Fairfax, siete personas fueron rescatadas de veh\u00edculos que quedaron atrapados en aguas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462473,"url":"https:\/\/noticiasya.com\/nacional\/2025\/05\/17\/detienen-hombre-asesinar-esposa-desaparicion-filadelfia-trax\/","url_meta":{"origin":1473236,"position":3},"title":"Detienen a un hombre sospechoso de asesinar a su esposa ocho a\u00f1os despu\u00e9s de su desaparici\u00f3n en un barrio de Filadelfia","author":"","date":"mayo 17, 2025","format":false,"excerpt":"El polic\u00eda estatal de Pensilvania, David Brodeur, quer\u00eda ver la reacci\u00f3n de Allen Gould cuando los investigadores y detectives rodeaban su casa.\u201cTenemos \u00f3rdenes de registro para su residencia en relaci\u00f3n con el homicidio de su esposa\u201d, le dijo Brodeur a Gould en julio de 2017.La esposa de Gould, Anna Maciejewska,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469728,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/02\/buscan-responsable-del-asesinato-dentista-y-esposa-ohio-trax\/","url_meta":{"origin":1473236,"position":4},"title":"La Polic\u00eda busca al homicida que mat\u00f3 a un dentista y su esposa mientras estaban en casa con sus dos ni\u00f1os","author":"","date":"enero 2, 2026","format":false,"excerpt":"Un respetado dentista y su esposa fueron asesinados a tiros en su lujosa casa de Ohio mientras sus dos hijos peque\u00f1os estaban dentro, seg\u00fan informaron las autoridades, y el responsable sigue en libertad.Los cuerpos de Spencer Tepe, de 37 a\u00f1os, y su esposa, Monique Tepe, de 39, fueron encontrados el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461649,"url":"https:\/\/noticiasya.com\/nacional\/2025\/04\/25\/muere-virginia-giuffre-acusadora-principe-andres-trax\/","url_meta":{"origin":1473236,"position":5},"title":"Muere Virginia Giuffre, sobreviviente de abuso sexual de Jeffrey Epstein y acusadora del pr\u00edncipe Andr\u00e9s","author":"","date":"abril 25, 2025","format":false,"excerpt":"Virginia Giuffre, quien aleg\u00f3 que el pr\u00edncipe Andr\u00e9s de Gran Breta\u00f1a abus\u00f3 de ella cuando era adolescente, se suicid\u00f3, seg\u00fan inform\u00f3 su familia. Ten\u00eda 41 a\u00f1os.\u201cCon el coraz\u00f3n profundamente roto anunciamos que Virginia falleci\u00f3 anoche en su granja en Australia Occidental\u201d, se lee en un comunicado de la familia.La Polic\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1473236"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473236\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1473236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1473236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1473236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}