{"id":1473243,"date":"2026-04-16T10:03:47","date_gmt":"2026-04-16T17:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/"},"modified":"2026-04-16T10:03:47","modified_gmt":"2026-04-16T17:03:47","slug":"libano-destruccion-ataques-israel-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/","title":{"rendered":"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel"},"content":{"rendered":"<p>A las puertas del Hospital Universitario Rafik Hariri de Beirut, el costo humano de los ataques israel\u00edes contra el L\u00edbano, que han durado semanas, se reflejaba en los rostros de familias desesperadas que esperaban noticias de sus seres queridos. Las puertas de las ambulancias se abr\u00edan justo en la entrada en un intento de ocultar la escena. Y entonces r\u00e1pidamente se introduc\u00edan en el hospital, una tras otra, las bolsas para cad\u00e1veres.<\/p>\n<p>\u201cHay muchos m\u00e1rtires. Desafortunadamente, varios de ellos a\u00fan esperan ser identificados\u201d, declar\u00f3 a CNN el director del hospital, Mohammad Zaatari. A pesar de ser el hospital p\u00fablico m\u00e1s grande del L\u00edbano y operar a plena capacidad, el centro se encuentra dentro de una zona de evacuaci\u00f3n ordenada por Israel, lo que significa que tambi\u00e9n podr\u00eda convertirse en un objetivo. Con cientos de pacientes, incluidos los de cuidados intensivos, la evacuaci\u00f3n no es una opci\u00f3n.<\/p>\n<p>Fuera de las puertas del hospital, Mohamed Jirani caminaba de un lado a otro. Su t\u00edo hab\u00eda sido ingresado despu\u00e9s de que un edificio de apartamentos fuera alcanzado por un ataque a\u00e9reo israel\u00ed el 8 de abril.<\/p>\n<p>\u201cNo est\u00e1n atacando a combatientes. La mayor\u00eda de los heridos eran mujeres y ni\u00f1os, o personas desplazada\u201d, declar\u00f3 a CNN. \u201c\u00bfPor qu\u00e9 atacan a civiles si no tenemos armas? Vayan a cualquier hospital de Beirut e intenten encontrar un solo combatiente de Hezbollah. Todos son civiles\u201d.<\/p>\n<p>Estas fueron las escenas en Beirut la semana pasada, despu\u00e9s de que la capital libanesa sufriera un ataque israel\u00ed de una magnitud sin precedentes, apenas unas horas despu\u00e9s de que se firmara un alto el fuego en la guerra de Estados Unidos e Israel con Ir\u00e1n. Ahora, mientras la diplomacia entre Israel y L\u00edbano cobra impulso, la ciudad tiene un respiro, aunque recuperarse de la devastaci\u00f3n llevar\u00e1 tiempo y los ataques en el sur contin\u00faan.<\/p>\n<p>El gobierno israel\u00ed afirma que ataca a combatientes e infraestructura pertenecientes al grupo pol\u00edtico y militante liban\u00e9s Hezbollah, respaldado por Ir\u00e1n, que lleva d\u00e9cadas en conflicto con Israel. El objetivo, seg\u00fan el primer ministro israel\u00ed, Benjamin Netanyahu, es asegurar la regi\u00f3n fronteriza norte de su pa\u00eds. En todo el L\u00edbano, la poblaci\u00f3n civil est\u00e1 sufriendo las peores consecuencias del conflicto, que se reaviv\u00f3 cuando Hezbollah comenz\u00f3 a disparar contra Israel al inicio de la guerra.<\/p>\n<p>El gobierno liban\u00e9s, que incluye representantes pol\u00edticos de Hezbollah, tambi\u00e9n ha presionado al grupo, ilegalizando su brazo paramilitar y ordenando a las fuerzas de seguridad del pa\u00eds que retiren de la capital todas las armas no estatales. Sin embargo, los dirigentes de Hezbollah argumentan que ellos, y no un ej\u00e9rcito nacional d\u00e9bil, son la \u00fanica fuerza capaz de defender al L\u00edbano de los ataques israel\u00edes y de una posible ocupaci\u00f3n en el sur.<\/p>\n<p>El sur del L\u00edbano, donde Hezbollah ha tenido tradicionalmente un basti\u00f3n, ha sufrido bombardeos y ataques terrestres casi constantes durante m\u00e1s de dos a\u00f1os. Ahora, esta \u00faltima guerra ha extendido su alcance mucho m\u00e1s all\u00e1 del frente. En todo el L\u00edbano, pueblos y ciudades que antes se consideraban seguros, incluida la capital, se han visto azotados por una impredecible ola de ataques mortales de las fuerzas israel\u00edes.<\/p>\n<p>El Ministerio de Salud liban\u00e9s afirma que m\u00e1s de 2.000 personas han muerto \u2014entre ellas al menos 172 ni\u00f1os y 91 trabajadores sanitarios\u2014 y 7.000 han resultado heridas en tan solo seis semanas. Los ataques a\u00e9reos israel\u00edes han causado muertos y heridos entre la poblaci\u00f3n civil en sus hogares, en sus trabajos e incluso mientras se refugiaban en campamentos improvisados \u200b\u200bpara desplazados.<\/p>\n<p>Hace poco m\u00e1s de una semana, las fuerzas israel\u00edes lanzaron su mayor ataque coordinado contra el L\u00edbano desde el inicio de esta \u00faltima guerra, atacando, seg\u00fan describieron, 100 objetivos de Hezbollah en apenas 10 minutos. Los ataques israel\u00edes suelen ir precedidos de alguna advertencia: el ominoso zumbido de drones a baja altura y una orden de evacuaci\u00f3n difundida en redes sociales por el portavoz en \u00e1rabe de las Fuerzas de Defensa de Israel. Sin embargo, este ataque se produjo sin previo aviso. CNN se ha puesto en contacto con las FDI para obtener declaraciones.<\/p>\n<p>Barrios bulliciosos del centro de Beirut, que hasta ahora no se consideraban en la l\u00ednea de fuego, fueron atacados con segundos de diferencia. Edificios residenciales, tiendas y negocios locales quedaron destruidos en un instante, dejando a las v\u00edctimas sepultadas bajo los escombros y a los supervivientes aferr\u00e1ndose a los restos ennegrecidos de sus apartamentos.<\/p>\n<p>Los hospitales de todo L\u00edbano se encuentran en estado de emergencia tras los ataques. CNN visit\u00f3 el Hospital General Makassed de Beirut, donde una ni\u00f1a de tres a\u00f1os se recuperaba de heridas graves en la mano izquierda. Su madre cont\u00f3 que su hija hab\u00eda salido a jugar cuando el centro educativo donde se refugiaban fue bombardeado.<\/p>\n<p>\u201cSal\u00ed corriendo gritando \u2018\u00a1Mi hija, mi hija!\u2019. No ve\u00eda nada, solo oscuridad. La o\u00eda decir \u2018mam\u00e1, mam\u00e1\u2019, me llamaba\u201d, relat\u00f3 la mujer a CNN. \u201cEstaba removiendo los escombros con las manos. Intentaba ver, pero no pod\u00eda. Y entonces vi su cara, su cabeza. La saqu\u00e9 yo misma y la cargu\u00e9. Estaba en estado de shock\u201d.<\/p>\n<p>En sus tres a\u00f1os, su hija ya ha vivido dos guerras entre Israel y L\u00edbano. Cuando se duerme, dijo su madre, se tapa los o\u00eddos para no o\u00edr el sonido de los bombardeos cercanos.<\/p>\n<p>\u201c\u00bfPor qu\u00e9 mi hija tiene que vivir as\u00ed? Se aferra a m\u00ed y se agarra a mi velo por el miedo. \u00bfQu\u00e9 han hecho nuestros hijos para merecer esto?\u201d, dijo.<\/p>\n<p>Funcionarios del hospital dijeron que se estaban preparando para m\u00e1s v\u00edctimas, pero advirtieron que podr\u00edan quedarse sin suministros r\u00e1pidamente si se enfrentaban a nuevos ataques masivos. La Organizaci\u00f3n Mundial de la Salud tambi\u00e9n advirti\u00f3 que los suministros m\u00e9dicos esenciales en algunos hospitales del L\u00edbano est\u00e1n a punto de agotarse.<\/p>\n<p>\u201cSi la guerra contin\u00faa, f\u00edsicamente estamos aqu\u00ed, estamos preparados\u201d, dijo Joumana Najjar, gerente general del Hospital Makassed. \u201cNuestros m\u00e9dicos est\u00e1n listos, nuestro personal est\u00e1 listo. Pero tenemos una capacidad limitada en cuanto a suministros, en cuanto a medicamentos. No s\u00e9 cu\u00e1nto durar\u00e1 la guerra ni cu\u00e1nto tiempo podremos sostenerla\u201d.<\/p>\n<p>\u201cSiempre debemos estar preocupados por Israel; no sabemos qu\u00e9 har\u00e1n despu\u00e9s. Vimos lo que hicieron en Gaza\u201d.<\/p>\n<p>Con \u00f3rdenes de evacuaci\u00f3n forzosa vigentes al sur del r\u00edo Litani, las fuerzas israel\u00edes han intensificado progresivamente su ofensiva terrestre y sus ataques a\u00e9reos, dejando pueblos enteros de la regi\u00f3n completamente destruidos.<\/p>\n<p>Desde el 2 de marzo, las fuerzas israel\u00edes tambi\u00e9n han redoblado su campa\u00f1a de destrucci\u00f3n de puentes vitales que conectan el sur del L\u00edbano con el resto del pa\u00eds, dejando la regi\u00f3n cada vez m\u00e1s aislada. M\u00e1s de un mill\u00f3n de personas en el pa\u00eds \u2014alrededor del 20 % de su poblaci\u00f3n total\u2014 han sido desplazadas.<\/p>\n<p>Muchas de estas familias se encuentran ahora refugiadas en campamentos de desplazados en Beirut y sus alrededores, alojadas en escuelas, estadios y espacios comunitarios. Otras, sin embargo, siguen en la calle, con cientos de tiendas de campa\u00f1a a lo largo del elegante paseo mar\u00edtimo de la ciudad.<\/p>\n<p>\u201cNuestra situaci\u00f3n es muy desoladora. Nos fuimos sin siquiera nuestra ropa; no pudimos traer nada. Nos dijeron que nos refugi\u00e1ramos aqu\u00ed, y hemos estado aqu\u00ed en estas tiendas desde entonces\u201d, dijo Abu Mohamed, de 85 a\u00f1os. \u201cPerdimos nuestra casa. Si volvi\u00e9ramos, tendr\u00edamos que llevarnos nuestra tienda de campa\u00f1a. No nos queda nada\u201d.<\/p>\n<p>A lo largo de su vida, Abu Mohamed ha presenciado varias guerras con Israel, e incluso una ocupaci\u00f3n israel\u00ed. Ahora, afirma, apoyar\u00e1 a cualquiera que defienda al pa\u00eds de las fuerzas israel\u00edes.<\/p>\n<p>\u201cPodemos soportar todo esto mientras la resistencia se mantenga firme. Lo dem\u00e1s no importa, si tenemos comida, bebida o cualquier otra cosa. Lo \u00fanico que importa son nuestros hombres en la frontera, ellos son quienes nos protegen. Est\u00e1n defendiendo nuestra tierra, defendiendo nuestro pa\u00eds, nuestra dignidad\u201d.<\/p>\n<p>Durante una visita a un campo de desplazados en Beirut, la ministra de Asuntos Sociales del L\u00edbano, Hanin Sayyed, declar\u00f3 a CNN que \u201cni siquiera una sola persona en la calle es aceptable\u201d para el gobierno liban\u00e9s. Se dice que se han proporcionado refugios alternativos a quienes viven en campamentos improvisados, pero muchos desplazados, seg\u00fan Sayyed, se han negado a ser reubicados.<\/p>\n<p>\u201cEl problema es que muchos no quieren irse. Quieren volver a casa, y es comprensible. A\u00fan conservan la esperanza de poder regresar ma\u00f1ana a sus hogares en Dahiyeh o en el sur. Me resulta dif\u00edcil decirles que no creo que eso vaya a suceder\u201d, explic\u00f3.<\/p>\n<p>Si bien el n\u00famero de desplazados internos en L\u00edbano sigue aumentando a medida que se ampl\u00edan las \u00f3rdenes de evacuaci\u00f3n, todav\u00eda hay muchos en el sur que optan por quedarse.<\/p>\n<p>En la antigua ciudad costera de Tiro, las calles estaban inquietantemente silenciosas cuando CNN la visit\u00f3. Para los residentes que se han quedado, el leve rugido de los aviones de combate israel\u00edes sobrevolando la zona y el humo que se eleva a lo lejos son un recordatorio constante de que su ciudad es ahora una l\u00ednea de frente. Los edificios residenciales han sido bombardeados repetidamente, e incluso las \u00f3rdenes de evacuaci\u00f3n se han extendido al mar, dejando a los pescadores sin poder ganarse la vida.<\/p>\n<p>Marwan Al-Jouni naci\u00f3 y creci\u00f3 en Tiro. Su barrio cristiano se ha librado en gran medida de los peores ataques israel\u00edes \u2014Hezbollah ha afianzado su presencia en las zonas musulmanas de la ciudad\u2014, pero afirm\u00f3 que su comunidad apoya a sus vecinos chi\u00edtas.<\/p>\n<p>\u201cNos mantenemos unidos y nos apoyamos mutuamente. Permanecemos juntos para no tener miedo\u201d, declar\u00f3 Al-Jouni. \u201cEn estos tiempos dif\u00edciles, no abandonaremos nuestra tierra. Nos mantendremos firmes, incluso ante toda la presi\u00f3n y las dificultades que afrontamos seguiremos aqu\u00ed\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A las puertas del Hospital Universitario Rafik Hariri de Beirut, el costo humano de los ataques israel\u00edes contra el L\u00edbano, que han durado semanas, se reflejaba en los rostros de familias desesperadas que esperaban noticias de sus seres queridos. Las puertas de las ambulancias se abr\u00edan justo en la entrada en un intento de ocultar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473243","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel - Noticias\" \/>\n<meta property=\"og:description\" content=\"A las puertas del Hospital Universitario Rafik Hariri de Beirut, el costo humano de los ataques israel\u00edes contra el L\u00edbano, que han durado semanas, se reflejaba en los rostros de familias desesperadas que esperaban noticias de sus seres queridos. Las puertas de las ambulancias se abr\u00edan justo en la entrada en un intento de ocultar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-16T17:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel\",\"datePublished\":\"2026-04-16T17:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/\"},\"wordCount\":1755,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/\",\"name\":\"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-16T17:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel - Noticias","og_description":"A las puertas del Hospital Universitario Rafik Hariri de Beirut, el costo humano de los ataques israel\u00edes contra el L\u00edbano, que han durado semanas, se reflejaba en los rostros de familias desesperadas que esperaban noticias de sus seres queridos. Las puertas de las ambulancias se abr\u00edan justo en la entrada en un intento de ocultar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-16T17:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/"},"author":{"name":"","@id":""},"headline":"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel","datePublished":"2026-04-16T17:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/"},"wordCount":1755,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/","name":"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-16T17:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hospitales colapsados \u200b\u200by comunidades destruidas: el L\u00edbano se tambalea tras los ataques sin precedentes de Israel","url":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/libano-destruccion-ataques-israel-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-16T17:03:47Z","datePublished":"2026-04-16T17:03:47Z","dateModified":"2026-04-16T17:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hospitales colapsados \\u200b\\u200by comunidades destruidas: el L\\u00edbano se tambalea tras los ataques sin precedentes de Israel\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/libano-destruccion-ataques-israel-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/libano-destruccion-ataques-israel-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-16T17:03:47Z\",\"datePublished\":\"2026-04-16T17:03:47Z\",\"dateModified\":\"2026-04-16T17:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473420,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/22\/israel-crimenes-guerra-mato-periodista-libano-trax\/","url_meta":{"origin":1473243,"position":0},"title":"El primer ministro del L\u00edbano acusa a Israel de cr\u00edmenes de guerra tras  ataque que mat\u00f3 a una periodista","author":"","date":"abril 22, 2026","format":false,"excerpt":"El primer ministro del L\u00edbano acus\u00f3 a Israel de cr\u00edmenes de guerra luego de que un ataque a\u00e9reo en el sur del pa\u00eds este mi\u00e9rcoles matara a una periodista e hiriera gravemente a otra.Amal Khalil, quien trabajaba para el peri\u00f3dico liban\u00e9s Al Akhbar, muri\u00f3 mientras realizaba su trabajo period\u00edstico, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456040,"url":"https:\/\/noticiasya.com\/nacional\/2024\/11\/23\/ataques-beirut-libano-beirut-23-noviembre-trax\/","url_meta":{"origin":1473243,"position":1},"title":"Mueren al menos a 11 personas en ataques israel\u00edes en el centro de Beirut, seg\u00fan Defensa Civil","author":"","date":"noviembre 23, 2024","format":false,"excerpt":"(CNN) -- Al menos 11 personas murieron y varias resultaron heridas despu\u00e9s de que un ataque israel\u00ed arrasara durante la madrugada de este s\u00e1bado un edificio residencial de varias plantas en el centro de Beirut, seg\u00fan informaron las autoridades libanesas.Los equipos de rescate libaneses buscaban este s\u00e1bado por la ma\u00f1ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455724,"url":"https:\/\/noticiasya.com\/nacional\/2024\/11\/10\/libano-gaza-siria-ataques-israel-trax\/","url_meta":{"origin":1473243,"position":2},"title":"El L\u00edbano, Gaza y Siria sufren mort\u00edferos ataques de Israel: m\u00e1s de 80 muertos, seg\u00fan informes","author":"","date":"noviembre 10, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 M\u00e1s de 80 personas murieron en ataques israel\u00edes en el L\u00edbano, el norte de Gaza y Siria desde el s\u00e1bado por la noche, seg\u00fan informes.La Agencia Nacional de Noticias (NNA, por sus siglas en ingl\u00e9s) inform\u00f3 este domingo de ataques a\u00e9reos en la ciudad de Almat, en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452687,"url":"https:\/\/noticiasya.com\/nacional\/2024\/09\/14\/ejercito-israeli-ataca-almacenamiento-hezbollah-libano-trax\/","url_meta":{"origin":1473243,"position":3},"title":"El ej\u00e9rcito israel\u00ed dice que atac\u00f3 instalaciones de almacenamiento de armas de Hezbollah en varias \u00e1reas del L\u00edbano","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(CNN) -- El ej\u00e9rcito de Israel dice que atac\u00f3 \u201cinstalaciones de almacenamiento de armas\u201d de Hezbollah en m\u00faltiples ataques a\u00e9reos en todo el L\u00edbano este s\u00e1bado.Uno de los ataques, en las afueras de la ciudad de Al-Kawakh, en la gobernaci\u00f3n de Baalbek-Hermel, dej\u00f3 cuatro heridos, tres de ellos ni\u00f1os, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457888,"url":"https:\/\/noticiasya.com\/nacional\/2025\/01\/26\/tres-personas-murieron-residentes-libano-desafian-ordenes-israelies-trax\/","url_meta":{"origin":1473243,"position":4},"title":"Tres personas murieron mientras residentes del sur del L\u00edbano desaf\u00edan las \u00f3rdenes israel\u00edes de no regresar a sus hogares","author":"","date":"enero 26, 2025","format":false,"excerpt":"Tropas israel\u00edes mataron a tres personas e hirieron a otras 31 en el sur del L\u00edbano, inform\u00f3 el Gobierno liban\u00e9s, mientras los residentes de las aldeas cercanas a la frontera desafiaban las \u00f3rdenes de las fuerzas israel\u00edes de no regresar a sus hogares.\u201cUn ciudadano muri\u00f3 en Houla y otros nueve\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455051,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/12\/israel-hezbollah-enfrentamientos-frontera-bajas-trax\/","url_meta":{"origin":1473243,"position":5},"title":"La \u00faltima guerra de Israel contra Hezbollah termin\u00f3 en tablas. Los encarnizados enfrentamientos fronterizos sugieren que no ser\u00e1 f\u00e1cil ganar","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN) -- El hospital de Ziv, en el norte de Israel, est\u00e1 en alerta m\u00e1xima. Las operaciones no urgentes est\u00e1n suspendidas, se ha pedido al personal que considere la posibilidad de donar sangre cuando sea necesario y todos los pacientes -incluidos los reci\u00e9n nacidos en la unidad de maternidad- han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1473243"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473243\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1473243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1473243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1473243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}