{"id":1473260,"date":"2026-04-16T19:03:38","date_gmt":"2026-04-17T02:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/"},"modified":"2026-04-16T19:03:38","modified_gmt":"2026-04-17T02:03:38","slug":"fmi-reanuda-relaciones-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","title":{"rendered":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n"},"content":{"rendered":"<p>El Fondo Monetario Internacional (FMI) anunci\u00f3 este jueves la reanudaci\u00f3n de sus relaciones con Venezuela bajo el Gobierno de la presidenta interina, Delcy Rodr\u00edguez, tras haberlas suspendido en 2019 por cuestiones de \u201creconocimiento del Gobierno\u201d, seg\u00fan inform\u00f3 la directora gerente Kristalina Georgieva.<\/p>\n<p>El FMI anunci\u00f3 este jueves en Washington la reanudaci\u00f3n de sus relaciones con Venezuela, una decisi\u00f3n adoptada en consonancia con \u201clas opiniones de los miembros del Fondo Monetario Internacional que representan la mayor\u00eda del poder de voto total del FMI\u201d, seg\u00fan el comunicado oficial difundido por el organismo.<\/p>\n<p>La decisi\u00f3n sucede durante las Reuniones de Primavera del FMI y el Banco Mundial que iniciaron el 13 de abril y concluir\u00e1n el s\u00e1bado.<\/p>\n<p>Adem\u00e1s, la reanudaci\u00f3n llega en un momento en el que Caracas ha retomado sus relaciones diplom\u00e1ticas con Estados Unidos, desde la captura de Nicol\u00e1s Maduro el pasado 3 de enero y el visto bueno que Rodr\u00edguez recibi\u00f3 al aceptar las condiciones econ\u00f3micas y petroleras de Trump y que se han materializado en varias leyes aprobadas en Venezuela para permitir la inversi\u00f3n extranjera en petr\u00f3leo y miner\u00eda.<\/p>\n<p>El Fondo record\u00f3 adem\u00e1s que Venezuela es miembro de la instituci\u00f3n desde 1946, pero que las relaciones con el pa\u00eds hab\u00edan sido suspendidas en marzo de 2019, cuando el organismo decidi\u00f3 pausar sus contactos \u201cdebido a cuestiones de reconocimiento del gobierno\u201d.<\/p>\n<p>Venezuela atraves\u00f3 una dura crisis pol\u00edtica ese a\u00f1o, cuando Maduro asumi\u00f3 un nuevo mandato que la oposici\u00f3n consider\u00f3 ileg\u00edtimo, llevando a la autoproclamaci\u00f3n de Juan Guaid\u00f3 como presidente encargado, que fue reconocido por decenas de pa\u00edses alrededor del mundo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Fondo Monetario Internacional (FMI) anunci\u00f3 este jueves la reanudaci\u00f3n de sus relaciones con Venezuela bajo el Gobierno de la presidenta interina, Delcy Rodr\u00edguez, tras haberlas suspendido en 2019 por cuestiones de \u201creconocimiento del Gobierno\u201d, seg\u00fan inform\u00f3 la directora gerente Kristalina Georgieva. El FMI anunci\u00f3 este jueves en Washington la reanudaci\u00f3n de sus relaciones con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473260","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Fondo Monetario Internacional (FMI) anunci\u00f3 este jueves la reanudaci\u00f3n de sus relaciones con Venezuela bajo el Gobierno de la presidenta interina, Delcy Rodr\u00edguez, tras haberlas suspendido en 2019 por cuestiones de \u201creconocimiento del Gobierno\u201d, seg\u00fan inform\u00f3 la directora gerente Kristalina Georgieva. El FMI anunci\u00f3 este jueves en Washington la reanudaci\u00f3n de sus relaciones con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T02:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n\",\"datePublished\":\"2026-04-17T02:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/\",\"name\":\"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-17T02:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n - Noticias","og_description":"El Fondo Monetario Internacional (FMI) anunci\u00f3 este jueves la reanudaci\u00f3n de sus relaciones con Venezuela bajo el Gobierno de la presidenta interina, Delcy Rodr\u00edguez, tras haberlas suspendido en 2019 por cuestiones de \u201creconocimiento del Gobierno\u201d, seg\u00fan inform\u00f3 la directora gerente Kristalina Georgieva. El FMI anunci\u00f3 este jueves en Washington la reanudaci\u00f3n de sus relaciones con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-17T02:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n","datePublished":"2026-04-17T02:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","name":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-17T02:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El FMI reanuda sus relaciones con Venezuela tras siete a\u00f1os de suspensi\u00f3n","url":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/04\/16\/fmi-reanuda-relaciones-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-17T02:03:38Z","datePublished":"2026-04-17T02:03:38Z","dateModified":"2026-04-17T02:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El FMI reanuda sus relaciones con Venezuela tras siete a\\u00f1os de suspensi\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/fmi-reanuda-relaciones-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/16\\\/fmi-reanuda-relaciones-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-17T02:03:38Z\",\"datePublished\":\"2026-04-17T02:03:38Z\",\"dateModified\":\"2026-04-17T02:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473285,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/17\/cambios-banco-central-guerra-perez-orix\/","url_meta":{"origin":1473260,"position":0},"title":"Cambios en el Banco Central de Venezuela: \u00bfqui\u00e9n era la presidenta del organismo y qui\u00e9n lleg\u00f3 en su lugar?","author":"","date":"abril 17, 2026","format":false,"excerpt":"Delcy Rodr\u00edguez, presidenta encargada de Venezuela desde el derrocamiento de Nicol\u00e1s Maduro en enero, sigue haciendo cambios en el Gobierno y esta vez fue el turno del Banco Central de Venezuela (BCV): el jueves, Rodr\u00edguez anunci\u00f3 que Laura Guerra renunci\u00f3 a la presidencia del organismo y Luis P\u00e9rez fue designado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443546,"url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/11\/que-sigue-tras-el-acuerdo-del-fondo-monetario-internacional-y-el-gobierno-argentino\/","url_meta":{"origin":1473260,"position":1},"title":"\u00bfQu\u00e9 sigue tras el acuerdo del Fondo Monetario Internacional y el Gobierno argentino?","author":"","date":"enero 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Fondo Monetario Internacional (FMI) anunci\u00f3 que lleg\u00f3 a un acuerdo con el Gobierno de Argentina, lo que le permitir\u00e1 al pa\u00eds obtener un desembolso de US$ 4.700 millones. El entendimiento se dio en el marco de la s\u00e9ptima revisi\u00f3n del acuerdo del Programa de Facilidades Extendidas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458970,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/20\/la-preocupacion-del-fmi-antes-del-acuerdo-con-el-fmi-segun-hector-torres\/","url_meta":{"origin":1473260,"position":2},"title":"Los reparos que puede tener el FMI antes del acuerdo con el gobierno, seg\u00fan H\u00e9ctor Torres","author":"","date":"febrero 20, 2025","format":false,"excerpt":"H\u00e9ctor Torres, exrepresentante de la Argentina ante el FMI, habl\u00f3 este jueves en CNN Radio sobre la reuni\u00f3n de Javier Milei con Kristalina Georgieva en Washington y un posible nuevo acuerdo con el Fondo Monetario Internacional.\u201cNo creo que el Fondo est\u00e9 tratando de dilucidar la responsabilidad del presidente\u201d, explic\u00f3 Torres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456742,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/18\/el-salvador-acuerdo-fmi-1400-millones-orix\/","url_meta":{"origin":1473260,"position":3},"title":"El Salvador avanza en acuerdo de Servicio Ampliado con el Fondo Monetario Internacional por US$ 1.400 millones","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"El Fondo Monetario Internacional (FMI) inform\u00f3 este mi\u00e9rcoles en un comunicado que alcanz\u00f3 un acuerdo con autoridades de El Salvador por un servicio Ampliado del Fondo por US$ 1.400 millones, a usarse en un programa de 40 meses.\u201cEl acuerdo est\u00e1 sujeto a la aprobaci\u00f3n del Directorio Ejecutivo del FMI y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460499,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/27\/argentina-y-el-fmi-tramitan-un-prestamo-por-ususd-20-000-millones\/","url_meta":{"origin":1473260,"position":4},"title":"Argentina y el FMI tramitan un pr\u00e9stamo por US$ 20.000 millones","author":"","date":"marzo 27, 2025","format":false,"excerpt":"El ministro de Econom\u00eda de Argentina, Luis Caputo, revel\u00f3 este jueves que el pa\u00eds est\u00e1 cerca de cerrar un nuevo acuerdo con el Fondo Monetario Internacional para un pr\u00e9stamo de US$ 20.000 millones.Caputo asegur\u00f3 durante una exposici\u00f3n en la Conferencia Anual sobre Regulaci\u00f3n y Supervisi\u00f3n de Seguros en Am\u00e9rica Latina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460653,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/31\/delgado-economista-el-gobierno-se-adelanto-en-anunciar-el-acuerdo-con-el-fmi\/","url_meta":{"origin":1473260,"position":5},"title":"Delgado, economista: &#171;El gobierno se adelant\u00f3 en anunciar el acuerdo con el FMI&#187;","author":"","date":"marzo 31, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Ricardo Delgado, economista y presidente de la consultora Analytica, dialog\u00f3 este lunes con Regreso CNN con Mariana Arias y Pepe Gil Vidal sobre la incertidumbre en los mercados y la comunicaci\u00f3n del gobierno respecto al acuerdo con el Fondo Monetario Internacional (FMI).\u201cEste ha sido un d\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1473260"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473260\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1473260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1473260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1473260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}