{"id":1473326,"date":"2026-04-20T05:03:44","date_gmt":"2026-04-20T12:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/"},"modified":"2026-04-20T05:03:44","modified_gmt":"2026-04-20T12:03:44","slug":"machado-advierte-peligroso-retrasar-elecciones-venezuela-efe","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","title":{"rendered":"Mar\u00eda Corina Machado advierte que es &#171;m\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos"},"content":{"rendered":"<p>La l\u00edder opositora Mar\u00eda Corina Machado asegur\u00f3 este domingo que \u201ces importante\u201d que Venezuela celebre elecciones democr\u00e1ticas lo antes posible para que \u201clos venezolanos no se desesperen y toda la energ\u00eda se canalice de una manera c\u00edvica\u201d.<\/p>\n<p>En una entrevista con EFE en Madrid, la premio nobel de la paz dijo que \u201caquellos que ven un riesgo en el proceso electoral, no est\u00e1n viendo que no hacer elecciones conlleva un riesgo mucho mayor\u201d.<\/p>\n<p>\u201cSi los venezolanos sienten que lo que est\u00e1 pasando es un tema econ\u00f3mico, por la plata, y no por la gente, pueden perder completamente la paciencia\u201d, advirti\u00f3.<\/p>\n<p>\u201cDe hecho yo voy a volver a Venezuela para asegurarme de que el proceso sea pac\u00edfico y que se canalice toda esa energ\u00eda, toda esa angustia, alrededor de un proceso electoral\u201d, anunci\u00f3 la venezolana, que abandon\u00f3 el pa\u00eds para recoger el Premio Nobel de la Paz y hasta el momento no ha dado a conocer su fecha de vuelta a un pa\u00eds cuyos actuales gobernantes la acusan de conspiraci\u00f3n.<\/p>\n<p>Para llevar a cabo una transici\u00f3n pac\u00edfica, Mar\u00eda Corina Machado estar\u00eda dispuesta a sentarse a dialogar con la actual presidenta encargada de Venezuela, Delcy Rodr\u00edguez.<\/p>\n<p>\u201cNosotros le hemos ofrecido, como vencedores de la elecci\u00f3n del 28 de julio, nuestra disposici\u00f3n a lograr un acuerdo para una transici\u00f3n negociada en m\u00faltiples oportunidades -revel\u00f3-, pero ella no ha querido\u201d.<\/p>\n<p>Asimismo, Machado dijo que est\u00e1 \u201cen comunicaci\u00f3n\u201d y en \u201cproceso de intercambio de informaci\u00f3n permanente\u201d con \u201cpersonas que est\u00e1n en distintas instancias del r\u00e9gimen y la administraci\u00f3n p\u00fablica\u201d para llevar a cabo un \u201cproceso de transici\u00f3n pacifica\u201d.<\/p>\n<p>La premio nobel est\u00e1 convencida de que Venezuela \u201cest\u00e1 preparada, decidida y absolutamente deseosa\u201d de llevar a cabo elecciones libres, \u201cporque es la manera de sanar heridas y de poder iniciar el proceso de retorno de nuestros hijos a casa\u201d.<\/p>\n<p>Asimismo subray\u00f3 que \u201cel proceso se podr\u00eda poner en marcha ma\u00f1ana mismo\u201d y calcula que \u201ccuarenta semanas es el plazo necesario para tener listos todos los aspectos t\u00e9cnicos\u201d.<\/p>\n<p>No obstante reconoce que \u201ctambi\u00e9n hay que tener en cuanta alguna consideraciones de orden pol\u00edtico\u201d, por lo que no puede adelantar una fecha.<\/p>\n<p>Aun as\u00ed insisti\u00f3 en que \u201cel proceso ya no se puede detener\u201d, porque la captura del exmandatario Nicol\u00e1s Maduro \u201cderrib\u00f3 todos los diques\u201d y ahora \u201cel cauce es imparable\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La l\u00edder opositora Mar\u00eda Corina Machado asegur\u00f3 este domingo que \u201ces importante\u201d que Venezuela celebre elecciones democr\u00e1ticas lo antes posible para que \u201clos venezolanos no se desesperen y toda la energ\u00eda se canalice de una manera c\u00edvica\u201d. En una entrevista con EFE en Madrid, la premio nobel de la paz dijo que \u201caquellos que ven [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473326","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mar\u00eda Corina Machado advierte que es &quot;m\u00e1s peligroso&quot; aplazar los comicios en Venezuela que acelerarlos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mar\u00eda Corina Machado advierte que es &quot;m\u00e1s peligroso&quot; aplazar los comicios en Venezuela que acelerarlos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La l\u00edder opositora Mar\u00eda Corina Machado asegur\u00f3 este domingo que \u201ces importante\u201d que Venezuela celebre elecciones democr\u00e1ticas lo antes posible para que \u201clos venezolanos no se desesperen y toda la energ\u00eda se canalice de una manera c\u00edvica\u201d. En una entrevista con EFE en Madrid, la premio nobel de la paz dijo que \u201caquellos que ven [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T12:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mar\u00eda Corina Machado advierte que es &#171;m\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos\",\"datePublished\":\"2026-04-20T12:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/\"},\"wordCount\":450,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/\",\"name\":\"Mar\u00eda Corina Machado advierte que es \\\"m\u00e1s peligroso\\\" aplazar los comicios en Venezuela que acelerarlos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-20T12:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mar\u00eda Corina Machado advierte que es &#171;m\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mar\u00eda Corina Machado advierte que es \"m\u00e1s peligroso\" aplazar los comicios en Venezuela que acelerarlos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","og_locale":"es_ES","og_type":"article","og_title":"Mar\u00eda Corina Machado advierte que es \"m\u00e1s peligroso\" aplazar los comicios en Venezuela que acelerarlos - Noticias","og_description":"La l\u00edder opositora Mar\u00eda Corina Machado asegur\u00f3 este domingo que \u201ces importante\u201d que Venezuela celebre elecciones democr\u00e1ticas lo antes posible para que \u201clos venezolanos no se desesperen y toda la energ\u00eda se canalice de una manera c\u00edvica\u201d. En una entrevista con EFE en Madrid, la premio nobel de la paz dijo que \u201caquellos que ven [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","og_site_name":"Noticias","article_published_time":"2026-04-20T12:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/"},"author":{"name":"","@id":""},"headline":"Mar\u00eda Corina Machado advierte que es &#171;m\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos","datePublished":"2026-04-20T12:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/"},"wordCount":450,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","url":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","name":"Mar\u00eda Corina Machado advierte que es \"m\u00e1s peligroso\" aplazar los comicios en Venezuela que acelerarlos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-20T12:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mar\u00eda Corina Machado advierte que es &#171;m\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mar\u00eda Corina Machado advierte que es &#171;m\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos","url":"http:\/\/noticiasya.com\/nacional\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/04\/20\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-20T12:03:44Z","datePublished":"2026-04-20T12:03:44Z","dateModified":"2026-04-20T12:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mar\\u00eda Corina Machado advierte que es &#171;m\\u00e1s peligroso&#187; aplazar los comicios en Venezuela que acelerarlos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/20\\\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/20\\\/machado-advierte-peligroso-retrasar-elecciones-venezuela-efe\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-20T12:03:44Z\",\"datePublished\":\"2026-04-20T12:03:44Z\",\"dateModified\":\"2026-04-20T12:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450199,"url":"https:\/\/noticiasya.com\/nacional\/2024\/06\/10\/maria-corina-machado-critica-revocacion-invitacion-observadores-union-europea-orix\/","url_meta":{"origin":1473326,"position":0},"title":"Mar\u00eda Corina Machado: La revocaci\u00f3n de la invitaci\u00f3n a observadores de la Uni\u00f3n Europea \u201ces una se\u00f1al muy negativa\u201d","author":"","date":"junio 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En una intervenci\u00f3n este lunes ante la Comisi\u00f3n de Asuntos Iberoamericanos del Senado de Espa\u00f1a, la l\u00edder opositora venezolana Mar\u00eda Corina Machado pidi\u00f3 que la Uni\u00f3n Europea (UE) insista contra la revocaci\u00f3n de Venezuela a la invitaci\u00f3n a la Misi\u00f3n de Observaci\u00f3n Internacional del bloque para las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451349,"url":"https:\/\/noticiasya.com\/nacional\/2024\/07\/22\/maria-corina-machado-venezuela-elecciones-conclusiones-entrevista-conclu-orix\/","url_meta":{"origin":1473326,"position":1},"title":"Mar\u00eda Corina Machado en Conclusiones: Maduro ha hecho de su campa\u00f1a la violencia, es lo \u00fanico que le queda","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Mar\u00eda Corina Machado asegur\u00f3 en Conclusiones de CNN con Fernando del Rinc\u00f3n que Nicol\u00e1s Maduro ha hecho de su campa\u00f1a la violencia debido a que es lo \u00fanico que le queda, pues el r\u00e9gimen se ha desgastado tanto que \"ya est\u00e1 derrotado\".La semana pasada, el presidente Nicol\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467272,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/10\/alegria-descontento-venezolanos-reaccionan-nobel-machado-orix\/","url_meta":{"origin":1473326,"position":2},"title":"De la alegr\u00eda al descontento: as\u00ed reaccionan los venezolanos al Nobel de la Paz otorgado a Mar\u00eda Corina Machado","author":"","date":"octubre 10, 2025","format":false,"excerpt":"Venezuela se despert\u00f3 este viernes con una noticia de alcance global: el Comit\u00e9 Noruego del Nobel otorg\u00f3 el Premio Nobel de la Paz a la l\u00edder opositora venezolana Mar\u00eda Corina Machado, por lo que describi\u00f3 como su trabajo para \u201cpromover los derechos democr\u00e1ticos del pueblo\u201d y \u201cmantener encendida la llama\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458760,"url":"https:\/\/noticiasya.com\/nacional\/2025\/02\/14\/maria-corina-machado-premio-justicia-social-georgia-orix\/","url_meta":{"origin":1473326,"position":3},"title":"Mar\u00eda Corina Machado recibe premio de justicia social d\u200bel Instituto Tecnol\u00f3gico de Georgia","author":"","date":"febrero 14, 2025","format":false,"excerpt":"La dirigente opositora venezolana Mar\u00eda Corina Machado recibi\u00f3 este viernes el premio Ivan Allen Jr. de Justicia Social, un galard\u00f3n que el Instituto Tecnol\u00f3gico de Georgia, en Estados Unidos, entrega desde 2011 a personas de todo el mundo que \u201cact\u00faan con valent\u00eda para mejorar la condici\u00f3n humana\u201d, seg\u00fan su p\u00e1gina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447067,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/17\/maria-corina-machado-no-sacaran-oposicion-venezolana-ruta-electoral-y-decisiones-correctas-para-avanzar-orix\/","url_meta":{"origin":1473326,"position":4},"title":"Mar\u00eda Corina Machado asegura que no sacar\u00e1n a la oposici\u00f3n venezolana de la ruta electoral y que tomar\u00e1 \u201clas decisiones correctas para avanzar\u201d","author":"","date":"marzo 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La aspirante presidencial opositora venezolana Mar\u00eda Corina Machado difundi\u00f3 este domingo un video en sus redes sociales, en el cual asegura que el gobierno del presidente Nicol\u00e1s Maduro quiere montar unas elecciones a su medida.Agrega que ella y los partidos que la respaldan han decidido que no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464926,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/28\/chavismo-anuncia-triunfo-elecciones-municipales-maduro-orix\/","url_meta":{"origin":1473326,"position":5},"title":"Sin sorpresas: a un a\u00f1o de las cuestionadas elecciones presidenciales, chavismo anuncia triunfo en comicios municipales","author":"","date":"julio 28, 2025","format":false,"excerpt":"Este lunes se cumple un a\u00f1o de las cuestionadas elecciones presidenciales en Venezuela, en las cuales Nicol\u00e1s Maduro anunci\u00f3 su reelecci\u00f3n en medio de acusaciones de fraude.El resultado fue rechazado por parte de la oposici\u00f3n, que aleg\u00f3 que su candidato Edmundo Gonz\u00e1lez fue el verdadero ganador, y tambi\u00e9n por parte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1473326"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473326\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1473326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1473326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1473326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}