{"id":1473608,"date":"2026-04-28T12:03:53","date_gmt":"2026-04-28T19:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/"},"modified":"2026-04-28T12:03:53","modified_gmt":"2026-04-28T19:03:53","slug":"polymarket-maduro-soldado-apuestas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","title":{"rendered":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente"},"content":{"rendered":"<p>El militar de fuerzas especiales involucrado en la captura del presidente depuesto de Venezuela Nicol\u00e1s Maduro se declar\u00f3 inocente este martes de usar informaci\u00f3n clasificada sobre el operativo para obtener m\u00e1s de US$ 400.000 en ganancias ilegales.<\/p>\n<p>Gannon Ken Van Dyke, un militar activo de 38 a\u00f1os destinado en Fort Bragg, compareci\u00f3 vestido de civil ante la jueza Margaret Garnett en Nueva York.<\/p>\n<p>El caso es la primera vez que fiscales federales presentan cargos relacionados con apuestas realizadas en un mercado de predicci\u00f3n, el popular espacio donde las personas apuestan \u201cs\u00ed\u201d o \u201cno\u201d sobre resultados que van desde partidos deportivos y la boda de Taylor Swift hasta eventos geopol\u00edticos.<\/p>\n<p>Los fiscales alegan que Van Dyke particip\u00f3 en la planificaci\u00f3n y ejecuci\u00f3n de la in\u00e9dita acci\u00f3n militar en las primeras horas del 3 de enero de 2026, cuando militares de EE.UU. sacaron a Maduro y a su esposa del palacio presidencial en Caracas, Venezuela, bajo intenso fuego cruzado.<\/p>\n<p>Las autoridades aseguran que Van Dyke utiliz\u00f3 su conocimiento sobre la operaci\u00f3n clasificada para hacer apuestas en Polymarket en los d\u00edas y horas previas al operativo. Presuntamente apost\u00f3 US$ 32.000 sobre la participaci\u00f3n de EE.UU. en Venezuela, incluida una apuesta a que Maduro estar\u00eda \u201cfuera\u201d de Venezuela antes de finales de enero. Tras el exitoso operativo, Van Dyke obtuvo m\u00e1s de US$ 400.000 en ganancias.<\/p>\n<p>Seg\u00fan la acusaci\u00f3n, Van Dyke transfiri\u00f3 las ganancias a una b\u00f3veda extranjera de criptomonedas antes de moverlas a una cuenta de corretaje en l\u00ednea reci\u00e9n creada. Tras reportes period\u00edsticos que se\u00f1alaron la exitosa apuesta, el documento judicial sostiene que Van Dyke pidi\u00f3 a Polymarket eliminar su cuenta.<\/p>\n<p>Seg\u00fan la acusaci\u00f3n, fue fotografiado poco despu\u00e9s del operativo en \u201clo que parece ser la cubierta de un barco en el mar, al amanecer, usando uniforme militar de EE.UU. y portando un rifle, junto a otras tres personas con uniforme militar estadounidense\u201d.<\/p>\n<p>Van Dyke fue arrestado el jueves por la noche y acusado de uso indebido de informaci\u00f3n gubernamental confidencial para beneficio personal, robo de informaci\u00f3n gubernamental no p\u00fablica, fraude de materias primas, fraude electr\u00f3nico y realizaci\u00f3n de una transacci\u00f3n monetaria ilegal. El viernes compareci\u00f3 por primera vez ante un tribunal federal en Carolina del Norte y fue liberado tras pagar una fianza de US$ 250.000.<\/p>\n<p>La apuesta relacionada con Maduro es una de varias operaciones sospechosas que han llamado la atenci\u00f3n recientemente. Legisladores y reportes de prensa han se\u00f1alado grandes movimientos en el mercado de futuros del petr\u00f3leo antes de anuncios clave relacionados con el conflicto entre EE.UU. e Ir\u00e1n.<\/p>\n<p>Tras el arresto de Van Dyke, el presidente Donald Trump dijo en respuesta a preguntas que le preocupa la creciente tendencia global de apostar sobre eventos geopol\u00edticos y afirm\u00f3 que el mundo se ha convertido en \u201cun casino\u201d. \u201cNo estoy contento con eso\u201d, a\u00f1adi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El militar de fuerzas especiales involucrado en la captura del presidente depuesto de Venezuela Nicol\u00e1s Maduro se declar\u00f3 inocente este martes de usar informaci\u00f3n clasificada sobre el operativo para obtener m\u00e1s de US$ 400.000 en ganancias ilegales. Gannon Ken Van Dyke, un militar activo de 38 a\u00f1os destinado en Fort Bragg, compareci\u00f3 vestido de civil [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473608","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente - Noticias\" \/>\n<meta property=\"og:description\" content=\"El militar de fuerzas especiales involucrado en la captura del presidente depuesto de Venezuela Nicol\u00e1s Maduro se declar\u00f3 inocente este martes de usar informaci\u00f3n clasificada sobre el operativo para obtener m\u00e1s de US$ 400.000 en ganancias ilegales. Gannon Ken Van Dyke, un militar activo de 38 a\u00f1os destinado en Fort Bragg, compareci\u00f3 vestido de civil [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-28T19:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente\",\"datePublished\":\"2026-04-28T19:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/\"},\"wordCount\":529,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/\",\"name\":\"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-28T19:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente - Noticias","og_description":"El militar de fuerzas especiales involucrado en la captura del presidente depuesto de Venezuela Nicol\u00e1s Maduro se declar\u00f3 inocente este martes de usar informaci\u00f3n clasificada sobre el operativo para obtener m\u00e1s de US$ 400.000 en ganancias ilegales. Gannon Ken Van Dyke, un militar activo de 38 a\u00f1os destinado en Fort Bragg, compareci\u00f3 vestido de civil [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-28T19:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/"},"author":{"name":"","@id":""},"headline":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente","datePublished":"2026-04-28T19:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/"},"wordCount":529,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","name":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-28T19:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente","url":"http:\/\/noticiasya.com\/nacional\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-28T19:03:53Z","datePublished":"2026-04-28T19:03:53Z","dateModified":"2026-04-28T19:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Soldado que apost\\u00f3 en Polymarket sobre captura de Maduro y gan\\u00f3 US$ 400.000 se declar\\u00f3 inocente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/28\\\/polymarket-maduro-soldado-apuestas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2026\\\/04\\\/28\\\/polymarket-maduro-soldado-apuestas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-28T19:03:53Z\",\"datePublished\":\"2026-04-28T19:03:53Z\",\"dateModified\":\"2026-04-28T19:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473447,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/23\/arrestan-soldado-apuesta-captura-maduro-trax\/","url_meta":{"origin":1473608,"position":0},"title":"Arrestan a soldado de fuerzas especiales de EE.UU. tras presuntamente ganar US$ 400.000 en apuesta sobre la captura de Maduro","author":"","date":"abril 23, 2026","format":false,"excerpt":"Un soldado de fuerzas especiales de EE.UU. involucrado en la captura del presidente de Venezuela Nicol\u00e1s Maduro fue arrestado por presuntamente apostar por esa operaci\u00f3n, obteniendo US$ 400.000 en ganancias, seg\u00fan una persona familiarizada con el asunto.La operaci\u00f3n de tama\u00f1o desproporcionado llam\u00f3 la atenci\u00f3n de las fuerzas del orden casi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473473,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/24\/trump-soldado-apuesta-maduro-polymarket-trax\/","url_meta":{"origin":1473608,"position":1},"title":"La defensa desafortunada de Trump a un soldado acusado de apostar por la ca\u00edda de Maduro en Polymarket","author":"","date":"abril 24, 2026","format":false,"excerpt":"Por primera vez, vemos que se exige responsabilidad legal por la oleada de operaciones especulativas sospechosamente oportunas en mercados de predicci\u00f3n, justo antes de importantes decisiones de la administraci\u00f3n Trump.El Departamento de Justicia ha imputado a un soldado de las fuerzas especiales estadounidenses que presuntamente utiliz\u00f3 informaci\u00f3n clasificada para ganar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473491,"url":"https:\/\/noticiasya.com\/nacional\/2026\/04\/24\/apuestas-informacion-privilegiada-polymarket-trax\/","url_meta":{"origin":1473608,"position":2},"title":"De la ca\u00edda de Maduro a los ataques en Ir\u00e1n: apuestas levantan dudas sobre uso de informaci\u00f3n privilegiada","author":"","date":"abril 24, 2026","format":false,"excerpt":"Despu\u00e9s de que militares estadounidenses capturaran al presidente de Venezuela, Nicol\u00e1s Maduro, en enero, la imagen de \u00e9l esposado y con los ojos vendados mientras vest\u00eda un pants de Nike no fue lo \u00fanico que se volvi\u00f3 viral.Pronto, Internet bull\u00eda por un operador an\u00f3nimo en Polymarket, el mercado de predicci\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469805,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/05\/nicolas-maduro-cilia-flores-audiencia-nueva-york-trax\/","url_meta":{"origin":1473608,"position":3},"title":"\u00bfQu\u00e9 pas\u00f3 en la audiencia de Nicol\u00e1s Maduro y Cilia Flores y qu\u00e9 sigue en el proceso?","author":"","date":"enero 5, 2026","format":false,"excerpt":"Durante la primera audiencia en Nueva York en el caso contra el presidente de Venezuela Nicol\u00e1s Maduro y su esposa Cilia Flores, los acusados proclamaron su inocencia y acusaron al Gobierno de EE.UU. de secuestrarlos en su hogar.Tanto Maduro como su esposa se declararon inocentes de los cargos de drogas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469859,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/07\/juan-orlando-hernandez-maduro-procesos-judiciales-trump-orix\/","url_meta":{"origin":1473608,"position":4},"title":"Uno recibi\u00f3 un indulto y el otro fue derrocado: c\u00f3mo difieren los procesos judiciales de Juan Orlando Hern\u00e1ndez y Maduro","author":"","date":"enero 7, 2026","format":false,"excerpt":"Dos expresidentes. Dos procesos federales por narcotr\u00e1fico. Un mismo tribunal en Manhattan. Y una Casa Blanca con posturas contradictorias.Las causas judiciales en Estados Unidos contra el expresidente de Honduras, Juan Orlando Hern\u00e1ndez, y el l\u00edder venezolano, Nicol\u00e1s Maduro, se inscriben en el mismo sistema federal, pero llegaron hasta all\u00ed por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469825,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/06\/maneras-defensa-desbaratar-caso-maduro-trax\/","url_meta":{"origin":1473608,"position":5},"title":"Las m\u00faltiples maneras en que los abogados de Maduro podr\u00edan intentar desbaratar el caso en su contra","author":"","date":"enero 6, 2026","format":false,"excerpt":"El caso contra el derrocado presidente de Venezuela Nicol\u00e1s Maduro no ha avanzado en los \u00faltimos seis a\u00f1os.Tras su captura y su primera comparecencia ante el tribunal federal de Manhattan, llegar a juicio podr\u00eda llevar a\u00fan m\u00e1s a\u00f1os, con un sinf\u00edn de inusuales batallas pol\u00edticas y legales por delante.El caso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1473608"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1473608\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1473608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1473608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1473608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}